{"id":83393,"date":"2021-02-09T12:15:18","date_gmt":"2021-02-09T15:15:18","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=83393"},"modified":"2021-02-11T12:21:35","modified_gmt":"2021-02-11T15:21:35","slug":"fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas\/","title":{"rendered":"F\u00e1bio Andr\u00e9 Rheinheimer une arte e tecnologia na mostra &#8220;Naves po\u00e9ticas&#8221;"},"content":{"rendered":"<p style=\"font-weight: 400\">O arquiteto, curador e artista visual F\u00e1bio Andr\u00e9 Rheinheimer inaugura exposi\u00e7\u00e3o individual em Porto Alegre, depois de sua estreia em dezembro, em S\u00e3o Paulo. \u00c9 o \u201cProjeto Naves Po\u00e9ticas\u201d, nessa quarta-feira, 10 de fevereiro, no Espa\u00e7o Cultural Correios, localizado no t\u00e9rreo da Av. Sete de Setembro, 1020, no Centro Hist\u00f3rico, em Porto Alegre. A mostra segue at\u00e9 27 de mar\u00e7o, com entrada franca.<\/p>\n<figure id=\"attachment_83398\" aria-describedby=\"caption-attachment-83398\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"83398\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas\/exposicao-fabio-199\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-scaled.jpg\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;JULIANA BARATOJO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1612355991&quot;,&quot;copyright&quot;:&quot;JULIANA BARATOJO&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"EXPOSI\u00c7\u00c3O fabio-199\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; F\u00e1bio Andr\u00e9 Rheinheimer, apresenta projeto &amp;#8220;Naves po\u00e9ticas&amp;#8221;\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-1024x683.jpg\" class=\"size-medium wp-image-83398\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-1024x683.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-199-1200x800.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-83398\" class=\"wp-caption-text\">F\u00e1bio Andr\u00e9 Rheinheimer, apresenta projeto &#8220;no Espa\u00e7o Cultural dos Correios&#8221;. Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">A exposi\u00e7\u00e3o \u00e9 formada por 20 obras em formato de escultura tridimensionais. Com materiais como l\u00e2minas de acr\u00edlico r\u00edgido e LED, Rheinheimer comp\u00f5e sua obra de formas e luzes, produzindo um grande efeito cenogr\u00e1fico. Pelas caracter\u00edsticas de transpar\u00eancia e luminosidade, as obras podem ser expostas como elementos de decora\u00e7\u00e3o ou paisagismo. O projeto, que come\u00e7ou em 2015, est\u00e1 sendo ampliado para esta mostra. \u201cO resultado formal da pesquisa, que relaciona arte e tecnologia, s\u00e3o as NAVES PO\u00c9TICAS, as quais se apresentam enquanto objeto tridimensional h\u00edbrido que, assim sendo, dialoga harmonicamente com ambas as \u00e1reas em que atuo: as artes visuais e o design\u201d, detalha.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"83394\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas\/exposicao-fabio-5\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-scaled.jpg\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;JULIANA BARATOJO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1612349099&quot;,&quot;copyright&quot;:&quot;JULIANA BARATOJO&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"EXPOSI\u00c7\u00c3O fabio-5\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-683x1024.jpg\" class=\"alignnone size-medium wp-image-83394\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-200x300.jpg 200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-683x1024.jpg 683w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-768x1152.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-1024x1536.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-1365x2048.jpg 1365w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-1200x1800.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-5-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<p style=\"font-weight: 400\">No ano passado, Rheinheimer completou 33 anos de carreira art\u00edstica com a exposi\u00e7\u00e3o \u201cA Tempestade\u201d, em cartaz em Porto Alegre e em S\u00e3o Paulo. Tamb\u00e9m foi o curador da exposi\u00e7\u00e3o \u201cM\u00faltiplos Olhares\u201d, que apresentou diferentes vis\u00f5es de 28 fot\u00f3grafos. Tamb\u00e9m desenvolveu sua primeira galeria virtual, utilizando seus conhecimentos como arquiteto.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"83395\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas\/exposicao-fabio-23\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-scaled.jpg\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;JULIANA BARATOJO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1612350135&quot;,&quot;copyright&quot;:&quot;JULIANA BARATOJO&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"EXPOSI\u00c7\u00c3O fabio-23\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-1024x683.jpg\" class=\"alignnone size-medium wp-image-83395\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-1024x683.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-23-1200x800.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"font-weight: 400\"><strong>Exposi\u00e7\u00e3o:<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Projeto Naves Po\u00e9ticas (2014|2020), objetos de F\u00e1bio Andr\u00e9 Rheinheimer<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Abertura<\/strong>:10 de fevereiro, das 10h \u00e0s 17h<\/p>\n<p style=\"font-weight: 400\"><strong>Visita\u00e7\u00e3o:<\/strong>\u00a0de 10 de fevereiro a 27 de mar\u00e7o de 2021<\/p>\n<p style=\"font-weight: 400\"><strong>Hor\u00e1rios:\u00a0<\/strong>de segunda a sexta das 10 \u00e0s 17h.<\/p>\n<p style=\"font-weight: 400\"><strong>Local:<\/strong>\u00a0Espa\u00e7o Cultural Correios, Av. Sete de Setembro, N\u00ba 1020, Pra\u00e7a da Alf\u00e2ndega &#8211; Centro Hist\u00f3rico, Porto Alegre<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"83397\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas\/exposicao-fabio-173\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-scaled.jpg\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;JULIANA BARATOJO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1612354921&quot;,&quot;copyright&quot;:&quot;JULIANA BARATOJO&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"EXPOSI\u00c7\u00c3O fabio-173\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-683x1024.jpg\" class=\"alignnone size-medium wp-image-83397\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-200x300.jpg 200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-683x1024.jpg 683w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-768x1152.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-1024x1536.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-1365x2048.jpg 1365w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-1200x1800.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-173-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>O arquiteto, curador e artista visual F\u00e1bio Andr\u00e9 Rheinheimer inaugura exposi\u00e7\u00e3o individual em Porto Alegre, depois de sua estreia em dezembro, em S\u00e3o Paulo. \u00c9 o \u201cProjeto Naves Po\u00e9ticas\u201d, nessa quarta-feira, 10 de fevereiro, no Espa\u00e7o Cultural Correios, localizado no t\u00e9rreo da Av. Sete de Setembro, 1020, no Centro Hist\u00f3rico, em Porto Alegre. A mostra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":83396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-83393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg","jetpack-related-posts":[{"id":83867,"url":"https:\/\/www.jornalja.com.br\/cultura\/volta-naves-poeticas-esculturas-tridimensionais-iluminadas-de-fabio-rheinheimer\/","url_meta":{"origin":83393,"position":0},"title":"Volta &#8220;Naves Po\u00e9ticas&#8221;, esculturas tridimensionais iluminadas, de Fabio Rheinheimer.","author":"Higino Barros","date":"2 de maio de 2021","format":false,"excerpt":"A exposi\u00e7\u00e3o Naves Po\u00e9ticas, do arquiteto, artista visual e curador F\u00e1bio Andr\u00e9 Rheinheimer, est\u00e1 de portas abertas para receber o p\u00fablico no Espa\u00e7o Cultural Correios, em Porto Alegre. O local havia sido fechado, em fun\u00e7\u00e3o do agravamento da pandemia, logo ap\u00f3s a inaugura\u00e7\u00e3o da exposi\u00e7\u00e3o. Agora, os visitantes t\u00eam at\u00e9\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/fabio-4-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/fabio-4-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/fabio-4-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/fabio-4-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/fabio-4-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/fabio-4-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":80376,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-tempestade-na-celebracao-de-fabio-andre-rheinheimer\/","url_meta":{"origin":83393,"position":1},"title":"&quot;A Tempestade&quot; na celebra\u00e7\u00e3o de F\u00e1bio Andr\u00e9 Rheinheimer","author":"Higino Barros","date":"8 de janeiro de 2020","format":false,"excerpt":"Um dos mais ativos agente cultural e curador de artes pl\u00e1sticas de Porto Alegre, o artista visual e arquiteto F\u00e1bio Andr\u00e9 Rheinheimer celebra 33 anos de sua primeira exposi\u00e7\u00e3o individual com \u201cA Tempestade\u201d. Agora ele deixa o papel de pedra para se tornar vitrine.\u00a0 O cen\u00e1rio de cultura e artes\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-Exposi%C3%A7%C3%A3o-F%C3%A1bio-67.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-Exposi%C3%A7%C3%A3o-F%C3%A1bio-67.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-Exposi%C3%A7%C3%A3o-F%C3%A1bio-67.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-Exposi%C3%A7%C3%A3o-F%C3%A1bio-67.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":73868,"url":"https:\/\/www.jornalja.com.br\/cultura\/desenhos-com-luz-mostra-a-producao-de-29-fotografos-em-58-obras-no-espaco-cultural-correios\/","url_meta":{"origin":83393,"position":2},"title":"&quot;Desenhos com luz&quot; mostra a produ\u00e7\u00e3o de 29 fot\u00f3grafos em 58 obras, no Espa\u00e7o Cultural Correios","author":"da Reda\u00e7\u00e3o","date":"11 de abril de 2019","format":false,"excerpt":"Segundo o material de divulga\u00e7\u00e3o da mostra, a fotografia transcende ao real e ganha status de arte na exposi\u00e7\u00e3o \"Desenhos com Luz\", que inaugura nesse s\u00e1bado, 13 de abril, em vernissage das 11h \u00e0s 13h, no Espa\u00e7o Cultural Correios, na Av. Sete de Setembro, 1020, na Pra\u00e7a da Alf\u00e2ndega, em\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/04\/arte-foto-Da-janela-Lateral-Fernando-Castro-450x321.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84220,"url":"https:\/\/www.jornalja.com.br\/cultura\/multiplos-olhares-de-31-artistas-visuais-em-exposicao-no-espaco-cultural-correios\/","url_meta":{"origin":83393,"position":3},"title":"M\u00faltiplos olhares de 31 artistas visuais em exposi\u00e7\u00e3o, no Espa\u00e7o Cultural Correios\u00a0","author":"da Reda\u00e7\u00e3o","date":"22 de julho de 2021","format":false,"excerpt":"Exposi\u00e7\u00e3o, que inaugura no dia 31 de julho, re\u00fane obras de 31 artistas sob a curadoria de F\u00e1bio Andr\u00e9 Rheinheimer. A 5\u00aa edi\u00e7\u00e3o do Projeto M\u00faltiplos Olhares chega de forma revista e ampliada ao Espa\u00e7o Cultural Correios. Com a curadoria do artista e arquiteto F\u00e1bio Andr\u00e9 Rheinheimer, a exposi\u00e7\u00e3o apresenta\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/arte-anderson-neves-credito-do-artista-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/arte-anderson-neves-credito-do-artista-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/arte-anderson-neves-credito-do-artista-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/arte-anderson-neves-credito-do-artista-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/arte-anderson-neves-credito-do-artista-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/arte-anderson-neves-credito-do-artista-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84881,"url":"https:\/\/www.jornalja.com.br\/cultura\/imagens-em-movimento-na-mostra-as-cidades-oniricas-de-manoel-petry\/","url_meta":{"origin":83393,"position":4},"title":"Imagens em movimento, na mostra &#8220;As cidades on\u00edricas&#8221;, de\u00a0Manoel\u00a0Petry","author":"da Reda\u00e7\u00e3o","date":"4 de outubro de 2021","format":false,"excerpt":"\u00a0 Fotos que viram pintura e trazem a arte do inesperado. A exposi\u00e7\u00e3o \u201cCidades On\u00edricas\u201d, do fot\u00f3grafo e publicit\u00e1rio\u00a0Manoel\u00a0Petry, revela a inquietude do artista em 28 imagens em\u00a0overlaps. Com a curadoria do artista e arquiteto F\u00e1bio Andr\u00e9 Rheinheimer, a mostra come\u00e7a no dia 9 de outubro e segue at\u00e9 20\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/manoel-petryexposicao-cidades-oniricas2021-75668-103x.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/manoel-petryexposicao-cidades-oniricas2021-75668-103x.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/manoel-petryexposicao-cidades-oniricas2021-75668-103x.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/manoel-petryexposicao-cidades-oniricas2021-75668-103x.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/manoel-petryexposicao-cidades-oniricas2021-75668-103x.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/manoel-petryexposicao-cidades-oniricas2021-75668-103x.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83124,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-tempestade-exposicao-individual-de-fabio-andre-rheinheimer-chega-a-sao-paulo\/","url_meta":{"origin":83393,"position":5},"title":"&#8220;A Tempestade&#8221;, exposi\u00e7\u00e3o individual de F\u00e1bio Andr\u00e9 Rheinheimer, chega \u00e0 S\u00e3o Paulo","author":"da Reda\u00e7\u00e3o","date":"1 de dezembro de 2020","format":false,"excerpt":"O ano de 2020 est\u00e1 sendo marcado por estreias para o artista visualF\u00e1bio Andr\u00e9 Rheinheimer. Como curador, ele promoveu sua primeira exposi\u00e7\u00e3o virtual e tamb\u00e9m desenvolveu sua primeira galeria virtual, utilizando seus conhecimentos como arquiteto. Mas \u00e9 em dezembro que uma das principais conquistas de sua trajet\u00f3ria de 33 anos\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/12\/exposicao-fabio-76-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/12\/exposicao-fabio-76-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/12\/exposicao-fabio-76-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/12\/exposicao-fabio-76-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/12\/exposicao-fabio-76-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/12\/exposicao-fabio-76-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-lH3","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=83393"}],"version-history":[{"count":3,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83393\/revisions"}],"predecessor-version":[{"id":83401,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83393\/revisions\/83401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/83396"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=83393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=83393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=83393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}