{"id":83457,"date":"2021-02-23T12:57:05","date_gmt":"2021-02-23T15:57:05","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=83457"},"modified":"2021-02-23T12:57:05","modified_gmt":"2021-02-23T15:57:05","slug":"novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/","title":{"rendered":"Novos cr\u00edticos de teatro\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC"},"content":{"rendered":"<div id=\":nc\" class=\"ii gt\">\n<div id=\":nd\" class=\"a3s aiL \">\n<div dir=\"ltr\">\n<p dir=\"ltr\">O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada para artistas e espectadores de artes c\u00eanicas.<\/p>\n<p dir=\"ltr\">Contemplado pelo Edital FAC Movimento RS, da Secretaria de Estado da Cultura do Rio Grande do Sul, o projeto ser\u00e1 realizado de forma virtual durante todo o primeiro semestre do ano. O lan\u00e7amento ocorre no dia 27 de fevereiro \u00e0s 19h30 pelas redes sociais do NEELIC, com a presen\u00e7a dos professores, dos atores do grupo e da professora de Lingu\u00edstica e Letras da UFRGS Lodenir Karnopp, que atua na \u00e1rea da educa\u00e7\u00e3o de surdos.<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"83461\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/teatro-4-primeiro-amor-credito-marcio-garcia\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg\" data-orig-size=\"2500,1666\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;Marcio.Garcia&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1555785036&quot;,&quot;copyright&quot;:&quot;@Marcio.Garcia&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;1600&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"TEATRO 4 primeiro amor &amp;#8211; cr\u00e9dito marcio garcia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-1024x682.jpg\" class=\"alignnone size-medium wp-image-83461\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-1024x682.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p dir=\"ltr\">Com inscri\u00e7\u00f5es gratuitas, a Escola de Cr\u00edtica Teatral quer incentivar o surgimento de novos cr\u00edticos de teatro, por meio de um processo imersivo de forma\u00e7\u00e3o. Ser\u00e3o, ao todo, 33 encontros virtuais, incluindo aulas te\u00f3ricas e pr\u00e1ticas, frui\u00e7\u00e3o de espet\u00e1culos, debates e exerc\u00edcios de escrita. Para nutrir a turma de conhecimento sobre a trajet\u00f3ria da cr\u00edtica cultural no Brasil, o curso vai trazer textos de figuras ic\u00f4nicas na \u00e1rea, a exemplo de Anatol Rosenfeld, D\u00e9cio de Almeida Prado, Barbara Heliodora e S\u00e1bato Magaldi, al\u00e9m de apresentar tamb\u00e9m o trabalho de cr\u00edticos contempor\u00e2neos brasileiros. Al\u00e9m disso, os alunos v\u00e3o assistir a espet\u00e1culos online gratuitamente e produzir resenhas sobre as pe\u00e7as.<\/p>\n<p dir=\"ltr\">A Escola \u00e9 aberta a jovens e adultos a partir de 15 anos de idade e tem carga hor\u00e1ria total de 72 horas. As aulas iniciam no dia 15 de mar\u00e7o e se encerram em agosto, com a publica\u00e7\u00e3o de um site com as resenhas produzidas pelos alunos. As inscri\u00e7\u00f5es podem ser realizadas pelo email <a href=\"mailto:cursosneelic@gmail.com\" target=\"_blank\" rel=\"noopener\">cursosneelic@gmail.com<\/a> ou WhatsApp 51 99274-9933.<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"83459\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/teatro-2-credito-marcio-garcia-1\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1.jpg\" data-orig-size=\"2500,1666\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;Marcio.Garcia&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1559939861&quot;,&quot;copyright&quot;:&quot;@Marcio.Garcia&quot;,&quot;focal_length&quot;:&quot;32&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"TEATRO 2 Cr\u00e9dito M\u00e1rcio Garcia 1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-1024x682.jpg\" class=\"alignnone size-medium wp-image-83459\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-1024x682.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-2-credito-marcio-garcia-1-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p dir=\"ltr\"><strong>Outras atividades<\/strong><\/p>\n<p dir=\"ltr\">A programa\u00e7\u00e3o do Ver a Cena envolve ainda uma mostra de espet\u00e1culos do repert\u00f3rio do grupo NEELIC, em atividade desde 2013 em Porto Alegre, com apresenta\u00e7\u00f5es online de \u201cCapital\u201d, \u201cPrimeiro Amor\u201d e \u201cMERDA!\u201d, al\u00e9m da cria\u00e7\u00e3o e da estreia da primeira pe\u00e7a de teatro infantil do grupo, chamada \u201cTra\u00e7a Letra e Tra\u00e7a Tudo\u201d.<\/p>\n<p dir=\"ltr\">Outro destaque do projeto \u00e9 seu car\u00e1ter de acessibilidade: cada espet\u00e1culo proposto pelo NEELIC ter\u00e1 uma apresenta\u00e7\u00e3o com tradu\u00e7\u00e3o para Libras e uma com audiodescri\u00e7\u00e3o. Todos os v\u00eddeos criados durante as oficinas, que ficar\u00e3o dispon\u00edveis no Youtube, ter\u00e3o legendas para melhor acessibilidade de pessoas surdas ou com defici\u00eancia auditiva e audiodescri\u00e7\u00e3o para pessoas cegas ou com defici\u00eancia visual. Completam a programa\u00e7\u00e3o a realiza\u00e7\u00e3o de tr\u00eas ensaios abertos, um debate aberto ao p\u00fablico e 12 proje\u00e7\u00f5es de v\u00eddeo.<\/p>\n<p dir=\"ltr\"><strong>Escola de Cr\u00edtica<\/strong><\/p>\n<p dir=\"ltr\">Nas aulas, os estudantes poder\u00e3o tomar contato com o estudo da cr\u00edtica a partir de um enfoque geneal\u00f3gico. Um retorno ao pensamento da Antiguidade cl\u00e1ssica e do Medievo nos leva a refletir e a explorar a atualidade das no\u00e7\u00f5es de \u00e9tico-est\u00e9tica, beleza\/fei\u00fara, tr\u00e1gico, mimese, catarse, sublime e consola\u00e7\u00e3o como ferramentas conceituais para abordar a arte da presen\u00e7a e da cena no tempo presente.<\/p>\n<p dir=\"ltr\">O curso ter\u00e1 ainda aulas destinadas \u00e0 produ\u00e7\u00e3o textual de cr\u00edticas teatrais. Para tanto, ser\u00e3o estudadas as caracter\u00edsticas da resenha cr\u00edtica e as especificidades deste g\u00eanero textual quando voltado aos espet\u00e1culos de teatro. Nestes encontros, ser\u00e3o exploradas qualidades discursivas essenciais para a produ\u00e7\u00e3o de um bom texto, o que abrir\u00e1 caminhos para a escrita de uma cr\u00edtica consistente. Espera-se que os e as estudantes sejam capazes, ao final do curso, de planejar, (re)escrever e revisar seus textos de maneira eficaz. A hist\u00f3ria do jornalismo cultural e da cr\u00edtica de arte no Brasil tamb\u00e9m est\u00e3o contempladas nos encontros.<\/p>\n<p dir=\"ltr\">O corpo docente da Escola de Cr\u00edtica \u00e9 composto por professores com experi\u00eancia em suas respectivas \u00e1reas de atua\u00e7\u00e3o, como Marcio Pizarro Noronha (doutor em Hist\u00f3ria e doutor em Antropologia, professor no curso de licenciatura em Dan\u00e7a (ESEFID UFRGS)), Desir\u00e9e Pessoa (doutora em Artes C\u00eanicas UNIRIO e diretora do grupo NEELIC) e Samuel Oliveira (mestre e doutorando em Letras pela UFRGS.). Completam o quadro os editores do site Nonada &#8211; Jornalismo Cultural: Rafael Gloria (mestre em Comunica\u00e7\u00e3o pela UFRGS e especialista em Jornalismo Digital pela PUCRS) e Tha\u00eds Seganfredo (graduada em Jornalismo pela UFRGS)<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"83460\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/teatro-3-credito-marcio-garcia\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia.jpg\" data-orig-size=\"2500,1666\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;Marcio.Garcia&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1559939700&quot;,&quot;copyright&quot;:&quot;@Marcio.Garcia&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"TEATRO 3 Cr\u00e9dito M\u00e1rcio Garcia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-1024x682.jpg\" class=\"alignnone size-medium wp-image-83460\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-1024x682.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-3-credito-marcio-garcia-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p dir=\"ltr\"><strong>Servi\u00e7o<\/strong><\/p>\n<p dir=\"ltr\">Escola de Cr\u00edtica Teatral<\/p>\n<p dir=\"ltr\">Aulas de 15 de mar\u00e7o a 8 de agosto, no turno da noite<\/p>\n<p dir=\"ltr\">Curso Gratuito e aberto a artistas e espectadores a partir de 15 anos<\/p>\n<p dir=\"ltr\">Inscri\u00e7\u00f5es at\u00e9 12 de mar\u00e7o pelo email <a href=\"mailto:cursosneelic@gmail.com\" target=\"_blank\" rel=\"noopener\">cursosneelic@gmail.com<\/a> ou WhatsApp 51 99274-9933.<\/p>\n<p><span id=\"m_-1666584407607227026gmail-docs-internal-guid-77c46d28-7fff-4aee-1bf8-430704eefd5f\"><span style=\"color: #888888\"><br \/>\n<\/span><\/span><\/p>\n<div><\/div>\n<p><span style=\"color: #888888\">&#8212;<br \/>\n<\/span><\/p>\n<div dir=\"ltr\" data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div><\/div>\n<div><span style=\"color: #000000;font-family: georgia, serif\">\u00a0<\/span><\/div>\n<div><span style=\"color: #000000;font-family: georgia, serif\">\u00a0<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"yj6qo\"><\/div>\n<div class=\"adL\"><\/div>\n<\/div>\n<\/div>\n<div id=\":rb\" class=\"hq gt\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":83458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-83457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1666\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-02-23T15:57:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-02-23T15:57:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#article\",\"name\":\"Novos cr\\u00edticos de teatro no projeto \\u201cVer a Cena\\u201d, do grupo NEELIC | Cultura\",\"headline\":\"Novos cr\\u00edticos de teatro\\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/teatro-1-img-2904-cor-3-marcio-garcia-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Cena de \\\"O primeiro amor\\\"- Fotos de Marcio Garcia\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2021-02-23T12:57:05-03:00\",\"dateModified\":\"2021-02-23T12:57:05-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#listItem\",\"name\":\"Novos cr\\u00edticos de teatro\\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#listItem\",\"position\":3,\"name\":\"Novos cr\\u00edticos de teatro\\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/\",\"name\":\"Novos cr\\u00edticos de teatro no projeto \\u201cVer a Cena\\u201d, do grupo NEELIC | Cultura\",\"description\":\"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\\u00e7\\u00e3o e o desenvolvimento de um grande programa art\\u00edstico c\\u00eanico, com estreia de espet\\u00e1culo, mostra de repert\\u00f3rio e uma Escola de Cr\\u00edtica Teatral, voltada\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/teatro-1-img-2904-cor-3-marcio-garcia-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Cena de \\\"O primeiro amor\\\"- Fotos de Marcio Garcia\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\\\/#mainImage\"},\"datePublished\":\"2021-02-23T12:57:05-03:00\",\"dateModified\":\"2021-02-23T12:57:05-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura","description":"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#article","name":"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura","headline":"Novos cr\u00edticos de teatro\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-1-img-2904-cor-3-marcio-garcia-scaled.jpg","width":2560,"height":1707,"caption":"Cena de \"O primeiro amor\"- Fotos de Marcio Garcia\/ Divulga\u00e7\u00e3o"},"datePublished":"2021-02-23T12:57:05-03:00","dateModified":"2021-02-23T12:57:05-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#listItem","name":"Novos cr\u00edticos de teatro\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#listItem","position":3,"name":"Novos cr\u00edticos de teatro\u00a0no projeto &#8220;Ver a Cena&#8221;, do grupo NEELIC","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/","name":"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura","description":"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-1-img-2904-cor-3-marcio-garcia-scaled.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#mainImage","width":2560,"height":1707,"caption":"Cena de \"O primeiro amor\"- Fotos de Marcio Garcia\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/#mainImage"},"datePublished":"2021-02-23T12:57:05-03:00","dateModified":"2021-02-23T12:57:05-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura","og:description":"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada","og:url":"https:\/\/www.jornalja.com.br\/cultura\/novos-criticos-de-teatro-no-projeto-ver-a-cena-do-grupo-neelic\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg","og:image:width":2500,"og:image:height":1666,"article:published_time":"2021-02-23T15:57:05+00:00","article:modified_time":"2021-02-23T15:57:05+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Novos cr\u00edticos de teatro no projeto \u201cVer a Cena\u201d, do grupo NEELIC | Cultura","twitter:description":"O Grupo NEELIC inicia o ano de 2021 apresentando uma iniciativa que pretende ampliar os olhares sobre o teatro no Rio Grande do Sul. O projeto Ver a Cena envolve a cria\u00e7\u00e3o e o desenvolvimento de um grande programa art\u00edstico c\u00eanico, com estreia de espet\u00e1culo, mostra de repert\u00f3rio e uma Escola de Cr\u00edtica Teatral, voltada","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-4-primeiro-amor-credito-marcio-garcia.jpg"},"aioseo_meta_data":{"post_id":"83457","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-02-23 15:29:09","updated":"2025-06-04 12:29:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":84415,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/","url_meta":{"origin":83457,"position":0},"title":"A estreia de &#8220;Classe Cordial&#8221;, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS.","author":"da Reda\u00e7\u00e3o","date":"17 de agosto de 2021","format":false,"excerpt":"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos & Bem Acompanhados est\u00e3o \u00e0 frente do projeto \"Classe Cordial\" que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":81557,"url":"https:\/\/www.jornalja.com.br\/cultura\/escola-espaco-do-ator-promove-uma-semana-de-portas-abertas-com-aulas-gratuitas\/","url_meta":{"origin":83457,"position":1},"title":"Escola &quot;Espa\u00e7o do Ator&quot; promove uma Semana de Portas Abertas, com aulas gratuitas","author":"da Reda\u00e7\u00e3o","date":"27 de fevereiro de 2020","format":false,"excerpt":"Os aspirantes \u00e0s artes c\u00eanicas t\u00eam oportunidade de aperfei\u00e7oar suas t\u00e9cnicas. O Espa\u00e7o do Ator est\u00e1 oferecendo uma semana de aulas gratuitas nos cursos de teatro ao p\u00fablico infantil, adolescente e adulto. Os cursos da escola s\u00e3o de pre\u00e7os populares e disp\u00f5e oficinas, nas quais os alunos, na conclus\u00e3o do\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/02\/arte-teatro.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/02\/arte-teatro.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/02\/arte-teatro.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/02\/arte-teatro.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/02\/arte-teatro.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":90562,"url":"https:\/\/www.jornalja.com.br\/cultura\/atos-e-cenas-do-rs-inscricoes-abertas-para-selecionar-20-espetaculos\/","url_meta":{"origin":83457,"position":2},"title":"&#8220;Atos e Cenas do RS&#8221;: inscri\u00e7\u00f5es abertas para selecionar 20 espet\u00e1culos","author":"da Reda\u00e7\u00e3o","date":"3 de fevereiro de 2025","format":false,"excerpt":"O edital \u201cAtos e Cenas do RS\u201d, para ocupa\u00e7\u00e3o do Teatro Oficina Olga Reverbel, foi lan\u00e7ado nesta segunda-feira (3\/2), pela Secretaria de Estado da Cultura (Sedac), por meio do Instituto Estadual de Artes C\u00eanicas (Ieacen) e da Funda\u00e7\u00e3o Teatro S\u00e3o Pedro (FTSP). A iniciativa busca contemplar 20 espet\u00e1culos de artes\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/02\/cultura-atos-e-cenas-edital.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/02\/cultura-atos-e-cenas-edital.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/02\/cultura-atos-e-cenas-edital.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/02\/cultura-atos-e-cenas-edital.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/02\/cultura-atos-e-cenas-edital.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/02\/cultura-atos-e-cenas-edital.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":91201,"url":"https:\/\/www.jornalja.com.br\/cultura\/uta-e-pretago-apresentam-mesa-farta-e-zaze-zaze-uma-festa-para-vavo-em-porto-alegre\/","url_meta":{"origin":83457,"position":3},"title":"UTA e Pretag\u00f4 apresentam Mesa Farta e Zaze Zaze: uma festa para Vav\u00f3,\u00a0em Porto Alegre","author":"Higino Barros","date":"16 de julho de 2025","format":false,"excerpt":"A troca e o encontro de dois grandes grupos de teatro do sul do Brasil, o UTA e o Pretag\u00f4, est\u00e1 sendo celebrada com uma circula\u00e7\u00e3o de seus mais recentes espet\u00e1culos pelo RS. As cidades de Canoas, Pelotas, Porto Alegre e Santa Maria est\u00e3o vendo ou revendo as montagens de\u00a0Mesa\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/07\/cena-sul-zaze-zaze-credito-fabio-zambom-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/07\/cena-sul-zaze-zaze-credito-fabio-zambom-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/07\/cena-sul-zaze-zaze-credito-fabio-zambom-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/07\/cena-sul-zaze-zaze-credito-fabio-zambom-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/07\/cena-sul-zaze-zaze-credito-fabio-zambom-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/07\/cena-sul-zaze-zaze-credito-fabio-zambom-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":92266,"url":"https:\/\/www.jornalja.com.br\/cultura\/teatro-bruno-kiefer-reabre-apos-reforma-de-r-36-milhoes\/","url_meta":{"origin":83457,"position":4},"title":"Teatro Bruno Kiefer reabre ap\u00f3s reforma de R$ 3,6 milh\u00f5es","author":"da Reda\u00e7\u00e3o","date":"28 de maio de 2026","format":false,"excerpt":"Inteiramente reformado, ao custo de R$ 3,6 milh\u00f5es, reabriu na quarta-feira (27\/5), o Teatro Bruno Kiefer, no 6\u00ba andar da Casa de Cultura Mario Quintana (CCMQ), em Porto Alegre. O governador Eduardo Leite, do secret\u00e1rio da Cultura, Andr\u00e9 Kryszczun, e da diretora da CCMQ, Adriana Sperandir participaram da reinaugura\u00e7\u00e3o. A\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84863,"url":"https:\/\/www.jornalja.com.br\/cultura\/arte-como-ciencia-apresenta-infancia-e-cena-contemporanea-com-melissa-ferreira\/","url_meta":{"origin":83457,"position":5},"title":"Arte como Ci\u00eancia apresenta  &#8220;Inf\u00e2ncia e cena contempor\u00e2nea&#8221;  com  Melissa Ferreira","author":"da Reda\u00e7\u00e3o","date":"1 de outubro de 2021","format":false,"excerpt":"O projeto Arte como Ci\u00eancia segue investigando a rela\u00e7\u00e3o entre o universo infantil e a cena. O assunto j\u00e1 foi abordado no especial de janeiro, por artistas-cientistas de oito pa\u00edses e, em fevereiro, pelo pesquisador cubano Luvel Garc\u00eda Leyva. Em outubro, o projeto convida a artista, pesquisadora e professora na\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/arte-acc-0510-melissa-ferreira.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/arte-acc-0510-melissa-ferreira.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/arte-acc-0510-melissa-ferreira.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/arte-acc-0510-melissa-ferreira.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/arte-acc-0510-melissa-ferreira.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/arte-acc-0510-melissa-ferreira.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-lI5","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/teatro-1-img-2904-cor-3-marcio-garcia-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=83457"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83457\/revisions"}],"predecessor-version":[{"id":83462,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83457\/revisions\/83462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/83458"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=83457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=83457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=83457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}