{"id":83769,"date":"2021-04-08T23:39:40","date_gmt":"2021-04-09T02:39:40","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=83769"},"modified":"2021-04-13T18:09:25","modified_gmt":"2021-04-13T21:09:25","slug":"uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/","title":{"rendered":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre"},"content":{"rendered":"<p>Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner.<\/p>\n<p>\u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul.<\/p>\n<p>Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez, o longa (realizado com recursos da Lei Aldir Blanc n\u00ba14.017\/2020) ser\u00e1 pr\u00e9-lan\u00e7ado de forma virtual no dia 16 de abril, com live de apresenta\u00e7\u00e3o e participa\u00e7\u00e3o dos autores e convidados.<\/p>\n<p>\u201cCavalo de Santo\u201d marca a estreia de Mirian Fichtner na dire\u00e7\u00e3o de cinema com um longa-metragem. Segundo ela, \u201co maior desafio\u00a0 enfrentado foi\u00a0 transpor a linguagem fotogr\u00e1fica do livro para a narrativa cinematogr\u00e1fica\u201d.<\/p>\n<p>O filme apresenta o complexo das religi\u00f5es afro-ga\u00fachas destacando o Batuque, a Umbanda e a Quimbanda com suas caracter\u00edsticas e peculiaridades regionais.<\/p>\n<p>A obra conta com a participa\u00e7\u00e3o de nomes importantes da ancestralidade religiosa afro-brasileira no Rio Grande do Sul e depoimentos de antrop\u00f3logos e soci\u00f3logos.<\/p>\n<p>Tamb\u00e9m aborda a hist\u00f3ria e a forma\u00e7\u00e3o das religi\u00f5es, o racismo, a intoler\u00e2ncia religiosa no RS e as diversas formas de luta do povo de religi\u00e3o para preservarem seus cultos e manterem a sua f\u00e9.<\/p>\n<p>O longa teve como ponto de partida os dados IBGE 2000 e 2010 que apontaram o Rio Grande do Sul como o estado com maior n\u00famero de terreiros e de fi\u00e9is declarados pertencentes a este segmento religioso, proporcionalmente ao n\u00famero da popula\u00e7\u00e3o.<\/p>\n<p>A FGV &#8211; Funda\u00e7\u00e3o Get\u00falio Vargas, em mapa das religi\u00f5es, elaborado em 2011, confirmou Porto Alegre como a capital das religi\u00f5es afro, no Brasil.<\/p>\n<p>Para Mirian, o objetivo do filme \u00e9 dar voz e protagonismo aos personagens do livro. \u201cAtrav\u00e9s do filme \u00e9 poss\u00edvel ouvir suas rezas, mostrar a cultura exuberante e conhecer a vida pulsante dos terreiros ga\u00fachos. \u00c9 uma forma de preservar os saberes e mem\u00f3rias desta cultura imaterial no Rio Grande do Sul, transmitida pela oralidade da ancestralidade negra no Estado\u201d.<\/p>\n<p>O filme longa-metragem \u201cCavalo de Santo\u201d foi produzido\u00a0 pela Cubo Filmes, em parceria com a Esta\u00e7\u00e3o Filmes, a Pluf Fotografias e a Caminho do Mar Solu\u00e7\u00f5es Culturais. Contou com o apoio da lei Aldir Blanc para sua finaliza\u00e7\u00e3o e lan\u00e7amento.<\/p>\n<p>(Com informa\u00e7\u00f5es da Assessoria de Imprensa)<\/p>\n<p>Ficha T\u00e9cnica<\/p>\n<p>Dire\u00e7\u00e3o \u2013 Mirian Fichtner e Carlos Caramez<\/p>\n<p>Roteiro \u2013 Carlos Caramez<\/p>\n<p>Dire\u00e7\u00e3o de Fotografia \u2013 Mirian Fichtner<\/p>\n<p>Dire\u00e7\u00e3o de Produ\u00e7\u00e3o \u2013 Cl\u00e1udio Fagundes e Carlos Caramez<\/p>\n<p>Montagem \u2013 Jorge Bazzo e Cl\u00e1udio Fagundes<\/p>\n<p>Pesquisa \u2013 Mirian Fichtner e Carlos Caramez<\/p>\n<p>Realiza\u00e7\u00e3o &#8211; Cubo Filmes<\/p>\n<p>Coprodu\u00e7\u00e3o \u2013 Esta\u00e7\u00e3o Filmes, Pluf Fotografias e Caminho do Mar Solu\u00e7\u00f5es Culturais<\/p>\n<p>Coordena\u00e7\u00e3o Leis de Incentivo e Produ\u00e7\u00e3o \u2013 Rosane Furtado<\/p>\n<p>Divulga\u00e7\u00e3o \u2013 Buda Comunica\u00e7\u00e3o<\/p>\n<p>Coloriza\u00e7\u00e3o \u2013 Cubo Filmes<\/p>\n<p>\u00c1udio \u2013 Cubo Filmes<\/p>\n<p>Servi\u00e7o:<\/p>\n<p>Pr\u00e9-Lan\u00e7amento do longa-metragem \u201cCavalo de Santo\u201d<\/p>\n<p>Site: cavalodesantofilme.com.br<\/p>\n<p>Dia 16\/4<\/p>\n<p>20h &#8211; live de apresenta\u00e7\u00e3o com autores e convidados<\/p>\n<p>20h30min &#8211; pr\u00e9-lan\u00e7amento do filme<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":83771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-83769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-09T02:39:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-13T21:09:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#article\",\"name\":\"Uma viagem pela capital das religi\\u00f5es afro no Brasil: Porto Alegre | Cultura\",\"headline\":\"Uma viagem pela capital das religi\\u00f5es afro no Brasil: Porto Alegre\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/cavalo-de-santo-abertura-site-e-filme-1.jpeg\",\"width\":1920,\"height\":1080},\"datePublished\":\"2021-04-08T23:39:40-03:00\",\"dateModified\":\"2021-04-13T18:09:25-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#listItem\",\"name\":\"Uma viagem pela capital das religi\\u00f5es afro no Brasil: Porto Alegre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#listItem\",\"position\":3,\"name\":\"Uma viagem pela capital das religi\\u00f5es afro no Brasil: Porto Alegre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/\",\"name\":\"Uma viagem pela capital das religi\\u00f5es afro no Brasil: Porto Alegre | Cultura\",\"description\":\"Lan\\u00e7amento marcado para o dia 16 de abril, o document\\u00e1rio longa-metragem \\u201cCavalo de Santo\\u201d, baseado no livro hom\\u00f4nimo da fot\\u00f3grafa Mirian Fichtner. \\u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/cavalo-de-santo-abertura-site-e-filme-1.jpeg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\\\/#mainImage\"},\"datePublished\":\"2021-04-08T23:39:40-03:00\",\"dateModified\":\"2021-04-13T18:09:25-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura","description":"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#article","name":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura","headline":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg","width":1920,"height":1080},"datePublished":"2021-04-08T23:39:40-03:00","dateModified":"2021-04-13T18:09:25-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#listItem","name":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#listItem","position":3,"name":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/","name":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura","description":"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg","@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/#mainImage"},"datePublished":"2021-04-08T23:39:40-03:00","dateModified":"2021-04-13T18:09:25-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura","og:description":"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,","og:url":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2021-04-09T02:39:40+00:00","article:modified_time":"2021-04-13T21:09:25+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre | Cultura","twitter:description":"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista e produtor cultural Carlos Caramez,","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"83769","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-09 02:13:30","updated":"2025-06-04 12:34:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":87504,"url":"https:\/\/www.jornalja.com.br\/cultura\/oi-nois-aqui-traveiz-celebra-45-anos-de-teatro-com-programacao-intensa-em-2023\/","url_meta":{"origin":83769,"position":0},"title":"&#8220;\u00d3i N\u00f3is Aqui Traveiz&#8221; celebra 45 anos de teatro de grupo com programa\u00e7\u00e3o intensa em 2023","author":"da Reda\u00e7\u00e3o","date":"31 de janeiro de 2023","format":false,"excerpt":"\u00a0 \u00a0\u00a0 O Museu da Cena do \u00d3i N\u00f3is Aqui Traveiz e o novo espet\u00e1culo de rua, Ubu Tropical, s\u00e3o os principais lan\u00e7amentos para o ano. A programa\u00e7\u00e3o segue com mostra de repert\u00f3rio, oficinas e resid\u00eancias art\u00edsticas, lan\u00e7amento do livro \u2018Mem\u00f3ria do Teatro de Grupo Brasileiro\u2019\u00a0e a participa\u00e7\u00e3o no festival\u00a0Tanto\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83439,"url":"https:\/\/www.jornalja.com.br\/cultura\/introducao-a-metodologia-de-danca-afro-gaucha-com-iara-deodoro\/","url_meta":{"origin":83769,"position":1},"title":"Introdu\u00e7\u00e3o a Metodologia de Dan\u00e7a Afro-Ga\u00facha, com Iara Deodoro","author":"da Reda\u00e7\u00e3o","date":"22 de fevereiro de 2021","format":false,"excerpt":"Iara Deodoro \u00e9 uma refer\u00eancia no Sul do Brasil quando se fala em dan\u00e7a afro-ga\u00facha. Fundadora do Grupo Afro-Sul de M\u00fasica e Dan\u00e7a, criado em 1974, \u00e9 a mulher \u00e0 frente do Afro-Sul Odomode, um renomado espa\u00e7o que acolhe e difunde a arte dos tambores, o maracatu, as manifesta\u00e7\u00f5es populares\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/bale-5-o-feminino-sagrado-fotobrunogomes-0153.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/bale-5-o-feminino-sagrado-fotobrunogomes-0153.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/bale-5-o-feminino-sagrado-fotobrunogomes-0153.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/bale-5-o-feminino-sagrado-fotobrunogomes-0153.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/bale-5-o-feminino-sagrado-fotobrunogomes-0153.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/bale-5-o-feminino-sagrado-fotobrunogomes-0153.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":89263,"url":"https:\/\/www.jornalja.com.br\/cultura\/replicantes-40-anos-da-banda-em-exposicao-imersiva-no-museu-do-trabalho\/","url_meta":{"origin":83769,"position":2},"title":"Replicantes: 40 anos da banda, em exposi\u00e7\u00e3o imersiva, no Museu do Trabalho","author":"da Reda\u00e7\u00e3o","date":"25 de mar\u00e7o de 2024","format":false,"excerpt":"A hist\u00f3ria de uma das bandas mais importantes da cena punk rock nacional chega ao Museu do Trabalho com a exposi\u00e7\u00e3o\u00a0Os Replicantes 1984\/2024. A abertura acontece dia 27 de mar\u00e7o e a mostra permanece at\u00e9 19 de maio, com um passeio imersivo e essencialmente musical em duas salas do Museu\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/replicantes-2013-12-09-773-osreplicantes-30anos-showfotofernandachemale-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/replicantes-2013-12-09-773-osreplicantes-30anos-showfotofernandachemale-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/replicantes-2013-12-09-773-osreplicantes-30anos-showfotofernandachemale-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/replicantes-2013-12-09-773-osreplicantes-30anos-showfotofernandachemale-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/replicantes-2013-12-09-773-osreplicantes-30anos-showfotofernandachemale-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/replicantes-2013-12-09-773-osreplicantes-30anos-showfotofernandachemale-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83325,"url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-odilon-lopez-50-anos-resgata-legado-de-cineasta-negro-gaucho\/","url_meta":{"origin":83769,"position":3},"title":"Projeto \u201cOdilon Lopez \u2013 50 Anos\u201d resgata legado de cineasta negro ga\u00facho.","author":"da Reda\u00e7\u00e3o","date":"22 de janeiro de 2021","format":false,"excerpt":"\u00a0 Iniciativa realizar\u00e1 curso gratuito a dist\u00e2ncia sobre cinema documental e grava\u00e7\u00e3o de curta-metragem. Pioneiro no Rio Grande do Sul e um dos primeiros diretores negros do cinema no Brasil, Odilon Lopez \u00e9 a inspira\u00e7\u00e3o para um importante resgate da hist\u00f3ria e mem\u00f3ria do audiovisual no Estado. Lan\u00e7ado pelo coletivo\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/audiovisual-odilon-lopez-reeproducao.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":89126,"url":"https:\/\/www.jornalja.com.br\/cultura\/dez-artistas-visuais-gauchas-sao-presencas-marcantes-em-exposicao-da-delphus-galeria\/","url_meta":{"origin":83769,"position":4},"title":"Dez artistas visuais ga\u00fachas s\u00e3o &#8220;Presen\u00e7as Marcantes&#8221; em exposi\u00e7\u00e3o da Delphus Galeria","author":"da Reda\u00e7\u00e3o","date":"29 de fevereiro de 2024","format":false,"excerpt":"Dez artistas visuais ga\u00fachas envolvidas com as quest\u00f5es do universo feminino integram a exposi\u00e7\u00e3o \u201cPresen\u00e7as Marcantes\u201d, que ser\u00e1 aberta na manh\u00e3 de segunda-feira (4\/3) na Delphus Galeria de Arte e Molduras, na Capital, em homenagem \u00e0s mulheres, cuja data internacional transcorre dia 8. Com curadoria de Denise Giacomoni, a mostra\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-5obra-de-rose-osorio-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-5obra-de-rose-osorio-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-5obra-de-rose-osorio-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-5obra-de-rose-osorio-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-5obra-de-rose-osorio-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-5obra-de-rose-osorio-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":91541,"url":"https:\/\/www.jornalja.com.br\/cultura\/raiz-afro-gaucha-novo-espetaculo-da-companhia-afro-sul-de-musica-e-danca-em-apresentacao-no-araujo-vianna\/","url_meta":{"origin":83769,"position":5},"title":"Raiz Afro-Ga\u00facha,\u00a0novo espet\u00e1culo da Companhia Afro-Sul de M\u00fasica e Dan\u00e7a, em apresenta\u00e7\u00e3o no Ara\u00fajo Vianna","author":"da Reda\u00e7\u00e3o","date":"3 de novembro de 2025","format":false,"excerpt":"A apresenta\u00e7\u00e3o encerra a Trilha Cultural, uma s\u00e9rie de eventos que o grupo prop\u00f5e entre\u00a019 e 23 de novembro\u00a0para celebrar o m\u00eas da Consci\u00eancia Negra e seus 50 anos de exist\u00eancia \u00a0 Um novo espet\u00e1culo, gestado com muito afeto e dedica\u00e7\u00e3o ao longo de quase dois anos por um dos\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/afro-sul-antonio-filippi-de-castro-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/afro-sul-antonio-filippi-de-castro-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/afro-sul-antonio-filippi-de-castro-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/afro-sul-antonio-filippi-de-castro-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/afro-sul-antonio-filippi-de-castro-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/afro-sul-antonio-filippi-de-castro-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-lN7","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=83769"}],"version-history":[{"count":5,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83769\/revisions"}],"predecessor-version":[{"id":83777,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/83769\/revisions\/83777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/83771"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=83769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=83769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=83769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}