{"id":84325,"date":"2021-08-10T13:44:34","date_gmt":"2021-08-10T16:44:34","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=84325"},"modified":"2021-08-11T18:48:22","modified_gmt":"2021-08-11T21:48:22","slug":"documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/","title":{"rendered":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia"},"content":{"rendered":"<p>O projeto de curta-metragem document\u00e1rio &#8221; N\u00f3s que fazemos girar&#8221;<br \/>\ncontemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de Porto Alegre.<\/p>\n<figure id=\"attachment_84326\" aria-describedby=\"caption-attachment-84326\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84326\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/audio-3-foto_-anna-ortega\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-scaled.jpg\" data-orig-size=\"2560,1613\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS Rebel T6i&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1625659360&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0015625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"AUDIO 3 Foto_ Anna Ortega\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Foto: Anna Ortega\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-1024x645.jpg\" class=\"size-medium wp-image-84326\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg\" alt=\"\" width=\"300\" height=\"189\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-1024x645.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-768x484.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-1536x968.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-2048x1291.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-1200x756.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-84326\" class=\"wp-caption-text\">Foto: Anna Ortega\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Para que o maior n\u00famero de pessoas possa ficar em casa durante a pandemia de Covid-19, que j\u00e1 compreende mais de um ano, os entregadores continuam girando as rodas de suas bicicletas e motos para tornar poss\u00edvel a continuidade da economia e de diversas atividades \u00e0 dist\u00e2ncia. O curta-metragem document\u00e1rio pretende colocar no centro da discuss\u00e3o os sujeitos que normalmente s\u00e3o vistos em uma posi\u00e7\u00e3o intermedi\u00e1ria e mesmo sem identidade.<\/p>\n<figure id=\"attachment_84328\" aria-describedby=\"caption-attachment-84328\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84328\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/audio-foto_-mariana-alves1\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-scaled.jpg\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;Luiza Prado\/JC&quot;,&quot;camera&quot;:&quot;Canon EOS 7D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1627990500&quot;,&quot;copyright&quot;:&quot;Luiza Prado\/JC&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"AUDIO Foto_ Mariana Alves(1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Foto: Mariana Alves\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-1024x683.jpg\" class=\"size-medium wp-image-84328\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-1024x683.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves1-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-84328\" class=\"wp-caption-text\">Foto: Mariana Alves\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Al\u00e9m do document\u00e1rio, a equipe de jovens cineastas e comunicadores reunidos no projeto tamb\u00e9m vai propor o curso &#8220;Giro no Audiovisual&#8221; , focado em aproximar o p\u00fablico interessado ao universo da realiza\u00e7\u00e3o audiovisual, seus processos, equipes e fases de produ\u00e7\u00e3o. O curso acontecer\u00e1 durante todo o m\u00eas de Setembro, \u00e0s quartas-feiras \u00e0<br \/>\nnoite e ser\u00e1 ministrado por Lucas Furtado, tamb\u00e9m roteirista e diretor de &#8220;N\u00f3s que fazemos girar&#8221; . Ser\u00e3o 5 aulas online, com material de acompanhamento e certificado. A organiza\u00e7\u00e3o do curso abrir\u00e1 inicialmente 20 vagas e 50% delas s\u00e3o direcionadas \u00e0<br \/>\npessoas negras, ind\u00edgenas e LGBTQIA+. O formul\u00e1rio para inscri\u00e7\u00e3o no curso ser\u00e1 disponibilizado em breve no Instagram do projeto @nosquefazemosgirar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84331\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/audio-visual-1\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-scaled.jpg\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;Luiza Prado\/JC&quot;,&quot;camera&quot;:&quot;Canon EOS 7D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1627989835&quot;,&quot;copyright&quot;:&quot;Luiza Prado\/JC&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"AUDIO VISUAL 1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-1024x683.jpg\" class=\"alignnone size-medium wp-image-84331\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-1024x683.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-visual-1-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Ficha t\u00e9cnica<\/strong><\/p>\n<p>N\u00d3S QUE FAZEMOS GIRAR &#8211; Curta-metragem document\u00e1rio.<br \/>\nSinopse: Em meio ao caos urbano e \u00e0 pandemia de covid-19, quatro entregadores lutam para sobreviver e encontrar seu lugar no mundo.<br \/>\nGIRO NO AUDIOVISUAL &#8211; Curso online sobre realiza\u00e7\u00e3o audiovisual.<br \/>\nDura\u00e7\u00e3o: Dias 01, 08, 15, 22 e 29 de Setembro de 2021, no per\u00edodo da noite.<br \/>\nMaiores informa\u00e7\u00f5es e formul\u00e1rio de inscri\u00e7\u00e3o ser\u00e3o divulgados em breve no Instagram do projeto @nosquefazemosgirar.<br \/>\nEQUIPE DO PROJETO<br \/>\nRoteiro: Lucas Furtado e Glauber Cruz<br \/>\nDire\u00e7\u00e3o: Lucas Furtado<br \/>\nProdu\u00e7\u00e3o Executiva e Coordena\u00e7\u00e3o de Comunica\u00e7\u00e3o: Ana Lu\u00edsa Moura<br \/>\nDesign Visual e Dire\u00e7\u00e3o de Produ\u00e7\u00e3o: Bruna Anele<br \/>\nDire\u00e7\u00e3o de Fotografia: Theo Tajes<br \/>\nDire\u00e7\u00e3o de Som: Raysa Fisch<br \/>\nMontagem: Glauber Cruz<br \/>\n* Projeto executado atrav\u00e9s do Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas realizado com recursos da Lei Aldir Blanc no 14.017\/20.<\/p>\n<figure id=\"attachment_84330\" aria-describedby=\"caption-attachment-84330\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84330\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/audio-foto_-mariana-alves3\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-scaled.jpg\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;Luiza Prado\/JC&quot;,&quot;camera&quot;:&quot;Canon EOS 7D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1627986914&quot;,&quot;copyright&quot;:&quot;Luiza Prado\/JC&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"AUDIO Foto_ Mariana Alves(3)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Foto: Mariana Alves\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-1024x683.jpg\" class=\"size-medium wp-image-84330\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-1024x683.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-2048x1365.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves3-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-84330\" class=\"wp-caption-text\">Foto: Mariana Alves\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>CONTATOS<br \/>\nE-mail: nqfgprojeto@gmail.com<br \/>\nInstagram: @nosquefazemosgirar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto de curta-metragem document\u00e1rio &#8221; N\u00f3s que fazemos girar&#8221; contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-84325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O projeto de curta-metragem document\u00e1rio &quot; N\u00f3s que fazemos girar&quot; contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O projeto de curta-metragem document\u00e1rio &quot; N\u00f3s que fazemos girar&quot; contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-10T16:44:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-11T21:48:22+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O projeto de curta-metragem document\u00e1rio &quot; N\u00f3s que fazemos girar&quot; contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#article\",\"name\":\"Document\\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura\",\"headline\":\"Document\\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/audio-foto-mariana-alves-4-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Foto: Mariana Alves\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2021-08-10T13:44:34-03:00\",\"dateModified\":\"2021-08-11T18:48:22-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#listItem\",\"name\":\"Document\\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#listItem\",\"position\":3,\"name\":\"Document\\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/\",\"name\":\"Document\\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura\",\"description\":\"O projeto de curta-metragem document\\u00e1rio \\\" N\\u00f3s que fazemos girar\\\" contemplado no Edital Cria\\u00e7\\u00e3o e Forma\\u00e7\\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\\\/20, come\\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/audio-foto-mariana-alves-4-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Foto: Mariana Alves\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\\\/#mainImage\"},\"datePublished\":\"2021-08-10T13:44:34-03:00\",\"dateModified\":\"2021-08-11T18:48:22-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura","description":"O projeto de curta-metragem document\u00e1rio \" N\u00f3s que fazemos girar\" contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#article","name":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura","headline":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves-4-scaled.jpg","width":2560,"height":1707,"caption":"Foto: Mariana Alves\/ Divulga\u00e7\u00e3o"},"datePublished":"2021-08-10T13:44:34-03:00","dateModified":"2021-08-11T18:48:22-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#listItem","name":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#listItem","position":3,"name":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/","name":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura","description":"O projeto de curta-metragem document\u00e1rio \" N\u00f3s que fazemos girar\" contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves-4-scaled.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#mainImage","width":2560,"height":1707,"caption":"Foto: Mariana Alves\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/#mainImage"},"datePublished":"2021-08-10T13:44:34-03:00","dateModified":"2021-08-11T18:48:22-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura","og:description":"O projeto de curta-metragem document\u00e1rio &quot; N\u00f3s que fazemos girar&quot; contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de","og:url":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-entregadores-de-aplicativos-de-porto-alegre-em-tempos-de-pandemia\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg","article:published_time":"2021-08-10T16:44:34+00:00","article:modified_time":"2021-08-11T21:48:22+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Document\u00e1rio sobre entregadores de aplicativos de Porto Alegre em tempos de pandemia | Cultura","twitter:description":"O projeto de curta-metragem document\u00e1rio &quot; N\u00f3s que fazemos girar&quot; contemplado no Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas, realizado com recursos da Lei Aldir Blanc no 14.017\/20, come\u00e7ou suas filmagens em agosto e vai mostrar a rotina, as experi\u00eancias na rua e o impacto da pandemia na vida de quatro entregadores de aplicativo de","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-3-foto-anna-ortega-300x189.jpg"},"aioseo_meta_data":{"post_id":"84325","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-10 16:00:35","updated":"2025-06-04 12:42:54","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":90916,"url":"https:\/\/www.jornalja.com.br\/cultura\/documentario-sobre-mulheres-indigenas-na-cinemateca-paulo-amorim\/","url_meta":{"origin":84325,"position":0},"title":"Document\u00e1rio sobre mulheres ind\u00edgenas, na Cinemateca Paulo Amorim","author":"Higino Barros","date":"16 de abril de 2025","format":false,"excerpt":"\u00a0O protagonismo feminino ind\u00edgena na atua\u00e7\u00e3o coletiva em defesa dos direitos dos povos origin\u00e1rios \u00e9 o tema central do document\u00e1rio\u00a0Kunha Kara\u00ed e as Narrativas da Terra, que chega \u00e0s telas da\u00a0Cinemateca Paulo Amorim\u00a0nesta quinta-feira (17). As sess\u00f5es acontecem diariamente (exceto na segunda-feira),\u00a0sempre \u00e0s 19h, at\u00e9 o dia 23 de abril,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/04\/exposicao-5-img-20250416-wa0016.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/04\/exposicao-5-img-20250416-wa0016.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/04\/exposicao-5-img-20250416-wa0016.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/04\/exposicao-5-img-20250416-wa0016.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/04\/exposicao-5-img-20250416-wa0016.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":83325,"url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-odilon-lopez-50-anos-resgata-legado-de-cineasta-negro-gaucho\/","url_meta":{"origin":84325,"position":1},"title":"Projeto \u201cOdilon Lopez \u2013 50 Anos\u201d resgata legado de cineasta negro ga\u00facho.","author":"da Reda\u00e7\u00e3o","date":"22 de janeiro de 2021","format":false,"excerpt":"\u00a0 Iniciativa realizar\u00e1 curso gratuito a dist\u00e2ncia sobre cinema documental e grava\u00e7\u00e3o de curta-metragem. Pioneiro no Rio Grande do Sul e um dos primeiros diretores negros do cinema no Brasil, Odilon Lopez \u00e9 a inspira\u00e7\u00e3o para um importante resgate da hist\u00f3ria e mem\u00f3ria do audiovisual no Estado. Lan\u00e7ado pelo coletivo\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/audiovisual-odilon-lopez-reeproducao.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":83769,"url":"https:\/\/www.jornalja.com.br\/cultura\/uma-viagem-pela-capital-da-religioes-afro-no-brasil-porto-alegre\/","url_meta":{"origin":84325,"position":2},"title":"Uma viagem pela capital das religi\u00f5es afro no Brasil: Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de abril de 2021","format":false,"excerpt":"Lan\u00e7amento marcado para o dia 16 de abril, o document\u00e1rio longa-metragem \u201cCavalo de Santo\u201d, baseado no livro hom\u00f4nimo da fot\u00f3grafa Mirian Fichtner. \u00c9 resultado de dez anos de pesquisas, entre os terreiros ga\u00fachos e retrata o universo religioso afro-brasileiro no Rio Grande do Sul. Dirigido pela fot\u00f3grafa e pelo jornalista\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/cavalo-de-santo-abertura-site-e-filme-1.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":81987,"url":"https:\/\/www.jornalja.com.br\/cultura\/soldados-que-combateram-a-guerrilha-do-araguaia-ganham-voz-em-documentario\/","url_meta":{"origin":84325,"position":3},"title":"Soldados que combateram a Guerrilha do Araguaia ganham voz em document\u00e1rio","author":"da Reda\u00e7\u00e3o","date":"17 de maio de 2020","format":false,"excerpt":"\u00c0s margens do Rio Araguaia, um grupo de militantes comunistas se mobilizou para tentar construir uma revolu\u00e7\u00e3o a partir do campo, aos moldes de Cuba e da China. O contexto era o de um regime militar em seu momento mais r\u00edgido, entre as d\u00e9cadas de 1960 e 1970. Para impedir\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-soldados-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-soldados-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-soldados-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-soldados-scaled.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85380,"url":"https:\/\/www.jornalja.com.br\/cultura\/exibicao-de-documentario-e-outras-acoes-da-ccmq-dao-visibilidade-ao-jornal-boca-de-rua\/","url_meta":{"origin":84325,"position":4},"title":"Exibi\u00e7\u00e3o de document\u00e1rio e outras a\u00e7\u00f5es da CCMQ d\u00e3o visibilidade ao\u00a0Jornal Boca de Rua","author":"Higino Barros","date":"18 de janeiro de 2022","format":false,"excerpt":"O N\u00facleo Educativo da Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da Secretaria de Estado da Cultura (Sedac), repercute, ao longo do m\u00eas de janeiro, a trajet\u00f3ria do Jornal Boca de Rua, publica\u00e7\u00e3o inteiramente produzida por pessoas em situa\u00e7\u00e3o de rua em Porto Alegre. O jornal \u00e9 tema do document\u00e1rio\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/de-olhos-abertos-foto-kimba-2-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/de-olhos-abertos-foto-kimba-2-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/de-olhos-abertos-foto-kimba-2-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/de-olhos-abertos-foto-kimba-2-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/de-olhos-abertos-foto-kimba-2-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/de-olhos-abertos-foto-kimba-2-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84271,"url":"https:\/\/www.jornalja.com.br\/cultura\/todo-mundo-tem-um-sonho-em-documentario-exposicao-fotografica-e-workshop-virtual\/","url_meta":{"origin":84325,"position":5},"title":"\u201cTodo mundo tem um sonho\u201d, em document\u00e1rio, exposi\u00e7\u00e3o fotogr\u00e1fica e workshop virtual","author":"da Reda\u00e7\u00e3o","date":"3 de agosto de 2021","format":false,"excerpt":"O espet\u00e1culo \u201cTodo mundo tem um sonho\u201d, produ\u00e7\u00e3o original do Pertence Cultural em parceria com as artistas Paula Carvalho (diretora) e Bianca Bueno (core\u00f3grafa), e que levou ao palco mais de 100 pessoas com defici\u00eancia ao palco do Theatro S\u00e3o Pedro, em setembro de 2019, vai estrear em formato de\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/teatro-pegorer-estudio-22-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/teatro-pegorer-estudio-22-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/teatro-pegorer-estudio-22-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/teatro-pegorer-estudio-22-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/teatro-pegorer-estudio-22-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/teatro-pegorer-estudio-22-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-lW5","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/audio-foto-mariana-alves-4-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=84325"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84325\/revisions"}],"predecessor-version":[{"id":84332,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84325\/revisions\/84332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/84327"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=84325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=84325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=84325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}