{"id":84415,"date":"2021-08-17T12:26:43","date_gmt":"2021-08-17T15:26:43","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=84415"},"modified":"2021-08-17T12:35:44","modified_gmt":"2021-08-17T15:35:44","slug":"a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/","title":{"rendered":"A estreia de &#8220;Classe Cordial&#8221;, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS."},"content":{"rendered":"<p style=\"font-weight: 400\"><em>O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &#8220;Classe Cordial&#8221; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h.<\/em><\/p>\n<p style=\"font-weight: 400\">Relatos sobre casos reais presentes em espa\u00e7os manicomiais e uma pesquisa ampla sobre a tem\u00e1tica &#8211; que vem sendo desenvolvida pela equipe do projeto desde 2020 &#8211; o espet\u00e1culo virtual prop\u00f5e um debate que envolve o p\u00fablico e o privado. Nesse sentido, ao levar para a cena uma personagem que insere-se em ambas as esferas, o espet\u00e1culo aborda a hist\u00f3ria de muitas mulheres nesse tr\u00e2nsito criativo entre o real e o documental, estampando na tela uma classe cordial que se materializa no paradoxo de pessoas que discursam sobre uma forma de conv\u00edvio social pac\u00edfica e agregadora, mas que, na pr\u00e1tica, excluem, silenciam e segregam. Uma classe cordial que, muitas vezes, \u00e9 constitu\u00edda por todos e todas n\u00f3s. Todos os dias.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84418\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png\" data-orig-size=\"2208,1242\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mani Deborah Finocchiaro &amp;#8211; fotos Deborah Finocchiaro (8)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-1024x576.png\" class=\"alignnone size-medium wp-image-84418\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-300x169.png 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-1024x576.png 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-768x432.png 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-1536x864.png 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-2048x1152.png 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8-1200x675.png 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"font-weight: 400\"><em>So<\/em><em>bre a equipe<\/em><\/p>\n<p style=\"font-weight: 400\">Jardel Rocha, diretor do espet\u00e1culo, \u00e9 ator e professor de teatro, al\u00e9m de diretor. Integra o Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica, onde recebeu cinco indica\u00e7\u00f5es e dois pr\u00eamios de Melhor Ator pelo espet\u00e1culo \u201cJunho: Uma Aventura Imagin\u00e1ria\u201d, incluindo a Indica\u00e7\u00e3o de Melhor Ator no Pr\u00eamio Olhares da Cena. \u00c9 professor e diretor de Teatro na ACEFH no munic\u00edpio de Harmonia, dirigindo grupos de crian\u00e7as, adolescentes e adultos. \u00c9 diretor do premiado espet\u00e1culo \u2018\u2019Filhas do Sal\u201d\u00a0\u00a0e dirige a Cia de Solos &amp; Bem Acompanhados, uma das mais atuante do estado, desde o ano de 2019.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84417\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2.png\" data-orig-size=\"2208,1242\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mani Deborah Finocchiaro &amp;#8211; fotos Deborah Finocchiaro (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-1024x576.png\" class=\"alignnone size-medium wp-image-84417\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-300x169.png 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-1024x576.png 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-768x432.png 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-1536x864.png 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-2048x1152.png 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-2-1200x675.png 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"font-weight: 400\">Deborah Finocchiaro\u00a0tem um vasto curr\u00edculo e in\u00fameros pr\u00eamios em sua carreira\u00a0Estreou no teatro em 1985.\u00a0Bacharel em Interpreta\u00e7\u00e3o Teatral no DAD \/ UFRGS (1992) e esteve presente em centenas de trabalhos como atriz no teatro, cinema e televis\u00e3o. \u00c9 tamb\u00e9m diretora, locutora, produtora, apresentadora, roteirista e ministrante. Ao longo de sua carreira,\u00a0recebeu 33 pr\u00eamios, entre eles 9 de Melhor Espet\u00e1culo, 18 de Melhor Atriz, 1 de Melhor Dire\u00e7\u00e3o, 1 de Melhor Texto Adaptado, 1 de Melhor Roteiro e 3 como\u00a0Melhor Artista de Teatro.\u00a0Em 2006 fundou a Companhia de Solos &amp; Bem Acompanhados, que traz em seu repert\u00f3rio dezenas de trabalhos.\u00a0Em 2014 foi a artista homenageada do 21\u00ba Festival Internacional de Teatro\u00a0Porto Alegre Em Cena, ganhando a biografia \u201c<em>A Arte Transformadora\u201d<\/em>, escrita pelo jornalista Luiz Gonzaga Lopes, que\u00a0integra o 5\u00ba volume da cole\u00e7\u00e3o\u00a0Ga\u00fachos Em Cena. Em 2020\u00a0foi tema do document\u00e1rio \u201cDeborah! O Ato da Casa\u201d, longa-metragem\u00a0produzido durante a quarentena, dire\u00e7\u00e3o\u00a0Luiz Alberto Cassol\u00a0(2020).<\/p>\n<p style=\"font-weight: 400\">Thiago Silva\u00a0\u00e9 dramaturgo, diretor e pesquisador em Artes C\u00eanicas com forma\u00e7\u00e3o em Dire\u00e7\u00e3o Teatral pelo Departamento de Arte Dram\u00e1tica da UFRGS, onde atuou como bolsista de pesquisa em Escrita Dramat\u00fargica. Escreveu mais de quinze textos teatrais encenados e publicados, entre eles os textos infanto-juvenis &#8220;Junho: Uma Aventura Imagin\u00e1ria&#8221;, que possui dois pr\u00eamios e seis indica\u00e7\u00f5es de Melhor Dramaturgia Original e &#8220;Alice: Al\u00e9m da Toca do Coelho&#8221;, vencedor do Pr\u00eamio Tibicuera de Melhor Dramaturgia.<\/p>\n<p style=\"font-weight: 400\">Angelo Primon, respons\u00e1vel pela cria\u00e7\u00e3o da trilha sonora, tema mais de 30 anos de brilhante carreira. Compositor, multi-instrumentista e produtor Angelo Primon \u00e9 Bacaharel em M\u00fasica Popular pela UFRGS e j\u00e1 atuou com artistas de v\u00e1rias tend\u00eancias: Nei Lisboa, Gilberto Gil, Richard Serraria, Adriana Deffenti, Daniel Drexler, Orquestra de C\u00e2mara da ULBRA e Grupo Cuidado que Mancha, Grupo M\u00fasica Mundana e Violas ao sul. Foi vencedor do Trof\u00e9u A\u00e7orianos como Melhor Instrumentista categoria MPB nos anos de 2006, 2008 e 2016\/17. Desenvolve pesquisas sobre as sonoridades da viola de dez cordas, viola de cocho, rabeca, oud \u00e1rabe, surtarang, surbahar e sitar indiano.<\/p>\n<p style=\"font-weight: 400\">Everton Wilbert Vieira<strong>,\u00a0<\/strong>o iluminador do projeto, \u00e9 formado em eletrot\u00e9cnica pela Escola T\u00e9cnica Prudente de Moraes. Entre suas forma\u00e7\u00f5es detacam-se os cursos \u2018Dramaturgia da luz\u2019 e \u2018Projeto caixa c\u00eanica\u2019. Recebeu opr\u00eamios como iluminador nos espet\u00e1culos \u201cFilhas do sal\u201d,\u00a0\u00a0e \u201cO sonho de tr\u00e1s das nuvens\u201d.<\/p>\n<p style=\"font-weight: 400\"><em>Sobre os grupos<\/em><\/p>\n<p style=\"font-weight: 400\">O\u00a0<strong>Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica<\/strong>\u00a0nasceu em 2016 e mant\u00e9m um car\u00e1ter transversal, investigativo e de pesquisa em suas montagens, desenvolvendo trabalhos que versam sobre assuntos e perspectivas diversas, tais como o di\u00e1logo entre Hist\u00f3ria e Dramaturgia, a pesquisa est\u00e9tica e de linguagem no Teatro Infantil e os processos de cria\u00e7\u00e3o est\u00e9tica e dramat\u00fargica. Entre os trabalhos desenvolvidos pelo grupo, est\u00e3o o document\u00e1rio c\u00eanico \u201cDESTERRO: sobre restos que n\u00e3o importam mais\u201d, apresentado entre os anos de 2017 e 2018, e o espet\u00e1culo infantil \u201cJunho: Uma Aventura Imagin\u00e1ria\u201d, que j\u00e1 contemplou mais de cinco mil crian\u00e7as em sua plateia e soma trinta pr\u00eamios. Atualmente, o grupo segue com o processo de pesquisa e cria\u00e7\u00e3o de trabalhos adultos e infantis, entre eles &#8220;SIM ONE NINA&#8221;, espet\u00e1culo baseado na vida e obra da cantora Nina Simone, &#8220;As Viagens de Tio Cosme&#8221;, &#8220;Piquenique: Uma Hist\u00f3ria de Fantasmas&#8221; e &#8220;Classe Cordial&#8221;.<\/p>\n<p style=\"font-weight: 400\">A<strong>\u00a0Companhia de Solos &amp; Bem Acompanhados<\/strong>, um\u00a0dos n\u00facleos de cria\u00e7\u00e3o c\u00eanica mais atuantes do Rio Grande do Sul, se caracteriza pela versatilidade, escolha de temas que estimulam a reflex\u00e3o e o pensamento cr\u00edtico e mescla de diferentes linguagens. Atingiu mais de quinhentas mil pessoas com seus espet\u00e1culos, oficinas e performances. Entre suas realiza\u00e7\u00f5es est\u00e3o os espet\u00e1culos \u201cPois \u00e9, Vizinha&#8230;\u201d, dire\u00e7\u00e3o Deborah Finocchiaro (1993);\u00a0\u201cSobre Anjos &amp; Grilos &#8211; O Universo de Mario Quintana\u201d (2006 &#8211; al\u00e9m do espet\u00e1culo cont\u00e9m CD, lan\u00e7ado em 2015 e DVD, lan\u00e7ado em 2017); \u201cO Macaco &amp; A Velha\u201d, de Ivo Bender (2011); \u201cUm Certo Capit\u00e3o Verissimo\u201d, dire\u00e7\u00e3o Paulo Mauro (2012);\u00a0\u00a0\u201cGPS GAZA\u201d, orienta\u00e7\u00e3o Camila Bauer (2014); \u201cCaio do C\u00e9u\u201d, dire\u00e7\u00e3o Lu\u00eds Artur Nunes (2017) e \u201cDi\u00e1rio Secreto de Uma Secret\u00e1ria Bilingue\u201d, dire\u00e7\u00e3o de Vin\u00edcius Piedade e Deborah Finocchiaro (2019). Os projetos \u201cHist\u00f3rias de Um Canto do Mundo &#8211; Mem\u00f3rias de Porto Alegre e do Rio Grande do Sul\u201d (que consiste em um espet\u00e1culo solo, um recital, um show musical e um registro da obra em livro\/CD &#8211; 2008);\u00a0\u201cPalavra de Bolso &#8211; Onde a Literatura ganha Voz\u201d (2015) e \u201cSarau Voador &#8211; Literatura e Improvisos Transcriados\u201d (2018).\u00a0As obras literomusicais: \u201cA Espessura da Vida\u201d (2018), \u201cLeitura \u00e0s Cegas\u201d (2018); \u201cBen\u00e7\u00e3o Poetinha\u201d, a partir da obra de Vinicius de Morais (2018) e \u201cPalavra Balada (2018).\u00a0O espet\u00e1culo audiovisual \u201cInvis\u00edveis &#8211; Hist\u00f3rias Para Acordar\u201d, dire\u00e7\u00e3o Deborah Finocchiaro (2020). A webs\u00e9rie \u201cConfession\u00e1rio &#8211; Relatos de Casa\u201d, dire\u00e7\u00e3o Deborah Finocchiaro e Luiz Alberto Cassol (2020\/2021).\u00a0\u00a0E os programas \/ podcasts \u201cEsta\u00e7\u00e3o Confession\u00e1rio\u201d e \u201cEsta\u00e7\u00e3o Sarau Voador\u201d, ambos na Rede Esta\u00e7\u00e3o Democracia e no Spotify (2021).\u00a0Al\u00e9m de dezenas de indica\u00e7\u00f5es, recebeu in\u00fameros pr\u00eamios e percorreu mais de oitenta cidades no RS, Uruguai e Argentina, participando de temporadas, projetos, mostras e festivais nacionais e internacionais.<\/p>\n<p style=\"font-weight: 400\">\u00a0<strong>SERVI\u00c7O:<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Classe Cordial<\/strong><\/p>\n<p style=\"font-weight: 400\">Estreia dia 23 de agosto, \u00e0s 19h<\/p>\n<p style=\"font-weight: 400\">Temporada de 23 de agosto a 14 de setembro<\/p>\n<p style=\"font-weight: 400\">Dispon\u00edvel gratuitamente no YouTube do Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica<\/p>\n<p style=\"font-weight: 400\"><strong>Redes do projeto \/ Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica:<\/strong><\/p>\n<p style=\"font-weight: 400\">YouTube:\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCuAt0RC6b9FqV9oaikOQbNg\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/channel\/UCuAt0RC6b9FqV9oaikOQbNg&amp;source=gmail&amp;ust=1629298248532000&amp;usg=AFQjCNHPYomNn7PH7plI_UL1SF49DFRGVw\">https:\/\/www.youtube.com\/channel\/UCuAt0RC6b9FqV9oaikOQbNg<\/a><\/p>\n<p style=\"font-weight: 400\">Instagram: @classecordial<\/p>\n<p style=\"font-weight: 400\">Facebook:\u00a0<a href=\"https:\/\/www.facebook.com\/projetoclassecordial\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.facebook.com\/projetoclassecordial&amp;source=gmail&amp;ust=1629298248533000&amp;usg=AFQjCNEiVflvp1tuHbaGlHacwiOFmP75og\">https:\/\/www.facebook.com\/projetoclassecordial<\/a><\/p>\n<p style=\"font-weight: 400\"><em>*<\/em><em>\u00a0Este projeto est\u00e1 sendo executado\u00a0<\/em><em>atrav\u00e9s do Edital Cria\u00e7\u00e3o e Forma\u00e7\u00e3o Diversidade das Culturas<\/em>\u00a0<em>realizado com recursos da Lei Aldir Blanc n\u00b0 14.017\/20.<\/em><\/p>\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &#8220;Classe Cordial&#8221; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-84415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &quot;Classe Cordial&quot; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &quot;Classe Cordial&quot; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2208\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1242\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-17T15:26:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-17T15:35:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &quot;Classe Cordial&quot; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#article\",\"name\":\"A estreia de \\u201cClasse Cordial\\u201d, espet\\u00e1culo de v\\u00eddeo-teatro de dois grupos do RS. | Cultura\",\"headline\":\"A estreia de &#8220;Classe Cordial&#8221;, espet\\u00e1culo de v\\u00eddeo-teatro de dois grupos do RS.\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png\",\"width\":2208,\"height\":1242,\"caption\":\"A atriz Deborah Finocchiaro Fotos: Deborah Finocchiaro\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2021-08-17T12:26:43-03:00\",\"dateModified\":\"2021-08-17T12:35:44-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#listItem\",\"name\":\"A estreia de &#8220;Classe Cordial&#8221;, espet\\u00e1culo de v\\u00eddeo-teatro de dois grupos do RS.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#listItem\",\"position\":3,\"name\":\"A estreia de &#8220;Classe Cordial&#8221;, espet\\u00e1culo de v\\u00eddeo-teatro de dois grupos do RS.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/\",\"name\":\"A estreia de \\u201cClasse Cordial\\u201d, espet\\u00e1culo de v\\u00eddeo-teatro de dois grupos do RS. | Cultura\",\"description\":\"O Coletivo N\\u00f4made de Teatro e Pesquisa C\\u00eanica e a Companhia de Solos & Bem Acompanhados est\\u00e3o \\u00e0 frente do projeto \\\"Classe Cordial\\\" que trata de um assunto pertinente e atual na sociedade brasileira: espa\\u00e7os manicomiais. O espet\\u00e1culo de v\\u00eddeo-teatro estreia dia 23 de agosto, \\u00e0s 19h. Relatos sobre casos reais presentes em espa\\u00e7os manicomiais\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#mainImage\",\"width\":2208,\"height\":1242,\"caption\":\"A atriz Deborah Finocchiaro Fotos: Deborah Finocchiaro\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\\\/#mainImage\"},\"datePublished\":\"2021-08-17T12:26:43-03:00\",\"dateModified\":\"2021-08-17T12:35:44-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura","description":"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos & Bem Acompanhados est\u00e3o \u00e0 frente do projeto \"Classe Cordial\" que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#article","name":"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura","headline":"A estreia de &#8220;Classe Cordial&#8221;, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS.","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png","width":2208,"height":1242,"caption":"A atriz Deborah Finocchiaro Fotos: Deborah Finocchiaro\/ Divulga\u00e7\u00e3o"},"datePublished":"2021-08-17T12:26:43-03:00","dateModified":"2021-08-17T12:35:44-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#listItem","name":"A estreia de &#8220;Classe Cordial&#8221;, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#listItem","position":3,"name":"A estreia de &#8220;Classe Cordial&#8221;, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/","name":"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura","description":"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos & Bem Acompanhados est\u00e3o \u00e0 frente do projeto \"Classe Cordial\" que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#mainImage","width":2208,"height":1242,"caption":"A atriz Deborah Finocchiaro Fotos: Deborah Finocchiaro\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/#mainImage"},"datePublished":"2021-08-17T12:26:43-03:00","dateModified":"2021-08-17T12:35:44-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura","og:description":"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &quot;Classe Cordial&quot; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais","og:url":"https:\/\/www.jornalja.com.br\/cultura\/a-estreia-de-classe-cordial-espetaculo-de-video-teatro-de-dois-grupos-do-rs\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png","og:image:width":2208,"og:image:height":1242,"article:published_time":"2021-08-17T15:26:43+00:00","article:modified_time":"2021-08-17T15:35:44+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"A estreia de \u201cClasse Cordial\u201d, espet\u00e1culo de v\u00eddeo-teatro de dois grupos do RS. | Cultura","twitter:description":"O Coletivo N\u00f4made de Teatro e Pesquisa C\u00eanica e a Companhia de Solos &amp; Bem Acompanhados est\u00e3o \u00e0 frente do projeto &quot;Classe Cordial&quot; que trata de um assunto pertinente e atual na sociedade brasileira: espa\u00e7os manicomiais. O espet\u00e1culo de v\u00eddeo-teatro estreia dia 23 de agosto, \u00e0s 19h. Relatos sobre casos reais presentes em espa\u00e7os manicomiais","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-8.png"},"aioseo_meta_data":{"post_id":"84415","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-17 15:02:53","updated":"2025-06-04 12:43:25","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":87504,"url":"https:\/\/www.jornalja.com.br\/cultura\/oi-nois-aqui-traveiz-celebra-45-anos-de-teatro-com-programacao-intensa-em-2023\/","url_meta":{"origin":84415,"position":0},"title":"&#8220;\u00d3i N\u00f3is Aqui Traveiz&#8221; celebra 45 anos de teatro de grupo com programa\u00e7\u00e3o intensa em 2023","author":"da Reda\u00e7\u00e3o","date":"31 de janeiro de 2023","format":false,"excerpt":"\u00a0 \u00a0\u00a0 O Museu da Cena do \u00d3i N\u00f3is Aqui Traveiz e o novo espet\u00e1culo de rua, Ubu Tropical, s\u00e3o os principais lan\u00e7amentos para o ano. A programa\u00e7\u00e3o segue com mostra de repert\u00f3rio, oficinas e resid\u00eancias art\u00edsticas, lan\u00e7amento do livro \u2018Mem\u00f3ria do Teatro de Grupo Brasileiro\u2019\u00a0e a participa\u00e7\u00e3o no festival\u00a0Tanto\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":73544,"url":"https:\/\/www.jornalja.com.br\/cultura\/elas-leva-ao-palco-as-diferentes-faces-e-papeis-da-mulher-contemporanea\/","url_meta":{"origin":84415,"position":1},"title":"&quot;ELAS&quot; leva ao palco as diferentes faces e pap\u00e9is da mulher contempor\u00e2nea","author":"da Reda\u00e7\u00e3o","date":"28 de mar\u00e7o de 2019","format":false,"excerpt":"\u00a0 Cinco mulheres se encontram em um espa\u00e7o-tempo permeado por fragmentos de imagens, sons e sensa\u00e7\u00f5es. ELAS se identificam, se distinguem e se reconhecem em imagens refletidas. Partindo de uma pesquisa sobre a po\u00e9tica da performance, o diretorEverson Silva\u00a0recria uma linguagem de sonho. O som se transforma em a\u00e7\u00e3o e\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":89986,"url":"https:\/\/www.jornalja.com.br\/cultura\/espetaculo-a-fome-ganha-nova-temporada-na-sala-alvaro-moreyra\/","url_meta":{"origin":84415,"position":2},"title":"Espet\u00e1culo &#8221; A FOME&#8221; ganha nova temporada na Sala \u00c1lvaro Moreyra","author":"da Reda\u00e7\u00e3o","date":"1 de outubro de 2024","format":false,"excerpt":"Em um universo majoritariamente machista, a atriz e dramaturga Sissi Venturin entrega-se a uma personagem que \u00e9 a voz de muitas mulheres em situa\u00e7\u00f5es de abuso. Ela mergulha em si para descobrir o poder de sua FOME e saciar seus desejos mais proibidos. O mon\u00f3logo ter\u00e1 tr\u00eas sess\u00f5es, dias 4,\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/a-fome1-foto-morgana-mazzon-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/a-fome1-foto-morgana-mazzon-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/a-fome1-foto-morgana-mazzon-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/a-fome1-foto-morgana-mazzon-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/a-fome1-foto-morgana-mazzon-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/a-fome1-foto-morgana-mazzon-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":92266,"url":"https:\/\/www.jornalja.com.br\/cultura\/teatro-bruno-kiefer-reabre-apos-reforma-de-r-36-milhoes\/","url_meta":{"origin":84415,"position":3},"title":"Teatro Bruno Kiefer reabre ap\u00f3s reforma de R$ 3,6 milh\u00f5es","author":"da Reda\u00e7\u00e3o","date":"28 de maio de 2026","format":false,"excerpt":"Inteiramente reformado, ao custo de R$ 3,6 milh\u00f5es, reabriu na quarta-feira (27\/5), o Teatro Bruno Kiefer, no 6\u00ba andar da Casa de Cultura Mario Quintana (CCMQ), em Porto Alegre. O governador Eduardo Leite, do secret\u00e1rio da Cultura, Andr\u00e9 Kryszczun, e da diretora da CCMQ, Adriana Sperandir participaram da reinaugura\u00e7\u00e3o. A\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83633,"url":"https:\/\/www.jornalja.com.br\/cultura\/o-desafio-de-se-tornar-mae-em-tempos-de-pandemia-ganha-espetaculo-teatral-virtual\/","url_meta":{"origin":84415,"position":4},"title":"O desafio de se tornar m\u00e3e, em tempos de pandemia, ganha espet\u00e1culo teatral virtual","author":"da Reda\u00e7\u00e3o","date":"24 de mar\u00e7o de 2021","format":false,"excerpt":"A ga\u00facha radicada h\u00e1 dez anos em Salvador, Josy Acosta,\u00a0estreia\u00a0no dia\u00a03 de abril, no\u00a0Youtube, um\u00a0espet\u00e1culo teatral sobre os desafios da maternidade na pandemia.\u201cY\u00e8y\u00e9\u201d (em yorub\u00e1 arcaico pode ser traduzido como m\u00e3e) \u00e9 fruto do projeto Mama \u00c1frica, aprovado no Pr\u00eamio das Artes Jorge Portugal. A pe\u00e7a foi constru\u00edda a partir\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/contacao-foto-ismael-silva-3-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/contacao-foto-ismael-silva-3-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/contacao-foto-ismael-silva-3-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/contacao-foto-ismael-silva-3-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/contacao-foto-ismael-silva-3-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/contacao-foto-ismael-silva-3-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":89728,"url":"https:\/\/www.jornalja.com.br\/cultura\/jeferson-cabral-estreia-espetaculo-de-danca-teatro-bixa-no-teatro-do-sesc\/","url_meta":{"origin":84415,"position":5},"title":"Jeferson Cabral estreia espet\u00e1culo de dan\u00e7a-teatro\u00a0BIXA , no Teatro do SESC","author":"da Reda\u00e7\u00e3o","date":"16 de julho de 2024","format":false,"excerpt":"Protagonizada pelo ator-bailarino Jeferson Cabral, nova montagem da Mimese Companhia de Dan\u00e7a Coisa ter\u00e1 \u00fanica apresenta\u00e7\u00e3o \u00e0s\u00a019h do dia 19 de\u00a0julho \u00a0Autobiografia performatizada do\u00a0ator e bailarino Jeferson Cabral, o espet\u00e1culo de dan\u00e7a-teatro\u00a0BIXA\u00a0ter\u00e1 sua sess\u00e3o de estreia\u00a0\u00e0s\u00a019h\u00a0do\u00a0dia 19 de julho, no\u00a0Teatro do SESC Alberto Bins\u00a0(av. Alberto Bins. 665).\u00a0Os ingressos antecipados custam\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/bixa-foto-de-julia-oliveira2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/bixa-foto-de-julia-oliveira2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/bixa-foto-de-julia-oliveira2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/bixa-foto-de-julia-oliveira2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/bixa-foto-de-julia-oliveira2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-lXx","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/mani-deborah-finocchiaro-fotos-deborah-finocchiaro-1.png","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=84415"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84415\/revisions"}],"predecessor-version":[{"id":84420,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84415\/revisions\/84420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/84416"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=84415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=84415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=84415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}