{"id":84707,"date":"2021-09-21T17:56:28","date_gmt":"2021-09-21T20:56:28","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=84707"},"modified":"2021-09-22T17:19:18","modified_gmt":"2021-09-22T20:19:18","slug":"revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/","title":{"rendered":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro"},"content":{"rendered":"<p style=\"font-weight: 400\"><strong><em>O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro.<\/em><\/strong><\/p>\n<p style=\"font-weight: 400\">A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX Gala de Excel\u00eancia em Dan\u00e7a. No palco, estrelas do canto e do ballet integram um espet\u00e1culo em 4 apresenta\u00e7\u00f5es, \u00e0s 10h30 e \u00e0s 16h, nos dias 25 e 26 de setembro. Os ingressos est\u00e3o \u00e0 venda nas unidades da escola na Cel. Corte Real, 227, no telefone (51) 98590-0618, e na Cel. Lucas de Oliveira, 158, no telefone (51) 99933-3310.<\/p>\n<figure id=\"attachment_84714\" aria-describedby=\"caption-attachment-84714\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84714\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-pedrocoppeti_fabioalt\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-scaled.jpeg\" data-orig-size=\"2560,1707\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"bal\u00e9 PedroCoppeti_FabioAlt\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Pedro Coppeti. Foto:_Fabio Alt\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-1024x683.jpeg\" class=\"size-medium wp-image-84714\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-1024x683.jpeg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-768x512.jpeg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-1536x1024.jpeg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-2048x1365.jpeg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-1200x800.jpeg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-84714\" class=\"wp-caption-text\">Ator e cantor Pedro Coppeti, um dos convidados. Foto: Fabio Alt\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<figure id=\"attachment_84710\" aria-describedby=\"caption-attachment-84710\" style=\"width: 249px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84710\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-deboranetorockinrio_cicerorodrigues\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues.jpeg\" data-orig-size=\"1063,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"D\u00e9bora Neto. Foto: Cicero Rodrigues\/ Divulga\u00e7\u00e3o\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;A cantora D\u00e9bora Neto. Foto: Cicero Rodrigues\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues-850x1024.jpeg\" class=\"size-medium wp-image-84710\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues-249x300.jpeg\" alt=\"\" width=\"249\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues-249x300.jpeg 249w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues-850x1024.jpeg 850w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues-768x925.jpeg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-deboranetorockinrio-cicerorodrigues.jpeg 1063w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><figcaption id=\"caption-attachment-84710\" class=\"wp-caption-text\">A cantora D\u00e9bora Neto. Foto: Cicero Rodrigues\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Desta vez, a excel\u00eancia em dan\u00e7a, que faz parte da trajet\u00f3ria de mais de 40 anos do Ballet Vera Bublitz, divide os holofotes com talentos da m\u00fasica. Um dos convidados \u00e9 o ator e cantor ga\u00facho Pedro Coppeti, destaque nos palcos internacionais. Radicado em Nova York, Coppeti \u00e9 formado em Teatro Musical pela The American Musical and Dramatic Academy (AMDA), com um curr\u00edculo de diversas apresenta\u00e7\u00f5es na Broadway, inclusive no lend\u00e1rio Carnegie Hall. Na IX Gala de Excel\u00eancia em Dan\u00e7a, o cantor interpreta, nas apresenta\u00e7\u00f5es de domingo, 26 de setembro, um trecho de O Corcunda de Notre Dame, ao lado da cantora ga\u00facha D\u00e9bora Neto, destaque em festivais de m\u00fasica e que emocionou a plateia do espet\u00e1culo Os Miser\u00e1veis Experience, em 2019, no Theatro S\u00e3o Pedro.<\/p>\n<figure id=\"attachment_84716\" aria-describedby=\"caption-attachment-84716\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84716\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-valentina-correa4_roque-rodrigues-agencia-studio-models\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models.jpg\" data-orig-size=\"1772,1181\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS Rebel T6i&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1615632826&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;26&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"bal\u00e9 VALENTINA CORREA4_Roque Rodrigues Ag\u00eancia Studio Models\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;A cantora Valentina Corr\u00eaa. Foto: Roque Rodrigues Ag\u00eancia Studio Models\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-1024x682.jpg\" class=\"size-medium wp-image-84716\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-1024x682.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models-1200x800.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-valentina-correa4-roque-rodrigues-agencia-studio-models.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-84716\" class=\"wp-caption-text\">A cantora Valentina Corr\u00eaa. Foto: Roque Rodrigues \/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Aluna do Ballet Vera Bublitz desde os 2 anos de idade, a cantora Valentina Corr\u00eaa, de 9 anos, tamb\u00e9m estar\u00e1 no palco. Ela brilhou na mais recente edi\u00e7\u00e3o do The Voice Kids, em 2021. No espet\u00e1culo, Valentina vai cantar, no s\u00e1bado, 25 de setembro, \u201cAl\u00e9m do Arco-\u00cdris\u201d, do M\u00e1gico de OZ, acompanhada pelo pianista Tiago Lewis, pai da tamb\u00e9m aluna Ol\u00edvia.<\/p>\n<figure id=\"attachment_84708\" aria-describedby=\"caption-attachment-84708\" style=\"width: 200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84708\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-alicia-sassi5_cesar-rodrigues\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues.jpg\" data-orig-size=\"1360,2040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Photographer: Cesar Rodrigues&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1629560734&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;73&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"bal\u00e9 Alicia Sassi5_C\u00e9sar Rodrigues\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Alicia Sassi. Foto: C\u00e9sar Rodrigues\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-683x1024.jpg\" class=\"size-medium wp-image-84708\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-200x300.jpg 200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-683x1024.jpg 683w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-768x1152.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-1024x1536.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues-1200x1800.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-alicia-sassi5-cesar-rodrigues.jpg 1360w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-84708\" class=\"wp-caption-text\">Alicia Sassi. Foto: C\u00e9sar Rodrigues\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<figure id=\"attachment_84711\" aria-describedby=\"caption-attachment-84711\" style=\"width: 200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84711\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-giovana-ryff1_cesar-rodrigues\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues.jpg\" data-orig-size=\"1360,2040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Photographer: Cesar Rodrigues&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1629557844&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;60&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"bal\u00e9 Giovana Ryff1_C\u00e9sar Rodrigues\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Giovana Ryff. Foto: C\u00e9sar Rodrigues\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-683x1024.jpg\" class=\"size-medium wp-image-84711\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-200x300.jpg 200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-683x1024.jpg 683w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-768x1152.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-1024x1536.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues-1200x1800.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-giovana-ryff1-cesar-rodrigues.jpg 1360w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-84711\" class=\"wp-caption-text\">Giovana Ryff. Foto: C\u00e9sar Rodrigues\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Entre os bailarinos que comp\u00f5em o espet\u00e1culo, revela\u00e7\u00f5es da dan\u00e7a que nasceram no Ballet Vera Bublitz, como Patrick Bublitz, Alicia Sassi, Catarina Kallfelz da Costa, Giovana Ryff, Isabela de Azevedo e Azevedo, Isabela Huyer, Julia Petry Quinto, Julia Xavier, Maiara Terra y Castro e Marina Miguel Starosta. Eles interpretam trechos de cl\u00e1ssicos de ballets de repert\u00f3rio, como Gisele, Dom Quixote, Paquita, Quebra-Nozes e Bela Adormecida. \u201cNas apresenta\u00e7\u00f5es, os bailarinos antecipam coreografias que ser\u00e3o apresentadas em festivais internacionais de dan\u00e7a de 2022\u201d, revela a diretora Carlla Bublitz. Mesmo na pandemia, os bailarinos t\u00eam se dedicado com afinco para a dan\u00e7a, em aulas intensivas de segunda a s\u00e1bado, para poderem brilhar nos palcos. \u201cO alimento mais importante para os jovens \u00e9 fazerem o que amam\u201d, destaca Vera Bublitz.<\/p>\n<figure id=\"attachment_84713\" aria-describedby=\"caption-attachment-84713\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84713\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-patrick-bublitz_daniel-martins\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-scaled.jpg\" data-orig-size=\"2560,2555\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1555102275&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;123&quot;,&quot;iso&quot;:&quot;1250&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"bal\u00e9 Patrick Bublitz_Daniel Martins\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Patrick Bublitz. Foto: Daniel MartinsDivulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-1024x1022.jpg\" class=\"size-medium wp-image-84713\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-300x300.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-1024x1022.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-768x767.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-1536x1533.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-2048x2044.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-patrick-bublitz-daniel-martins-1200x1200.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-84713\" class=\"wp-caption-text\">Patrick Bublitz. Foto: Daniel Martins. Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<figure id=\"attachment_84712\" aria-describedby=\"caption-attachment-84712\" style=\"width: 240px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84712\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/bale-marina-miguel-starosta-e-julia-petry-quinto_daniel-martins\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins.jpg\" data-orig-size=\"1281,1602\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS-1D X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1625408804&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;160&quot;,&quot;iso&quot;:&quot;5000&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Marina Miguel Starosta e J\u00falia Petry Quinto_Daniel Martins\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Marina Miguel Starosta e J\u00falia Petry Quinto. Foto:_Daniel Martins\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-819x1024.jpg\" class=\"size-medium wp-image-84712\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-240x300.jpg 240w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-819x1024.jpg 819w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-768x960.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-1228x1536.jpg 1228w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins-1200x1501.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-marina-miguel-starosta-e-julia-petry-quinto-daniel-martins.jpg 1281w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-84712\" class=\"wp-caption-text\">Marina Miguel Starosta e J\u00falia Petry Quinto. Foto:_Daniel Martins\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><strong>Agende-se<\/strong>:<\/p>\n<p style=\"font-weight: 400\"><strong>XIX Gala de Excel\u00eancia em Dan\u00e7a Ballet Vera Bublitz<\/strong><\/p>\n<p style=\"font-weight: 400\">25 de setembro (s\u00e1bado): 10h30 e 16h<br \/>\n26 de setembro (domingo): 10h30 e 16h<\/p>\n<p style=\"font-weight: 400\">Local: Theatro S\u00e3o Pedro (Pra\u00e7a Marechal Deodoro, s\/n \u2013 Centro Hist\u00f3rico \u2013 Porto Alegre)<\/p>\n<p style=\"font-weight: 400\">Capacidade: 170 lugares por espet\u00e1culo<\/p>\n<p style=\"font-weight: 400\"><strong>Valor \u00fanico:\u00a0<\/strong>R$ 100<\/p>\n<p style=\"font-weight: 400\"><strong>Ingressos antecipados:<\/strong><\/p>\n<ol>\n<li style=\"font-weight: 400\">Cel. Corte Real, 227<br \/>\nWhatsapp: (51) 98590-0618<\/li>\n<\/ol>\n<ol>\n<li style=\"font-weight: 400\">Cel. Lucas de Oliveira, 158<\/li>\n<\/ol>\n<p style=\"font-weight: 400\">Whatsapp: (51) 99933-3310<\/p>\n<p style=\"font-weight: 400\">Os ingressos tamb\u00e9m poder\u00e3o ser adquiridos nos dias do espet\u00e1culo na bilheteria do Theatro S\u00e3o Pedro, dependendo da disponibilidade de assentos.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-84707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-21T20:56:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-09-22T20:19:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#article\",\"name\":\"Revela\\u00e7\\u00f5es da dan\\u00e7a e da m\\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\\u00e3o Pedro | Cultura\",\"headline\":\"Revela\\u00e7\\u00f5es da dan\\u00e7a e da m\\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\\u00e3o Pedro\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/bale-bvb-daniel-martins.jpg\",\"width\":2444,\"height\":1199},\"datePublished\":\"2021-09-21T17:56:28-03:00\",\"dateModified\":\"2021-09-22T17:19:18-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#listItem\",\"name\":\"Revela\\u00e7\\u00f5es da dan\\u00e7a e da m\\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\\u00e3o Pedro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#listItem\",\"position\":3,\"name\":\"Revela\\u00e7\\u00f5es da dan\\u00e7a e da m\\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\\u00e3o Pedro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/\",\"name\":\"Revela\\u00e7\\u00f5es da dan\\u00e7a e da m\\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\\u00e3o Pedro | Cultura\",\"description\":\"O cantor Pedro Coppeti, que j\\u00e1 estrelou espet\\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\\u00eaa, do The Voice Kids, est\\u00e3o entre os destaques das apresenta\\u00e7\\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\\u00e3o Pedro para a IX\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/bale-bvb-daniel-martins.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#mainImage\",\"width\":2444,\"height\":1199},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\\\/#mainImage\"},\"datePublished\":\"2021-09-21T17:56:28-03:00\",\"dateModified\":\"2021-09-22T17:19:18-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura","description":"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#article","name":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura","headline":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-bvb-daniel-martins.jpg","width":2444,"height":1199},"datePublished":"2021-09-21T17:56:28-03:00","dateModified":"2021-09-22T17:19:18-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#listItem","name":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#listItem","position":3,"name":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/","name":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura","description":"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-bvb-daniel-martins.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#mainImage","width":2444,"height":1199},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/#mainImage"},"datePublished":"2021-09-21T17:56:28-03:00","dateModified":"2021-09-22T17:19:18-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura","og:description":"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX","og:url":"https:\/\/www.jornalja.com.br\/cultura\/revelacoes-da-danca-e-da-musica-apresentadas-pelo-ballet-vera-bublitz-no-theatro-sao-pedro\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg","article:published_time":"2021-09-21T20:56:28+00:00","article:modified_time":"2021-09-22T20:19:18+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Revela\u00e7\u00f5es da dan\u00e7a e da m\u00fasica, apresentadas pelo Ballet Vera Bublitz, no Theatro S\u00e3o Pedro | Cultura","twitter:description":"O cantor Pedro Coppeti, que j\u00e1 estrelou espet\u00e1culos da Broadway, e a cantora-mirim Valentina Corr\u00eaa, do The Voice Kids, est\u00e3o entre os destaques das apresenta\u00e7\u00f5es que ocorrem nos dias 25 e 26 de setembro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz (BVB), volta ao Theatro S\u00e3o Pedro para a IX","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-pedrocoppeti-fabioalt-300x200.jpeg"},"aioseo_meta_data":{"post_id":"84707","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-21 20:17:18","updated":"2025-06-04 12:46:48","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":84122,"url":"https:\/\/www.jornalja.com.br\/cultura\/ballet-vera-bublitz-de-volta-ao-theatro-sao-pedro-em-cinco-apresentacoes\/","url_meta":{"origin":84707,"position":0},"title":"Ballet Vera Bublitz de volta ao Theatro S\u00e3o Pedro, em cinco apresenta\u00e7\u00f5es","author":"da Reda\u00e7\u00e3o","date":"29 de junho de 2021","format":false,"excerpt":"O Ballet Vera Bubliz volta ao palco do Theatro S\u00e3o Pedro, dois anos depois do Festival Internacional de Dan\u00e7a de Porto Alegre (FIDPOA). \u00c9 a VIII Gala de Excel\u00eancia em Dan\u00e7a que ter\u00e1 em cinco apresenta\u00e7\u00f5es nos dias 2, 3 e 4 de julho. Os ingressos est\u00e3o \u00e0 venda nas\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/espetaculo-bela-adormecida-daniel-martins.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/espetaculo-bela-adormecida-daniel-martins.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/espetaculo-bela-adormecida-daniel-martins.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/espetaculo-bela-adormecida-daniel-martins.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/espetaculo-bela-adormecida-daniel-martins.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/espetaculo-bela-adormecida-daniel-martins.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":86764,"url":"https:\/\/www.jornalja.com.br\/cultura\/ballet-vera-bublitz-e-as-revelacoes-da-danca-em-noite-de-gala-no-theatro-sao-pedro\/","url_meta":{"origin":84707,"position":1},"title":"Ballet Vera Bublitz e as revela\u00e7\u00f5es da dan\u00e7a em noite de gala, no Theatro S\u00e3o Pedro","author":"da Reda\u00e7\u00e3o","date":"28 de setembro de 2022","format":false,"excerpt":"O Theatro S\u00e3o Pedro recebe neste s\u00e1bado, 1\u00ba de outubro, \u00e0s 16 horas, a X Gala Excel\u00eancia em Dan\u00e7a do Ballet Vera Bublitz. No espet\u00e1culo, a mais tradicional escola de dan\u00e7a do Estado refor\u00e7a sua voca\u00e7\u00e3o de revelar talentos para o mundo e de trazer grandes nomes nacionais e internacionais\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/bale-2-luiz-paulo-martins-2-acervo-pessoal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/bale-2-luiz-paulo-martins-2-acervo-pessoal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/bale-2-luiz-paulo-martins-2-acervo-pessoal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/bale-2-luiz-paulo-martins-2-acervo-pessoal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":89781,"url":"https:\/\/www.jornalja.com.br\/cultura\/homenagem-no-theatro-sao-pedro-com-exposicao-e-danca-celebram-os-80-anos-de-vera-bublitz\/","url_meta":{"origin":84707,"position":2},"title":"Homenagem no Theatro S\u00e3o Pedro, com exposi\u00e7\u00e3o e dan\u00e7a celebram os 80 anos de Vera Bublitz","author":"da Reda\u00e7\u00e3o","date":"7 de agosto de 2024","format":false,"excerpt":"\u00a0 Solenidade ser\u00e1 no dia 15 de agosto e inicia, \u00e0s 19h, com\u00a0exposi\u00e7\u00e3o que retrata a trajet\u00f3ria de 80 anos da mestre da dan\u00e7a, seguida por espet\u00e1culo beneficente. Um dos grandes nomes da dan\u00e7a do Estado ser\u00e1 homenageada pelo principal templo da cultura do Rio Grande do Sul. Vera Bublitz\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/08\/vera-bublitz-no-theatro-sao-pedro-estudio-daniel-martins.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/08\/vera-bublitz-no-theatro-sao-pedro-estudio-daniel-martins.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/08\/vera-bublitz-no-theatro-sao-pedro-estudio-daniel-martins.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/08\/vera-bublitz-no-theatro-sao-pedro-estudio-daniel-martins.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/08\/vera-bublitz-no-theatro-sao-pedro-estudio-daniel-martins.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":87467,"url":"https:\/\/www.jornalja.com.br\/cultura\/bye-bye-summer-class-2023-com-o-ballet-vera-bublitz-no-theatro-sao-pedro\/","url_meta":{"origin":84707,"position":3},"title":"&#8220;Bye Bye Summer Class 2023&#8221;, com o Ballet Vera Bublitz, no Theatro S\u00e3o Pedro","author":"da Reda\u00e7\u00e3o","date":"26 de janeiro de 2023","format":false,"excerpt":"Theatro S\u00e3o Pedro recebe espet\u00e1culo do Ballet Vera Bublitz neste s\u00e1bado, 28 de janeiro, \u00e0s 16 hrs. Entrada franca. Um espet\u00e1culo ao ar livre e aberto ao p\u00fablico \u00e9 a pedida do pr\u00f3ximo s\u00e1bado, 28 de janeiro. A mais tradicional escola de dan\u00e7a do Estado, o Ballet Vera Bublitz, traz\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/bale-alicia-prietsch-dresch-e-caleo-alencar-carlos-aguiar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/bale-alicia-prietsch-dresch-e-caleo-alencar-carlos-aguiar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/bale-alicia-prietsch-dresch-e-caleo-alencar-carlos-aguiar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/bale-alicia-prietsch-dresch-e-caleo-alencar-carlos-aguiar.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/01\/bale-alicia-prietsch-dresch-e-caleo-alencar-carlos-aguiar.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":87303,"url":"https:\/\/www.jornalja.com.br\/cultura\/ballet-vera-bublitz-danca-dom-quixote-no-theatro-sao-pedro-no-final-de-semana\/","url_meta":{"origin":84707,"position":4},"title":"Ballet Vera Bublitz dan\u00e7a &#8220;Dom Quixote&#8221; no Theatro S\u00e3o Pedro, no final de semana","author":"da Reda\u00e7\u00e3o","date":"7 de dezembro de 2022","format":false,"excerpt":"Adapta\u00e7\u00e3o ser\u00e1 apresentada em 4 sess\u00f5es nos dias 10 e 11 de dezembro. Espet\u00e1culo ter\u00e1 a participa\u00e7\u00e3o dos bailarinos Paulo Rodrigues e Marcos Silva, que est\u00e3o entre os melhores do Brasil na atualidade, do argentino Martin Miguel Moyano e do cubano Luis Gonzales. O Ballet Vera Bublitz (BVB) entrou para\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/12\/dom-quixote-ballet-vera-bublitz-daniel-martins.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/12\/dom-quixote-ballet-vera-bublitz-daniel-martins.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/12\/dom-quixote-ballet-vera-bublitz-daniel-martins.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/12\/dom-quixote-ballet-vera-bublitz-daniel-martins.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/12\/dom-quixote-ballet-vera-bublitz-daniel-martins.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/12\/dom-quixote-ballet-vera-bublitz-daniel-martins.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":87946,"url":"https:\/\/www.jornalja.com.br\/cultura\/festival-internacional-de-danca-traz-nomes-consagrados-do-bale-a-porto-alegre\/","url_meta":{"origin":84707,"position":5},"title":"Festival Internacional de Dan\u00e7a traz nomes consagrados do bal\u00e9 \u00e0 Porto Alegre","author":"Higino Barros","date":"1 de junho de 2023","format":false,"excerpt":"3\u00ba FIDPOA, que ocorre de 6 a 11 de junho, no Theatro S\u00e3o Pedro, ter\u00e1 convites gratuitos para entidades, escolas e universidades p\u00fablicas, al\u00e9m de \u00e1udio descri\u00e7\u00e3o e libras na apresenta\u00e7\u00e3o de abertura. Rui Cesar Cruz, que veio de uma comunidade do RJ e hoje brilha nos palcos dos EUA,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/danca-5-rui-cesar-cruz-2-marinho.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/danca-5-rui-cesar-cruz-2-marinho.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/danca-5-rui-cesar-cruz-2-marinho.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/danca-5-rui-cesar-cruz-2-marinho.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-m2f","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/bale-bvb-daniel-martins.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=84707"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84707\/revisions"}],"predecessor-version":[{"id":84722,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84707\/revisions\/84722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/84709"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=84707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=84707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=84707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}