{"id":84724,"date":"2021-09-23T15:38:32","date_gmt":"2021-09-23T18:38:32","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=84724"},"modified":"2021-09-23T15:38:32","modified_gmt":"2021-09-23T18:38:32","slug":"chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/","title":{"rendered":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25"},"content":{"rendered":"<div>\n<p><em>O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram\u00a0<a href=\"https:\/\/www.instagram.com\/ccmarioquintana\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/ccmarioquintana\/&amp;source=gmail&amp;ust=1632507099762000&amp;usg=AFQjCNGJAZwdk99pE5apo0_kdlg_bm8KTg\">@ccmarioquintana<\/a>, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da Secretaria de Estado da Cultura (Sedac), completa 31 anos.\u00a0<\/em><\/p>\n<p>A CCMQ chegou a anunciar a participa\u00e7\u00e3o de Lenine, mas o pernambucano precisou, de \u00faltima hora, cancelar a agenda por motivo de for\u00e7a maior, plenamente justific\u00e1vel. \u201cFoi com muita agilidade que conseguimos, em menos de 24h, viabilizar a participa\u00e7\u00e3o de Chico C\u00e9sar, artista da mesma grandeza de Lenine, que era nosso convidado inicial. Agradecemos o empenho de Lenine e a pronta disposi\u00e7\u00e3o de Chico C\u00e9sar em substituir o parceiro\u201d, explica Diego Groisman, diretor da Casa de Cultura.<\/p>\n<p>O evento mensal, que se tornou um dos principais projetos virtuais da CCMQ durante o per\u00edodo de distanciamento social, vem reunindo desde o ano passado m\u00fasicos de diferentes gera\u00e7\u00f5es, promovendo o encontro de diversos jovens talentos da cena regional e nacional com artistas consagrados como Maria Rita, Adriana Calcanhotto, Filipe Catto, Marcelo Jeneci, Alice Caymmi e Moreno Veloso, entre outros.<\/p>\n<p>O paraibano Francisco C\u00e9sar Gon\u00e7alves nasceu em 26 de janeiro de 1964, no munic\u00edpio de Catol\u00e9 do Rocha, interior da Para\u00edba. Aos dezesseis anos,\u00a0<a href=\"https:\/\/www.instagram.com\/oficialchicocesar\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/oficialchicocesar\/&amp;source=gmail&amp;ust=1632507099762000&amp;usg=AFQjCNEVlxielJb331_N9niC-eRf9jlyOQ\">Chico C\u00e9sar<\/a>\u00a0foi para a capital Jo\u00e3o Pessoa, onde se formou em jornalismo pela Universidade Federal da Para\u00edba. Nesse per\u00edodo, integrou o grupo Jaguaribe Carne, que fazia poesia de vanguarda. Mudou-se para S\u00e3o Paulo, aos 21 anos, trabalhando como jornalista e revisor de textos. Aperfei\u00e7oou-se no viol\u00e3o, multiplicou suas composi\u00e7\u00f5es e come\u00e7ou a formar o seu p\u00fablico. Suas can\u00e7\u00f5es s\u00e3o poesias de alto poder de encanto ling\u00fc\u00edstico e sua carreira art\u00edstica tem repercuss\u00e3o internacional.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84726\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/chico-cesar2_foto_jose-de-holanda\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg\" data-orig-size=\"922,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Chico C\u00e9sar2_Foto_Jos\u00e9 de Holanda\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Chico C\u00e9sar2_Foto_Jos\u00e9 de Holanda&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg\" class=\"size-medium wp-image-84726\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda-270x300.jpg\" alt=\"\" width=\"270\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda-270x300.jpg 270w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda-768x853.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg 922w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/p>\n<p>O sucesso da turn\u00ea pela Alemanha, em 1991, fez Chico C\u00e9sar\u00a0\u00a0deixar o jornalismo para se dedicar exclusivamente \u00e0 m\u00fasica. Foi quando formou a banda Cuscuz Cl\u00e3 (que seria o nome de seu segundo \u00e1lbum). Em 1995 lan\u00e7ava o primeiro CD \u201cAos Vivos\u201d (Velas), ac\u00fastico e ao vivo, com participa\u00e7\u00f5es de Lenine e o lend\u00e1rio Lany Gordin. Em 1996, sucesso nacional e internacional com o \u00e1lbum, \u201cCuscuz Cl\u00e3\u201d (MZA\/PolyGram).<\/p>\n<p>O quinto CD, \u201cRespeitem Meus Cabelos, Brancos\u201d (2002) come\u00e7ou a ser pr\u00e9-produzido em Londres e teve participa\u00e7\u00f5es especial\u00edssimas de Nina Miranda e Chris Franck (integrantes da banda Smoke City), Nan\u00e1 Vasconcelos e Carlinhos Brown. \u201cDe uns tempos pra c\u00e1\u201d (2005), trouxe 12 faixas autorais em formato camer\u00edstico com o Quinteto da Para\u00edba. Com \u201cFrancisco Forr\u00f3 y Frevo\u201d, em 2008, Chico C\u00e9sar mergulha no esp\u00edrito das festas populares nordestinas (carnaval e festejos juninos) e estabelece o di\u00e1logo entre estes ritmos e batidas universais, como o reggae e\u00a0o ska. O frevo ganha a novidade da mistura da linguagem das orquestras de metais de Pernambuco com a guitarra baiana dos trios el\u00e9tricos da Salvador, criados por Dod\u00f4 e Osmar. Depois do lan\u00e7amento do DVD\u00a0\u201cAos Vivos Agora\u201d (2012), Chico C\u00e9sar, que n\u00e3o lan\u00e7ava novo disco de in\u00e9ditas h\u00e1 oito anos, trouxe \u00e0 luz \u201cEstado de Poesia\u201d (2015), vencedor da 29\u00aa edi\u00e7\u00e3o do Pr\u00eamio da M\u00fasica Brasileira (2018) na categoria melhor \u00e1lbum de \u201cPop\/Rock\/Reggae\/Hip hop\/Funk\u201d.<\/p>\n<p>O trabalho de 2019 faz um coment\u00e1rio robusto das viv\u00eancias pol\u00edtico-sociais, no convulsionado momento brasileiro. Todas as 13 faixas de \u201cO Amor \u00c9 um Ato Revolucion\u00e1rio\u201d t\u00eam letra e m\u00fasica, assinadas apenas por Chico C\u00e9sar. O \u00e1lbum traz alguns convidados, como a adolescente paraibana Agnes Nunes (com quem Chico C\u00e9sar divide os vocais em \u201cDe Peito Aberto\u201d), a jovem cantautora pernambucana Flaira Ferro (em \u201cCruviana\u201d) e o guitarrista paulistano Luiz Carlini (em \u201cO Amor \u00e9 um Ato Revolucion\u00e1rio\u201d), que em um longo improviso revisita seu mitol\u00f3gico solo da primeira grava\u00e7\u00e3o de \u201cOvelha Negra\u201d com Rita Lee e Tutti Frutti.<\/p>\n<p><strong>Festejada pela cr\u00edtica<\/strong><\/p>\n<figure id=\"attachment_84728\" aria-describedby=\"caption-attachment-84728\" style=\"width: 200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84728\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/duda-brack2_foto_fabio-audi\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi.jpg\" data-orig-size=\"667,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Duda Brack2_foto_F\u00e1bio Audi\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Duda Brack. Fotos: F\u00e1bio Audi\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi.jpg\" class=\"size-medium wp-image-84728\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-200x300.jpg 200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi.jpg 667w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-84728\" class=\"wp-caption-text\">Duda Brack. Fotos: F\u00e1bio Audi\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Aos 26 anos, radicada no Rio de Janeiro, a cantora e compositora ga\u00facha\u00a0<a href=\"https:\/\/www.instagram.com\/dudabrack\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/dudabrack\/&amp;source=gmail&amp;ust=1632507099762000&amp;usg=AFQjCNFTlfsA-2Qke7D3mi3eOkonShTIYw\">Duda Brack<\/a>\u00a0lan\u00e7ou em 2015 o primeiro disco solo, intitulado \u201c\u00c9&#8221;. Desde ent\u00e3o, vem sendo apontada como uma das grandes vozes femininas a emergir na cena musical contempor\u00e2nea. Festejada pela cr\u00edtica especializada como artista revela\u00e7\u00e3o, abriu shows de\u00a0Elza Soares, Otto e Alceu Valen\u00e7a. Em 2017, a convite de Charles Gavin (ex-Tit\u00e3s) e da gravadora Deck, Duda gravou o \u00e1lbum \u201cPrimavera nos dentes &#8211; tributo aos Secos &amp; Molhados\u201d. Muito bem recebida pelos integrantes da banda original, a grava\u00e7\u00e3o recebeu elogios de Ney Matogrosso.<\/p>\n<p>O segundo disco solo de Duda Brack, \u201cCaCo de ViDRo\u201d, pelos selos Matogrosso (de Ney Matogrosso) e Al\u00e1 Comunica\u00e7\u00e3o e Cultura (de Jorginho Veloso), tem lan\u00e7amento programado para 15 de outubro. Heterog\u00eaneo e diverso, o \u00e1lbum passeia por muitos g\u00eaneros musicais como maculel\u00ea, pagod\u00e3o baiano, cumbia, folk e funk. Produzido pela pr\u00f3pria Duda, em parceria com Gabriel Ventura, \u201cCaCo de ViDRo\u201d conta com a colabora\u00e7\u00e3o de Lucio Maia (Na\u00e7\u00e3o Zumbi), do grupo de percuss\u00e3o Os Capoeira, arranjos de cordas de Maycon Ananias, arranjos de sopros de Vitor Tosta e participa\u00e7\u00e3o especial de Ney Matogrosso, Baiana System e Francisco Gil. O repert\u00f3rio do trabalho apresenta can\u00e7\u00f5es autorais de Duda, em parcerias com os amigos Chico Chico e Gui Fleming, e de outros compositores como Alzira Esp\u00edndola, Bruna Caram, Julia Vargas e Ian Ramil.<\/p>\n<figure id=\"attachment_84727\" aria-describedby=\"caption-attachment-84727\" style=\"width: 208px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"84727\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/duda-brack2_foto_fabio-audi-2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-2.jpg\" data-orig-size=\"693,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Duda Brack2_foto_F\u00e1bio Audi (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Duda Brack. Foto: F\u00e1bio Audi \/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-2.jpg\" class=\"size-medium wp-image-84727\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-2-208x300.jpg\" alt=\"\" width=\"208\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-2-208x300.jpg 208w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/duda-brack2-foto-fabio-audi-2.jpg 693w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><figcaption id=\"caption-attachment-84727\" class=\"wp-caption-text\">Duda Brack. Foto: F\u00e1bio Audi \/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>O diretor da CCMQ, Diego Groisman destaca o empenho da equipe curatorial ao definir as atra\u00e7\u00f5es desta edi\u00e7\u00e3o especial do Casa Virtual, que celebra os 31 anos\u00a0 do complexo cultural. \u201cA obra musical de Chico C\u00e9sar \u00e9 fortemente alicer\u00e7ada na poesia e faz com que a celebra\u00e7\u00e3o dos 31 anos mantenha uma rela\u00e7\u00e3o com Mario Quintana. A participa\u00e7\u00e3o da ga\u00facha Duda Brack refor\u00e7a uma liga\u00e7\u00e3o afetiva com a Casa de Cultura. A presen\u00e7a dos dois artistas reafirma nossa dedica\u00e7\u00e3o em proporcionar ao p\u00fablico o contato com grandes nomes ao mesmo tempo em que buscamos repercutir o trabalho de jovens talentos\u201d, comenta Groisman.<\/p>\n<p>Casa Virtual Especial 31 anos da CCMQ \u2013 Chico C\u00e9sar e Duda Brack<br \/>\nQuando:\u00a025 de setembro | s\u00e1bado<br \/>\nHor\u00e1rio:\u00a020h<br \/>\nOnde:\u00a0Instagram\u00a0<a href=\"https:\/\/www.instagram.com\/ccmarioquintana\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/ccmarioquintana\/&amp;source=gmail&amp;ust=1632507099762000&amp;usg=AFQjCNGJAZwdk99pE5apo0_kdlg_bm8KTg\">@ccmarioquintana<\/a><\/p>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram\u00a0@ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-84724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"922\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-23T18:38:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-09-23T18:38:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#article\",\"name\":\"Chico C\\u00e9sar e Duda Brack no show de anivers\\u00e1rio da CCMQ , no s\\u00e1bado, dia 25 | Cultura\",\"headline\":\"Chico C\\u00e9sar e Duda Brack no show de anivers\\u00e1rio da CCMQ , no s\\u00e1bado, dia 25\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/chico-cesar1-fotos-jose-de-holanda.jpg\",\"width\":1015,\"height\":1024,\"caption\":\"Chico C\\u00e9sar. Fotos: Jos\\u00e9 de Holanda\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2021-09-23T15:38:32-03:00\",\"dateModified\":\"2021-09-23T15:38:32-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#listItem\",\"name\":\"Chico C\\u00e9sar e Duda Brack no show de anivers\\u00e1rio da CCMQ , no s\\u00e1bado, dia 25\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#listItem\",\"position\":3,\"name\":\"Chico C\\u00e9sar e Duda Brack no show de anivers\\u00e1rio da CCMQ , no s\\u00e1bado, dia 25\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/\",\"name\":\"Chico C\\u00e9sar e Duda Brack no show de anivers\\u00e1rio da CCMQ , no s\\u00e1bado, dia 25 | Cultura\",\"description\":\"O paraibano Chico C\\u00e9sar faz o Casa Virtual Especial do m\\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\\u00facha radicada no Rio de Janeiro. O show tem transmiss\\u00e3o ao vivo pelo Instagram @ccmarioquintana, \\u00e0s 20h do s\\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\\u00e7\\u00e3o da\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/chico-cesar1-fotos-jose-de-holanda.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#mainImage\",\"width\":1015,\"height\":1024,\"caption\":\"Chico C\\u00e9sar. Fotos: Jos\\u00e9 de Holanda\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\\\/#mainImage\"},\"datePublished\":\"2021-09-23T15:38:32-03:00\",\"dateModified\":\"2021-09-23T15:38:32-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura","description":"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#article","name":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura","headline":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar1-fotos-jose-de-holanda.jpg","width":1015,"height":1024,"caption":"Chico C\u00e9sar. Fotos: Jos\u00e9 de Holanda\/ Divulga\u00e7\u00e3o"},"datePublished":"2021-09-23T15:38:32-03:00","dateModified":"2021-09-23T15:38:32-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#listItem","name":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#listItem","position":3,"name":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/","name":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura","description":"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar1-fotos-jose-de-holanda.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#mainImage","width":1015,"height":1024,"caption":"Chico C\u00e9sar. Fotos: Jos\u00e9 de Holanda\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/#mainImage"},"datePublished":"2021-09-23T15:38:32-03:00","dateModified":"2021-09-23T15:38:32-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura","og:description":"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da","og:url":"https:\/\/www.jornalja.com.br\/cultura\/chico-cesar-e-duda-brack-no-show-de-aniversario-da-ccmq-no-sabado-dia-25\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg","og:image:width":922,"og:image:height":1024,"article:published_time":"2021-09-23T18:38:32+00:00","article:modified_time":"2021-09-23T18:38:32+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Chico C\u00e9sar e Duda Brack no show de anivers\u00e1rio da CCMQ , no s\u00e1bado, dia 25 | Cultura","twitter:description":"O paraibano Chico C\u00e9sar faz o Casa Virtual Especial do m\u00eas de setembro ao lado de Duda Brack, jovem cantora e compositora ga\u00facha radicada no Rio de Janeiro. O show tem transmiss\u00e3o ao vivo pelo Instagram @ccmarioquintana, \u00e0s 20h do s\u00e1bado, 25 de setembro, data em que a Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar2-foto-jose-de-holanda.jpg"},"aioseo_meta_data":{"post_id":"84724","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-23 18:25:39","updated":"2025-06-04 12:46:48","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":86536,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-guitarra-de-ricardo-silveira-se-encontra-com-o-baixo-de-gastao-villeroy-no-espaco-373\/","url_meta":{"origin":84724,"position":0},"title":"A guitarra de Ricardo Silveira se encontra com o baixo de Gast\u00e3o Villeroy, no Espa\u00e7o 373","author":"da Reda\u00e7\u00e3o","date":"26 de agosto de 2022","format":false,"excerpt":"\u00a0Conhecido por trabalhos ao lado de nomes, como Jo\u00e3o Bosco, Milton Nascimento, Ivan Lins, Elis Regina, Gilberto Gil, Ney Matogrosso, Diana Ross e Path\u00a0Metheny, Ricardo se apresenta nos dias 2 e 3 de setembro, \u00e0s 21h, com o baixista Gast\u00e3o Villeroy \u00a0O\u00a0guitarrista carioca Ricardo Silveira convida o baixista ga\u00facho, radicado\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/show-ricardo-silveira-foto-nando-chagas-3-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/show-ricardo-silveira-foto-nando-chagas-3-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/show-ricardo-silveira-foto-nando-chagas-3-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/show-ricardo-silveira-foto-nando-chagas-3-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/show-ricardo-silveira-foto-nando-chagas-3-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/show-ricardo-silveira-foto-nando-chagas-3-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84618,"url":"https:\/\/www.jornalja.com.br\/cultura\/cinco-novas-exposicoes-de-artes-visuais-em-setembro-na-ccmq\/","url_meta":{"origin":84724,"position":1},"title":"Cinco novas exposi\u00e7\u00f5es de artes visuais em setembro, na CCMQ","author":"da Reda\u00e7\u00e3o","date":"8 de setembro de 2021","format":false,"excerpt":"Com recentes indica\u00e7\u00f5es em tr\u00eas categorias do XIV Pr\u00eamio A\u00e7orianos de Artes Pl\u00e1sticas (Destaque A\u00e7\u00f5es de Difus\u00e3o e Inova\u00e7\u00e3o Institucional, Destaque Acervos e Destaque Institui\u00e7\u00e3o), a Casa de Cultura Mario Quintana (CCMQ \u2013 Andradas, 736 \u2013 Centro Hist\u00f3rico de Porto Alegre), institui\u00e7\u00e3o da Secretaria de Estado da Cultura (Sedac), consolida\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/casa-gino-bidart-reproducao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/casa-gino-bidart-reproducao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/casa-gino-bidart-reproducao.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/casa-gino-bidart-reproducao.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83936,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-pegada-jazzistica-do-bossa-50-e-a-guitarra-de-pedro-tagliani-no-fim-de-semana-do-butia\/","url_meta":{"origin":84724,"position":2},"title":"A pegada jazz\u00edstica do Bossa 50 e a guitarra de Pedro Tagliani, no fim de semana do Buti\u00e1","author":"da Reda\u00e7\u00e3o","date":"13 de maio de 2021","format":false,"excerpt":"O Buti\u00e1\u00a0recebe neste\u00a0s\u00e1bado (15) o Bossa 50, em uma homenagem ao movimento musical, com harmonia jazz\u00edstica, que projetou a m\u00fasica brasileira para o mundo.\u00a0No repert\u00f3rio do\u00a0grupo, formado por Chico Paix\u00e3o (voz e viol\u00e3o), Everton Velasquez (baixo e vocais), Leonardo Boff (piano e voz) e Diego Silveira (bateria),\u00a0cl\u00e1ssicos como: \u00c1gua de\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/butia-bossa-50-foto-aline-stoffel-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/butia-bossa-50-foto-aline-stoffel-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/butia-bossa-50-foto-aline-stoffel-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/butia-bossa-50-foto-aline-stoffel-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/butia-bossa-50-foto-aline-stoffel-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/butia-bossa-50-foto-aline-stoffel-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":77188,"url":"https:\/\/www.jornalja.com.br\/cultura\/clube-da-mpb-homenageia-paulo-cesar-pinheiro-no-ano-de-seu-aniversario-de-70-anoss\/","url_meta":{"origin":84724,"position":3},"title":"Clube da MPB homenageia Paulo C\u00e9sar Pinheiro no ano de seu anivers\u00e1rio de 70 anoss","author":"da Reda\u00e7\u00e3o","date":"8 de setembro de 2019","format":false,"excerpt":"Esta edi\u00e7\u00e3o do Clube da MPB, um projeto que est\u00e1 sempre conectado com a MPB e suas vertentes, homenageia Paulo Cesar Pinheiro que completa 70 anos. Ele nasceu no Rio de Janeiro em 28 de abril de 1949, dia em que o Brasil ganhou um grande compositor. S\u00e3o mais de\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":73713,"url":"https:\/\/www.jornalja.com.br\/cultura\/73713-2\/","url_meta":{"origin":84724,"position":4},"title":"J\u00e9ssica Berdet apresenta show \u2018(In) Vis\u00edvel\u2019 na Biblioteca P\u00fablica Estadual","author":"da Reda\u00e7\u00e3o","date":"6 de abril de 2019","format":false,"excerpt":"A atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 9 de abril (ter\u00e7a), \u00e0s 19h, na Biblioteca P\u00fablica do Estado (BPE-RS) \u00e9 J\u00e9ssica Berdet, no show autoral \u201c(In) Vis\u00edvel\u201d, a partir do \u00e1lbum hom\u00f4nimo da cantora, compositora e violonista. No acompanhamento, Dinho Oliveira (guitarra), Bruno Coelho (percuteria) e Bernardo Zubaran (harm\u00f4nica),\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/04\/chapeu-jessica-300x450.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":91634,"url":"https:\/\/www.jornalja.com.br\/cultura\/zeca-baleiro-toca-sua-musica-de-muitos-ritmos-em-porto-alegre\/","url_meta":{"origin":84724,"position":5},"title":"Zeca Baleiro toca sua m\u00fasica de muitos ritmos em Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"28 de novembro de 2025","format":false,"excerpt":"Eduardo Maretti Compositor j\u00e1 consagrado como uma das principais vozes da MPB p\u00f3s-gera\u00e7\u00e3o dos anos 1960, o maranhense Zeca Baleiro se apresenta em Porto Alegre nesta sexta-feira (28), no Audit\u00f3rio Ara\u00fajo Vianna, na companhia do m\u00fasico Adriano Magoo. O show \u00e9 intitulado Piano. Apesar de sua figura, que, mesmo depois\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/11\/zecabaleiro-divulgacao.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-m2w","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/chico-cesar1-fotos-jose-de-holanda.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=84724"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84724\/revisions"}],"predecessor-version":[{"id":84729,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/84724\/revisions\/84729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/84725"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=84724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=84724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=84724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}