{"id":85815,"date":"2022-04-20T18:57:57","date_gmt":"2022-04-20T21:57:57","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=85815"},"modified":"2022-04-20T18:57:57","modified_gmt":"2022-04-20T21:57:57","slug":"na-mostra-arte-alerta-uma-exposicao-com-interatividade","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/","title":{"rendered":"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\u00e7\u00e3o com interatividade"},"content":{"rendered":"<p style=\"font-weight: 400\">O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a possibilidade de cria\u00e7\u00e3o e interven\u00e7\u00e3o art\u00edstica pelos pr\u00f3prios visitantes, o que tem levado milhares de pessoas a conhecer o projeto por onde ele passa, especialmente crian\u00e7as e adolescentes. A abertura ser\u00e1 no dia 23 de abril, das 14h \u00e0s 17h, no Espa\u00e7o Cultural Correios, que fica localizado no t\u00e9rreo da Av. Sete de Setembro, 1020, no Centro Hist\u00f3rico de Porto Alegre.\u00a0Entrada franca.<\/p>\n<figure id=\"attachment_85819\" aria-describedby=\"caption-attachment-85819\" style=\"width: 206px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"85819\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/alerta-4-evanescimento-lesiane-lazzatotti-ogg\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg\" data-orig-size=\"1185,1723\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1646321075&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.0081967213114754&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ALERTA 4 Evanescimento &amp;#8211; Lesiane Lazzatotti Ogg\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Evanescimento &amp;#8211; Obra de Lesiane Lazzatotti Ogg&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg-704x1024.jpg\" class=\"size-medium wp-image-85819\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg-206x300.jpg\" alt=\"\" width=\"206\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg-206x300.jpg 206w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg-704x1024.jpg 704w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg-768x1117.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg-1056x1536.jpg 1056w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg 1185w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><figcaption id=\"caption-attachment-85819\" class=\"wp-caption-text\">Evanescimento &#8211; Obra de Lesiane Lazzatotti Ogg<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">\u201cO projeto Arte Alerta foi<strong>\u00a0<\/strong>criado com o intuito de juntar v\u00e1rios artistas em uma nobre causa de alertar as pessoas sobre a degrada\u00e7\u00e3o provocada pelo ser humano ao meio ambiente. Em um sentido mais amplo, envolvendo tamb\u00e9m outros aspectos do mundo contempor\u00e2neo que afetam a todos, como tecnologia e mudan\u00e7as de comportamento\u201d, explica Lesiane. \u201cO Arte Alerta tem como foco plantar uma semente nas novas gera\u00e7\u00f5es, conscientizando sobre a necessidade de preservar o planeta de nossas pr\u00f3prias a\u00e7\u00f5es predat\u00f3rias\u201d, complementa a artista.<\/p>\n<figure id=\"attachment_85823\" aria-describedby=\"caption-attachment-85823\" style=\"width: 238px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"85823\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/alerta-ncluidos-marilena-mota\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota.jpg\" data-orig-size=\"1274,1608\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1646750043&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Inclu\u00eddos &amp;#8211; Marilena Mota\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Inclu\u00eddos &amp;#8211; Marilena Mota&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-811x1024.jpg\" class=\"size-medium wp-image-85823\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-238x300.jpg\" alt=\"\" width=\"238\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-238x300.jpg 238w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-811x1024.jpg 811w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-768x969.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-1217x1536.jpg 1217w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota-1200x1515.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-ncluidos-marilena-mota.jpg 1274w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/><figcaption id=\"caption-attachment-85823\" class=\"wp-caption-text\">Inclu\u00eddos &#8211; Obra de Marilena Mota<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Nesta quarta edi\u00e7\u00e3o do Arte Alerta, primeira no Rio Grande do Sul, 16 artistas que integram o Atelier Baluarte, do Rio de Janeiro, entre eles a tamb\u00e9m ga\u00facha Riele, exibir\u00e3o suas pinturas com diferentes mensagens sobre a sens\u00edvel quest\u00e3o de preserva\u00e7\u00e3o do entorno, questionando a postura da humanidade em rela\u00e7\u00e3o \u00e0 natureza e \u00e0 vida.<\/p>\n<figure id=\"attachment_85818\" aria-describedby=\"caption-attachment-85818\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"85818\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/alerta-3-riele\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele.jpg\" data-orig-size=\"2390,1952\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ALERTA 3 Riele\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;A artista Riele e sua obra. Foto: Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-1024x836.jpg\" class=\"size-medium wp-image-85818\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-300x245.jpg\" alt=\"\" width=\"300\" height=\"245\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-300x245.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-1024x836.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-768x627.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-1536x1255.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-2048x1673.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-3-riele-1200x980.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-85818\" class=\"wp-caption-text\">A artista Riele e sua obra. Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Al\u00e9m das pinturas, ser\u00e3o oferecidas a\u00e7\u00f5es de arte-educa\u00e7\u00e3o, procurando inserir o p\u00fablico na mostra, convidando-os a produzir arte e a interagir a partir de trabalhos manuais orientados pela monitoria. Tamb\u00e9m ser\u00e1 exibido um videoarte sobre a natureza chamado \u201cAlma da Mata\u201d, assinado pelo curador Luiz Badia. O projeto se diferencia nesse aspecto da comunica\u00e7\u00e3o e intera\u00e7\u00e3o com o p\u00fablico, principalmente com as crian\u00e7as, j\u00e1 que \u00e9 delas que deve surgir um novo pensamento sobre a conviv\u00eancia entre o ser humano e a natureza.<\/p>\n<figure id=\"attachment_85821\" aria-describedby=\"caption-attachment-85821\" style=\"width: 231px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"85821\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/alerta-6-preconceito-riele\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele.jpg\" data-orig-size=\"1228,1593\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ALERTA 6 Preconceito &amp;#8211; Riele\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Preconceito &amp;#8211; Obra de Riele&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-789x1024.jpg\" class=\"size-medium wp-image-85821\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-231x300.jpg\" alt=\"\" width=\"231\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-231x300.jpg 231w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-789x1024.jpg 789w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-768x996.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-1184x1536.jpg 1184w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele-1200x1557.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-6-preconceito-riele.jpg 1228w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><figcaption id=\"caption-attachment-85821\" class=\"wp-caption-text\">Preconceito &#8211; Obra de Riele<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>Cidad\u00e3 do mundo<\/strong><br \/>\nNatural de Canoas, Lesiane Lazzarotti Ogg, \u00e9 cidad\u00e3 do mundo. Atualmente, radicada no Rio de Janeiro, a artista ga\u00facha come\u00e7ou sua carreira na arte com uma exposi\u00e7\u00e3o em Cuba e j\u00e1 exp\u00f4s no Carroussel do Louvre em Paris e na sede da ONU, em Nova York. Com uma forte atua\u00e7\u00e3o social, em comunidades da \u00c1frica e do Brasil, Lesiane \u00e9 membro da Academia Brasileira de Belas Artes, desde 2019.<\/p>\n<figure id=\"attachment_85820\" aria-describedby=\"caption-attachment-85820\" style=\"width: 236px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"85820\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/alerta-5-planeta-covid-marcia-crijo\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo.jpg\" data-orig-size=\"1270,1615\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1646750064&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ALERTA 5 Planeta Covid &amp;#8211; M\u00e1rcia Crij\u00f3\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Planeta Covid &amp;#8211; Obra de  M\u00e1rcia Crij\u00f3&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-805x1024.jpg\" class=\"size-medium wp-image-85820\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-236x300.jpg\" alt=\"\" width=\"236\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-236x300.jpg 236w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-805x1024.jpg 805w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-768x977.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-1208x1536.jpg 1208w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo-1200x1526.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-5-planeta-covid-marcia-crijo.jpg 1270w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><figcaption id=\"caption-attachment-85820\" class=\"wp-caption-text\">Planeta Covid &#8211; Obra de M\u00e1rcia Crij\u00f3<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>Servi\u00e7o:<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Exposi\u00e7\u00e3o interativa \u201cArte Alerta IV\u201d<\/strong><\/p>\n<p style=\"font-weight: 400\">Abertura: 23 de abril (s\u00e1bado), das 14h \u00e0s 17h.<\/p>\n<p style=\"font-weight: 400\">Visita\u00e7\u00e3o: 23 de abril a 4 de junho \u2013 ter\u00e7a a s\u00e1bado, das 10h \u00e0s 17h.<\/p>\n<p style=\"font-weight: 400\">Local: Espa\u00e7o Cultural Correios<\/p>\n<p style=\"font-weight: 400\">Endere\u00e7o: Av. Sete de Setembro, 1020, Centro Hist\u00f3rico, Porto Alegre<br \/>\nEntrada Franca<\/p>\n<figure id=\"attachment_85816\" aria-describedby=\"caption-attachment-85816\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"85816\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/alerta-1-arte-alerta-ii-divulgacao\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao.jpg\" data-orig-size=\"2096,1180\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Moto G (4)&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1466520945&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.68&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ALERTA 1 Arte Alerta II &amp;#8211; Divulga\u00e7\u00e3o\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Arte Alerta II &amp;#8211; Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-1024x576.jpg\" class=\"size-medium wp-image-85816\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-300x169.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-1024x576.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-768x432.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-1536x865.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-2048x1153.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-1-arte-alerta-ii-divulgacao-1200x676.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-85816\" class=\"wp-caption-text\">Arte Alerta II &#8211; Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":85817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-85815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1185\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1723\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-04-20T21:57:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-04-20T21:57:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#article\",\"name\":\"Na mostra \\u201cArte Alerta\\u201d, uma exposi\\u00e7\\u00e3o com interatividade | Cultura\",\"headline\":\"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\\u00e7\\u00e3o com interatividade\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/alerta-2-lesiane-ogg-2.jpg\",\"width\":2082,\"height\":2353,\"caption\":\"A artista  Lesiane Ogg. Foto: Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2022-04-20T18:57:57-03:00\",\"dateModified\":\"2022-04-20T18:57:57-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#listItem\",\"name\":\"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\\u00e7\\u00e3o com interatividade\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#listItem\",\"position\":3,\"name\":\"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\\u00e7\\u00e3o com interatividade\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/\",\"name\":\"Na mostra \\u201cArte Alerta\\u201d, uma exposi\\u00e7\\u00e3o com interatividade | Cultura\",\"description\":\"O Espa\\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\\u00e7\\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\\u00e7\\u00e3o de ter\\u00e7as a s\\u00e1bados. A mostra foi criada pela artista ga\\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\\u00e1 a\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/alerta-2-lesiane-ogg-2.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#mainImage\",\"width\":2082,\"height\":2353,\"caption\":\"A artista  Lesiane Ogg. Foto: Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\\\/#mainImage\"},\"datePublished\":\"2022-04-20T18:57:57-03:00\",\"dateModified\":\"2022-04-20T18:57:57-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura","description":"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#article","name":"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura","headline":"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\u00e7\u00e3o com interatividade","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-2-lesiane-ogg-2.jpg","width":2082,"height":2353,"caption":"A artista  Lesiane Ogg. Foto: Divulga\u00e7\u00e3o"},"datePublished":"2022-04-20T18:57:57-03:00","dateModified":"2022-04-20T18:57:57-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#listItem","name":"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\u00e7\u00e3o com interatividade"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#listItem","position":3,"name":"Na mostra &#8220;Arte Alerta&#8221;, uma exposi\u00e7\u00e3o com interatividade","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/","name":"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura","description":"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-2-lesiane-ogg-2.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#mainImage","width":2082,"height":2353,"caption":"A artista  Lesiane Ogg. Foto: Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/#mainImage"},"datePublished":"2022-04-20T18:57:57-03:00","dateModified":"2022-04-20T18:57:57-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura","og:description":"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a","og:url":"https:\/\/www.jornalja.com.br\/cultura\/na-mostra-arte-alerta-uma-exposicao-com-interatividade\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg","og:image:width":1185,"og:image:height":1723,"article:published_time":"2022-04-20T21:57:57+00:00","article:modified_time":"2022-04-20T21:57:57+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Na mostra \u201cArte Alerta\u201d, uma exposi\u00e7\u00e3o com interatividade | Cultura","twitter:description":"O Espa\u00e7o Cultural Correios, de Porto Alegre vai receber a exposi\u00e7\u00e3o interativa Arte Alerta IV, de 23 de abril a 4 junho, com visita\u00e7\u00e3o de ter\u00e7as a s\u00e1bados. A mostra foi criada pela artista ga\u00facha Lesiane Lazzarotti Ogg, atualmente radicada no Rio de Janeiro, e tem curadoria de Luiz Badia. Entre os diferenciais est\u00e1 a","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-4-evanescimento-lesiane-lazzatotti-ogg.jpg"},"aioseo_meta_data":{"post_id":"85815","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-04-20 21:30:54","updated":"2025-06-04 13:03:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":89322,"url":"https:\/\/www.jornalja.com.br\/cultura\/as-cores-de-marcelo-zanini-em-obras-de-grandes-dimensoes-no-espaco-cultural-correios\/","url_meta":{"origin":85815,"position":0},"title":"As cores de Marcelo Zanini, em obras de grandes dimens\u00f5es, no Espa\u00e7o Cultural Correios","author":"da Reda\u00e7\u00e3o","date":"9 de abril de 2024","format":false,"excerpt":"Vernissage da exposi\u00e7\u00e3o \u201cCroma\u201d ser\u00e1 no s\u00e1bado, 13 de abril, \u00e0s 11h. Mostra segue no local at\u00e9 o dia 18 de maio, com entrada franca. Segundo o material de divulga\u00e7\u00e3o, Marcelo Zanini alia paix\u00e3o e beleza em sua trajet\u00f3ria como artista e m\u00e9dico. O resultado dessa uni\u00e3o pode ser conferido\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/04\/marcelo-scheggie-marcelo-zanini-foto-wanderlei-oliveira.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/04\/marcelo-scheggie-marcelo-zanini-foto-wanderlei-oliveira.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/04\/marcelo-scheggie-marcelo-zanini-foto-wanderlei-oliveira.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/04\/marcelo-scheggie-marcelo-zanini-foto-wanderlei-oliveira.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":73868,"url":"https:\/\/www.jornalja.com.br\/cultura\/desenhos-com-luz-mostra-a-producao-de-29-fotografos-em-58-obras-no-espaco-cultural-correios\/","url_meta":{"origin":85815,"position":1},"title":"&quot;Desenhos com luz&quot; mostra a produ\u00e7\u00e3o de 29 fot\u00f3grafos em 58 obras, no Espa\u00e7o Cultural Correios","author":"da Reda\u00e7\u00e3o","date":"11 de abril de 2019","format":false,"excerpt":"Segundo o material de divulga\u00e7\u00e3o da mostra, a fotografia transcende ao real e ganha status de arte na exposi\u00e7\u00e3o \"Desenhos com Luz\", que inaugura nesse s\u00e1bado, 13 de abril, em vernissage das 11h \u00e0s 13h, no Espa\u00e7o Cultural Correios, na Av. Sete de Setembro, 1020, na Pra\u00e7a da Alf\u00e2ndega, em\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/04\/arte-foto-Da-janela-Lateral-Fernando-Castro-450x321.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":87772,"url":"https:\/\/www.jornalja.com.br\/cultura\/as-conexoes-transcendentes-de-heitor-bergamini-em-exposicao-no-espaco-cultural-correios\/","url_meta":{"origin":85815,"position":2},"title":"As Conex\u00f5es Transcendentes de Heitor Bergamini, em exposi\u00e7\u00e3o no Espa\u00e7o Cultural Correios","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2023","format":false,"excerpt":"A arte sustent\u00e1vel de Heitor Bergamini vai ocupar o Espa\u00e7o Cultural Correios, a partir de 27 de abril. O artista v\u00ea arte na sucata, nas ra\u00edzes do mangue, em barcos encalhados e transforma esse olhar em belas esculturas e imagens. \u201cConex\u00f5es Transcendentes\u201d tem curadoria do arquiteto F\u00e1bio Andr\u00e9 Rheinheimer e\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/conexoesrelevos-heitor-bergamini-lauren-kommers-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/conexoesrelevos-heitor-bergamini-lauren-kommers-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/conexoesrelevos-heitor-bergamini-lauren-kommers-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/conexoesrelevos-heitor-bergamini-lauren-kommers-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/conexoesrelevos-heitor-bergamini-lauren-kommers-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/conexoesrelevos-heitor-bergamini-lauren-kommers-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":87583,"url":"https:\/\/www.jornalja.com.br\/cultura\/na-exposicao-fotografica-elas-o-universo-feminino-plural-no-espaco-cultural-correios\/","url_meta":{"origin":85815,"position":3},"title":"Na exposi\u00e7\u00e3o fotogr\u00e1fica &#8220;Elas&#8221;, o universo feminino, no Espa\u00e7o Cultural Correios","author":"Higino Barros","date":"6 de mar\u00e7o de 2023","format":false,"excerpt":"Exposi\u00e7\u00e3o \u201cELAS\u201d, que apresenta obras de Anelise Ferreira, Gutemberg Ostemberg, La\u00e9rcio de Menezes e Marina Menezes, tem vernissage no s\u00e1bado, 11 de mar\u00e7o.\u00a0 A mulher lan\u00e7a olhares e desperta olhares. Na vis\u00e3o dos artistas, as interpreta\u00e7\u00f5es se multiplicam. S\u00e3o simb\u00f3licas, pictogr\u00e1ficas, sensuais ou po\u00e9ticas. Na exposi\u00e7\u00e3o \u201cELAS\u201d, que ser\u00e1 inaugurada\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/foto-24-vera-laercio-de-menezes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/foto-24-vera-laercio-de-menezes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/foto-24-vera-laercio-de-menezes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/foto-24-vera-laercio-de-menezes.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/foto-24-vera-laercio-de-menezes.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/foto-24-vera-laercio-de-menezes.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83393,"url":"https:\/\/www.jornalja.com.br\/cultura\/fabio-andre-rheinheimer-une-arte-e-tecnologia-na-exposicao-naves-poeticas\/","url_meta":{"origin":85815,"position":4},"title":"F\u00e1bio Andr\u00e9 Rheinheimer une arte e tecnologia na mostra &#8220;Naves po\u00e9ticas&#8221;","author":"da Reda\u00e7\u00e3o","date":"9 de fevereiro de 2021","format":false,"excerpt":"O arquiteto, curador e artista visual F\u00e1bio Andr\u00e9 Rheinheimer inaugura exposi\u00e7\u00e3o individual em Porto Alegre, depois de sua estreia em dezembro, em S\u00e3o Paulo. \u00c9 o \u201cProjeto Naves Po\u00e9ticas\u201d, nessa quarta-feira, 10 de fevereiro, no Espa\u00e7o Cultural Correios, localizado no t\u00e9rreo da Av. Sete de Setembro, 1020, no Centro Hist\u00f3rico,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/02\/exposicao-fabio-158-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":86677,"url":"https:\/\/www.jornalja.com.br\/cultura\/entre-utopias-e-distopias-contempla-diferentes-linguagens-artisticas-no-espaco-cultural-correios\/","url_meta":{"origin":85815,"position":5},"title":"&#8220;Entre Utopias e Distopias&#8221; contempla diferentes linguagens art\u00edsticas, no Espa\u00e7o Cultural Correios","author":"da Reda\u00e7\u00e3o","date":"14 de setembro de 2022","format":false,"excerpt":"\u00a0 O Centro Hist\u00f3rico de Porto Alegre se transforma em palco da cultura e da arte a partir do dia 17 setembro. A inaugura\u00e7\u00e3o da exposi\u00e7\u00e3o \u201cEntre Utopias e Distopias\u201d, no Espa\u00e7o Cultural Correios (Av. Sete de Setembro, 1020), no s\u00e1bado, dia 17 de setembro, a partir das 10h, lan\u00e7a\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/correios-recicla-te-denise-wichmann-reproducao-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/correios-recicla-te-denise-wichmann-reproducao-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/correios-recicla-te-denise-wichmann-reproducao-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/correios-recicla-te-denise-wichmann-reproducao-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/correios-recicla-te-denise-wichmann-reproducao-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/correios-recicla-te-denise-wichmann-reproducao-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-mk7","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/alerta-2-lesiane-ogg-2.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/85815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=85815"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/85815\/revisions"}],"predecessor-version":[{"id":85824,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/85815\/revisions\/85824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/85817"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=85815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=85815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=85815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}