{"id":87936,"date":"2023-06-01T11:02:18","date_gmt":"2023-06-01T14:02:18","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=87936"},"modified":"2023-06-01T11:02:18","modified_gmt":"2023-06-01T14:02:18","slug":"escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/","title":{"rendered":"Escritor Dem\u00e9trio Peixoto autografa &#8220;Retratos n\u00e3o falados&#8221;, no Espa\u00e7o Amelie"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>O escritor Dem\u00e9trio Peixoto autografa seu livro &#8220;Retratos n\u00e3o falados&#8221; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas.<\/p>\n<p>&#8220;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem para uma viagem \u00e0 alma. S\u00e3o cen\u00e1rios cotidianos onde o poema traduz o dia a dia, com doses nada homeop\u00e1ticas de sentimentos. \u00c9 uma a\u00e7\u00e3o e reflex\u00e3o combinadas com o efeito de brindar os antagonismos e eufemismos da vida urbana, social, sexual, cultural, f\u00edsica. A literatura sempre convidando para uma viagem necess\u00e1ria para dentro.&#8221;, explica o material de divulga\u00e7\u00e3o da obra. A produtora cultural Bet\u00e2nia Gon\u00e7alves conclui, &#8220;o Espa\u00e7o Amelie est\u00e1 de portas abertas para mais uma celebra\u00e7\u00e3o criativa&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O escritor Dem\u00e9trio Peixoto autografa seu livro &#8220;Retratos n\u00e3o falados&#8221; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. &#8220;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-87936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culturanotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O escritor Dem\u00e9trio Peixoto autografa seu livro &quot;Retratos n\u00e3o falados&quot; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. &quot;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O escritor Dem\u00e9trio Peixoto autografa seu livro &quot;Retratos n\u00e3o falados&quot; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. &quot;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-01T14:02:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-01T14:02:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O escritor Dem\u00e9trio Peixoto autografa seu livro &quot;Retratos n\u00e3o falados&quot; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. &quot;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#article\",\"name\":\"Escritor Dem\\u00e9trio Peixoto autografa \\u201cRetratos n\\u00e3o falados\\u201d, no Espa\\u00e7o Amelie | Cultura\",\"headline\":\"Escritor Dem\\u00e9trio Peixoto autografa &#8220;Retratos n\\u00e3o falados&#8221;, no Espa\\u00e7o Amelie\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/amelie.jpg\",\"width\":900,\"height\":1600},\"datePublished\":\"2023-06-01T11:02:18-03:00\",\"dateModified\":\"2023-06-01T11:02:18-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#webpage\"},\"articleSection\":\"Cultura-NOTAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"name\":\"Cultura-NOTAS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"position\":2,\"name\":\"Cultura-NOTAS\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#listItem\",\"name\":\"Escritor Dem\\u00e9trio Peixoto autografa &#8220;Retratos n\\u00e3o falados&#8221;, no Espa\\u00e7o Amelie\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#listItem\",\"position\":3,\"name\":\"Escritor Dem\\u00e9trio Peixoto autografa &#8220;Retratos n\\u00e3o falados&#8221;, no Espa\\u00e7o Amelie\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"name\":\"Cultura-NOTAS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/\",\"name\":\"Escritor Dem\\u00e9trio Peixoto autografa \\u201cRetratos n\\u00e3o falados\\u201d, no Espa\\u00e7o Amelie | Cultura\",\"description\":\"O escritor Dem\\u00e9trio Peixoto autografa seu livro \\\"Retratos n\\u00e3o falados\\\" no dia 2 de junho, a partir das 18, no Espa\\u00e7o Amelie. A produtora cultural Bet\\u00e2nia Gon\\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. \\\"Trata-se de um cen\\u00e1rio po\\u00e9tico plural, onde o autor d\\u00e1 ao leitor uma passagem\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/amelie.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#mainImage\",\"width\":900,\"height\":1600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\\\/#mainImage\"},\"datePublished\":\"2023-06-01T11:02:18-03:00\",\"dateModified\":\"2023-06-01T11:02:18-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura","description":"O escritor Dem\u00e9trio Peixoto autografa seu livro \"Retratos n\u00e3o falados\" no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. \"Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#article","name":"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura","headline":"Escritor Dem\u00e9trio Peixoto autografa &#8220;Retratos n\u00e3o falados&#8221;, no Espa\u00e7o Amelie","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/amelie.jpg","width":900,"height":1600},"datePublished":"2023-06-01T11:02:18-03:00","dateModified":"2023-06-01T11:02:18-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#webpage"},"articleSection":"Cultura-NOTAS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","name":"Cultura-NOTAS"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","position":2,"name":"Cultura-NOTAS","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#listItem","name":"Escritor Dem\u00e9trio Peixoto autografa &#8220;Retratos n\u00e3o falados&#8221;, no Espa\u00e7o Amelie"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#listItem","position":3,"name":"Escritor Dem\u00e9trio Peixoto autografa &#8220;Retratos n\u00e3o falados&#8221;, no Espa\u00e7o Amelie","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","name":"Cultura-NOTAS"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/","name":"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura","description":"O escritor Dem\u00e9trio Peixoto autografa seu livro \"Retratos n\u00e3o falados\" no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. \"Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/amelie.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#mainImage","width":900,"height":1600},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/#mainImage"},"datePublished":"2023-06-01T11:02:18-03:00","dateModified":"2023-06-01T11:02:18-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura","og:description":"O escritor Dem\u00e9trio Peixoto autografa seu livro &quot;Retratos n\u00e3o falados&quot; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. &quot;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem","og:url":"https:\/\/www.jornalja.com.br\/cultura\/escritor-demetrio-peixoto-autografa-retratos-nao-falados-no-espaco-amelie\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2023-06-01T14:02:18+00:00","article:modified_time":"2023-06-01T14:02:18+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Escritor Dem\u00e9trio Peixoto autografa \u201cRetratos n\u00e3o falados\u201d, no Espa\u00e7o Amelie | Cultura","twitter:description":"O escritor Dem\u00e9trio Peixoto autografa seu livro &quot;Retratos n\u00e3o falados&quot; no dia 2 de junho, a partir das 18, no Espa\u00e7o Amelie. A produtora cultural Bet\u00e2nia Gon\u00e7alves convida a conhecer a obra do autor que traz passagens, pensamentos e poemas. &quot;Trata-se de um cen\u00e1rio po\u00e9tico plural, onde o autor d\u00e1 ao leitor uma passagem","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"87936","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-01 13:51:43","updated":"2025-06-04 13:39:18","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":89145,"url":"https:\/\/www.jornalja.com.br\/cultura\/elisa-lucinda-mostra-ensaio-para-uma-ideia-espetaculo-que-reune-poemas-e-cancoes\/","url_meta":{"origin":87936,"position":0},"title":"Elisa Lucinda mostra\u00a0&#8220;Ensaio para uma ideia&#8221;, espet\u00e1culo  que re\u00fane poemas e can\u00e7\u00f5es","author":"Higino Barros","date":"4 de mar\u00e7o de 2024","format":false,"excerpt":"A partir das 20h, no espa\u00e7o Cultural 512, a autora recebe o p\u00fablico e aproveita para autografar seus livros ap\u00f3s a apresenta\u00e7\u00e3o. A entrada \u00e9 franca Segundo o material de divulga\u00e7\u00e3o \"Ensaio para uma ideia\" re\u00fane poemas e can\u00e7\u00f5es que brotam espontaneamente no cora\u00e7\u00e3o da artista, cantora, autora, compositora, atriz,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/elisa-lucinda-foto-jonathan-estrella-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/elisa-lucinda-foto-jonathan-estrella-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/elisa-lucinda-foto-jonathan-estrella-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/elisa-lucinda-foto-jonathan-estrella-3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/elisa-lucinda-foto-jonathan-estrella-3.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":85308,"url":"https:\/\/www.jornalja.com.br\/cultura\/libretos-editora-celebra-20-anos-de-atuacao-investindo-na-bibliodiversidade\/","url_meta":{"origin":87936,"position":1},"title":"Libretos Editora celebra 20 anos de atua\u00e7\u00e3o, investindo na\u00a0bibliodiversidade","author":"da Reda\u00e7\u00e3o","date":"14 de dezembro de 2021","format":false,"excerpt":"Fundada por Cl\u00f4 Barcellos, jornalista, designer e artista visual e por Rafael Guimaraens, escritor e jornalista, a Libretos atua desde 2001 na \u00e1rea de mem\u00f3ria e humanidades e, em duas d\u00e9cadas, publicou cerca de 200 livros, entre romances, contos, n\u00e3o-fic\u00e7\u00e3o, infantis, juvenis, ebooks e audiolivros, al\u00e9m das s\u00e9ries Universidade e\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/foto-banca-da-libretos-na-67a-feira-do-livro-de-porto-alegre.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/foto-banca-da-libretos-na-67a-feira-do-livro-de-porto-alegre.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/foto-banca-da-libretos-na-67a-feira-do-livro-de-porto-alegre.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/foto-banca-da-libretos-na-67a-feira-do-livro-de-porto-alegre.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":87795,"url":"https:\/\/www.jornalja.com.br\/cultura\/ruido-silencio-poesias-por-dora-lampert-comprova-a-forca-da-poesia-feminina-gaucha\/","url_meta":{"origin":87936,"position":2},"title":"&#8220;Ru\u00eddo Sil\u00eancio \u2013 Poesias&#8221;, por Dora Lampert, comprova a for\u00e7a da poesia feminina ga\u00facha","author":"da Reda\u00e7\u00e3o","date":"24 de abril de 2023","format":false,"excerpt":"Segundo o material de divulga\u00e7\u00e3o \"o Rio Grande do Sul se destaca como celeiro de novos talentos no cen\u00e1rio da poesia e prosa brasileira contempor\u00e2nea e na vanguarda, surgem com grande for\u00e7a as mulheres escritoras e poetas do Estado. Entre elas, Dora Lampert. Em seu livro de estreia, RU\u00cdDO SIL\u00caNCIO\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/dora-img-20230424-wa0006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/dora-img-20230424-wa0006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/dora-img-20230424-wa0006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/dora-img-20230424-wa0006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/04\/dora-img-20230424-wa0006.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":85168,"url":"https:\/\/www.jornalja.com.br\/cultura\/grenal-de-poesia-reune-ricardo-silvestrin-e-sandro-santos-durante-a-feira-do-livro\/","url_meta":{"origin":87936,"position":3},"title":"Grenal de poesia re\u00fane Ricardo Silvestrin e Sandro Santos durante a Feira do Livro","author":"da Reda\u00e7\u00e3o","date":"8 de novembro de 2021","format":false,"excerpt":"Durante a\u00a067\u00aa Feira do Livro de Porto Alegre, a Libretos promove o\u00a0Grenal de poesia, entre os autores e ilustradores de \u201cCarta Aberta ao Dem\u00f4nio\u201d e \u201cpoemas azuis\u201d. O sarau integra a programa\u00e7\u00e3o da\u00a0Libretos H\u00edbrida\u00a0e estreia\u00a0no YouTube no dia\u00a009 de novembro, \u00e0s 19 horas. \"Carta Aberta ao Dem\u00f4nio\"\u00a0(Libretos, 2021, 104 p\u00e1ginas),\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/grenal-sala-9-nov-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/grenal-sala-9-nov-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/grenal-sala-9-nov-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/grenal-sala-9-nov-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/grenal-sala-9-nov-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/grenal-sala-9-nov-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84674,"url":"https:\/\/www.jornalja.com.br\/cultura\/preta-poesia-feminina-leva-aos-palcos-a-producao-de-cinco-poetas-negras-gauchas\/","url_meta":{"origin":87936,"position":4},"title":"\u2018Preta Poesia Feminina\u2019 leva aos palcos a produ\u00e7\u00e3o de cinco poetas negras ga\u00fachas","author":"da Reda\u00e7\u00e3o","date":"15 de setembro de 2021","format":false,"excerpt":"\u00a0 Quatro apresenta\u00e7\u00f5es no estado do RS marcam a estreia do projeto\u00a0Preta Poesia Feminina, que traz a atriz\u00a0Silvia Duarte como protagonista de uma homenagem a cinco poetas negras ga\u00fachas: Ana dos Santos, Delma Gon\u00e7alves, Isabete Fagundes Almeida, F\u00e1tima Farias e Lilian Rocha. Com produ\u00e7\u00e3o executiva da montagem da obra teatral\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/teatro-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/teatro-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/teatro-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/09\/teatro-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85029,"url":"https:\/\/www.jornalja.com.br\/cultura\/especial-a-traca-biblio-e-o-poeta-tera-apresentacoes-em-comunidades-da-periferia\/","url_meta":{"origin":87936,"position":5},"title":"Especial &#8220;A Tra\u00e7a Bibli\u00f3 e o Poeta&#8221; ter\u00e1 apresenta\u00e7\u00f5es em comunidades da periferia","author":"da Reda\u00e7\u00e3o","date":"23 de outubro de 2021","format":false,"excerpt":"\u00a0O especial\u00a0\u00a0A Tra\u00e7a Bibli\u00f3 e o Poeta \u2013Brincando com os versos de Quintana, com a atriz Dinorah Ara\u00fajo, integra a programa\u00e7\u00e3o\u00a0Tra\u00e7a Bibli\u00f3 Revisitada 30 anos de incentivo \u00e0 leitura e amor aos livros,\u00a0 \u00a0homenageia as crian\u00e7as e marca as comemora\u00e7\u00f5es\u00a0 dos 30 anos de trajet\u00f3ria no teatro, da consagrada personagem\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/traca-biblio7-foto-kevin-nicolai-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/traca-biblio7-foto-kevin-nicolai-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/traca-biblio7-foto-kevin-nicolai-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/traca-biblio7-foto-kevin-nicolai-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/traca-biblio7-foto-kevin-nicolai-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/traca-biblio7-foto-kevin-nicolai-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-mSk","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/amelie.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=87936"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87936\/revisions"}],"predecessor-version":[{"id":87938,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87936\/revisions\/87938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/87937"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=87936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=87936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=87936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}