{"id":87979,"date":"2023-06-13T11:58:28","date_gmt":"2023-06-13T14:58:28","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=87979"},"modified":"2023-06-13T11:58:28","modified_gmt":"2023-06-13T14:58:28","slug":"luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/","title":{"rendered":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta"},"content":{"rendered":"<p><strong>Geraldo Hasse<\/strong><br \/>\nQuando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a<br \/>\nditadura militar.<\/p>\n<p>A cada novo livro, a gente vai se apegando aos<br \/>\nexemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d, de Fl\u00e1vio Tavares, e \u201cOpera\u00e7\u00e3o Condor: O Sequestro dos Uruguaios\u201d, de Luiz Claudio Cunha, s\u00f3 para citar dois campe\u00f5es do tema.<\/p>\n<p>Surpresa: a primeira impress\u00e3o sobre o presente entregue pelo carteiro logo se desfez. Na orelha de \u201cTempo dos Cardos\u201d (express\u00e3o recolhida de um poema de Manuel Bandeira), consta que o autor Celso Horta foi preso<br \/>\nem 1969, aos 21 anos, em S\u00e3o Paulo, como militante da ALN, comandada pelo ex-deputado comunista Carlos Marighella.<\/p>\n<p>Ap\u00f3s deixar a pris\u00e3o em 1977, formou-se em comunica\u00e7\u00e3o social e trabalhou pelo resto da vida na imprensa partid\u00e1ria (PT) e sindical (CUT). Nesta breve nota biogr\u00e1fica, n\u00e3o se menciona a ABR \u2013 Ag\u00eancia Brasileira de Reportagem, t\u00edpico \u00f3rg\u00e3o da imprensa nanica tocado Celso Horta com a ajuda de amigos em 1980. Foi<br \/>\na\u00ed que o conheci em S\u00e3o Paulo. Depois disso, nunca mais nos encontramos.<br \/>\nAssim, ler \u201cTempo dos Cardos\u201d (Express\u00e3o Popular, 342 p\u00e1ginas) significou uma retomada de contato, poucos dias depois de saber da morte do autor &#8212; Celso tinha 75 anos e n\u00e3o chegou a ver impressa a obra a que<br \/>\ndedicou seus \u00faltimos dez anos de vida. No lan\u00e7amento em S\u00e3o Paulo, no dia 23\/5, falou por ele sua filha Joana Horta.<br \/>\n\u201cTempo dos Cardos\u201d n\u00e3o esconde origens nem objetivos: \u00e9 uma narrativa de militante de esquerda. Enaltece dirigentes da guerra revolucion\u00e1ria contra a ditadura militar e o imperialismo ianque, mas focaliza com<br \/>\ninequ\u00edvoco faro jornal\u00edstico a hist\u00f3ria das dissid\u00eancias da esquerda brasileira sobre como enfrentar o governo militar durante os chamados anos de chumbo (1968\/1980). Embora fa\u00e7a men\u00e7\u00e3o a diversos epis\u00f3dios ocorridos no per\u00edodo acima, o narrador se concentra sobretudo na<br \/>\nhist\u00f3ria do Movimento de Liberta\u00e7\u00e3o Popular (Molipo), pequena organiza\u00e7\u00e3o pol\u00edtica sa\u00edda do ventre da Alian\u00e7a de Liberta\u00e7\u00e3o Nacional (ALN), a qual nasceu como \u201cdissid\u00eancia armada\u201d do Partido Comunista Brasileiro (PCB), quando este decidiu que n\u00e3o pegar em armas contra o regime autorit\u00e1rio.<br \/>\nBoa parte do livro procura recuperar a trajet\u00f3ria de Jo\u00e3o Leonardo da Silva Rocha, baiano como Marighella. Nascido em 1939 em Amargosa, ele morreu aos 36 anos no sudoeste da Bahia, onde se achava trabalhando como<br \/>\npe\u00e3o de fazenda numa regi\u00e3o infestada de grileiros e posseiros de terras devolutas. Professor secund\u00e1rio e estudante de Direito em S\u00e3o Paulo, Jo\u00e3o Leonardo era culto e possu\u00eda lideran\u00e7a, mas na luta para n\u00e3o ser<br \/>\npreso acabou se isolando no interior do Nordeste. Por tr\u00eas anos sobreviveu como sitiante solit\u00e1rio em Pernambuco. Quando se sentiu acuado por uma comitiva de policiais militares da Bahia, fugiu para o Sul em busca de contato com companheiros de luta.<\/p>\n<p>Jos\u00e9 Dirceu, um deles, sobreviveu cinco anos com nome falso em Cruzeiro do Oeste, PR, de onde voltou \u00e0 vida normal gra\u00e7as \u00e0 anistia de 1979.<\/p>\n<p>A maioria dos molipeanos participou de treinamento de guerrilha em Cuba. Alguns n\u00e3o voltaram para o Brasil ao se dar conta de que n\u00e3o teriam condi\u00e7\u00f5es objetivas de sobreviv\u00eancia no pa\u00eds natal.<\/p>\n<p>Em sua narrativa, Horta fala n\u00e3o s\u00f3 dos cabe\u00e7as, mas de militantes que trabalharam em \u201catividades an\u00f4nimas\u201d na retaguarda dos movimentos guerrilheiros.<\/p>\n<p>No apoio log\u00edstico, destacou-se Ana Cerqueira Cesar<br \/>\nCorbisier, que aparece em v\u00e1rios trechos do livro, sempre com uma participa\u00e7\u00e3o luminosa. Nascida em S\u00e3o Paulo, formada em sociologia na USP, ela se afastou dos filhos para lutar contra a ditadura.<\/p>\n<p>Em dado momento da hist\u00f3ria, saiu de Havana a fim de recuperar o contato com Jo\u00e3o Leonardo, extraviado no Nordeste do Brasil.<br \/>\nDepois de um m\u00eas peregrinando por cidades como Arcoverde, Caruaru e Garanhuns, reencontrou o companheiro \u2013 s\u00f3 para continuarem se escondendo.<\/p>\n<p>Ap\u00f3s tr\u00eas dias de pura deriva na regi\u00e3o mais pobre do<br \/>\nBrasil, os dois se separaram sem trocar endere\u00e7os. Fugitivos, sabiam que a guerra estava perdida. Seu objetivo era sobreviver para, de alguma forma, contar o que aconteceu.<\/p>\n<p>\u00c9 o que se espera ainda da soci\u00f3loga Ana Corbisier. Aos 82 anos, ela deu uma rara contribui\u00e7\u00e3o ao livro de Celso<br \/>\nHorta, mas tudo indica que tem muni\u00e7\u00e3o para ir mais longe e mais fundo.<\/p>\n<p>Gra\u00e7as a essas historietas humanas dilu\u00eddas na obra final de Celso Horta, os leitores podem ter uma boa no\u00e7\u00e3o do quanto foi desigual a luta armada contra a ditadura militar: algumas centenas de pessoas de esquerda reunidas em organiza\u00e7\u00f5es prec\u00e1rias, mal armadas, praticamente sem apoio externo, foram massacradas por um numeroso ex\u00e9rcito profissional, bem equipado e com cobertura pol\u00edtica para praticar atrocidades em unidades militares clandestinas.<\/p>\n<p>Essa cr\u00f4nica policial-militar \u00e9 bem conhecida, mas de tempos em tempos aparecem novidades que clamam por justi\u00e7a. Uma das revela\u00e7\u00f5es de \u201cTempo dos Cardos\u201d \u00e9 que falta confirmar onde, no sudoeste da Bahia, foi sepultado Jo\u00e3o Leonardo, abatido pela Pol\u00edcia Militar baiana em Palmas do Monte Alto em novembro de 1975. Ali perto, em Guanambi, vivia o violeiro Elomar Figueira de Melo, que dedicou uma \u201cincelen\u00e7a\u201d ao conterr\u00e2neo<br \/>\nfalecido.\u00a0 Falta saber tamb\u00e9m qual foi a participa\u00e7\u00e3o dos \u00f3rg\u00e3os federais como o Servi\u00e7o Nacional de Informa\u00e7\u00f5es na morte do \u201cguerrilheiro\u201d identificado pelo outro lado como \u201cpistoleiro\u201d.<br \/>\nPor falta de uma melhor organiza\u00e7\u00e3o cronol\u00f3gica, o livro de Celso Horta antecipa informa\u00e7\u00f5es que se repetem mais de uma vez em algumas partes do livro.<\/p>\n<p>Entretanto, \u00e9 melhor repetir do que esconder, falsear ou omitir.<br \/>\n\u201cTempo dos Cardos\u201d tem qualidades para figurar na Hist\u00f3ria como uma das mais ricas narrativas sobre os anseios, motiva\u00e7\u00f5es e temores dos que h\u00e1 mais de 50 anos pretenderam derrubar a ditadura. Como se sabe, a luta continua.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-87979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-13T14:58:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-13T14:58:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#article\",\"name\":\"Luta armada: novo cap\\u00edtulo de uma hist\\u00f3ria ainda incompleta | Cultura\",\"headline\":\"Luta armada: novo cap\\u00edtulo de uma hist\\u00f3ria ainda incompleta\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/cultura-livros-celso-horta.jpeg\",\"width\":759,\"height\":427},\"datePublished\":\"2023-06-13T11:58:28-03:00\",\"dateModified\":\"2023-06-13T11:58:28-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#listItem\",\"name\":\"Luta armada: novo cap\\u00edtulo de uma hist\\u00f3ria ainda incompleta\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#listItem\",\"position\":3,\"name\":\"Luta armada: novo cap\\u00edtulo de uma hist\\u00f3ria ainda incompleta\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/\",\"name\":\"Luta armada: novo cap\\u00edtulo de uma hist\\u00f3ria ainda incompleta | Cultura\",\"description\":\"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \\u201cTempo dos Cardos\\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\\u00e1pida, ciente do qu\\u00e3o pesadas s\\u00e3o as narrativas sobre a hist\\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\\u00edveis: \\u201cMem\\u00f3rias do Esquecimento\\u201d,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/cultura-livros-celso-horta.jpeg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#mainImage\",\"width\":759,\"height\":427},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\\\/#mainImage\"},\"datePublished\":\"2023-06-13T11:58:28-03:00\",\"dateModified\":\"2023-06-13T11:58:28-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura","description":"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#article","name":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura","headline":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/cultura-livros-celso-horta.jpeg","width":759,"height":427},"datePublished":"2023-06-13T11:58:28-03:00","dateModified":"2023-06-13T11:58:28-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#listItem","name":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#listItem","position":3,"name":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/","name":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura","description":"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/cultura-livros-celso-horta.jpeg","@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#mainImage","width":759,"height":427},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/#mainImage"},"datePublished":"2023-06-13T11:58:28-03:00","dateModified":"2023-06-13T11:58:28-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura","og:description":"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,","og:url":"https:\/\/www.jornalja.com.br\/cultura\/luta-armada-novo-capitulo-de-uma-historia-ainda-incompleta\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2023-06-13T14:58:28+00:00","article:modified_time":"2023-06-13T14:58:28+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Luta armada: novo cap\u00edtulo de uma hist\u00f3ria ainda incompleta | Cultura","twitter:description":"Geraldo Hasse Quando o Correio entregou o pacote contendo o livro \u201cTempo dos Cardos\u201d, de Celso Horta, premeditei fazer uma leitura diagonal r\u00e1pida, ciente do qu\u00e3o pesadas s\u00e3o as narrativas sobre a hist\u00f3ria da luta armada contra a ditadura militar. A cada novo livro, a gente vai se apegando aos exemplares, inesquec\u00edveis: \u201cMem\u00f3rias do Esquecimento\u201d,","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"87979","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-13 05:11:11","updated":"2025-06-04 13:41:02","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":89207,"url":"https:\/\/www.jornalja.com.br\/cultura\/30o-porto-alegre-em-cena-anuncia-mostra-de-cinema-e-ciclo-de-paineis\/","url_meta":{"origin":87979,"position":0},"title":"30\u00ba Porto Alegre em Cena anuncia mostra de cinema e ciclo de pain\u00e9is","author":"da Reda\u00e7\u00e3o","date":"12 de mar\u00e7o de 2024","format":false,"excerpt":"Etapa 2024 do festival promove ainda o Ponto de Encontro Petrobras\/Porto Alegre em Cena, que re\u00fane artistas e p\u00fablico em trocas de saberes, shows e performances no Espa\u00e7o Cultural 512 Trazendo uma aproxima\u00e7\u00e3o do teatro e do cinema, a\u00a0Mostra Petrobras\/Porto Alegre em Cena Z\u00e9 Celso Martinez Corr\u00eaa, ocorre nos dias\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/poa-copia-de-pamela-amaro-1-credito-josemar-afrovulto-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/poa-copia-de-pamela-amaro-1-credito-josemar-afrovulto-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/poa-copia-de-pamela-amaro-1-credito-josemar-afrovulto-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/poa-copia-de-pamela-amaro-1-credito-josemar-afrovulto-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/poa-copia-de-pamela-amaro-1-credito-josemar-afrovulto-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/03\/poa-copia-de-pamela-amaro-1-credito-josemar-afrovulto-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":91316,"url":"https:\/\/www.jornalja.com.br\/cultura\/daniel-de-andrade-1948-2025\/","url_meta":{"origin":87979,"position":1},"title":"Daniel de Andrade (1948 &#8211; 2025)\u00a0","author":"Elmar Bones","date":"26 de agosto de 2025","format":false,"excerpt":"CARLOS CARAMEZ O meu amigo Dani Boy ou Daniel de Andrade Sim\u00f5es, que faleceu hoje, era um baiano ga\u00facho muito retado, talentoso fot\u00f3grafo e jornalista, que vai deixar muitas saudades e um acervo fotogr\u00e1fico important\u00edssimo. Nascido em Rio Real(BA), adotou o Rio Grande do Sul como sua morada definitiva. Casou\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":88508,"url":"https:\/\/www.jornalja.com.br\/cultura\/tabajara-ruas-autor-e-personagem-oitenta-e-um-invernos-depois\/","url_meta":{"origin":87979,"position":2},"title":"Tabajara Ruas: o autor e o personagem, oitenta e um invernos depois","author":"da Reda\u00e7\u00e3o","date":"23 de outubro de 2023","format":false,"excerpt":"Aos 81 anos, comemorados em agosto, Tabajara Ruas chega \u00e0 69a Feira do Livro de Porto Alegre, da qual \u00e9 patrono, com um lan\u00e7amento, tr\u00eas reedi\u00e7\u00f5es,\u00a0 um roteiro de filme e muitos projetos. Consagrado autor, personifica o escritor cioso do seu of\u00edcio.\u00a0 \u00a0 \u00a0 GERALDO HASSE O escritor Tabajara Ruas\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/131535381-1664331743750650-1086884596229614811-n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/131535381-1664331743750650-1086884596229614811-n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/131535381-1664331743750650-1086884596229614811-n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/131535381-1664331743750650-1086884596229614811-n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":91666,"url":"https:\/\/www.jornalja.com.br\/cultura\/bar-tutti-giorni-resgata-sua-historia-com-reencontro-de-cartunistas-e-show-musical\/","url_meta":{"origin":87979,"position":3},"title":"Bar Tutti Giorni resgata sua hist\u00f3ria com reencontro de cartunistas e show musical","author":"da Reda\u00e7\u00e3o","date":"4 de dezembro de 2025","format":false,"excerpt":"A cena cultural de Porto Alegre ganha um importante reencontro nesta sexta-feira, 5 de dezembro, com o retorno dos encontros de cartunistas no tradicional bar Tutti Giorni, na escadaria do Viaduto Ot\u00e1vio Rocha, na avenida Borges de Medeiros, ao lado do Hotel Savoy. Sob nova gest\u00e3o do agente cultural Pepe\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":90031,"url":"https:\/\/www.jornalja.com.br\/cultura\/velha-capital-viamao-faz-contraponto-a-porto-alegre-nas-celebracoes-aos-farrapos\/","url_meta":{"origin":87979,"position":4},"title":"Velha capital, Viam\u00e3o faz contraponto a Porto Alegre nas celebra\u00e7\u00f5es aos Farrapos","author":"da Reda\u00e7\u00e3o","date":"8 de outubro de 2024","format":false,"excerpt":"A Feira Liter\u00e1ria de Viam\u00e3o deste ano, que aconteceu de 20 a 29 de setembro, teve como tema a Revolu\u00e7\u00e3o Farroupilha. Ao contr\u00e1rio do que faz Porto Alegre, com o Acampamento Farroupilha, que se tornou um shopping gauchesco, Viam\u00e3o faz da Semana Farroupilha um per\u00edodo de reflex\u00f5es e manifesta\u00e7\u00f5es culturais.\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/1000046824-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/1000046824-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/1000046824-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/1000046824-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/1000046824-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/1000046824-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":87071,"url":"https:\/\/www.jornalja.com.br\/cultura\/o-amargo-santo-da-purificacao-mova-montagem-do-oi-nois-aqui-traveiz-estreia-na-redencao\/","url_meta":{"origin":87979,"position":5},"title":"&#8220;O Amargo Santo da Purifica\u00e7\u00e3o&#8221;, em nova montagem do \u00d3i N\u00f3is Aqui Traveiz, estreia na Reden\u00e7\u00e3o","author":"da Reda\u00e7\u00e3o","date":"10 de novembro de 2022","format":false,"excerpt":"\u00a0 Numa data tamb\u00e9m emblem\u00e1tica, o Dia da Consci\u00eancia Negra, 20 de novembro, a premiada encena\u00e7\u00e3o marca sua volta em nova montagem, \u00e0s 17h, pr\u00f3ximo ao chafariz central do parque. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0A Tribo de Atuadores \u00d3i Nois Aqui Traveiz estreia a sua nova vers\u00e3o\u00a0de O Amargo Santo da Purifica\u00e7\u00e3o - uma\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/11\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/11\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/11\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/11\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/11\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/11\/teatro-o-amargo-santo-pedro-isaias-lucas-16-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-mT1","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/cultura-livros-celso-horta.jpeg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=87979"}],"version-history":[{"count":3,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87979\/revisions"}],"predecessor-version":[{"id":87983,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87979\/revisions\/87983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/87982"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=87979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=87979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=87979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}