{"id":87986,"date":"2023-06-19T19:28:10","date_gmt":"2023-06-19T22:28:10","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=87986"},"modified":"2023-06-19T19:29:19","modified_gmt":"2023-06-19T22:29:19","slug":"a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/","title":{"rendered":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">A premiada pianista e compositora Dunia Elias\u00a0se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show\u00a0Dunia Elias Quarteto, ser\u00e1 no dia\u00a022 de junho, \u00e0s\u00a020h, no\u00a0Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um\u00a0repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai, com tempero jazz\u00edstico. Os ingressos custam R$ 40,00 e podem ser adquiridos pelo\u00a0<a href=\"https:\/\/www.sympla.com.br\/evento\/dunia-elias-quarteto\/2021005\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.sympla.com.br\/evento\/dunia-elias-quarteto\/2021005&amp;source=gmail&amp;ust=1687297858726000&amp;usg=AOvVaw0m1Xab4XoRvlJGlje6HkIF\">https:\/\/www.sympla.com.br\/evento\/dunia-elias-quarteto\/2021005<\/a>.<\/p>\n<p style=\"font-weight: 400\">Dunia Elias \u00e9 conhecida pelo p\u00fablico ga\u00facho como uma artista original, que se expressa como pianista, compositora e atriz-pianista, tendo sido v\u00e1rias vezes premiada em festivais, no Rio Grande do Sul e fora dele.\u00a0 Suas composi\u00e7\u00f5es refletem essas influ\u00eancias que permeiam seu universo sonoro: \u201cChoro Pampeano\u201d (Pr\u00eamio Plauto Cruz no Festival de Choro de Porto Alegre 2005), \u201cAntonio Abdallah\u201d (milonga e dan\u00e7a \u00e1rabe), \u201cCandombe no Bomfim\u201d (2\u00ba lugar no 13\u00ba Festival de M\u00fasica de Porto Alegre), \u201cO Choro do Bugio\u201d (Melhor M\u00fasica Instrumental no XI Musicanto). Tr\u00eas dos instrumentistas mais vers\u00e1teis do Estado a acompanham, formando uma parceria de longa data:\u00a0Artur Elias\u00a0\u00a0(flauta),\u00a0Giovani Berti\u00a0\u00a0(percuss\u00e3o) \u00a0e\u00a0Miguel Tejera\u00a0(contrabaixo).<\/p>\n<figure id=\"attachment_87988\" aria-describedby=\"caption-attachment-87988\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"87988\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/foto-dunia-elias-foto-de-anibal-elias-carneiro\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg\" data-orig-size=\"2500,1667\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1670182855&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;200&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Foto Dunia Elias &amp;#8211; foto de Anibal Elias Carneiro\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Dunia Elias &amp;#8211; foto de Anibal Elias Carneiro\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-1024x683.jpg\" class=\"size-medium wp-image-87988\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-1024x683.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-1536x1024.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-2048x1366.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-87988\" class=\"wp-caption-text\">Dunia Elias &#8211; foto de Anibal Elias Carneiro\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">\u201c<em>Dunia Elias h\u00e1 muitos anos se tornou um patrim\u00f4nio musical da nossa cidade. A quantidade de m\u00fasicos com quem ela colaborou, os pr\u00eamios que j\u00e1 recebeu e o p\u00fablico que tem arrebatado com seu toque pessoal ao piano, fazem dela uma artista de primeira import\u00e2ncia no cen\u00e1rio da m\u00fasica brasileira feita em Porto Alegre<\/em>\u201d, afirma Hique Gomez, amigo e parceiro de Dunia. Segundo Hique, a artista deixa sua marca por onde quer que se apresente.\u00a0<em>\u201cNo meu trabalho T\u00e3n-T\u00e3ngo, Dunia traz uma colabora\u00e7\u00e3o indel\u00e9vel, e eu costumo dizer que n\u00e3o h\u00e1 no Brasil quem possa substitu\u00ed-la, tamanha contribui\u00e7\u00e3o que trouxe \u00e0\u00a0minha carreira. Compositora com claras influ\u00eancias dos pa\u00edses vizinhos traz o sotaque leg\u00edtimo do tango e da milonga, assim como toca chorinho como uma das filhas prediletas de Chiquinha Gonzaga. Na consolida\u00e7\u00e3o da fus\u00e3o entre as culturas do cone sul, Dunia tem um papel de grande import\u00e2ncia, emprestando a naturalidade de seu sotaque multicultural e evidenciando a legitimidade das culturas de fronteiras.\u00a0O HiperPampa se desvenda no teclado de Dunia,\u00a0e o Brasil merece conhecer o seu talento<\/em>.\u201d, finaliza Hique.<\/p>\n<p style=\"font-weight: 400\">O show Dunia Elias Quarteto<strong>\u00a0<\/strong>foi contemplado no Edital de Ocupa\u00e7\u00e3o para Espet\u00e1culos de M\u00fasica \u2013 CHC 2023.<\/p>\n<p style=\"font-weight: 400\"><strong>Sobre Dunia Elias<\/strong><\/p>\n<p style=\"font-weight: 400\">Pianista e compositora, atuando tanto na m\u00fasica de concerto como na m\u00fasica popular, especialmente na m\u00fasica instrumental brasileira. Suas apresenta\u00e7\u00f5es incluem m\u00fasica de c\u00e2mara, m\u00fasica popular, trabalhos como atriz-pianista, solos com orquestra, trilhas para cinema mudo, e suas pr\u00f3prias composi\u00e7\u00f5es. Dentre diversos pr\u00eamios recebidos figuram Melhor M\u00fasica Instrumental do XI Musicanto Latino-Americano para sua composi\u00e7\u00e3o \u201cO Choro do Bugio\u201d, 2\u00ba lugar no I Festival de M\u00fasica Instrumental do RS (com \u201cLuzazul\u201d), Pr\u00eamio Plauto Cruz no Concurso de Choro de Porto Alegre (com \u201cChoro Pampeano\u201d), e 2\u00ba lugar no 13\u00ba Festival de M\u00fasica de Porto Alegre (com \u201cCandombe no Bomfim\u201d).\u00a0 \u00c9 pianista do espet\u00e1culo \u201cT\u00e3nT\u00e3ngo\u201d, de Hique Gomez, vencedor do Pr\u00eamio A\u00e7orianos de Melhor Espet\u00e1culo de 2012, tendo sido apresentado em v\u00e1rias cidades do Rio Grande do Sul e do Brasil. Desde 2007 toca no Tango Show com o bandoneonista uruguaio Carlitos Magallanes, tendo a honra de ter sido indicada pelo grande pianista e arranjador Carlos Garofali.\u00a0 O quarteto Dunia Elias se apresentou no Bento Jazz &amp; Wine Festival, em novembro de 2022, com grande sucesso. No palco, companheiros de longa data: Artur Elias na flauta, Giovani Berti na percuss\u00e3o e Miguel Tejera no contrabaixo.<\/p>\n<p style=\"font-weight: 400\"><strong>FICHA T\u00c9CNICA:<\/strong><\/p>\n<p style=\"font-weight: 400\">DUNIA ELIAS \u2013 Piano<\/p>\n<p style=\"font-weight: 400\">ARTUR ELIAS \u2013 Flauta<\/p>\n<p style=\"font-weight: 400\">GIOVANI BERTI \u2013 Percuss\u00e3o<\/p>\n<p style=\"font-weight: 400\">MIGUEL TEJERA \u2013 Contrabaixo<\/p>\n<p><strong>SERVI\u00c7O<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>O QUE:\u00a0<\/strong>Show<strong>\u00a0<\/strong>Dunia Elias Quarteto<\/p>\n<p><strong>DATA:<\/strong>\u00a022 de junho<\/p>\n<p><strong>HOR\u00c1RIO:<\/strong>\u00a020h<\/p>\n<p><strong>LOCAL:<\/strong>\u00a0Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia)<\/p>\n<p><strong>INGRESSOS:\u00a0<\/strong>R$ 40,00 (inteira) e R$ 20,00 (meia entrada)<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>INFORMA\u00c7\u00d5ES:<\/strong><a href=\"https:\/\/www.sympla.com.br\/evento\/dunia-elias-quarteto\/2021005\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.sympla.com.br\/evento\/dunia-elias-quarteto\/2021005&amp;source=gmail&amp;ust=1687297858726000&amp;usg=AOvVaw0m1Xab4XoRvlJGlje6HkIF\">https:\/\/www.sympla.com.br\/evento\/dunia-elias-quarteto\/2021005<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A premiada pianista e compositora Dunia Elias\u00a0se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show\u00a0Dunia Elias Quarteto, ser\u00e1 no dia\u00a022 de junho, \u00e0s\u00a020h, no\u00a0Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um\u00a0repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-87986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-19T22:28:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-19T22:29:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#article\",\"name\":\"A musicalidade vers\\u00e1til do Dunia Elias Quarteto em apresenta\\u00e7\\u00e3o \\u00fanica, no Teatro da Santa Casa | Cultura\",\"headline\":\"A musicalidade vers\\u00e1til do Dunia Elias Quarteto em apresenta\\u00e7\\u00e3o \\u00fanica, no Teatro da Santa Casa\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/foto-02-dunia-elias-quarteto-foto-de-anibal-elias-carneiro-scaled.jpg\",\"width\":2560,\"height\":1446,\"caption\":\"Dunia Elias Quarteto.  Foto de Anibal Elias Carneiro\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2023-06-19T19:28:10-03:00\",\"dateModified\":\"2023-06-19T19:29:19-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#listItem\",\"name\":\"A musicalidade vers\\u00e1til do Dunia Elias Quarteto em apresenta\\u00e7\\u00e3o \\u00fanica, no Teatro da Santa Casa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#listItem\",\"position\":3,\"name\":\"A musicalidade vers\\u00e1til do Dunia Elias Quarteto em apresenta\\u00e7\\u00e3o \\u00fanica, no Teatro da Santa Casa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/\",\"name\":\"A musicalidade vers\\u00e1til do Dunia Elias Quarteto em apresenta\\u00e7\\u00e3o \\u00fanica, no Teatro da Santa Casa | Cultura\",\"description\":\"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\\u00e7\\u00e3o \\u00fanica na capital ga\\u00facha. O show Dunia Elias Quarteto, ser\\u00e1 no dia 22 de junho, \\u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\\u00eancia, 75, Bairro Independ\\u00eancia). No palco um repert\\u00f3rio de m\\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/foto-02-dunia-elias-quarteto-foto-de-anibal-elias-carneiro-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#mainImage\",\"width\":2560,\"height\":1446,\"caption\":\"Dunia Elias Quarteto.  Foto de Anibal Elias Carneiro\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\\\/#mainImage\"},\"datePublished\":\"2023-06-19T19:28:10-03:00\",\"dateModified\":\"2023-06-19T19:29:19-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura","description":"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#article","name":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura","headline":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-02-dunia-elias-quarteto-foto-de-anibal-elias-carneiro-scaled.jpg","width":2560,"height":1446,"caption":"Dunia Elias Quarteto.  Foto de Anibal Elias Carneiro\/ Divulga\u00e7\u00e3o"},"datePublished":"2023-06-19T19:28:10-03:00","dateModified":"2023-06-19T19:29:19-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#listItem","name":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#listItem","position":3,"name":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/","name":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura","description":"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-02-dunia-elias-quarteto-foto-de-anibal-elias-carneiro-scaled.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#mainImage","width":2560,"height":1446,"caption":"Dunia Elias Quarteto.  Foto de Anibal Elias Carneiro\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/#mainImage"},"datePublished":"2023-06-19T19:28:10-03:00","dateModified":"2023-06-19T19:29:19-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura","og:description":"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,","og:url":"https:\/\/www.jornalja.com.br\/cultura\/a-musicalidade-versatil-do-dunia-elias-quarteto-em-apresentacao-unica-no-teatro-da-santa-casa\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg","og:image:width":2500,"og:image:height":1667,"article:published_time":"2023-06-19T22:28:10+00:00","article:modified_time":"2023-06-19T22:29:19+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"A musicalidade vers\u00e1til do Dunia Elias Quarteto em apresenta\u00e7\u00e3o \u00fanica, no Teatro da Santa Casa | Cultura","twitter:description":"A premiada pianista e compositora Dunia Elias se prepara para uma apresenta\u00e7\u00e3o \u00fanica na capital ga\u00facha. O show Dunia Elias Quarteto, ser\u00e1 no dia 22 de junho, \u00e0s 20h, no Teatro do CHC Santa Casa (Avenida Independ\u00eancia, 75, Bairro Independ\u00eancia). No palco um repert\u00f3rio de m\u00fasicas com identidade sonora do sul do Brasil, passeando um pouco pela Argentina e Uruguai,","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-dunia-elias-foto-de-anibal-elias-carneiro.jpg"},"aioseo_meta_data":{"post_id":"87986","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-19 22:15:19","updated":"2025-06-04 13:41:02","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":90951,"url":"https:\/\/www.jornalja.com.br\/cultura\/um-painel-sonoro-gaucho-contemporaneo-na-ccmq-neste-sabado-dia-26\/","url_meta":{"origin":87986,"position":0},"title":"Um painel sonoro ga\u00facho contempor\u00e2neo na CCMQ, neste s\u00e1bado dia 26","author":"Higino Barros","date":"25 de abril de 2025","format":false,"excerpt":"Depois de grandes shows em Encantado e Os\u00f3rio, s\u00e1bado,\u00a0dia 26 de abril,\u00a0\u00e9 a vez de\u00a0Porto Alegre\u00a0receber o\u00a01\u00ba Festival Sul Universal. O evento reflete toda a diversidade musical produzida no Rio Grande do Sul, com\u00a0influ\u00eancias das sonoridades brasileira e latino-americana. As apresenta\u00e7\u00f5es na capital ga\u00facha acontecem a partir das 18h30, na\u00a0Travessa\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/04\/festival-quinteto-canjerana-foto-claudio-zagonel-neto-1-300x200.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":90350,"url":"https:\/\/www.jornalja.com.br\/cultura\/album-elis-tom-ganha-tributo-de-adriana-deffenti-e-luiz-henrique-new-em-show-que-celebra-os-50-anos-do-disco\/","url_meta":{"origin":87986,"position":1},"title":"\u00c1lbum \u2018Elis &amp; Tom\u2019 ganha tributo de Adriana Deffenti e Luiz Henrique New em show que celebra os 50 anos do disco","author":"da Reda\u00e7\u00e3o","date":"26 de novembro de 2024","format":false,"excerpt":"A programa\u00e7\u00e3o conta, ainda, com lan\u00e7amento de \u00e1lbum de Fausto Prado & Caetano Silveira, o brazilian jazz de James Liberato e a for\u00e7a da MPB na voz de Jana\u00edna Maia Nesta\u00a0quarta (27),\u00a0Fausto Prado & Caetano Silveira\u00a0lan\u00e7am o \u00e1lbum \u2018Tantos e Diversos\u2019, no Espa\u00e7o 373. O novo trabalho traz dez can\u00e7\u00f5es\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/espaco-adriana-deffenti-e-luis-new1-foto-jose-kalil.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/espaco-adriana-deffenti-e-luis-new1-foto-jose-kalil.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/espaco-adriana-deffenti-e-luis-new1-foto-jose-kalil.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/espaco-adriana-deffenti-e-luis-new1-foto-jose-kalil.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/espaco-adriana-deffenti-e-luis-new1-foto-jose-kalil.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/espaco-adriana-deffenti-e-luis-new1-foto-jose-kalil.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":81922,"url":"https:\/\/www.jornalja.com.br\/cultura\/bar-parangole-lanca-serie-de-lives-para-arrecadar-recursos-aos-artistas\/","url_meta":{"origin":87986,"position":2},"title":"Bar Parangol\u00e9 lan\u00e7a s\u00e9rie de &#8216;lives&#8217; para arrecadar recursos aos artistas","author":"Cleber Dioni Tentardini","date":"4 de maio de 2020","format":false,"excerpt":"O Parangol\u00e9, tradicional bar e restaurante da Cidade Baixa, em Porto Alegre, inicia nesta ter\u00e7a-feira, 05, uma s\u00e9rie de lives na sua p\u00e1gina no Facebook para relembrar um pouco das boas noites de m\u00fasica e arrecadar recursos aos artistas, que est\u00e3o parados sem conseguir se apresentar. O propriet\u00e1rio do bar,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/89992006_1573940352743916_6373561240530190336_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/89992006_1573940352743916_6373561240530190336_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/89992006_1573940352743916_6373561240530190336_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/89992006_1573940352743916_6373561240530190336_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":82501,"url":"https:\/\/www.jornalja.com.br\/cultura\/ospa-live-dedicada-ao-dia-estadual-do-patrimonio-cultural\/","url_meta":{"origin":87986,"position":3},"title":"OSPA Live dedicada ao Dia Estadual do Patrim\u00f4nio Cultural","author":"da Reda\u00e7\u00e3o","date":"13 de agosto de 2020","format":false,"excerpt":"A Funda\u00e7\u00e3o Orquestra Sinf\u00f4nica de Porto Alegre (FOSPA)\u00a0alia hist\u00f3ria com a melodia de seus 70 anos de trajet\u00f3ria em edi\u00e7\u00e3o dedicada \u00e0 programa\u00e7\u00e3o do\u00a0Dia Estadual do Patrim\u00f4nio Cultural, promovido pela Secretaria de Estado da Cultura (Sedac). Na segunda edi\u00e7\u00e3o do evento, que neste ano celebra \u201cNarrativas abrangentes: mem\u00f3rias e identidades\u201d,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/ospa-1-credito-isabellacortez-2-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/ospa-1-credito-isabellacortez-2-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/ospa-1-credito-isabellacortez-2-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/ospa-1-credito-isabellacortez-2-scaled.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":78888,"url":"https:\/\/www.jornalja.com.br\/cultura\/o-bandolin-de-elias-barbosa-e-o-acordeon-de-matheus-kleber-no-cafe-fon-fon\/","url_meta":{"origin":87986,"position":4},"title":"O bandolin de Elias Barboza e o acordeon de Matheus Kleber no Caf\u00e9 Fon Fon","author":"da Reda\u00e7\u00e3o","date":"4 de novembro de 2019","format":false,"excerpt":"Na pr\u00f3xima quinta-feira, dia 7 de novembro, o Caf\u00e9 Fon Fon receber\u00e1 um show de dois jovens e talentosos m\u00fasicos ga\u00fachos:\u00a0Elias Barboza no bandolim e Matheus Kleber no acordeon. A dupla mostrar\u00e1 ao p\u00fablico suas composi\u00e7\u00f5es instrumentais, al\u00e9m de cl\u00e1ssicos de Jacob do Bandolim, Sivuca e Paulinho da Viola. Tudo\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/11\/Matheus-Kleber.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":83304,"url":"https:\/\/www.jornalja.com.br\/cultura\/roda-de-choro-presencial-no-parangole-com-entrada-gratuita\/","url_meta":{"origin":87986,"position":5},"title":"Roda de Choro, presencial, no Parangol\u00e9 com entrada gratuita","author":"da Reda\u00e7\u00e3o","date":"19 de janeiro de 2021","format":false,"excerpt":"Depois de dez meses sem programa\u00e7\u00e3o de shows presenciais, o bar Parangol\u00e9 retoma aos poucos sua agenda, inicialmente, com m\u00fasica instrumental. Uma edi\u00e7\u00e3o especial de sua tradicional Roda de Choro ocorre neste s\u00e1bado, a partir das 19h. A apresenta\u00e7\u00e3o \u00e9 uma contrapartida do Inciso II da Lei Aldir Blanc, destinado\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/parangole-elias-barboza-credito-tiago-trindade.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/parangole-elias-barboza-credito-tiago-trindade.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/parangole-elias-barboza-credito-tiago-trindade.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/parangole-elias-barboza-credito-tiago-trindade.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/parangole-elias-barboza-credito-tiago-trindade.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/01\/parangole-elias-barboza-credito-tiago-trindade.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-mT8","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/foto-02-dunia-elias-quarteto-foto-de-anibal-elias-carneiro-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=87986"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87986\/revisions"}],"predecessor-version":[{"id":87991,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/87986\/revisions\/87991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/87987"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=87986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=87986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=87986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}