{"id":88377,"date":"2023-10-02T14:22:57","date_gmt":"2023-10-02T17:22:57","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=88377"},"modified":"2023-10-02T18:24:44","modified_gmt":"2023-10-02T21:24:44","slug":"projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/","title":{"rendered":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\u00aa exposi\u00e7\u00e3o"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na\u00a0quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria.<\/p>\n<p style=\"font-weight: 400\">\n<figure id=\"attachment_88391\" aria-describedby=\"caption-attachment-88391\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88391\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg\" data-orig-size=\"1076,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara Obra de autoria de Edilberto Sierra, da Col\u201cmbia\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Obra de autoria de Edilberto Sierra, da Col\u00f4mbia\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia-1020x1024.jpg\" class=\"size-medium wp-image-88391\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia-300x300.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia-1020x1024.jpg 1020w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia-768x771.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg 1076w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88391\" class=\"wp-caption-text\">Obra de autoria de Edilberto Sierra, da Col\u00f4mbia\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0 mostra prossegue at\u00e9 28\/10. Essa edi\u00e7\u00e3o, denominada de Miniarte Futura, celebrar\u00e1 os 20 anos ininterruptos de realiza\u00e7\u00f5es, incluindo homenagens aos ex-coordenadores internacionais, aos pioneiros e a artistas j\u00e1 falecidos cujas obras constam do acervo do projeto, que re\u00fane cerca de 3 mil imagens.<\/p>\n<figure id=\"attachment_88379\" aria-describedby=\"caption-attachment-88379\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88379\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-_clara-pechansky_foto-de-flavio-wild\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild.jpg\" data-orig-size=\"2362,2349\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464830748&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;32&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"clara _Clara Pechansky_foto de Fl\u00e1vio Wild\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Clara Pechansky.Foto de Fl\u00e1vio Wild\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-1024x1018.jpg\" class=\"size-medium wp-image-88379\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-300x298.jpg\" alt=\"\" width=\"300\" height=\"298\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-300x298.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-1024x1018.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-768x764.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-1536x1528.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-2048x2037.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-clara-pechansky-foto-de-flavio-wild-1200x1193.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88379\" class=\"wp-caption-text\">Clara Pechansky.Foto de Fl\u00e1vio Wild\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">\u201cEstou muito contente por poder resgatar artistas que participaram dessa hist\u00f3ria e prestar homenagem aos que j\u00e1 se foram\u201d, diz Clara, de 86 anos de idade e 67 de uma reconhecida carreira como pintora, desenhista, capista da lend\u00e1ria Editora Globo, gravadora e gestora cultural, com obras em importantes acervos de museus e galerias no pa\u00eds e no exterior.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_88408\" aria-describedby=\"caption-attachment-88408\" style=\"width: 298px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88408\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-scaled.jpg\" data-orig-size=\"2545,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara Obra de autoria de Zoravia Bettiol, de Porto Alegre\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Obra de autoria de Zoravia Bettiol, de Porto Alegre\/&lt;br \/&gt;\nDivulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-1018x1024.jpg\" class=\"size-medium wp-image-88408\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-298x300.jpg\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-298x300.jpg 298w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-1018x1024.jpg 1018w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-768x773.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-1527x1536.jpg 1527w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-2036x2048.jpg 2036w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-zoravia-bettiol-de-porto-alegre-1-1200x1207.jpg 1200w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/><figcaption id=\"caption-attachment-88408\" class=\"wp-caption-text\">Obra de autoria de Zoravia Bettiol, de Porto Alegre\/<br \/>Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">A Miniarte, montada em pain\u00e9is pela restauradora Eliete Corr\u00eaa, apresentar\u00e1 obras de autoria de 163 artistas, origin\u00e1rios dos seguintes 12 pa\u00edses: Argentina, Col\u00f4mbia, Costa Rica, Equador, Espanha, Estados Unidos, Holanda, \u00cdndia, Irlanda do Norte, M\u00e9xico, Portugal e Brasil. Afora esses, j\u00e1 estiveram representados em edi\u00e7\u00f5es anteriores, entre outros, pa\u00edses como Inglaterra, Austr\u00e1lia, Canad\u00e1, Chile, Cuba, Fran\u00e7a, Nova Zel\u00e2ndia e Venezuela.<\/p>\n<p style=\"font-weight: 400\">Clara idealizou o Projeto Miniarte Internacional, centrado em obras de pequeno formato, para promover o interc\u00e2mbio art\u00edstico entre criadores de diferentes pa\u00edses e regi\u00f5es geogr\u00e1ficas. Nas primeiras edi\u00e7\u00f5es os artistas enviavam as obras pelo Correio. Com o passar do tempo e as dificuldades impostas pelas aduanas internacionais, a Miniarte passou a reproduzir as obras em fotos. As facilidades proporcionadas pela internet ajudaram a consolidar o novo formato. Com a pandemia a participa\u00e7\u00e3o virtual dos artistas aumentou, bem como o car\u00e1ter internacional da Miniarte.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_88399\" aria-describedby=\"caption-attachment-88399\" style=\"width: 263px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88399\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-11-obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-scaled.jpg\" data-orig-size=\"2242,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS REBEL T5&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1502812714&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;21&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"clara 11.Obra El Payaso, do mexicano Jorge Luis Hurtado Reyes\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;.Obra El Payaso, do mexicano Jorge Luis Hurtado Reyes\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-897x1024.jpg\" class=\"size-medium wp-image-88399\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-263x300.jpg\" alt=\"\" width=\"263\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-263x300.jpg 263w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-897x1024.jpg 897w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-768x877.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-1345x1536.jpg 1345w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-1793x2048.jpg 1793w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-11obra-el-payaso-do-mexicano-jorge-luis-hurtado-reyes-1200x1370.jpg 1200w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><figcaption id=\"caption-attachment-88399\" class=\"wp-caption-text\">.Obra El Payaso, do mexicano Jorge Luis Hurtado Reyes\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Ao longo dos anos, foram realizadas Miniarte que tiveram como t\u00edtulo &#8211; e sugest\u00e3o de tema para os artistas &#8211; Magia, Vida, Ilus\u00e3o, Enigma, Verdade, Fantasia. As cole\u00e7\u00f5es de obras das s\u00e3o expostas em locais como galerias, museus, bibliotecas, funda\u00e7\u00f5es e institutos culturais. A primeira edi\u00e7\u00e3o foi na Usina do Gas\u00f4metro e a 10\u00aa na Casa de Cultura Mario Quintana, por exemplo.<\/p>\n<figure id=\"attachment_88406\" aria-describedby=\"caption-attachment-88406\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88406\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul.jpg\" data-orig-size=\"1772,1752\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone XR&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1634726758&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0082644628099174&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"clara Obra de autoria de M\u00a0rcia Marostega, de Santa Cruz do Sul\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Obra de autoria de M\u00e1rcia Marostega, de Santa Cruz do Sul\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-1024x1012.jpg\" class=\"size-medium wp-image-88406\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-300x297.jpg\" alt=\"\" width=\"300\" height=\"297\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-300x297.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-1024x1012.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-768x759.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-1536x1519.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul-1200x1186.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-m-rcia-marostega-de-santa-cruz-do-sul.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88406\" class=\"wp-caption-text\">Obra de autoria de M\u00e1rcia Marostega, de Santa Cruz do Sul\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Outra edi\u00e7\u00e3o da Miniarte Futura j\u00e1 tem data e local para ocorrer em 2024: 4 de maio do ano que vem, no Centro Municipal de Cultura de Gramado.<\/p>\n<p style=\"font-weight: 400\">\n<figure id=\"attachment_88405\" aria-describedby=\"caption-attachment-88405\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88405\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica.jpg\" data-orig-size=\"1900,1900\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara Obra de autoria de Josefina Su\u00a0rez, da Costa Rica\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Obra de autoria de Josefina Suarez, da Costa Rica\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-1024x1024.jpg\" class=\"size-medium wp-image-88405\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-300x300.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-1024x1024.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-768x768.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-1536x1536.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica-1200x1200.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-josefina-su-rez-da-costa-rica.jpg 1900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88405\" class=\"wp-caption-text\">Obra de autoria de Josefina Suarez, da Costa Rica\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">SERVI\u00c7O<\/p>\n<p style=\"font-weight: 400\">Miniarte Futura<\/p>\n<p style=\"font-weight: 400\">Abertura: quinta-feira (5\/10)<\/p>\n<p style=\"font-weight: 400\">Hor\u00e1rio: das 18h \u00e0s 20h<\/p>\n<p style=\"font-weight: 400\">Visita guiada: s\u00e1bado (7), \u00e0s 11h<\/p>\n<p style=\"font-weight: 400\">Visita\u00e7\u00e3o: at\u00e9 28\/10<\/p>\n<p style=\"font-weight: 400\">Local: Gravura Galeria<\/p>\n<p style=\"font-weight: 400\">Endere\u00e7o:\u00a0Rua Corte Real, 647, bairro Petr\u00f3polis<\/p>\n<p style=\"font-weight: 400\">Hor\u00e1rio: segunda \u00e0 sexta das 9h30 \u00e0s 18h30; s\u00e1bado das 9h30 \u00e0s 13h30<\/p>\n<p style=\"font-weight: 400\">Fone:\u00a051 3333-1946<\/p>\n<p style=\"font-weight: 400\">&#8211;<\/p>\n<figure id=\"attachment_88404\" aria-describedby=\"caption-attachment-88404\" style=\"width: 295px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88404\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-els-van-asten-da-holanda\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda.jpg\" data-orig-size=\"1983,2014\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;ONEPLUS A5010&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1618497626&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.103&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara Obra de autoria de Els Van Asten, da Holanda\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Obra de autoria de Els Van Asten, da Holanda\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-1008x1024.jpg\" class=\"size-medium wp-image-88404\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-295x300.jpg\" alt=\"\" width=\"295\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-295x300.jpg 295w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-1008x1024.jpg 1008w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-768x780.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-1512x1536.jpg 1512w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda-1200x1219.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-els-van-asten-da-holanda.jpg 1983w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><figcaption id=\"caption-attachment-88404\" class=\"wp-caption-text\">Obra de autoria de Els Van Asten, da Holanda\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>A exposi\u00e7\u00e3o no olhar da artista<\/strong><\/p>\n<p style=\"font-weight: 400\">Clara: \u201cDe m\u00e3os dadas pela arte\u201d<\/p>\n<p style=\"font-weight: 400\"><em>Pergunta: Quando o projeto nasceu imaginava que teria tal amplitude e dura\u00e7\u00e3o?<\/em><\/p>\n<p style=\"font-weight: 400\">Resposta: Clara Pechansky\u00a0&#8211; A Miniarte, nestes 20 anos, criou uma grande teia de comunica\u00e7\u00e3o entre artistas. Tenho orgulho de ter sido a geradora dessa rede que at\u00e9 hoje se mant\u00e9m viva, porque artistas de 38 pa\u00edses ainda se comunicam comigo e entre si, seja em ingl\u00eas, em espanhol ou em portugu\u00eas. Eles se movimentam em seus pa\u00edses de origem, criando novos desafios e convidando colegas para participar de exposi\u00e7\u00f5es ou outros eventos. Com a pandemia muita coisa mudou, mas a arte seguiu viva e se impulsionou de novas maneiras. A Miniarte \u00e9 o elo que re\u00fane todos, desde os pioneiros aos rec\u00e9m-chegados.<\/p>\n<figure id=\"attachment_88401\" aria-describedby=\"caption-attachment-88401\" style=\"width: 256px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88401\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-13-obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-scaled.jpg\" data-orig-size=\"2184,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"clara 13.Obra de autoria de Radi\u00a0 Pereira dos Santos, de Porto Alegre\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;.Obra de autoria de Radi\u00a0 Pereira dos Santos, de Porto Alegre\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-874x1024.jpg\" class=\"size-medium wp-image-88401\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-256x300.jpg\" alt=\"\" width=\"256\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-256x300.jpg 256w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-874x1024.jpg 874w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-768x900.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-1310x1536.jpg 1310w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-1747x2048.jpg 1747w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-13obra-de-autoria-de-radi-pereira-dos-santos-de-porto-alegre-1200x1407.jpg 1200w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><figcaption id=\"caption-attachment-88401\" class=\"wp-caption-text\">.Obra de autoria de Radi\u00a0 Pereira dos Santos, de Porto Alegre\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Seguimos juntos, sob minha lideran\u00e7a e de outros colegas, parceiros antigos e novos da Miniarte, fazendo a teia crescer democraticamente, sem exigir curr\u00edculo de ningu\u00e9m, mas sempre de m\u00e3os dadas pela arte. \u00c9 o grande abra\u00e7o universal. Com a evolu\u00e7\u00e3o dessa teia, foi necess\u00e1rio trabalhar de forma mais espec\u00edfica com pa\u00edses da Am\u00e9rica Latina. Em 2018, criei o Projeto Fiesta de Paz Brasil, que agrega literatura \u00e0s \u00e0rtes visuais. Poetas e escritores s\u00e3o chamados para escrever sobre nossas obras, ampliando a teia de comunica\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400\"><em>P: De que forma a pandemia impactou o projeto em termos de ades\u00e3o de artistas inscritos e do conte\u00fado apresentado pelos participantes?<\/em><\/p>\n<figure id=\"attachment_88397\" aria-describedby=\"caption-attachment-88397\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88397\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-10-obra-de-autoria-de-gra%e2%80%a1a-craidy-de-porto-alegre\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre.jpg\" data-orig-size=\"2048,1993\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara 10.Obra de autoria de Gra\u2021a Craidy, de Porto Alegre\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;.Obra de autoria de Gra\u00e7a Craidy, de Porto Alegre\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-1024x997.jpg\" class=\"size-medium wp-image-88397\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-300x292.jpg\" alt=\"\" width=\"300\" height=\"292\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-300x292.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-1024x997.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-768x747.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-1536x1495.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre-1200x1168.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-10obra-de-autoria-de-graa-craidy-de-porto-alegre.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88397\" class=\"wp-caption-text\">.Obra de autoria de Gra\u00e7a Craidy, de Porto Alegre\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">R: Clara\u00a0&#8211; Houve uma total reviravolta no projeto. At\u00e9 ent\u00e3o, as obras chegavam de forma f\u00edsica, pelo Correio ou pessoalmente. Eu j\u00e1 havia reduzido o formato das obras de 20 x 20 cm para 18&#215;18 cm, para permitir que mais obras coubessem nos pain\u00e9is, j\u00e1 que cada edi\u00e7\u00e3o sempre recebia no m\u00ednimo duas centenas de artistas. Decidi ent\u00e3o criar a Miniarte Verdade, para a qual os artistas enviaram fotografias que foram impressas, e as obras, portanto eram s\u00f3 virtuais. Outra modifica\u00e7\u00e3o ocorreu devido \u00e0 dificuldade de circula\u00e7\u00e3o de dinheiro, ent\u00e3o eu tornei a Miniarte gratuita e totalmente virtual. Dessa maneira, chegamos \u00e0 participa\u00e7\u00e3o de cerca de 400 artistas. A Miniarte ent\u00e3o se tornou cada vez mais virtual, e passamos a publicar cat\u00e1logos somente na internet, e nossas cole\u00e7\u00f5es completas est\u00e3o no Flickr:\u00a0\u00a0<a href=\"http:\/\/www.flickr.com\/photos\/miniart2010\/sets\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.flickr.com\/photos\/miniart2010\/sets\/&amp;source=gmail&amp;ust=1696349874194000&amp;usg=AOvVaw15fBfpjFVRdGM_RIhYWYzB\">http:\/\/www.flickr.com\/photos\/miniart2010\/sets\/<\/a>\u00a0e tamb\u00e9m no website da Miniarte (<a href=\"http:\/\/www.miniartex.org\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.miniartex.org&amp;source=gmail&amp;ust=1696349874194000&amp;usg=AOvVaw37irtE3o0-vY0ilXOzBuTC\">www.miniartex.org<\/a>).<\/p>\n<figure id=\"attachment_88393\" aria-describedby=\"caption-attachment-88393\" style=\"width: 293px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88393\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-1-obra-de-autoria-de-danu-dunne-da-irlanda-do-norte\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte.jpg\" data-orig-size=\"1777,1817\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;SM-G950F&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1678147696&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.2&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.071428571428571&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"clara 1.Obra de autoria de Danu Dunne, da Irlanda do Norte\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Obra de autoria de Danu Dunne, da Irlanda do Norte\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-1001x1024.jpg\" class=\"size-medium wp-image-88393\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-293x300.jpg\" alt=\"\" width=\"293\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-293x300.jpg 293w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-1001x1024.jpg 1001w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-768x785.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-1502x1536.jpg 1502w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte-1200x1227.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-1obra-de-autoria-de-danu-dunne-da-irlanda-do-norte.jpg 1777w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><figcaption id=\"caption-attachment-88393\" class=\"wp-caption-text\">Obra de autoria de Danu Dunne, da Irlanda do Norte\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><em>P:Olhando o acervo formado pelas cole\u00e7\u00f5es ao longo do tempo que an\u00e1lise art\u00edstica faz?<\/em><\/p>\n<p style=\"font-weight: 400\">R: Clara\u00a0&#8211; A pandemia foi um turning point na organiza\u00e7\u00e3o das edi\u00e7\u00f5es da Miniarte, gerando novas ideias e novas maneiras de mostrar as obras. Temos at\u00e9 agora uma hist\u00f3ria de quase 50 edi\u00e7\u00f5es, cada uma em um local diferente, sempre coordenadas por artistas, entre galerias particulares e p\u00fablicas, museus, centros de cultura e academias.<\/p>\n<p style=\"font-weight: 400\">Quanto \u00e0 an\u00e1lise art\u00edstica, \u00e9 evidente que houve um aperfei\u00e7oamento na obra de cada artista, seja na t\u00e9cnica, seja porque a qualidade da resolu\u00e7\u00e3o das fotos melhorou, permitindo a impress\u00e3o de cada obra com suas cores e detalhes originais. Artistas que v\u00eam h\u00e1 anos participando da Miniarte sem d\u00favida tiveram um crescimento t\u00e9cnico indiscut\u00edvel, e isso \u00e9 muito gratificante. Posso tamb\u00e9m acompanhar a trajet\u00f3ria de artistas que lancei h\u00e1 tempos, quando eram emergentes, e que, devido ao car\u00e1ter democr\u00e1tico da Miniarte, tiveram sua primeira oportunidade de expor em exposi\u00e7\u00f5es internacionais ao lado de artistas conhecidos, j\u00e1 que a Miniarte \u00e9 exposta em ordem alfab\u00e9tica.<\/p>\n<figure id=\"attachment_88392\" aria-describedby=\"caption-attachment-88392\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88392\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre.jpg\" data-orig-size=\"2362,2362\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"clara .Obra de autoria de Erm\u00a1nia Marasca Soccol, de Porto Alegre\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Obra de autoria de Erm\u00a1nia Marasca Soccol, de Porto Alegre\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-1024x1024.jpg\" class=\"size-medium wp-image-88392\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-300x300.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-1024x1024.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-768x768.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-1536x1536.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-2048x2048.jpg 2048w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ermnia-marasca-soccol-de-porto-alegre-1200x1200.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88392\" class=\"wp-caption-text\">Obra de autoria de Erm\u00a1nia Marasca Soccol, de Porto Alegre\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><em>P: Produzir arte em pequeno formato facilita a vida do artista?<\/em><\/p>\n<p style=\"font-weight: 400\">R: Clara\u00a0&#8211; Pelo contr\u00e1rio, trabalhar em pequeno formato \u00e9 muito mais dif\u00edcil do que criar algo em formato grande. Quando um iniciante come\u00e7a a pintar ou desenhar, ele tem medo e sempre sugere: \u2018vou come\u00e7ar com uma telinha pequena\u2019. Grande erro. Ao tentar pintar uma obra pequena, o candidato a artista est\u00e1 empilhando todos os problemas e eles ficam sobrepostos, como se numa corrida de obst\u00e1culos todos os saltos tivessem que ser dados ao mesmo tempo. Fica bem mais f\u00e1cil espalhar os obst\u00e1culos por uma superf\u00edcie grande, onde ser\u00e1 poss\u00edvel identificar todos os saltos a serem trabalhados. Falo como supervisora e orientadora de arte, como algu\u00e9m que nunca permitiu o uso de borracha em seu atelier, porque \u00e9 necess\u00e1rio acompanhar o pensamento daquele que est\u00e1 come\u00e7ando, e para isso as marcas do seu tra\u00e7o, deixadas vis\u00edveis, ajudam a acompanhar e entender o caminho percorrido.<\/p>\n<figure id=\"attachment_88403\" aria-describedby=\"caption-attachment-88403\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88403\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre.jpg\" data-orig-size=\"960,960\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara Obra de autoria de Ana Lovatto, de POrto Alegre\" data-image-description=\"\" data-image-caption=\"&lt;p&gt; Obra de autoria de Ana Lovatto, de Porto Alegre\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre.jpg\" class=\"size-medium wp-image-88403\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre-300x300.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre-150x150.jpg 150w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre-768x768.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-ana-lovatto-de-porto-alegre.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88403\" class=\"wp-caption-text\">Obra de autoria de Ana Lovatto, de Porto Alegre\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><em>P: Requer quais virtudes, principalmente?<\/em><\/p>\n<p style=\"font-weight: 400\">R: Clara\u00a0&#8211; Requer reflex\u00e3o, t\u00e9cnica e, sobretudo, paci\u00eancia. A Miniarte espraiou esse desafio: criar uma obra pequena \u00e9 distribuir todos os problemas de composi\u00e7\u00e3o, equil\u00edbrio, luz e sombra e demais fundamentos do desenho e da pintura num espa\u00e7o reduzido. Desde o in\u00edcio exigiu-se dos artistas obras em pequeno formato, era 20 x 20 cm e ultimamente passou a ser 18 x 18 cm.<\/p>\n<figure id=\"attachment_88402\" aria-describedby=\"caption-attachment-88402\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88402\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/clara-14-obra-de-autoria-de-cristovaeo-coutinho-de-manaus\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus.jpg\" data-orig-size=\"1280,1189\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"clara 14.Obra de autoria de Cristov\u00c6o Coutinho, de Manaus\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Obra de autoria de Cristov\u00c6o Coutinho, de Manaus\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus-1024x951.jpg\" class=\"size-medium wp-image-88402\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus-300x279.jpg\" alt=\"\" width=\"300\" height=\"279\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus-300x279.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus-1024x951.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus-768x713.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus-1200x1115.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-14obra-de-autoria-de-cristovaeo-coutinho-de-manaus.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-88402\" class=\"wp-caption-text\">Obra de autoria de Cristov\u00e3o Coutinho, de Manaus\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">*Com Assessoria de Comunica\u00e7\u00e3o- Jornalista Carlos Souza(texto)<\/p>\n<p style=\"font-weight: 400\">FOTOS: Divulga\u00e7\u00e3o Miniarte \/ Clara Pechansky<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na\u00a0quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":88378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-88377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1076\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-02T17:22:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-02T21:24:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#article\",\"name\":\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \\u201cFutura\\u201d, sua 46\\u00aa exposi\\u00e7\\u00e3o | Cultura\",\"headline\":\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\\u00aa exposi\\u00e7\\u00e3o\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/51665531940-9e685c0042.jpg\",\"width\":375,\"height\":500},\"datePublished\":\"2023-10-02T14:22:57-03:00\",\"dateModified\":\"2023-10-02T18:24:44-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#listItem\",\"name\":\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\\u00aa exposi\\u00e7\\u00e3o\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#listItem\",\"position\":3,\"name\":\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\\u00aa exposi\\u00e7\\u00e3o\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/\",\"name\":\"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \\u201cFutura\\u201d, sua 46\\u00aa exposi\\u00e7\\u00e3o | Cultura\",\"description\":\"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\\u00facha Clara Pechansky, chega ao vig\\u00e9simo ano de exist\\u00eancia e monta, em Porto Alegre, sua 46\\u00aa edi\\u00e7\\u00e3o. A abertura ser\\u00e1 na quinta-feira (5\\\/10), das 18h \\u00e0s 20h, na Gravura Galeria. No s\\u00e1bado (7), \\u00e0s 11h, Clara far\\u00e1 visita guiada aberta ao p\\u00fablico. A visita\\u00e7\\u00e3o \\u00e0\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/51665531940-9e685c0042.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#mainImage\",\"width\":375,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\\\/#mainImage\"},\"datePublished\":\"2023-10-02T14:22:57-03:00\",\"dateModified\":\"2023-10-02T18:24:44-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura","description":"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#article","name":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura","headline":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\u00aa exposi\u00e7\u00e3o","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/51665531940-9e685c0042.jpg","width":375,"height":500},"datePublished":"2023-10-02T14:22:57-03:00","dateModified":"2023-10-02T18:24:44-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#listItem","name":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\u00aa exposi\u00e7\u00e3o"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#listItem","position":3,"name":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre &#8220;Futura&#8221;, sua 46\u00aa exposi\u00e7\u00e3o","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/","name":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura","description":"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/51665531940-9e685c0042.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#mainImage","width":375,"height":500},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/#mainImage"},"datePublished":"2023-10-02T14:22:57-03:00","dateModified":"2023-10-02T18:24:44-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura","og:description":"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0","og:url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-miniarte-completa-20-anos-exibindo-em-porto-alegre-futura-sua-46a-exposicao\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg","og:image:width":1076,"og:image:height":1080,"article:published_time":"2023-10-02T17:22:57+00:00","article:modified_time":"2023-10-02T21:24:44+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Projeto Miniarte completa 20 anos exibindo em Porto Alegre \u201cFutura\u201d, sua 46\u00aa exposi\u00e7\u00e3o | Cultura","twitter:description":"O Projeto Internacional Miniarte, criado em 2003 pela artista visual ga\u00facha Clara Pechansky, chega ao vig\u00e9simo ano de exist\u00eancia e monta, em Porto Alegre, sua 46\u00aa edi\u00e7\u00e3o. A abertura ser\u00e1 na quinta-feira (5\/10), das 18h \u00e0s 20h, na Gravura Galeria. No s\u00e1bado (7), \u00e0s 11h, Clara far\u00e1 visita guiada aberta ao p\u00fablico. A visita\u00e7\u00e3o \u00e0","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/clara-obra-de-autoria-de-edilberto-sierra-da-colmbia.jpg"},"aioseo_meta_data":{"post_id":"88377","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-02 16:21:35","updated":"2025-06-04 13:47:25","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":90990,"url":"https:\/\/www.jornalja.com.br\/cultura\/com-o-tema-surreal-miniarte-internacional-abre-inscricoes-para-sua-52a-edicao\/","url_meta":{"origin":88377,"position":0},"title":"Com o tema Surreal, Miniarte Internacional abre inscri\u00e7\u00f5es para sua 52\u00aa edi\u00e7\u00e3o","author":"da Reda\u00e7\u00e3o","date":"7 de maio de 2025","format":false,"excerpt":"\u00a0 O Projeto Miniarte Internacional est\u00e1 com inscri\u00e7\u00f5es abertas para a cole\u00e7\u00e3o \u201cSurreal\u201d, tema escolhido para ser abordado pelos participantes em 2025. Do dia 8 de maio at\u00e9 20 de julho, as inscri\u00e7\u00f5es individuais e de grupos t\u00eam desconto. Todas as informa\u00e7\u00f5es sobre a 52\u00aa edi\u00e7\u00e3o podem ser acessadas no\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/05\/1logomarca-miniarte-surreal.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/05\/1logomarca-miniarte-surreal.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/05\/1logomarca-miniarte-surreal.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/05\/1logomarca-miniarte-surreal.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83554,"url":"https:\/\/www.jornalja.com.br\/cultura\/um-panorama-das-artes-visuais-em-pequeno-formato-de-varias-regioes-do-mundo\/","url_meta":{"origin":88377,"position":1},"title":"Um panorama das artes visuais, em pequeno formato, de v\u00e1rias regi\u00f5es do mundo","author":"da Reda\u00e7\u00e3o","date":"19 de mar\u00e7o de 2021","format":false,"excerpt":"\u00a0 O Projeto Miniarte Internacional, criado e coordenado pela artista visual Clara Pechansky, j\u00e1 definiu o tema e tamb\u00e9m os locais e datas das duas exposi\u00e7\u00f5es a serem realizadas este ano no Estado. Os artistas que atenderem \u00e0 convocat\u00f3ria produzir\u00e3o obras sobre a tem\u00e1tica que mais se imp\u00f5e neste momento\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/clara-clara-pechansky-no-atelier-foto-luis-ventura-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/clara-clara-pechansky-no-atelier-foto-luis-ventura-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/clara-clara-pechansky-no-atelier-foto-luis-ventura-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/clara-clara-pechansky-no-atelier-foto-luis-ventura-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/clara-clara-pechansky-no-atelier-foto-luis-ventura-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/clara-clara-pechansky-no-atelier-foto-luis-ventura-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":85328,"url":"https:\/\/www.jornalja.com.br\/cultura\/miniarte-apresenta-tema-de-2022-regulamento-e-logomarca-da-mostra\/","url_meta":{"origin":88377,"position":2},"title":"Miniarte apresenta tema de 2022, regulamento e logomarca da mostra","author":"da Reda\u00e7\u00e3o","date":"29 de dezembro de 2021","format":false,"excerpt":"\u00a0 \u00a0 O Projeto Miniarte Internacional est\u00e1 de site novo, rec\u00e9m-colocado no ar (www.miniartex.org). O espa\u00e7o informa que o tema da Miniarte 2022 \u00e9 \u201cMagia\u201d, apresenta a logomarca da edi\u00e7\u00e3o, concebida pelo designer gr\u00e1fico Ronald Souza, e disponibiliza o regulamento da mostra em tr\u00eas idiomas: portugu\u00eas, espanhol e ingl\u00eas. O\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/logo-oficial-magia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/logo-oficial-magia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/logo-oficial-magia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/logo-oficial-magia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/logo-oficial-magia.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":82209,"url":"https:\/\/www.jornalja.com.br\/cultura\/o-lancamento-de-miniarte-verdade-virtual-com-a-participacao-de-cerca-de-400-artistas-de-12-paises\/","url_meta":{"origin":88377,"position":3},"title":"Exposi\u00e7\u00e3o internacional liderada por Clara Pechansky inaugura no dia 1\u00ba de julho","author":"da Reda\u00e7\u00e3o","date":"24 de junho de 2020","format":false,"excerpt":"Neste ano, o projeto criado em 2003 por Clara Pechansky ter\u00e1 lan\u00e7amento no dia 1\u00ba de julho, com o cat\u00e1logo MINIARTE VERDADE VIRTUAL, pelo site\u00a0www.miniartex.org. A partir desta quarta-feira, 24 de junho, o p\u00fablico j\u00e1 p\u00f4de assistir um v\u00eddeo mostrando uma pr\u00e9via do cat\u00e1logo nas redes sociais da artista no\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/exposicao-virtual-liana-timm-e-clara-pechansky-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/exposicao-virtual-liana-timm-e-clara-pechansky-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/exposicao-virtual-liana-timm-e-clara-pechansky-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/exposicao-virtual-liana-timm-e-clara-pechansky-scaled.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":89772,"url":"https:\/\/www.jornalja.com.br\/cultura\/miniarte-prorroga-prazo-de-inscricoes-e-ja-recebe-obras-de-artistas-inscritos\/","url_meta":{"origin":88377,"position":4},"title":"Miniarte prorroga prazo de inscri\u00e7\u00f5es e j\u00e1 recebe  obras de artistas inscritos","author":"Higino Barros","date":"29 de julho de 2024","format":false,"excerpt":"Levando em conta os embara\u00e7os que a recente cat\u00e1strofe clim\u00e1tica causou na vida das pessoas no Rio Grande do Sul, o Projeto Miniarte Internacional decidiu estender o per\u00edodo de inscri\u00e7\u00f5es at\u00e9 31 de agosto. A prorroga\u00e7\u00e3o de prazo vale para todos, ou seja, tamb\u00e9m para interessados em participar da Miniarte\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/mini-4jesus-obra-de-rita-gil-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/mini-4jesus-obra-de-rita-gil-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/mini-4jesus-obra-de-rita-gil-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/mini-4jesus-obra-de-rita-gil-scaled.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/mini-4jesus-obra-de-rita-gil-scaled.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/07\/mini-4jesus-obra-de-rita-gil-scaled.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84155,"url":"https:\/\/www.jornalja.com.br\/cultura\/com-261-artistas-miniarte-vida-bate-recorde-de-inscricoes-exposicoes-programadas-em-porto-alegre-e-gramado\/","url_meta":{"origin":88377,"position":5},"title":"Com 261 artistas, Miniarte Vida bate recorde de inscri\u00e7\u00f5es. Exposi\u00e7\u00f5es programadas em Porto Alegre e Gramado","author":"da Reda\u00e7\u00e3o","date":"7 de julho de 2021","format":false,"excerpt":"\u00a0 Exposi\u00e7\u00f5es est\u00e3o programadas para Gramado e Porto Alegre, al\u00e9m de um cat\u00e1logo virtual \u00a0Um n\u00famero recorde de artistas visuais - 261 \u2013 se inscreveu para participar da Miniarte Internacional deste ano, cujo tema \u00e9 Vida. Al\u00e9m de brasileiros, artistas de pa\u00edses como Argentina, Chile, Col\u00f4mbia, Cuba,\u00a0Venezuela,\u00a0Espanha, Estados Unidos, Fran\u00e7a,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/carlota-corso-espanha.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/carlota-corso-espanha.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/carlota-corso-espanha.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/carlota-corso-espanha.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/carlota-corso-espanha.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/07\/carlota-corso-espanha.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-mZr","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/10\/51665531940-9e685c0042.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=88377"}],"version-history":[{"count":3,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88377\/revisions"}],"predecessor-version":[{"id":88409,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88377\/revisions\/88409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/88378"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=88377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=88377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=88377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}