{"id":88677,"date":"2023-11-08T13:33:38","date_gmt":"2023-11-08T16:33:38","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=88677"},"modified":"2023-11-08T13:33:38","modified_gmt":"2023-11-08T16:33:38","slug":"mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/","title":{"rendered":"Mostra &#8220;(In)vis\u00edvel&#8221; re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar"},"content":{"rendered":"<div>\n<p>Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores em busca de tratamento e cuidados cont\u00ednuos da hipertens\u00e3o pulmonar que, em muitos casos, parece invis\u00edvel aos olhos da sociedade.<\/p>\n<p>Os fot\u00f3grafos respons\u00e1veis pelas imagens da campanha s\u00e3o: Cristina Negreiros, que clicou os pacientes de S\u00e3o Paulo (SP), e Renato Moura e Marina Carrilho, que clicaram os pacientes de Recife (PE). O local da exposi\u00e7\u00e3o \u00e9 a Feevale Campus 2 (\u00e1rea coberta) e a entrada \u00e9 gratuita. A organiza\u00e7\u00e3o \u00e9 feita pelo grupo de apoio da Associa\u00e7\u00e3o Brasileira de Apoio \u00e0 Fam\u00edlia com Hipertens\u00e3o Pulmonar e Doen\u00e7as Correlatas (ABRAF) no Rio Grande do Sul.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88678\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/cartaz\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-scaled.jpg\" data-orig-size=\"1845,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"cartaz\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-738x1024.jpg\" class=\"alignnone size-medium wp-image-88678\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg\" alt=\"\" width=\"216\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg 216w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-738x1024.jpg 738w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-768x1065.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-1107x1536.jpg 1107w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-1476x2048.jpg 1476w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-1200x1665.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-scaled.jpg 1845w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/p>\n<p>As telas ficar\u00e3o expostas entre os dias 06 e 30 de novembro, m\u00eas que \u00e9 dedicado \u00e0 conscientiza\u00e7\u00e3o da HP, uma doen\u00e7a rara, cr\u00f4nica, incur\u00e1vel e progressiva, ou seja, o quadro pode piorar sem tratamento. Estima-se que cerca de<a href=\"https:\/\/www.correiobraziliense.com.br\/ciencia-e-saude\/2023\/05\/5093538-hipertensao-arterial-pulmonar-silenciosa-doenca-afeta-100-mil-brasileiros.html\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.correiobraziliense.com.br\/ciencia-e-saude\/2023\/05\/5093538-hipertensao-arterial-pulmonar-silenciosa-doenca-afeta-100-mil-brasileiros.html&amp;source=gmail&amp;ust=1699544618775000&amp;usg=AOvVaw0M-p0v_PNbd29hkOOF0MyL\">\u00a0100 mil pessoas<\/a>\u00a0vivem com HP no Brasil atualmente. \u201cA exposi\u00e7\u00e3o \u00e9 muito importante para mostrar hist\u00f3rias de vida de pessoas que t\u00eam a doen\u00e7a. No m\u00eas de conscientiza\u00e7\u00e3o, al\u00e9m de difundir informa\u00e7\u00f5es sobre a doen\u00e7a, vamos dar voz \u00e0s pessoas que vivem com a HP, para que elas mostrem e contem sobre seus medos, desafios e sonhos\u201d, destaca Fl\u00e1via Lima, presidente da ABRAF.<\/p>\n<p><strong>Voluntariado e conscientiza\u00e7\u00e3o\u00a0<\/strong><\/p>\n<p>Para a realiza\u00e7\u00e3o da mostra ser poss\u00edvel, a ajuda de alguns volunt\u00e1rios \u00e9 imprescind\u00edvel. Entre essas pessoas, est\u00e1 a professora Gillaine Goulart, moradora de Sapucaia do Sul (RS). Ela descobriu a HP em 2022, ap\u00f3s ter sintomas agravantes e recorrentes. \u201cComecei com muita fadiga, canseira e sem resist\u00eancia f\u00edsica para fazer caminhada, andar de bicicleta ou subir escadas. Por volta de setembro de 2021, os sintomas se agravaram e eu n\u00e3o conseguia me deslocar at\u00e9 o quarto, porque tinha que deitar ou iria desmaiar. A princ\u00edpio, pensei ser estresse e que iria passar. Ap\u00f3s trocar a medica\u00e7\u00e3o psicol\u00f3gica e n\u00e3o fazer efeito, em 5 de janeiro de 2022, desmaiei em casa e fui levada ao hospital. Realizei exames por mais de um m\u00eas, at\u00e9 fazer um cateterismo card\u00edaco direito e receber o diagn\u00f3stico de HP\u201d, conta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88681\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/iara-machado-frente-foto-page-0001\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-scaled.jpg\" data-orig-size=\"1591,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IARA-MACHADO-Frente&amp;#8212;Foto-page-0001\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-637x1024.jpg\" class=\"alignnone size-medium wp-image-88681\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-186x300.jpg\" alt=\"\" width=\"186\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-186x300.jpg 186w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-637x1024.jpg 637w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-768x1235.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-955x1536.jpg 955w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-1273x2048.jpg 1273w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-1200x1930.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/iara-machado-frente-foto-page-0001-scaled.jpg 1591w\" sizes=\"auto, (max-width: 186px) 100vw, 186px\" \/><\/p>\n<p>Ap\u00f3s o choque inicial, Gillaine foi encaminhada para um pneumologista e, na sequ\u00eancia, para a Santa Casa de Miseric\u00f3rdia de Porto Alegre (RS), um centro de refer\u00eancia para tratamento da doen\u00e7a no SUS. \u201cCheguei l\u00e1 em uma cadeira de rodas e sem conseguir falar direito. Os m\u00e9dicos me convidaram para participar de uma pesquisa cl\u00ednica de um medicamento,\u00a0 e ap\u00f3s o envio dos documentos j\u00e1 comecei a ser medicada. Quando tive o diagn\u00f3stico, o ch\u00e3o abriu e a depress\u00e3o tomou conta, porque perdemos a resist\u00eancia e a for\u00e7a f\u00edsica. Nos sentimos in\u00fateis, e as pessoas pensam que estamos fingindo. Voltamos a ser crian\u00e7a, aprender a viver novamente, fazer tudo diferente, inclusive construir uma nova vida a partir da HP\u201d. Atualmente, ela trata a doen\u00e7a e atua na conscientiza\u00e7\u00e3o e divulga\u00e7\u00e3o de informa\u00e7\u00f5es sobre o tema.<\/p>\n<p>Outra paciente de HP e volunt\u00e1ria da Abraf em Porto Alegre \u00e9 a doceira Taline de Oliveira, que descobriu a doen\u00e7a ap\u00f3s diversos exames. \u201cEu estava com minha rotina normal, indo ao trabalho e cuidando da casa e dos filhos, quando comecei a perceber que, ao ir r\u00e1pido no banheiro \u00e0 noite, meu cora\u00e7\u00e3o disparava. O primeiro exame que fiz foi o eletrocardiograma, que j\u00e1 apresentou altera\u00e7\u00f5es. Fui encaminhada para outra cl\u00ednica e fiz diversos exames, at\u00e9 me informarem que eu tinha um sopro no cora\u00e7\u00e3o e precisaria operar. Fiquei duas semanas internada e realizando outros exames. Estava com a cirurgia marcada, mas na manh\u00e3 do procedimento, ele foi cancelado ap\u00f3s uma conversa entre a equipe m\u00e9dica\u201d, explica.<\/p>\n<p>A partir de ent\u00e3o, sem diagn\u00f3stico conclusivo e com a cirurgia desmarcada, o medo tomou conta de Taline. Ap\u00f3s sair do hospital, algumas outras doen\u00e7as foram citadas por m\u00e9dicos, como a ansiedade. Mais uma bateria de exames foi realizada e ela foi encaminhada para o ambulat\u00f3rio de hipertens\u00e3o pulmonar da Santa Casa. \u201cAtualmente, fa\u00e7o o tratamento com as medica\u00e7\u00f5es corretas, que me ajudam muito, junto \u00e0 reabilita\u00e7\u00e3o pulmonar, que tem me dado melhor qualidade de vida\u201d.<\/p>\n<p>\u201cTenho um lema: informa\u00e7\u00f5es salvam vidas. Quando descobri a doen\u00e7a, fiquei muito perdida e sem rumo, ningu\u00e9m conhecia ou tinha uma palavra de \u00e2nimo para dar, todos ficavam apavorados e eu ficava com medo cada vez que, na consulta, o m\u00e9dico me explicava o que eu tinha. Com o passar do tempo, fui entendendo que quanto mais eu aprender sobre a minha doen\u00e7a, mais posso me ajudar e recorrer a outros fatores para me dar qualidade de vida\u201d, explica Taline.<\/p>\n<p><strong>Servi\u00e7o\u00a0<\/strong><\/p>\n<p><strong><em>Exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edveis<\/em><\/strong><\/p>\n<p><strong>Data:\u00a0<\/strong>De 06\/11 \u00e0 30\/11<br \/>\n<strong>Hor\u00e1rio:\u00a0<\/strong>Das 09h \u00e0s 20h<br \/>\n<strong>Local:\u00a0<\/strong>Feevale Campus 2 &#8211; \u00e1rea coberta.\u00a0Rua Arlindo Pasqualini n\u00ba 103 &#8211; Vila Nova &#8211; Novo Hamburgo (RS)<\/p>\n<p><strong>Entrada:<\/strong>\u00a0Gratuita<\/p>\n<p><strong>Sobre a ABRAF<\/strong><\/p>\n<p>A Associa\u00e7\u00e3o Brasileira de Apoio \u00e0 Fam\u00edlia com Hipertens\u00e3o Pulmonar e Doen\u00e7as Correlatas (ABRAF) \u00e9 uma organiza\u00e7\u00e3o sem fins lucrativos que busca apoiar a comunidade afetada por Hipertens\u00e3o Pulmonar e Doen\u00e7as Correlatas, por meio de conscientiza\u00e7\u00e3o, apoio e promo\u00e7\u00e3o de pol\u00edticas p\u00fablicas. Fundada em 2006, a ABRAF fortalece a voz dos pacientes e profissionais de sa\u00fade para enfrentar os desafios dessas condi\u00e7\u00f5es de forma colaborativa e eficaz. Saiba mais em<a href=\"https:\/\/abraf.ong\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/abraf.ong\/&amp;source=gmail&amp;ust=1699544618775000&amp;usg=AOvVaw3DKIgXDXxEzQqYx7qoKmuU\">\u00a0https:\/\/abraf.ong<\/a>\/<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":88680,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-88677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culturanotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-08T16:33:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-08T16:33:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#article\",\"name\":\"Mostra \\u201c(In)vis\\u00edvel\\u201d re\\u00fane fotografias e hist\\u00f3rias de pessoas portadoras de Hipertens\\u00e3o Pulmonar | Cultura\",\"headline\":\"Mostra &#8220;(In)vis\\u00edvel&#8221; re\\u00fane fotografias e hist\\u00f3rias de pessoas portadoras de Hipertens\\u00e3o Pulmonar\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/11\\\/exposicao-congresso-medico-1.jpg\",\"width\":669,\"height\":589,\"caption\":\"Exposi\\u00e7\\u00e3o em Congresso medico\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2023-11-08T13:33:38-03:00\",\"dateModified\":\"2023-11-08T13:33:38-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#webpage\"},\"articleSection\":\"Cultura-NOTAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"name\":\"Cultura-NOTAS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"position\":2,\"name\":\"Cultura-NOTAS\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#listItem\",\"name\":\"Mostra &#8220;(In)vis\\u00edvel&#8221; re\\u00fane fotografias e hist\\u00f3rias de pessoas portadoras de Hipertens\\u00e3o Pulmonar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#listItem\",\"position\":3,\"name\":\"Mostra &#8220;(In)vis\\u00edvel&#8221; re\\u00fane fotografias e hist\\u00f3rias de pessoas portadoras de Hipertens\\u00e3o Pulmonar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"name\":\"Cultura-NOTAS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/\",\"name\":\"Mostra \\u201c(In)vis\\u00edvel\\u201d re\\u00fane fotografias e hist\\u00f3rias de pessoas portadoras de Hipertens\\u00e3o Pulmonar | Cultura\",\"description\":\"Durante todo o m\\u00eas de novembro, Novo Hamburgo (RS) receber\\u00e1 a exposi\\u00e7\\u00e3o fotogr\\u00e1fica (In)vis\\u00edvel, que re\\u00fane fotografias e hist\\u00f3rias de 24 pessoas que vivem com Hipertens\\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\\u00e7a e chamar a aten\\u00e7\\u00e3o para a luta dos pacientes e cuidadores\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/11\\\/exposicao-congresso-medico-1.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#mainImage\",\"width\":669,\"height\":589,\"caption\":\"Exposi\\u00e7\\u00e3o em Congresso medico\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\\\/#mainImage\"},\"datePublished\":\"2023-11-08T13:33:38-03:00\",\"dateModified\":\"2023-11-08T13:33:38-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura","description":"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#article","name":"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura","headline":"Mostra &#8220;(In)vis\u00edvel&#8221; re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/exposicao-congresso-medico-1.jpg","width":669,"height":589,"caption":"Exposi\u00e7\u00e3o em Congresso medico\/ Divulga\u00e7\u00e3o"},"datePublished":"2023-11-08T13:33:38-03:00","dateModified":"2023-11-08T13:33:38-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#webpage"},"articleSection":"Cultura-NOTAS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","name":"Cultura-NOTAS"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","position":2,"name":"Cultura-NOTAS","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#listItem","name":"Mostra &#8220;(In)vis\u00edvel&#8221; re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#listItem","position":3,"name":"Mostra &#8220;(In)vis\u00edvel&#8221; re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","name":"Cultura-NOTAS"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/","name":"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura","description":"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/exposicao-congresso-medico-1.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#mainImage","width":669,"height":589,"caption":"Exposi\u00e7\u00e3o em Congresso medico\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/#mainImage"},"datePublished":"2023-11-08T13:33:38-03:00","dateModified":"2023-11-08T13:33:38-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura","og:description":"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores","og:url":"https:\/\/www.jornalja.com.br\/cultura\/mostra-invisivel-reune-fotografias-e-historias-de-pessoas-portadoras-de-hipertensao-pulmonar\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg","article:published_time":"2023-11-08T16:33:38+00:00","article:modified_time":"2023-11-08T16:33:38+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Mostra \u201c(In)vis\u00edvel\u201d re\u00fane fotografias e hist\u00f3rias de pessoas portadoras de Hipertens\u00e3o Pulmonar | Cultura","twitter:description":"Durante todo o m\u00eas de novembro, Novo Hamburgo (RS) receber\u00e1 a exposi\u00e7\u00e3o fotogr\u00e1fica (In)vis\u00edvel, que re\u00fane fotografias e hist\u00f3rias de 24 pessoas que vivem com Hipertens\u00e3o Pulmonar (HP). Todas as imagens expostas buscam retratar com sensibilidade a rotina de quem convive com a doen\u00e7a e chamar a aten\u00e7\u00e3o para a luta dos pacientes e cuidadores","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/cartaz-216x300.jpg"},"aioseo_meta_data":{"post_id":"88677","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-08 16:15:42","updated":"2025-06-04 13:53:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":83848,"url":"https:\/\/www.jornalja.com.br\/cultura\/como-um-musico-de-jazz-marcos-monteiro-e-sua-exposicao-na-galeria-da-escadaria\/","url_meta":{"origin":88677,"position":0},"title":"\u201cComo um m\u00fasico de jazz\u201d. Marcos Monteiro e sua exposi\u00e7\u00e3o na Galeria da Escadaria.","author":"Higino Barros","date":"28 de abril de 2021","format":false,"excerpt":"\u00a0 Higino Barros Dia 1\u00ba de Maio, a Galeria Escadaria , no viaduto da Borges de Medeiros, abriga sua segunda exposi\u00e7\u00e3o, desde que foi aberta em abril de 2021, em plena pandemia do Corona Virus. Agora ser\u00e1 a vez de Marcos Monteiro, 65 anos, natural de Bag\u00e9, fot\u00f3grafo, produtor cultural\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/exposicao-marcos-8.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/exposicao-marcos-8.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/exposicao-marcos-8.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/exposicao-marcos-8.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/04\/exposicao-marcos-8.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":86664,"url":"https:\/\/www.jornalja.com.br\/cultura\/o-combate-a-pandemia-na-visao-de-quem-esteve-na-linha-de-frente\/","url_meta":{"origin":88677,"position":1},"title":"O combate \u00e0 pandemia na vis\u00e3o de quem esteve na linha de frente","author":"Elmar Bones","date":"12 de setembro de 2022","format":false,"excerpt":"Ser\u00e1 lan\u00e7ado na quarta-feira, 14, o livro \"Cr\u00f4nicas da Pandemia\", do\u00a0 cardiologista Rog\u00e9rio Gomes,na Delphus Galeria de Arte (Av. Crist\u00f3v\u00e3o Colombo, 1501), 19 horas. O livro reune relatos -ora emocionados, ora indignados - de quem esteve na linha de frente no auge do combate ao Covid 19. Uma exposi\u00e7\u00e3o de\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/cultura-rogerio-gomes-karine-viana.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/cultura-rogerio-gomes-karine-viana.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/cultura-rogerio-gomes-karine-viana.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/cultura-rogerio-gomes-karine-viana.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/cultura-rogerio-gomes-karine-viana.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":92409,"url":"https:\/\/www.jornalja.com.br\/cultura\/5a-expo-mob-reune-imagens-de-63-fotografos-em-porto-alegre\/","url_meta":{"origin":88677,"position":2},"title":"5\u00aa Expo Mob re\u00fane imagens de 63 fot\u00f3grafos em Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"24 de agosto de 2026","format":false,"excerpt":"Em sua 5\u00aa edi\u00e7\u00e3o, a Expo Mob re\u00fane os trabalhos de 63 fot\u00f3grafos, provenientes de 19 cidades do Brasil e tamb\u00e9m do exterior, revelando a diversidade de olhares, hist\u00f3rias e linguagens que a fotografia produzida por dispositivos m\u00f3veis \u00e9 capaz de alcan\u00e7ar. S\u00e3o diferentes territ\u00f3rios, experi\u00eancias e sensibilidades reunidos em\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/08\/expo-mob-camila-medeiros-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/08\/expo-mob-camila-medeiros-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/08\/expo-mob-camila-medeiros-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/08\/expo-mob-camila-medeiros-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/08\/expo-mob-camila-medeiros-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":87960,"url":"https:\/\/www.jornalja.com.br\/cultura\/mobfotografia-exposicao-com-fotos-de-celular-reune-90-imagens-de-45-fotografos\/","url_meta":{"origin":88677,"position":3},"title":"&#8220;Mobfotografia&#8221;: exposi\u00e7\u00e3o com fotos de celular  re\u00fane 90 imagens de 45 fot\u00f3grafos","author":"da Reda\u00e7\u00e3o","date":"9 de junho de 2023","format":false,"excerpt":"\u2019Mobgrafia - Express\u00e3o Urbana\u201d \u00e9 a exposi\u00e7\u00e3o que ocupar\u00e1 a Galeria Escadaria, em sua segunda edi\u00e7\u00e3o, a partir desse s\u00e1bado,\u00a0 dia 10 de junho, reunindo 90 imagens de 45 fot\u00f3grafos, feitas em celulares ou tablets. Com curadoria do publicit\u00e1rio e fot\u00f3grafo Marcos Monteiro, a iniciativa tem um car\u00e1ter duplamente democr\u00e1tico,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/expo-mobgrafia-2022-img-5064-foto-marcos-monteiro.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/expo-mobgrafia-2022-img-5064-foto-marcos-monteiro.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/expo-mobgrafia-2022-img-5064-foto-marcos-monteiro.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/06\/expo-mobgrafia-2022-img-5064-foto-marcos-monteiro.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":90077,"url":"https:\/\/www.jornalja.com.br\/cultura\/as-imagens-do-desassossego-na-pintura-de-sandra-goncalves\/","url_meta":{"origin":88677,"position":4},"title":"As &#8220;Imagens do Desassossego&#8221; na pintura de Sandra Gon\u00e7alves","author":"da Reda\u00e7\u00e3o","date":"15 de outubro de 2024","format":false,"excerpt":"\u00a0 Temas como o feminic\u00eddio, a viol\u00eancia e o silenciamento hist\u00f3rico das mulheres est\u00e3o presentes na exposi\u00e7\u00e3o que inaugura nesta ter\u00e7a-feira, 15 de outubro, \u00e0s 19h, no Espa\u00e7o de Artes da UFSCPA. \u00a0As mulheres, resilientes e sobreviventes, buscam for\u00e7as na vida marcada pelo vermelho na exposi\u00e7\u00e3o \u201cImagens do Desassossego\u201d da\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/copia-de-10-tudo-danca-transmutacao-18-2021-100-x-70-cm-72-dpi.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/copia-de-10-tudo-danca-transmutacao-18-2021-100-x-70-cm-72-dpi.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/copia-de-10-tudo-danca-transmutacao-18-2021-100-x-70-cm-72-dpi.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/copia-de-10-tudo-danca-transmutacao-18-2021-100-x-70-cm-72-dpi.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/copia-de-10-tudo-danca-transmutacao-18-2021-100-x-70-cm-72-dpi.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":86988,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-fotografia-fora-dos-parametros-tradicionais-de-negra-angela-na-galeria-escadaria\/","url_meta":{"origin":88677,"position":5},"title":"A fotografia fora dos par\u00e2metros tradicionais, de Negra Angela, na Galeria Escadaria","author":"da Reda\u00e7\u00e3o","date":"31 de outubro de 2022","format":false,"excerpt":"Um conjunto expositivo formado por 13 fotos em grandes dimens\u00f5es (2mx1m), dispostos ao longo da escadaria do Viaduto Borges de Medeiros, em pleno Centro Hist\u00f3rico de Porto Alegre, comp\u00f5e \u201cO mundo da Nega Angela\u201d, t\u00edtulo da exposi\u00e7\u00e3o da fot\u00f3grafa\u00a0Angela Cristina Ribeiro dos Santos, que inaugura no pr\u00f3ximo dia\u00a005 de novembro,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/10\/mundodanegaangela003.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/10\/mundodanegaangela003.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/10\/mundodanegaangela003.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/10\/mundodanegaangela003.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/10\/mundodanegaangela003.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-n4h","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/11\/exposicao-congresso-medico-1.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=88677"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88677\/revisions"}],"predecessor-version":[{"id":88683,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88677\/revisions\/88683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/88680"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=88677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=88677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=88677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}