{"id":89110,"date":"2024-02-27T12:28:11","date_gmt":"2024-02-27T15:28:11","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=89110"},"modified":"2024-02-27T12:28:11","modified_gmt":"2024-02-27T15:28:11","slug":"galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/","title":{"rendered":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o &#8220;Express\u00f5es&#8221;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\"><strong>Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o \u00a0no Pier da Usina do Gas\u00f4metro<\/strong><\/p>\n<figure id=\"attachment_89123\" aria-describedby=\"caption-attachment-89123\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"89123\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/exposicao-expressoes-sergio-de-paula-ramos-1\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1.jpg\" data-orig-size=\"1600,1149\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Exposicao Expressoes &amp;#8211; Sergio de Paula Ramos 1\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Exposi\u00e7\u00e3o Express\u00f5es &amp;#8211; Sergio de Paula Ramos\/Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-1024x735.jpg\" class=\"size-medium wp-image-89123\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-300x215.jpg\" alt=\"\" width=\"300\" height=\"215\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-300x215.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-1024x735.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-768x552.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-1536x1103.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1-1200x862.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-sergio-de-paula-ramos-1.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-89123\" class=\"wp-caption-text\">Exposi\u00e7\u00e3o Express\u00f5es &#8211; Foto : Sergio de Paula Ramos\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla do Gua\u00edba, um dos cart\u00f5es postais mais emblem\u00e1ticos de Porto Alegre, visitado por milhares de pessoas\u00a0 mensalmente. A exposi\u00e7\u00e3o ter\u00e1 \u00a0abertura no s\u00e1bado, dia 2 de mar\u00e7o, ficando em cartaz at\u00e9 30 de maio. Com curadoria e concep\u00e7\u00e3o gr\u00e1fica do fot\u00f3grafo, designer gr\u00e1fico e produtor\u00a0 cultural Marcos Monteiro, pode ser conferida diariamente, ao longo de 24h.<\/p>\n<figure id=\"attachment_89120\" aria-describedby=\"caption-attachment-89120\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"89120\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/exposicao-expressoes-flavia_ferme2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2.jpg\" data-orig-size=\"1600,1062\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Marcos Monteiro&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1707470967&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Exposicao Expressoes &amp;#8211; flavia_ferme2\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Exposic\u00e3o Express\u00f5es; Foto: Fl\u00e1via Ferme\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-1024x680.jpg\" class=\"size-medium wp-image-89120\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-300x199.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-1024x680.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-768x510.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-1536x1020.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2-1200x797.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-flavia-ferme2.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-89120\" class=\"wp-caption-text\">Exposic\u00e3o Express\u00f5es; Foto: Fl\u00e1via Ferme\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Segundo o material de divulga\u00e7\u00e3o, &#8220;Os sonhos, ao se materializarem, trazem festa ao cora\u00e7\u00e3o de seus idealizadores. E a celebra\u00e7\u00e3o dessa festividade, quando compartilhada, a torna inesquec\u00edvel. Os autores das obras apresentadas criam novas concep\u00e7\u00f5es, imagens subliminares atrav\u00e9s de executadas com enorme esmero e criatividade, traduzidas na forma de d\u00edpticos e tr\u00edpticos. S\u00e3o eles: Fl\u00e1via Ferme, Fernando Zago, Iara Tonidandel, Joice Kreiss, Jorge Neumann, Maria Sallet Domingues e S\u00e9rgio De Paula Ramos, comemorando e partilhando por meio de seus trabalhos, a emo\u00e7\u00e3o que o ato fotogr\u00e1fico oferece.<\/p>\n<p style=\"font-weight: 400\">\n<figure id=\"attachment_89122\" aria-describedby=\"caption-attachment-89122\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"89122\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/exposicao-expressoes-joice-kreiss-2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2.jpg\" data-orig-size=\"1600,826\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;JOICE KREISS&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;JOICE KREISS&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Exposicao Expressoes &amp;#8211; joice kreiss 2\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Exposic\u00e3o Express\u00f5es. Foto: Joice Keiss\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-1024x529.jpg\" class=\"size-medium wp-image-89122\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-300x155.jpg\" alt=\"\" width=\"300\" height=\"155\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-300x155.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-1024x529.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-768x396.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-1536x793.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2-1200x620.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-joice-kreiss-2.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-89122\" class=\"wp-caption-text\">Exposi\u00e7\u00e2o Express\u00f5es. Foto: Joice Keiss\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Os contrastes de luz e sombra, as cores vibrantes ou suaves, as composi\u00e7\u00f5es meticulosamente pensadas ou os instantes espont\u00e2neos, s\u00e3o express\u00f5es de arte em que, cada imagem \u00e9 um universo em si, carregado de m\u00faltiplos significados e sentimentos. Assim, os sete fot\u00f3grafos tornam-se narradores de suas hist\u00f3rias, contadas por meio do conjunto de d\u00edpticos e tr\u00edpticos numa linguagem visual. Em um mundo que se diz cronometrado pelo tempo, a fotografia \u00e9 a arte que, ao se contrapor \u00e0 ideia de que o que passou n\u00e3o volta, transforma momentos fugazes em mem\u00f3rias eternas. Atrav\u00e9s da lente da c\u00e2mera, os fot\u00f3grafos revelam a beleza oculta no ordin\u00e1rio, eternizando instantes \u00edmpares.<\/p>\n<figure id=\"attachment_89112\" aria-describedby=\"caption-attachment-89112\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"89112\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/expo-expressoes-jorge-neumann-1-1\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1.jpg\" data-orig-size=\"1600,1066\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Jorge Neumann&quot;,&quot;camera&quot;:&quot;ILCE-7M4&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1699019878&quot;,&quot;copyright&quot;:&quot;Jorge Neumann&quot;,&quot;focal_length&quot;:&quot;200&quot;,&quot;iso&quot;:&quot;1250&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Expo Expressoes &amp;#8211; jorge neumann 1 (1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Exposi\u00e7\u00e3o  Express\u00f5es &amp;#8211; Foto: Jorge Neumann\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-1024x682.jpg\" class=\"size-medium wp-image-89112\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-300x200.jpg 300w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-1024x682.jpg 1024w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-768x512.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-1536x1023.jpg 1536w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1-1200x800.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-jorge-neumann-1-1.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-89112\" class=\"wp-caption-text\">Exposi\u00e7\u00e3o Express\u00f5es &#8211; Foto: Jorge Neumann\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">\nCada clique \u00e9 um suspiro da alma, uma forma de express\u00e3o que transcende as palavras e fala diretamente ao cora\u00e7\u00e3o. Nas paisagens vastas e nas faces an\u00f4nimas, as fotos que comp\u00f5em a coletiva revelam a humanidade em sua ess\u00eancia mais pura, explicitando a arte de cada um dos fot\u00f3grafos aqui presentes. Em cada imagem, uma express\u00e3o, uma hist\u00f3ria, um peda\u00e7o da alma humana nos olhos de quem a cria e de quem a contempla&#8221;.<\/p>\n<figure id=\"attachment_89115\" aria-describedby=\"caption-attachment-89115\" style=\"width: 200px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"89115\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/expo-expressoes-maria-domingues-sallet-2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2.jpg\" data-orig-size=\"1066,1600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1688474234&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Expo Expressoes &amp;#8211; maria domingues sallet 2\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Expo Express\u00f5es &amp;#8211; Maria Domingues Sallet\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2-682x1024.jpg\" class=\"size-medium wp-image-89115\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2-200x300.jpg 200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2-682x1024.jpg 682w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2-768x1153.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2-1023x1536.jpg 1023w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/expo-expressoes-maria-domingues-sallet-2.jpg 1066w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-89115\" class=\"wp-caption-text\">Expo Express\u00f5es &#8211; Maria Domingues Sallet\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>SERVI\u00c7O:<\/strong><\/p>\n<p style=\"font-weight: 400\">Abertura: 2 de mar\u00e7o (s\u00e1bado), a partir das 16h<\/p>\n<p style=\"font-weight: 400\">Encerramento: 30 de maio de 2024.<\/p>\n<p style=\"font-weight: 400\">Local: Pier da Usina do Gas\u00f4metro (Jo\u00e3o Goulart, 551) \u2013 Centro Hist\u00f3rico de Porto Alegre<\/p>\n<p style=\"font-weight: 400\">Visita\u00e7\u00e3o: Di\u00e1ria, 24h<\/p>\n<p style=\"font-weight: 400\">Contato: Com o curador, Marcos Monteiro (51-9935-0608) ou jornalista Vera Pinto (51-99104-1372)<\/p>\n<p style=\"font-weight: 400\">Entrada franca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o \u00a0no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":89121,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-89110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-27T15:28:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-27T15:28:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#article\",\"name\":\"Galeria Escadaria celebra tr\\u00eas anos de exist\\u00eancia com a exposi\\u00e7\\u00e3o \\u201cExpress\\u00f5es\\u201d | Cultura\",\"headline\":\"Galeria Escadaria celebra tr\\u00eas anos de exist\\u00eancia com a exposi\\u00e7\\u00e3o &#8220;Express\\u00f5es&#8221;\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/exposicao-expressoes-iara-tonidandel1.jpg\",\"width\":1600,\"height\":1066,\"caption\":\"Exposic\\u00e3o Express\\u00f5es Foto: Iara Tonidandel\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2024-02-27T12:28:11-03:00\",\"dateModified\":\"2024-02-27T12:28:11-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#listItem\",\"name\":\"Galeria Escadaria celebra tr\\u00eas anos de exist\\u00eancia com a exposi\\u00e7\\u00e3o &#8220;Express\\u00f5es&#8221;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#listItem\",\"position\":3,\"name\":\"Galeria Escadaria celebra tr\\u00eas anos de exist\\u00eancia com a exposi\\u00e7\\u00e3o &#8220;Express\\u00f5es&#8221;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1783485325\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/\",\"name\":\"Galeria Escadaria celebra tr\\u00eas anos de exist\\u00eancia com a exposi\\u00e7\\u00e3o \\u201cExpress\\u00f5es\\u201d | Cultura\",\"description\":\"Coletiva que re\\u00fane a obra de sete fot\\u00f3grafos tem abertura no dia 2 de mar\\u00e7o no Pier da Usina do Gas\\u00f4metro A Galeria Escadaria apresenta a exposi\\u00e7\\u00e3o fotogr\\u00e1fica \\u201cExpress\\u00f5es\\u201d, projeto que homenageia os tr\\u00eas anos da \\u00fanica galeria permanente a c\\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\\u00f4metro, junto \\u00e0 Orla\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/exposicao-expressoes-iara-tonidandel1.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#mainImage\",\"width\":1600,\"height\":1066,\"caption\":\"Exposic\\u00e3o Express\\u00f5es Foto: Iara Tonidandel\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\\\/#mainImage\"},\"datePublished\":\"2024-02-27T12:28:11-03:00\",\"dateModified\":\"2024-02-27T12:28:11-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura","description":"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#article","name":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura","headline":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o &#8220;Express\u00f5es&#8221;","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg","width":1600,"height":1066,"caption":"Exposic\u00e3o Express\u00f5es Foto: Iara Tonidandel\/ Divulga\u00e7\u00e3o"},"datePublished":"2024-02-27T12:28:11-03:00","dateModified":"2024-02-27T12:28:11-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#listItem","name":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o &#8220;Express\u00f5es&#8221;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#listItem","position":3,"name":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o &#8220;Express\u00f5es&#8221;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#authorImage","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/litespeed\/avatar\/2\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1783485325","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/","name":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura","description":"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#mainImage","width":1600,"height":1066,"caption":"Exposic\u00e3o Express\u00f5es Foto: Iara Tonidandel\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/#mainImage"},"datePublished":"2024-02-27T12:28:11-03:00","dateModified":"2024-02-27T12:28:11-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura","og:description":"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla","og:url":"https:\/\/www.jornalja.com.br\/cultura\/galeria-escadaria-celebra-tres-anos-de-existencia-com-a-exposicao-expressoes\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg","og:image:width":1600,"og:image:height":1066,"article:published_time":"2024-02-27T15:28:11+00:00","article:modified_time":"2024-02-27T15:28:11+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Galeria Escadaria celebra tr\u00eas anos de exist\u00eancia com a exposi\u00e7\u00e3o \u201cExpress\u00f5es\u201d | Cultura","twitter:description":"Coletiva que re\u00fane a obra de sete fot\u00f3grafos tem abertura no dia 2 de mar\u00e7o no Pier da Usina do Gas\u00f4metro A Galeria Escadaria apresenta a exposi\u00e7\u00e3o fotogr\u00e1fica \u201cExpress\u00f5es\u201d, projeto que homenageia os tr\u00eas anos da \u00fanica galeria permanente a c\u00e9u aberto do Brasil, localizada no pier da Usina do Gas\u00f4metro, junto \u00e0 Orla","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg"},"aioseo_meta_data":{"post_id":"89110","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-02-27 14:49:58","updated":"2025-06-04 14:02:34","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/02\/exposicao-expressoes-iara-tonidandel1.jpg","jetpack-related-posts":[{"id":88984,"url":"https:\/\/www.jornalja.com.br\/cultura\/street-expo-photo-e-atracao-no-pier-do-gasometro-ate-final-de-fevereiro\/","url_meta":{"origin":89110,"position":0},"title":"Street Expo Photo \u00e9 atra\u00e7\u00e3o no Pier do Gas\u00f4metro\u00a0at\u00e9 final de fevereiro","author":"Higino Barros","date":"17 de janeiro de 2024","format":false,"excerpt":"Mesmo com a tempestade que assolou Porto Alegre nessa ter\u00e7a-feira, nenhum dano ocorreu na \u00e1rea expositiva e a mostra prossegue at\u00e9 final de fevereiro. \u00a0\u00a0\u00a0\u00a0 A 6\u00aa Street Expo Photo re\u00fane imagens de 90 fot\u00f3grafos de diversos estados do Brasil e pa\u00edses da Europa, at\u00e9 o dia 29 de fevereiro,\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/01\/pier-street-expo-photo-2023-foto-betina-samaiajpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/01\/pier-street-expo-photo-2023-foto-betina-samaiajpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/01\/pier-street-expo-photo-2023-foto-betina-samaiajpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/01\/pier-street-expo-photo-2023-foto-betina-samaiajpg.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/01\/pier-street-expo-photo-2023-foto-betina-samaiajpg.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/01\/pier-street-expo-photo-2023-foto-betina-samaiajpg.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":90782,"url":"https:\/\/www.jornalja.com.br\/cultura\/g-mostra-identidades-celebra-os-cinco-anos-da-galeria-escadaria-com-imagens-de-sete-fotografos\/","url_meta":{"origin":89110,"position":1},"title":"Mostra \u201cIdentidades\u201d celebra os cinco anos da Galeria Escadaria, com imagens de sete fot\u00f3grafos","author":"da Reda\u00e7\u00e3o","date":"18 de mar\u00e7o de 2025","format":false,"excerpt":"\u00a0Para comemorar seus cinco anos de exist\u00eancia, a Galeria Escadaria selecionou sete fot\u00f3grafos \u2013 dois de S\u00e3o Paulo e cinco do Rio Grande do Sul - para compor a coletiva \u00a0\u201cIdentidades\u201d, que abre no dia 23 de mar\u00e7o (domingo), a partir das 16h, no Pier da Usina do Gas\u00f4metro. Com\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/03\/escadaria-jorge-lansarin-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/03\/escadaria-jorge-lansarin-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/03\/escadaria-jorge-lansarin-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/03\/escadaria-jorge-lansarin-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":88805,"url":"https:\/\/www.jornalja.com.br\/cultura\/ccom-homenagem-ao-fotografo-luiz-carlos-felizardo-a-street-expo-photo-no-pier-do-gasometro\/","url_meta":{"origin":89110,"position":2},"title":"Com homenagem ao fot\u00f3grafo Luiz Carlos Felizardo, a Street Expo Photo no Pier do  Gas\u00f4metro,","author":"da Reda\u00e7\u00e3o","date":"6 de dezembro de 2023","format":false,"excerpt":"\u00a0 Em sua 6\u00aa edi\u00e7\u00e3o, a Street Expo Photo ser\u00e1 realizada pela primeira vez no Pier da Usina do Gas\u00f4metro, no dia 9 de dezembro (s\u00e1bado), a partir das 16h, com a participa\u00e7\u00e3o de 90 fot\u00f3grafos de diversos estados do Brasil e pa\u00edses da Europa. Sediada tradicionalmente na Galeria Escadaria\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/12\/street-expo-photo-2023-walter-firmo-fotografado-cartolajpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/12\/street-expo-photo-2023-walter-firmo-fotografado-cartolajpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/12\/street-expo-photo-2023-walter-firmo-fotografado-cartolajpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/12\/street-expo-photo-2023-walter-firmo-fotografado-cartolajpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":92224,"url":"https:\/\/www.jornalja.com.br\/cultura\/exposicao-sete-cabecas-reune-trabalhos-de-fotografos-no-pier-do-gasometro\/","url_meta":{"origin":89110,"position":3},"title":"\u201cSete Cabe\u00e7as\u201d : sete fot\u00f3grafos em exposi\u00e7\u00e3o no P\u00eder do Gas\u00f4metro","author":"da Reda\u00e7\u00e3o","date":"18 de abril de 2026","format":false,"excerpt":"A Galeria Escadaria abre neste dia 18 de abril (s\u00e1bado), a partir das 15h, \u201cSete Cabe\u00e7as\u201d, exposi\u00e7\u00e3o que re\u00fane trabalhos de sete fot\u00f3grafos, que embora distintos em linguagem e abordagem, convergem em pot\u00eancia est\u00e9tica e relev\u00e2ncia contempor\u00e2nea.\u00a0 A curadoria \u00e9 de Marcos Monteiro, que j\u00e1 realizou 42 exposi\u00e7\u00f5es a c\u00e9u\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/04\/expo-sete-cabecas-iara-tonidndel-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/04\/expo-sete-cabecas-iara-tonidndel-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/04\/expo-sete-cabecas-iara-tonidndel-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/04\/expo-sete-cabecas-iara-tonidndel-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/04\/expo-sete-cabecas-iara-tonidndel-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":90391,"url":"https:\/\/www.jornalja.com.br\/cultura\/street-expo-photo-expoe-imagens-de-77-fotografos-no-pier-do-gasometro\/","url_meta":{"origin":89110,"position":4},"title":"Street Expo Photo exp\u00f5e imagens de 77 fot\u00f3grafos, no Pier do Gas\u00f4metro","author":"da Reda\u00e7\u00e3o","date":"3 de dezembro de 2024","format":false,"excerpt":"\u00a0 Seguindo fiel \u00e0 ideia original da Street Expo Photo (SEP), de trazer uma mescla ampla de olhares, a coletiva que j\u00e1 faz parte do calend\u00e1rio cultural de Porto Alegre chega \u00e0 7\u00aa edi\u00e7\u00e3o, reunindo o trabalho de 77 fot\u00f3grafos provenientes de 12 estados brasileiros, Portugal e Pa\u00edses Baixos. A\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/12\/expo-sep-iara-tonidandel.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/12\/expo-sep-iara-tonidandel.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/12\/expo-sep-iara-tonidandel.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/12\/expo-sep-iara-tonidandel.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/12\/expo-sep-iara-tonidandel.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":92109,"url":"https:\/\/www.jornalja.com.br\/cultura\/virada-sustentavel-apresenta-exposicao-de-araquem-alcantara\/","url_meta":{"origin":89110,"position":5},"title":"Virada sustent\u00e1vel apresenta exposi\u00e7\u00e3o de Araqu\u00e9m Alc\u00e2ntara","author":"da Reda\u00e7\u00e3o","date":"19 de mar\u00e7o de 2026","format":false,"excerpt":"A Virada Sustent\u00e1vel apresenta, entre suas atra\u00e7\u00f5es comemorativas dos 10 anos, a exposi\u00e7\u00e3o: O Brasil de Araqu\u00e9m Alc\u00e2ntara. Ser\u00e1 no dia 21 de mar\u00e7o, \u00e0s 17h, na Galeria Escadaria do p\u00eder da Usina do Gas\u00f4metro, em Porto Alegre. Esta exposi\u00e7\u00e3o cont\u00e9m fragmentos visuais de um Brasil que pulsa para al\u00e9m\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/03\/pantanal-img-20260317-wa0015.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/03\/pantanal-img-20260317-wa0015.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/03\/pantanal-img-20260317-wa0015.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/03\/pantanal-img-20260317-wa0015.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/03\/pantanal-img-20260317-wa0015.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/03\/pantanal-img-20260317-wa0015.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-nbg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/89110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=89110"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/89110\/revisions"}],"predecessor-version":[{"id":89125,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/89110\/revisions\/89125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/89121"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=89110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=89110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=89110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}