{"id":90065,"date":"2024-10-11T10:45:00","date_gmt":"2024-10-11T13:45:00","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=90065"},"modified":"2024-10-11T10:46:07","modified_gmt":"2024-10-11T13:46:07","slug":"musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/","title":{"rendered":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte"},"content":{"rendered":"<p style=\"font-weight: 400\"><em>Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere<\/em><\/p>\n<p style=\"font-weight: 400\">O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e\u00a0<em>home styling<\/em>\u00a0no espa\u00e7o cultural\u00a0Via Trastevere\u00a0(Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao vivo, palha\u00e7aria, comidas naturais, plantas e flores, al\u00e9m de viv\u00eancias com tem\u00e1ticas ecol\u00f3gicas, marcando a inaugura\u00e7\u00e3o da loja\u00a0Aywu Jardim Consciente, que ir\u00e1 operar no local.<\/p>\n<p style=\"font-weight: 400\">O evento inicia \u00e0s 13h30min deste s\u00e1bado (12), com anima\u00e7\u00e3o dedicada ao dia das crian\u00e7as, protagonizada pelo\u00a0ator \u00c1lex Garga. No mesmo dia, haver\u00e1 show da\u00a0violinista Clarissa Ferreira\u00a0e convidados, exposi\u00e7\u00e3o de acess\u00f3rios, cer\u00e2micas e decora\u00e7\u00f5es, pinturas e quadros em aquarela, e coquetel de lan\u00e7amento do projeto idealizado pela bi\u00f3loga\u00a0S\u00edlvia\u00a0Medeiros Thaler. A empresa, que nasceu com o prop\u00f3sito de levar vida e beleza para a casa das pessoas, \u00e9 focada n\u00e3o somente na est\u00e9tica das plantas, mas tamb\u00e9m na cura e no bem-estar que elas oferecem. Vendidas separadamente, mas tamb\u00e9m em cestas de presentes com cristais, incensos, \u00f3leos essenciais e velas, as plantas s\u00e3o energizadas e cultivadas em substrato especial, explica a empreendedora.<\/p>\n<p style=\"font-weight: 400\">Ainda no s\u00e1bado, \u00e0s 16h, a astr\u00f3loga e escritora\u00a0L\u00facia D. Torres\u00a0ir\u00e1 compartilhar com o p\u00fablico saberes sobre \u201cAstrologia e a primavera de 2024\u201d. No domingo (13), \u00e9 a vez de S\u00edlvia\u00a0Thaler (que tamb\u00e9m presta servi\u00e7os de harmoniza\u00e7\u00e3o de interior,\u00a0<em>home styling<\/em>\u00a0com plantas e paisagismo hol\u00edstico) conduzir a tem\u00e1tica \u201cAywu Jardim Consciente \u2013 o poder das plantas nos ambientes\u201d, em uma das viv\u00eancias e palestras que ocorrem \u00e0s 15h. \u00c0s 16h, outra atividade do g\u00eanero, \u201cTantra e a mulher desperta\u201d, ser\u00e1 ministrada pela fil\u00f3sofa e terapeuta transpessoal\u00a0Esha Helen.<\/p>\n<p style=\"font-weight: 400\">Tamb\u00e9m no domingo haver\u00e1 mostra e venda de artigos ind\u00edgenas (produzidos por uma fam\u00edlia\u00a0Mybia Guarani) e artesanatos de outros expositores, al\u00e9m de comidas naturais e Kombuchas. As apresenta\u00e7\u00f5es musicais do segundo dia de Feira ficam por conta da banda de mantras\u00a0Prema Yantra e Natureza Divina. Todas as atividades s\u00e3o gratuitas e seguem at\u00e9 \u00e0s 18h, em ambas as datas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e\u00a0home styling\u00a0no espa\u00e7o cultural\u00a0Via Trastevere\u00a0(Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-90065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culturanotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-11T13:45:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-11T13:46:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#article\",\"name\":\"M\\u00fasica ao vivo, palha\\u00e7os, comidas naturais e tem\\u00e1ticas ecol\\u00f3gicas, em Feira de Arte | Cultura\",\"headline\":\"M\\u00fasica ao vivo, palha\\u00e7os, comidas naturais e tem\\u00e1ticas ecol\\u00f3gicas, em Feira de Arte\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/10\\\/via-trastevere-divulgacao.jpg\",\"width\":673,\"height\":604,\"caption\":\"A feira acontece no bairro Bonfim. Via Trastevere\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2024-10-11T10:45:00-03:00\",\"dateModified\":\"2024-10-11T10:46:07-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#webpage\"},\"articleSection\":\"Cultura-NOTAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"name\":\"Cultura-NOTAS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"position\":2,\"name\":\"Cultura-NOTAS\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#listItem\",\"name\":\"M\\u00fasica ao vivo, palha\\u00e7os, comidas naturais e tem\\u00e1ticas ecol\\u00f3gicas, em Feira de Arte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#listItem\",\"position\":3,\"name\":\"M\\u00fasica ao vivo, palha\\u00e7os, comidas naturais e tem\\u00e1ticas ecol\\u00f3gicas, em Feira de Arte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/culturanotas\\\/#listItem\",\"name\":\"Cultura-NOTAS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/\",\"name\":\"M\\u00fasica ao vivo, palha\\u00e7os, comidas naturais e tem\\u00e1ticas ecol\\u00f3gicas, em Feira de Arte | Cultura\",\"description\":\"Atividades ocorrem neste s\\u00e1bado (12) e no domingo (13), no espa\\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\\u00e7\\u00e3o, refer\\u00eancias de paisagismo hol\\u00edstico e home styling no espa\\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\\u00e1 palco de uma feira autossustent\\u00e1vel, com m\\u00fasica ao\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/10\\\/via-trastevere-divulgacao.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#mainImage\",\"width\":673,\"height\":604,\"caption\":\"A feira acontece no bairro Bonfim. Via Trastevere\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\\\/#mainImage\"},\"datePublished\":\"2024-10-11T10:45:00-03:00\",\"dateModified\":\"2024-10-11T10:46:07-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura","description":"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#article","name":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura","headline":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/via-trastevere-divulgacao.jpg","width":673,"height":604,"caption":"A feira acontece no bairro Bonfim. Via Trastevere\/ Divulga\u00e7\u00e3o"},"datePublished":"2024-10-11T10:45:00-03:00","dateModified":"2024-10-11T10:46:07-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#webpage"},"articleSection":"Cultura-NOTAS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","name":"Cultura-NOTAS"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","position":2,"name":"Cultura-NOTAS","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#listItem","name":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#listItem","position":3,"name":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/#listItem","name":"Cultura-NOTAS"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/","name":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura","description":"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/via-trastevere-divulgacao.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#mainImage","width":673,"height":604,"caption":"A feira acontece no bairro Bonfim. Via Trastevere\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/#mainImage"},"datePublished":"2024-10-11T10:45:00-03:00","dateModified":"2024-10-11T10:46:07-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura","og:description":"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao","og:url":"https:\/\/www.jornalja.com.br\/cultura\/musica-ao-vivo-palhacos-comidas-naturais-plantas-flores-e-tematicas-ecologicas-em-feira-de-arte\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2024-10-11T13:45:00+00:00","article:modified_time":"2024-10-11T13:46:07+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"M\u00fasica ao vivo, palha\u00e7os, comidas naturais e tem\u00e1ticas ecol\u00f3gicas, em Feira de Arte | Cultura","twitter:description":"Atividades ocorrem neste s\u00e1bado (12) e no domingo (13), no espa\u00e7o cultural Via Trastevere O final de semana promete ser repleto de arte, decora\u00e7\u00e3o, refer\u00eancias de paisagismo hol\u00edstico e home styling no espa\u00e7o cultural Via Trastevere (Travessa da Paz 44, bairro Bom Fim), em Porto Alegre. A Galeria de Arte ser\u00e1 palco de uma feira autossustent\u00e1vel, com m\u00fasica ao","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"90065","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-11 13:35:10","updated":"2025-06-04 14:24:27","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":84421,"url":"https:\/\/www.jornalja.com.br\/cultura\/aceleradora-lanceiros-negros-promove-live-destacando-a-cena-musical-afro-gaucha\/","url_meta":{"origin":90065,"position":0},"title":"Aceleradora Lanceiros Negros promove live destacando a cena musical afro-ga\u00facha","author":"da Reda\u00e7\u00e3o","date":"17 de agosto de 2021","format":false,"excerpt":"\u00a0 \u00a0 Ser\u00e1 realizada nesta quinta-feira, dia 19 de agosto, \u00e0s 20h30min, a segunda live do projeto Aceleradora Lanceiros Negros. \u00a0Participam, como convidados, o rapper Rafa Rafuagi; a cantora e soci\u00f3loga Nina Fola, \u00a0e o rapper\u00a0e\u00a0beatmaker,\u00a0Zilla, com a tem\u00e1tica \u201cCena musical Afro-Ga\u00facha\u201d. A media\u00e7\u00e3o \u00e9 da comunicadora\u00a0Mall\u00ea Barcelos, com transmiss\u00e3o\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/lanceiros.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/lanceiros.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/lanceiros.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/lanceiros.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/lanceiros.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/lanceiros.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":85827,"url":"https:\/\/www.jornalja.com.br\/cultura\/roteiro-cultural-no-centro-de-porto-alegre-ganha-biblioteca-em-novo-endereco\/","url_meta":{"origin":90065,"position":1},"title":"Roteiro cultural no centro de Porto Alegre ganha biblioteca em novo endere\u00e7o","author":"da Reda\u00e7\u00e3o","date":"25 de abril de 2022","format":false,"excerpt":"O corredor cultural que se estende do Memorial do Rio Grande do Sul at\u00e9 a Usina do Gas\u00f4metro, no centro da capital ga\u00facha, ganha um novo espa\u00e7o. A biblioteca comunit\u00e1ria do Cirandar foi reinaugurada em novo endere\u00e7o no s\u00e1bado, dia 23 de abril. A nova sede fica localizada na Rua\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/bibilioteca-infantil-no-centro-cores-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/bibilioteca-infantil-no-centro-cores-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/bibilioteca-infantil-no-centro-cores-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/bibilioteca-infantil-no-centro-cores-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/bibilioteca-infantil-no-centro-cores-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/04\/bibilioteca-infantil-no-centro-cores-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84084,"url":"https:\/\/www.jornalja.com.br\/cultura\/casal-ricardo-giugliani-e-marla-trevisan-leva-aberto-espaco-cultural-para-a-serra\/","url_meta":{"origin":90065,"position":2},"title":"Casal Ricardo Giugliani e Marla Trevisan leva Aberto Espa\u00e7o Cultural para a Serra","author":"da Reda\u00e7\u00e3o","date":"17 de junho de 2021","format":false,"excerpt":"Nem s\u00f3 de turismo, gastronomia, lazer e natureza vive S\u00e3o Francisco de Paula, nos Campos de Cima da Serra. A partir do dia 1\u00ba de julho a cidade incluir\u00e1 no seu rol de atividades um espa\u00e7o cultural in\u00e9dito na regi\u00e3o, dedicado \u00e0 arte e \u00e0 promo\u00e7\u00e3o de obras do artista\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/aberto-3-1-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/aberto-3-1-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/aberto-3-1-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/aberto-3-1-scaled.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/aberto-3-1-scaled.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/06\/aberto-3-1-scaled.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":73295,"url":"https:\/\/www.jornalja.com.br\/cultura\/visoes-da-redencao-em-desenhos-gravuras-e-pinturas-de-ibere-camargo\/","url_meta":{"origin":90065,"position":3},"title":"Vis\u00f5es da Reden\u00e7\u00e3o em desenhos, gravuras e pinturas de Iber\u00ea Camargo","author":"da Reda\u00e7\u00e3o","date":"14 de mar\u00e7o de 2019","format":false,"excerpt":"A exposi\u00e7\u00e3o Vis\u00f5es da Reden\u00e7\u00e3o apresenta um recorte de 77 obras de Iber\u00ea Camargo (66 desenhos, tr\u00eas gravuras e oito pinturas) de \u00e1rvores e frequentadores do parque, que se desdobraram nas famosas s\u00e9ries Fantasmagoria e Ciclistas. Para celebrar os 247 anos de Porto Alegre, a Funda\u00e7\u00e3o Iber\u00ea inaugura no s\u00e1bado,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/03\/exposi%C3%A7%C3%A3o-Vis%C3%B5es-da-Reden%C3%A7%C3%A3o-Foto-R%C3%B4mulo-Fialdini-450x319.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":85314,"url":"https:\/\/www.jornalja.com.br\/cultura\/feira-bella-ciao-em-2a-edicao-com-60-expositores-e-convidados-especiais\/","url_meta":{"origin":90065,"position":4},"title":"Feira Bella Ciao, em 2\u00aa edi\u00e7\u00e3o, com 60 expositores e convidados especiais","author":"da Reda\u00e7\u00e3o","date":"15 de dezembro de 2021","format":false,"excerpt":"Neste domingo,\u00a0 19\/12, come\u00e7a a 2a edi\u00e7\u00e3o da Feira Bella Ciao,\u00a0 com mais de 60 expositores, de marcas autorais de roupas, acess\u00f3rios, artesanato, arte, literatura, cerveja artesanal, alimenta\u00e7\u00e3o vegana e convencional, al\u00e9m de convidados especiais, como o cartunista Santiago, o coletivo Reafro, a Cozinha Solid\u00e1ria do MTST, a ONG Alice\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/cultura-ilustracao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/cultura-ilustracao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/cultura-ilustracao.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/12\/cultura-ilustracao.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":78343,"url":"https:\/\/www.jornalja.com.br\/cultura\/exposicao-traz-a-tematica-da-linha-como-fio-condutor-e-de-conexao-entre-os-trabalhos-de-16-artistas\/","url_meta":{"origin":90065,"position":5},"title":"Exposi\u00e7\u00e3o traz a tem\u00e1tica da linha como fio condutor e de conex\u00e3o entre os trabalhos de 16 artistas.","author":"da Reda\u00e7\u00e3o","date":"16 de outubro de 2019","format":false,"excerpt":"\u00a0 \"Alinhando\", nova exposi\u00e7\u00e3o no Aberto Caminho de Artes tem curadoria de Ana Zavadil. Coquetel de inaugura\u00e7\u00e3o da exposi\u00e7\u00e3o acontecer\u00e1 s\u00e1bado, dia 19, das 11h \u00e0s 15h, na Rua Dr. Armando Barbedo, n\u00ba 356 no Bairro Tristeza, em Porto Alegre\/RS. \u00a0 A nova exposi\u00e7\u00e3o do espa\u00e7o cultural\u00a0Aberto Caminho de Artes\u00a0traz\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/10\/arte-Alexandra-Eckert-ABERTO-450x313.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-nqF","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/via-trastevere-divulgacao.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/90065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=90065"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/90065\/revisions"}],"predecessor-version":[{"id":90068,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/90065\/revisions\/90068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/90066"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=90065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=90065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=90065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}