{"id":90300,"date":"2024-11-20T12:34:51","date_gmt":"2024-11-20T15:34:51","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=90300"},"modified":"2024-12-07T08:33:45","modified_gmt":"2024-12-07T11:33:45","slug":"projeto-para-encher-um-metro-de-estante","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/","title":{"rendered":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante"},"content":{"rendered":"<p><strong>GERALDO HASSE<\/strong><\/p>\n<p>O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85.<\/p>\n<p>Come\u00e7ando em 2022, j\u00e1 lan\u00e7ou os quatro primeiros volumes com as biografias de Alberto Aleixo, Alexandre Baumgarten, Antonio Benetazzo e Carlos Alberto de Freitas, este lan\u00e7ado em outubro \u00faltimo.<\/p>\n<p>Promete para maio de 2025 o quinto &#8212; sobre Carlos Marighella. E seguir\u00e1 em ordem alfab\u00e9tica at\u00e9 chegar a Vladimir Herzog, o n\u00famero 36, e aos dois \u00faltimos: Walter de Souza Ribeiro e Wanio Jos\u00e9 de Mattos.<\/p>\n<p>Com exce\u00e7\u00e3o de Alexandre Baumgarten, v\u00edtima de uma queima de arquivo, todos os biografados eram de esquerda.<\/p>\n<p>N\u00e3o s\u00e3o biografias focadas s\u00f3 na vida das pessoas; todas servem como pretexto para amplas contextualiza\u00e7\u00f5es hist\u00f3ricas. No caso de Alberto Aleixo, por exemplo, que foi o respons\u00e1vel pelo jornal Voz Oper\u00e1ria, do PCB, o autor aproveita para juntar fragmentos da hist\u00f3ria da imprensa comunista no Brasil e no mundo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"90307\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/rolim-nelson-capa-livro\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png\" data-orig-size=\"441,549\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Rolim Nelson capa livro\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png\" class=\"alignnone size-full wp-image-90307\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png\" alt=\"\" width=\"441\" height=\"549\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png 441w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro-241x300.png 241w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/p>\n<p>Antes de iniciar em 2022 essa s\u00e9rie denominada Cole\u00e7\u00e3o Ponto Final*, Rolim lan\u00e7ou em 2015 &#8220;N\u00e3o Esquecemos a DITADURA &#8211; Mem\u00f3rias da Viol\u00eancia\u201d, livro de 360 p\u00e1ginas em que conta a hist\u00f3ria do per\u00edodo mais agitado de sua vida entre seus 18\/30 anos.<\/p>\n<p>Nascido em Bag\u00e9 em 1951, filho de um coronel do Ex\u00e9rcito, entrou em 69 na Faculdade de Engenharia em Porto Alegre e logo se envolveu nas lutas estudantis.<\/p>\n<p>Entusiasmado com o &#8220;Di\u00e1rio de Che Guevara&#8221;, emprestado por um colega da Geologia, aderiu ao PCdoB. \u201cVagas para os excedentes dos vestibulares\u201d foi uma das principais reivindica\u00e7\u00f5es em panfletos e passeatas.<\/p>\n<p>Em 71\/72, acabou respondendo pela dire\u00e7\u00e3o do DCE ap\u00f3s a expuls\u00e3o de quatro l\u00edderes de centros acad\u00eamicos da UFRGS.<\/p>\n<p>Em setembro de 1973, sentindo-se isolado e em perigo no Rio Grande do Sul, decidiu escapar. A p\u00e9. Quem o levou \u00e0 fronteira com a Argentina foi um tio.<\/p>\n<p>\u201cEle me deixou na cabeceira da ponte em Uruguaiana. Pedi que ficasse na camioneta Rural Willys observando se eu chegaria ao outro lado do rio\u201d, lembra Rolim, que temia ser pego na travessia para Paso de Los Libres.<\/p>\n<p>De trem, chegou a Buenos Aires. Pensava em ir para Santiago confraternizar com a brasileirada l\u00e1 acampada quando a capital argentina come\u00e7ou a receber fugitivos do golpe militar com que o general Pinochet derrubou o governo de Salvador Allende, eleito em 1970.<\/p>\n<p>Acolhido por peronistas influentes, especialmente Jorge Abelardo Ramos, autor do cl\u00e1ssico \u201cHist\u00f3ria da Na\u00e7\u00e3o Latino-americana\u201d, ficou na Argentina trabalhando em livrarias e gr\u00e1ficas da capital, de Tucuman e de Salta. Para todos os efeitos, era chamado de \u201cJuan\u201d, militante do Partido Socialista da Izquierda Nacional (PSIN).<\/p>\n<p>Assim passou a sobreviver de livros numa \u00e9poca de grande efervesc\u00eancia em Buenos Aires, a cidade que possu\u00eda mais livrarias do que no Brasil inteiro, segundo se dizia.<\/p>\n<p>Em fins de 1975, impressionado com a confus\u00e3o pol\u00edtica na Argentina, que caminhava para o golpe militar de mar\u00e7o de 76, buscou ref\u00fagio no Uruguai, mas foi preso na entrada do pa\u00eds.<\/p>\n<p>Ficou v\u00e1rios dias vendado em cadeias de passagem, no meio de tupamaros, mas se lembra de ter entrevisto por baixo da venda as palmeiras existentes na famosa pris\u00e3o de La Rambla.<\/p>\n<p>Um dia, foi embarcado num jipe militar em que viajou vendado de Montevideo a Rivera-Livramento. Soube depois que o objetivo da viagem era entreg\u00e1-lo \u00e0s autoridades militares brasileiras. Quem o levou foi um dos chefes do setor de informa\u00e7\u00f5es do Uruguai.<\/p>\n<p>Por incr\u00edvel que possa parecer \u2013 naquele momento j\u00e1 se articulava a Opera\u00e7\u00e3o Condor &#8211;, o preso n\u00e3o foi recebido.. A recusa brasileira foi veemente.<\/p>\n<p>Alguns dias depois de voltar de Rivera, onde ficou trancado num caminh\u00e3o-ba\u00fa, Rolim foi escoltado at\u00e9 o aeroporto de Montevideo, onde o colocaram num avi\u00e3o comercial da Varig para Porto Alegre.<\/p>\n<p>Era 15 de dezembro de 1975, o da em que foi recebido efusivamente por militantes que haviam feito campanha por sua liberta\u00e7\u00e3o. Entre eles, encontravam-se familiares, estudantes e pol\u00edticos do MDB, liderados na \u00e9poca por Pedro Simon.<\/p>\n<p>De volta ao seu ninho estudantil, Rolim recontatou amigos e colegas de antes, mas n\u00e3o teve \u00edmpeto para retomar a vida estudantil &#8212; faltavam dois anos para concluir o curso de engenharia.<\/p>\n<p>Em busca de trabalho, um dos seus bicos mais gratificantes foi no Teatro de Arena, onde cumpriu tarefas na portaria e nos bastidores de pe\u00e7as como Mockinpott e nas Rodas de Samba das sextas-feiras \u00e0 meia noite, sob a dire\u00e7\u00e3o de Jairo de Andrade.<\/p>\n<p>Durante o dia, o amigo Luiz Oscar Matzenbacher lhe arranjou um servi\u00e7o na se\u00e7\u00e3o de fotocomposi\u00e7\u00e3o do di\u00e1rio Zero Hora, onde ia tudo aparentemente bem at\u00e9 que, do sobsolo onde trabalhava, viu subir as escadas rumo \u00e0 reda\u00e7\u00e3o do jornal o delegado Pedro Seelig, que tinha contatos na dire\u00e7\u00e3o do jornal.\u00a0 E agora?<\/p>\n<p>Temendo ser ele, Nelson Rolim de Moura, o motivo da ilustre visita, abandonou seu posto e tomou o rumo de Florian\u00f3polis, onde j\u00e1 trabalhavam v\u00e1rios jornalistas sa\u00eddos do Rio Grande do Sul.<\/p>\n<p>Tudo isso e muito mais est\u00e1 contado detalhadamente no livro \u201cN\u00e3o Esquecemos a DITADURA \u2013 Mem\u00f3rias da Viol\u00eancia\u201d (Insular, 2015). Como suas anota\u00e7\u00f5es do ex\u00edlio haviam ca\u00eddo nas m\u00e3os da pol\u00edcia uruguaia, ele recorreu \u00e0 mem\u00f3ria e buscou amparo em relatos alheios para recontar acontecimentos que fazem parte da hist\u00f3ria do Brasil.<\/p>\n<p>Numa narrativa trepidante, combina fatos pessoais com informa\u00e7\u00f5es em tom levemente panflet\u00e1rio de esquerda. \u201cEsta \u00e9 uma longa cr\u00f4nica na primeira pessoa, como quase todos os livros publicados sobre esse per\u00edodo&#8230;\u201d (refere-se \u00e0 ditadura militar brasileira).<\/p>\n<p>\u201cN\u00e3o queria me colocar no papel central desta hist\u00f3ria, por\u00e9m esta me pareceu a forma mais simples de desenvolv\u00ea-la, at\u00e9 porque meu testemunho pessoal \u00e9 o fio condutor em quase toda a narrativa\u201d, orientada explicitamente por quatro far\u00f3is hist\u00f3ricos: as revolu\u00e7\u00f5es socialistas de 1917 na R\u00fassia, de 1949 na China, de 1959 em Cuba e dos anos 1970 no Chile de Allende.<\/p>\n<p>Como lanterna de popa, reconhece a Revolu\u00e7\u00e3o Francesa de 1789, que consagrou os direitos universais do Homem. Nesse livro de mem\u00f3rias, escrito quando estava completando 60 anos, ele afirma ter pressa de escrever porque \u201co tempo est\u00e1 passando muito r\u00e1pido\u201d.<\/p>\n<p>EM FLORIAN\u00d3POLIS<\/p>\n<p>Quando chegou \u00e0 ilha de Santa Catarina, no final dos anos 70, Rolim come\u00e7ou como rep\u00f3rter no jornal O Estado, o mais importante di\u00e1rio catarinense.<\/p>\n<p>Na reda\u00e7\u00e3o se tornou amigo do ga\u00facho M\u00e1rio Medaglia e do catarinense Cesar Valente, que havia estudado jornalismo em Porto Alegre. Naquele momento, v\u00e1rios jornalistas do Rio Grande do Sul chegavam para trabalhar no Di\u00e1rio Catarinense na capital e no Jornal de Santa Catarina em Blumenau, ambos criados pelo grupo RBS.<\/p>\n<p>Alguns dos migrantes chegaram para dar aulas no curso de Jornalismo da incipiente UFSC.<\/p>\n<p>Al\u00e9m de escrever, inclusive para sucursais de jornais de fora, Rolim se matriculou no curso de Hist\u00f3ria, mas n\u00e3o foi adiante nesse intento estudantil. Manteve na universidade a namorada Iara Germer, que se tornaria a m\u00e3e de seus quatro filhos.<\/p>\n<p>Na entrada dos anos 80, participou como s\u00f3cio-fundador do \u00a0mens\u00e1rio nanico Afinal, que n\u00e3o foi al\u00e9m de 13 edi\u00e7\u00f5es. \u201cN\u00f3s mud\u00e1vamos de gr\u00e1fica a cada edi\u00e7\u00e3o para evitar a apreens\u00e3o do jornal\u201d, lembra ele.<\/p>\n<p>O primeiro n\u00famero foi composto pela Coojornal de Porto Alegre. O \u00faltimo, por uma gr\u00e1fica de S\u00e3o Jos\u00e9 (SC), cujo dono lhe cobrou caro e o entregou \u00e0 pol\u00edcia.<\/p>\n<p>Na sequ\u00eancia, ele arranjou servi\u00e7os como assessor de imprensa e trabalhou na editora da UFSC, o que lhe abriu caminho para a funda\u00e7\u00e3o de sua pr\u00f3pria editora, a Insular, seu principal meio de sobreviv\u00eancia a partir da d\u00e9cada de 1990.<\/p>\n<p><strong>Cole\u00e7\u00e3o &#8220;Ponto Final&#8221;<\/strong><\/p>\n<p>Ap\u00f3s o lan\u00e7amento do seu livro de mem\u00f3rias, h\u00e1 nove anos, Rolim concluiu que estava na hora de desovar material acumulado ao longo de sua vida como editor de livros \u2013 a Insular tem um acervo de 1500 t\u00edtulos.<\/p>\n<p>Confessa ent\u00e3o que, ao transpor os 60 anos de vida, decidiu se desfazer de suas quatro paredes de livros, ficando somente com material sobre \u201cos crimes da ditadura\u201d.<\/p>\n<p>Sem um plano claramente delineado, escrevia freneticamente quando um de seus quatro netos lhe sugeriu que, em vez de fazer um catatau imensur\u00e1vel sobre as lutas contra a ditadura, dedicasse um livro a cada um dos seus personagens.<\/p>\n<p>Chegou assim \u00e0 lista de 38 nomes.<\/p>\n<p>Ao se voluntariar como histori\u00f3grafo, n\u00e3o teve tempo nem recursos para colher depoimentos, atendo-se apenas ao acervo bibliogr\u00e1fico e \u00e0 documenta\u00e7\u00e3o dispon\u00edvel, al\u00e9m de imbuir-se da vontade de realizar o projeto, iniciado em pleno isolamento imposto pela pandemia do coronavirus.<\/p>\n<p>Entretanto, a experi\u00eancia como editor de livros lhe deu amplo acesso a consultas de arquivos de jornais, obras liter\u00e1rias e teses acad\u00eamicas.<\/p>\n<p>Al\u00e9m disso, ele tem conclus\u00f5es pr\u00f3prias sobre a din\u00e2mica da Hist\u00f3ria. \u201cA imprensa sempre foi a alma dos partidos e das organiza\u00e7\u00f5es de esquerda\u201d, escreveu na biografia de Alberto Aleixo, relembrando o nascimento do jornal A Classe Oper\u00e1ria, lan\u00e7ado pelo rec\u00e9m-fundado PCB em 1\u00ba de maio de 1925, quando o mineiro Aleixo, nascido em Belo Horizonte em 1903, j\u00e1 trabalhava em jornal no Rio.<\/p>\n<p>Para produzir tantos livros em t\u00e3o pouco tempo \u2013 se lan\u00e7ar dois livros por ano, terminar\u00e1 sua tarefa dentro dos pr\u00f3ximos 16 anos &#8211;, Rolim dorme cedo e acorda antes das 4h da manh\u00e3 para escrever.<\/p>\n<p>No in\u00edcio do hor\u00e1rio comercial matutino vai para a Insular, empresa familiar onde se ocupa sobretudo de pesquisas para sua obra hist\u00f3rico-liter\u00e1ria,<\/p>\n<p>A \u00a0rotina da editora est\u00e1 aos cuidados de dois eficientes funcion\u00e1rios: o filho Daniel e a secret\u00e1ria Renata.<\/p>\n<p>*A LISTA DE BIOGRAFIAS DA COLE\u00c7\u00c3O PONTO FINAL:<\/p>\n<p>-Alberto Aleixo<\/p>\n<p>-Alexandre Von Baumgarten<\/p>\n<p>-Antonio Benetazzo<\/p>\n<p>-Carlos Alberto de Freitas<\/p>\n<p>-Carlos Marighella<\/p>\n<p>-Carlos Nicolau Danielli<\/p>\n<p>-David Capistrano da Costa<\/p>\n<p>-Edmur P\u00e9ricles Camargo<\/p>\n<p>-Elson Costa<\/p>\n<p>-Fl\u00e1vio Ferreira da Silva<\/p>\n<p>-Gerardo Magela da Costa<\/p>\n<p>-Gilberto Olimpio Maria<\/p>\n<p>-Hiran de Lima Pereira<\/p>\n<p>-Ieda Santos Delgado<\/p>\n<p>-Isarael Tavares Roque<\/p>\n<p>-Jane Vanini<\/p>\n<p>-Jayme Amorim de Miranda<\/p>\n<p>-Joaquim C\u00e2mara Ferreira<\/p>\n<p>-Jos\u00e9 Toledo de Oliveira<\/p>\n<p>-Lincoln Cordeiro Oest<\/p>\n<p>-Luiz Ricardo da Rocha Merlino<\/p>\n<p>-Luiz Ghilardini<\/p>\n<p>-Luiz In\u00e1cio Maranh\u00e3o Filho<\/p>\n<p>-Mariano Joaquim da Silva<\/p>\n<p>-Mario Alves de Souza Vieira<\/p>\n<p>-M\u00e1rio Eugenio de Oliveira<\/p>\n<p>-Mauricio Grabois<\/p>\n<p>-Nestor Veras<\/p>\n<p>-Norberto Armando Habegger<\/p>\n<p>-Orlando Bonfim Junior<\/p>\n<p>-Pedro Domiense de Oliveira<\/p>\n<p>-Pedro Pomar<\/p>\n<p>-Rui Pfutzenreuter<\/p>\n<p>-Sidney Fix Marques dos Santos<\/p>\n<p>-Thomaz Antonio Meirelles<\/p>\n<p>-Vladimir Herzog<\/p>\n<p>-Walter de Souza Ribeiro<\/p>\n<p>-Wanio Jos\u00e9 de Mattos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90303,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-90300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"441\" \/>\n\t\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-20T15:34:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-07T11:33:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#article\",\"name\":\"Jornalista biografa v\\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura\",\"headline\":\"Jornalista biografa v\\u00edtimas da ditadura: projeto para encher um metro de estante\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/11\\\/rolim-nelson-2.png\",\"width\":869,\"height\":626,\"caption\":\"Nelson Rolim: projeto para 16 anos de trabalho. Foto: UFPEL\\\/Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2024-11-20T12:34:51-03:00\",\"dateModified\":\"2024-12-07T08:33:45-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#listItem\",\"name\":\"Jornalista biografa v\\u00edtimas da ditadura: projeto para encher um metro de estante\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#listItem\",\"position\":3,\"name\":\"Jornalista biografa v\\u00edtimas da ditadura: projeto para encher um metro de estante\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/\",\"name\":\"Jornalista biografa v\\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura\",\"description\":\"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\\u00e1 quase 50 anos em Florian\\u00f3polis, onde toca a sua pr\\u00f3pria Editora Insular, est\\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\\u00f3ria liter\\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\\u00e7ando em 2022,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/11\\\/rolim-nelson-2.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#mainImage\",\"width\":869,\"height\":626,\"caption\":\"Nelson Rolim: projeto para 16 anos de trabalho. Foto: UFPEL\\\/Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/projeto-para-encher-um-metro-de-estante\\\/#mainImage\"},\"datePublished\":\"2024-11-20T12:34:51-03:00\",\"dateModified\":\"2024-12-07T08:33:45-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura","description":"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#article","name":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura","headline":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-2.png","width":869,"height":626,"caption":"Nelson Rolim: projeto para 16 anos de trabalho. Foto: UFPEL\/Divulga\u00e7\u00e3o"},"datePublished":"2024-11-20T12:34:51-03:00","dateModified":"2024-12-07T08:33:45-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#listItem","name":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#listItem","position":3,"name":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/","name":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura","description":"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-2.png","@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#mainImage","width":869,"height":626,"caption":"Nelson Rolim: projeto para 16 anos de trabalho. Foto: UFPEL\/Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/#mainImage"},"datePublished":"2024-11-20T12:34:51-03:00","dateModified":"2024-12-07T08:33:45-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura","og:description":"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,","og:url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-para-encher-um-metro-de-estante\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png","og:image:width":441,"og:image:height":549,"article:published_time":"2024-11-20T15:34:51+00:00","article:modified_time":"2024-12-07T11:33:45+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Jornalista biografa v\u00edtimas da ditadura: projeto para encher um metro de estante | Cultura","twitter:description":"GERALDO HASSE O bageense Nelson Rolim de Moura, que vive h\u00e1 quase 50 anos em Florian\u00f3polis, onde toca a sua pr\u00f3pria Editora Insular, est\u00e1 engajado de corpo e alma num projeto sem precedentes na hist\u00f3ria liter\u00e1ria brasileira: o de escrever sozinho 38 livros sobre jornalistas mortos ou desaparecidos pela ditadura de 1964-85. Come\u00e7ando em 2022,","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-capa-livro.png"},"aioseo_meta_data":{"post_id":"90300","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-20 14:30:07","updated":"2025-06-04 14:27:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":90086,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-biografia-ruy-carlos-ostermann-um-encontro-com-o-professor-chega-as-livrarias\/","url_meta":{"origin":90300,"position":0},"title":"A biografia &#8220;Ruy Carlos Ostermann \u2013 um encontro com o Professor&#8221;\u00a0chega \u00e0s livrarias","author":"da Reda\u00e7\u00e3o","date":"15 de outubro de 2024","format":false,"excerpt":"O livro Ruy Carlos Ostermann \u2013 um encontro com o Professor, estar\u00e1 dispon\u00edvel nas livrarias da cidade a partir de 19 de outubro. Ainda em fase de pr\u00e9-venda at\u00e9 dia 18, o livro j\u00e1 \u00e9 um sucesso segundo o material de divulga\u00e7\u00e3o. Escrita pelo jornalista e tamb\u00e9m comentarista esportivo Carlos\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes-4-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes-4-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes-4-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes-4-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes-4-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/10\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes-4-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":85356,"url":"https:\/\/www.jornalja.com.br\/cultura\/em-biografia-de-nara-leao-a-intimidade-de-uma-mulher-que-revolucionou-a-cultura-brasileira\/","url_meta":{"origin":90300,"position":1},"title":"Em biografia de Nara Le\u00e3o, a intimidade de uma mulher que revolucionou a cultura brasileira","author":"Higino Barros","date":"17 de janeiro de 2022","format":false,"excerpt":"Anivers\u00e1rio de 80 anos da cantora que foi s\u00edmbolo de resist\u00eancia \u00e0 ditadura militar seria no dia 19 de janeiro. Jornalista Tom Cardoso resgata sua hist\u00f3ria. Nara Le\u00e3o certamente foi uma das artistas mais importantes e influentes da cultura brasileira, n\u00e3o s\u00f3 pela sua obra, mas pelo que representou para\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/01\/nara-leao.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":91316,"url":"https:\/\/www.jornalja.com.br\/cultura\/daniel-de-andrade-1948-2025\/","url_meta":{"origin":90300,"position":2},"title":"Daniel de Andrade (1948 &#8211; 2025)\u00a0","author":"Elmar Bones","date":"26 de agosto de 2025","format":false,"excerpt":"CARLOS CARAMEZ O meu amigo Dani Boy ou Daniel de Andrade Sim\u00f5es, que faleceu hoje, era um baiano ga\u00facho muito retado, talentoso fot\u00f3grafo e jornalista, que vai deixar muitas saudades e um acervo fotogr\u00e1fico important\u00edssimo. Nascido em Rio Real(BA), adotou o Rio Grande do Sul como sua morada definitiva. Casou\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/08\/daniel-andrade-mar.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":90226,"url":"https:\/\/www.jornalja.com.br\/cultura\/livro-sobre-ruy-carlos-ostermann-tera-lancamento-bate-papo-e-autografos-dia-na-feira-do-livro-de-porto-alegre\/","url_meta":{"origin":90300,"position":3},"title":"Livro sobre Ruy Carlos Ostermann ter\u00e1 lan\u00e7amento, bate-papo e aut\u00f3grafos dia 12 na Feira do Livro de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"5 de novembro de 2024","format":false,"excerpt":"O Professor Ruy Ostermann estava feliz da vida no lan\u00e7amento de sua biografia, escrita pelo jornalista e tamb\u00e9m comentarista esportivo Carlos Guimar\u00e3es, no Book Hall, no \u00faltimo dia 23. \u201cMe senti vivo e disposto. Revi colegas e amigos, um momento realmente muito especial pra mim\u201d, afirma Ruy, que no alto\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/ruy-carlos-ostermann-e-carlos-guimaraes-rogerio-fernandes.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":81811,"url":"https:\/\/www.jornalja.com.br\/cultura\/barulhaco-desta-noite-e-para-lembrar-que-a-ditadura-ainda-vive\/","url_meta":{"origin":90300,"position":4},"title":"Barulha\u00e7o desta noite \u00e9 para lembrar que a ditadura ainda vive","author":"Elmar Bones","date":"31 de mar\u00e7o de 2020","format":false,"excerpt":"Nota do Comit\u00ea Carlos de R\u00e9 pela Verdade e a Justi\u00e7a: Em pleno ano de 2020, nosso pais segue padecendo a heran\u00e7a brutal dos crimes de lesa-humanidade e destrui\u00e7\u00e3o da Democracia. A impunidade dessas d\u00e9cadas germina nos autorit\u00e1rios e seviciadores de hoje, agora enquistados no Estado Brasileiro. H\u00e1 um ano,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/03\/1964-Luta-na-Janela.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":82693,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-vez-de-chacarera-blues-em-relancamento-nas-plataformas-digitais\/","url_meta":{"origin":90300,"position":5},"title":"A vez de Chacarera Blues, em relan\u00e7amento, nas plataformas digitais","author":"da Reda\u00e7\u00e3o","date":"21 de setembro de 2020","format":false,"excerpt":"Pioneiro na disponibiliza\u00e7\u00e3o integral na Internet h\u00e1 15 anos , o \u00e1lbum Chacarera Blues ser\u00e1 relan\u00e7ado nas\u00a0 plataformas digitais dia 25 de setembro data que se completam dez meses da morte do autor. Trabalho autoral de Alexandre Vieira, re\u00fane 16 can\u00e7\u00f5es, de mais de vinte anos de composi\u00e7\u00e3o,\u00a0 e conta\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/09\/capa-album-chacarera-blues.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/09\/capa-album-chacarera-blues.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/09\/capa-album-chacarera-blues.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/09\/capa-album-chacarera-blues.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/09\/capa-album-chacarera-blues.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/09\/capa-album-chacarera-blues.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-nus","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2024\/11\/rolim-nelson-2.png","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/90300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=90300"}],"version-history":[{"count":5,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/90300\/revisions"}],"predecessor-version":[{"id":90308,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/90300\/revisions\/90308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/90303"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=90300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=90300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=90300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}