{"id":91232,"date":"2025-08-02T19:39:18","date_gmt":"2025-08-02T22:39:18","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=91232"},"modified":"2025-08-02T19:40:41","modified_gmt":"2025-08-02T22:40:41","slug":"reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/","title":{"rendered":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio"},"content":{"rendered":"<p>Dono de v\u00e1rios bares e restaurantes em Porto Alegre,\u00a0 nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome.<\/p>\n<p>O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o de Artes C\u00eanicas j\u00e1 est\u00e1 a disposi\u00e7\u00e3o dos interessados na &#8220;permiss\u00e3o de uso&#8221;.<\/p>\n<p>O primeiro preg\u00e3o est\u00e1 marcada para ter\u00e7a-feira, 19 de agosto, \u00e0s 10h, e ser\u00e1 realizada no site <em>portaldecompraspublicas.com.br<\/em>.<\/p>\n<p>Os licitantes concorrem pela maior outorga mensal para explora\u00e7\u00e3o do espa\u00e7o. O valor a ser pago mensalmente ao Munic\u00edpio para a permiss\u00e3o de uso \u00e9 de R$ 2.400.<\/p>\n<p>O Centro Municipal de Cultura recebe atividades culturais durante todo o ano com a programa\u00e7\u00e3o do Teatro Renascen\u00e7a e da Sala \u00c1lvaro Moreyra.<\/p>\n<p>Tamb\u00e9m est\u00e3o instalados no local a Biblioteca P\u00fablica Municipal Josu\u00e9 Guimar\u00e3es e o Atelier Livre Xico Stockinger.<\/p>\n<p><strong>(Com informa\u00e7\u00f5es da Assessoria de Imprensa)<\/strong><br \/>\n<strong>\u00a0<\/strong><br \/>\n<strong>\u00a0<\/strong><br \/>\n<strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dono de v\u00e1rios bares e restaurantes em Porto Alegre,\u00a0 nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":85862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-91232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-02T22:39:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-02T22:40:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#article\",\"name\":\"Reabertura do Bar do Lupi: Prefeitura lan\\u00e7a edital para selecionar permission\\u00e1rio | Cultura\",\"headline\":\"Reabertura do Bar do Lupi: Prefeitura lan\\u00e7a edital para selecionar permission\\u00e1rio\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/musa-5-lupi-copy.png\",\"width\":853,\"height\":1280,\"caption\":\"Lupic\\u00ednio Rodrigues por Gra\\u00e7a Craidy\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2025-08-02T19:39:18-03:00\",\"dateModified\":\"2025-08-02T19:40:41-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#listItem\",\"name\":\"Reabertura do Bar do Lupi: Prefeitura lan\\u00e7a edital para selecionar permission\\u00e1rio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#listItem\",\"position\":3,\"name\":\"Reabertura do Bar do Lupi: Prefeitura lan\\u00e7a edital para selecionar permission\\u00e1rio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/\",\"name\":\"Reabertura do Bar do Lupi: Prefeitura lan\\u00e7a edital para selecionar permission\\u00e1rio | Cultura\",\"description\":\"Dono de v\\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\\u00e1 fechado, mas a prefeitura quer reabr\\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\\u00e7\\u00e3o\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/musa-5-lupi-copy.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#mainImage\",\"width\":853,\"height\":1280,\"caption\":\"Lupic\\u00ednio Rodrigues por Gra\\u00e7a Craidy\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\\\/#mainImage\"},\"datePublished\":\"2025-08-02T19:39:18-03:00\",\"dateModified\":\"2025-08-02T19:40:41-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura","description":"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#article","name":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura","headline":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/musa-5-lupi-copy.png","width":853,"height":1280,"caption":"Lupic\u00ednio Rodrigues por Gra\u00e7a Craidy\/ Divulga\u00e7\u00e3o"},"datePublished":"2025-08-02T19:39:18-03:00","dateModified":"2025-08-02T19:40:41-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#listItem","name":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#listItem","position":3,"name":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/","name":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura","description":"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/musa-5-lupi-copy.png","@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#mainImage","width":853,"height":1280,"caption":"Lupic\u00ednio Rodrigues por Gra\u00e7a Craidy\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/#mainImage"},"datePublished":"2025-08-02T19:39:18-03:00","dateModified":"2025-08-02T19:40:41-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura","og:description":"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o","og:url":"https:\/\/www.jornalja.com.br\/cultura\/reabertura-do-bar-do-lupi-prefeitura-lanca-edital-para-selecionar-permissionario\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2025-08-02T22:39:18+00:00","article:modified_time":"2025-08-02T22:40:41+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Reabertura do Bar do Lupi: Prefeitura lan\u00e7a edital para selecionar permission\u00e1rio | Cultura","twitter:description":"Dono de v\u00e1rios bares e restaurantes em Porto Alegre, nos quais dizia n\u00e3o querer ganhar dinheiro, mas apenas reunir os amigos, o compositor Lupic\u00edno Rodrigues ganhou um bar no Centro Municipal de Cultura que leva seu nome. O bar est\u00e1 fechado, mas a prefeitura quer reabr\u00ed-lo. Um edital da Secretaria de Cultura e da Coordena\u00e7\u00e3o","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"91232","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-08-02 22:10:03","updated":"2025-08-02 22:50:20","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":72105,"url":"https:\/\/www.jornalja.com.br\/cultura\/fumproarte-paga-dividas-a-produtores-culturais-e-retoma-edital-para-novos-projetos\/","url_meta":{"origin":91232,"position":0},"title":"Fumproarte paga d\u00edvidas a produtores culturais e retoma edital para  novos projetos","author":"da Reda\u00e7\u00e3o","date":"4 de janeiro de 2019","format":false,"excerpt":"A prefeitura, por meio da Secretaria Municipal da Cultura, d\u00e1 continuidade em 2019 ao calend\u00e1rio de pagamento das d\u00edvidas do Fundo Municipal de Apoio \u00e0 Produ\u00e7\u00e3o Art\u00edstica e Cultural de Porto Alegre (Fumproarte). Os pagamentos seguem um plano estruturado pela Secretaria Municipal da Fazenda. Para 2019 est\u00e1 projetado o valor\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":85963,"url":"https:\/\/www.jornalja.com.br\/cultura\/noite-dos-museus-o-reencontro-da-populacao-da-capital-com-a-cidade-atraves-da-arte\/","url_meta":{"origin":91232,"position":1},"title":"Noite dos Museus:  o reencontro da popula\u00e7\u00e3o da capital com a cidade , atrav\u00e9s da arte","author":"Higino Barros","date":"23 de maio de 2022","format":false,"excerpt":"Higino Barros Porto Alegre j\u00e1 tem o evento cultural mais impactante do ano: A Noite dos Museus, ocorrida no s\u00e1bado, dia 21, em 20 equipamentos culturais da cidade, que levou \u00e0s ruas da capital ga\u00facha cerca de 180 mil pessoas, segundo os c\u00e1lculos dos seus organizadores. H\u00e1 dois anos o\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/noite-dos-museus-palacio-piratini-foto-alvaro-bonadiman-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/noite-dos-museus-palacio-piratini-foto-alvaro-bonadiman-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/noite-dos-museus-palacio-piratini-foto-alvaro-bonadiman-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/noite-dos-museus-palacio-piratini-foto-alvaro-bonadiman-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":91666,"url":"https:\/\/www.jornalja.com.br\/cultura\/bar-tutti-giorni-resgata-sua-historia-com-reencontro-de-cartunistas-e-show-musical\/","url_meta":{"origin":91232,"position":2},"title":"Bar Tutti Giorni resgata sua hist\u00f3ria com reencontro de cartunistas e show musical","author":"da Reda\u00e7\u00e3o","date":"4 de dezembro de 2025","format":false,"excerpt":"A cena cultural de Porto Alegre ganha um importante reencontro nesta sexta-feira, 5 de dezembro, com o retorno dos encontros de cartunistas no tradicional bar Tutti Giorni, na escadaria do Viaduto Ot\u00e1vio Rocha, na avenida Borges de Medeiros, ao lado do Hotel Savoy. Sob nova gest\u00e3o do agente cultural Pepe\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/12\/tutti-o-retorno.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":87842,"url":"https:\/\/www.jornalja.com.br\/cultura\/time-de-futebol-de-musicos-celebra-26-anos-de-existencia-no-bar-odeon\/","url_meta":{"origin":91232,"position":3},"title":"Time de futebol de m\u00fasicos celebra 26 anos de exist\u00eancia, no Bar Odeon","author":"Higino Barros","date":"9 de maio de 2023","format":false,"excerpt":"\u00a0 Higino Barros O Bar Odeon, local m\u00edtico no centro de Porto Alegre, por ter uma programa\u00e7\u00e3o musical que contempla o que h\u00e1 de melhor na produ\u00e7\u00e3o instrumental e vocal ga\u00facha, principalmente jazz, abriga nesse s\u00e1bado, dia 13, uma comemora\u00e7\u00e3o: o encontro do Bota Fogo, um time de futebol que\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/05\/odeon-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/05\/odeon-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/05\/odeon-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/05\/odeon-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/05\/odeon-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":82407,"url":"https:\/\/www.jornalja.com.br\/cultura\/prefeitura-lanca-dois-editais-emergenciais-para-o-setor-cultural\/","url_meta":{"origin":91232,"position":4},"title":"Prefeitura lan\u00e7a dois editais emergenciais para o setor cultural","author":"da Reda\u00e7\u00e3o","date":"14 de julho de 2020","format":false,"excerpt":"Com o objetivo de premiar propostas de pessoas f\u00edsicas e jur\u00eddicas, com ou sem fins lucrativos, como de artistas, t\u00e9cnicos, produtores, grupos art\u00edsticos e espa\u00e7os da cadeia produtiva cultural estabelecidos em Porto Alegre, foram lan\u00e7ados, nesta ter\u00e7a-feira, 14, dois editais emergenciais de aux\u00edlio \u00e0 cultura. O an\u00fancio foi feito pelo\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/07\/200714-captura-de-tela-pmpa-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/07\/200714-captura-de-tela-pmpa-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/07\/200714-captura-de-tela-pmpa-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/07\/200714-captura-de-tela-pmpa-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":81797,"url":"https:\/\/www.jornalja.com.br\/cultura\/premio-acorianos-de-literatura-inscricao-pode-ser-por-email\/","url_meta":{"origin":91232,"position":5},"title":"Pr\u00eamio A\u00e7orianos de Literatura: inscri\u00e7\u00e3o pode ser por email.","author":"da Reda\u00e7\u00e3o","date":"27 de mar\u00e7o de 2020","format":"aside","excerpt":"A prefeitura retificou o edital do Pr\u00eamio A\u00e7orianos de Literatura. Os candidatos agora podem se inscrever pelo email\u00a0cll@smc.prefpoa.com.br\u00a0at\u00e9 a ter\u00e7a-feira, 31. A altera\u00e7\u00e3o ocorreu devido \u00e0 suspens\u00e3o das atividades do Centro Municipal de Cultura, em fun\u00e7\u00e3o da pandemia do coronav\u00edrus. Os candidatos devem enviar a ficha de inscri\u00e7\u00e3o e o\u2026","rel":"","context":"Em &quot;Cultura-NOTAS&quot;","block_context":{"text":"Cultura-NOTAS","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/culturanotas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-nJu","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/05\/musa-5-lupi-copy.png","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/91232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=91232"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/91232\/revisions"}],"predecessor-version":[{"id":91233,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/91232\/revisions\/91233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/85862"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=91232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=91232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=91232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}