{"id":100728,"date":"2026-02-10T18:07:42","date_gmt":"2026-02-10T21:07:42","guid":{"rendered":"https:\/\/www.jornalja.com.br\/geral\/?p=100728"},"modified":"2026-02-12T19:06:37","modified_gmt":"2026-02-12T22:06:37","slug":"caminhos-da-ditadura-em-porto-alegre-cruza-a-fronteira-e-vai-a-argentina","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/caminhos-da-ditadura-em-porto-alegre-cruza-a-fronteira-e-vai-a-argentina\/","title":{"rendered":"Caminhos da Ditadura em Porto Alegre cruza a fronteira e vai \u00e0 Argentina"},"content":{"rendered":"<p class=\"assina\">M\u00e1rcia Turcato<\/p>\n<p>A iniciativa Caminhos da Ditadura em Porto Alegre completa 10 anos. O projeto come\u00e7ou a ser constru\u00eddo em 2016 por estudantes do curso de Hist\u00f3ria da Universidade Federal do Rio Grande do Sul (UFRGS). Em janeiro de 2026, o Caminhos cruzou a fronteira e foi at\u00e9 Buenos Aires, capital da Argentina, dando mais contexto aos relatos de exterm\u00ednio que uniu ditaduras do Cone Sul sob as asas da Opera\u00e7\u00e3o Condor, coordenada pelos Estados Unidos, com o objetivo de eliminar advers\u00e1rios pol\u00edticos transfronteiri\u00e7os.<\/p>\n<p>A professora de Hist\u00f3ria Anita Natividade Carneiro, 30 anos, que criou o Caminhos em 2016, est\u00e1 \u00e0 frente do projeto que levou um grupo de 28 pessoas \u00e0 Argentina, em parceria com a arquiteta Cec\u00edlia Giovenardi Esteve, 38 anos, que tamb\u00e9m \u00e9 guia de turismo e integra o grupo de mediadoras do Caminhos. Juntas elas constru\u00edram um intenso roteiro de visitas a centros de mem\u00f3ria e encontros com sobreviventes de campos de exterm\u00ednio, ativistas, pessoas que foram sequestradas quando crian\u00e7as e outras que nasceram no c\u00e1rcere.<\/p>\n<p>O grupo conheceu testemunhos potentes que exp\u00f5em os b\u00e1rbaros m\u00e9todos de tortura e exterm\u00ednio praticados na Argentina durante a ditadura mais cruel vivida pelo pa\u00eds, de 24 de mar\u00e7o de 1976 a 10 de dezembro de 1983. Foram 2.818 dias de crimes hediondos cometidos pelo Estado, que implantou mais de 800 centros de tortura e exterm\u00ednio, sequestrou e desapareceu com 30.000 pessoas e se apropriou de 500 beb\u00eas nascidos na pris\u00e3o ou que foram sequestrados. At\u00e9 o momento, apenas 140 pessoas, nascidas no c\u00e1rcere, recuperam sua verdadeira identidade.<\/p>\n<p class=\"intertit\">Clube Atl\u00e9tico e Universidade das Madres<\/p>\n<p>O minucioso roteiro da viagem iniciou com uma visita ao local onde funcionou o Clube Atl\u00e9tico, que serviu como Centro Clandestino de Deten\u00e7\u00e3o, Tortura e Exterm\u00ednio, de 1976 a 1983. Cerca de 1.500 pessoas foram presas no local, \u201cque era um verdadeiro campo de concentra\u00e7\u00e3o\u201d, afirmou o sobrevivente Daniel Mercogliano, 75 anos, sequestrado em casa no dia 19 de abril de 1977. Ao dar seu testemunho, Daniel estava acompanhado de S\u00edlvia Fontana, irm\u00e3 de Liliana Fontana, sequestrada e desaparecida desde o dia 01 de julho de 1977.<\/p>\n<p>De acordo com o testemunho de Daniel, \u201cos centros de tortura faziam parte de um plano de exterm\u00ednio do governo militar, era terrorismo de Estado\u201d. Daniel disse tamb\u00e9m que \u201ca classe dominadora seguiu acumulando dinheiro e poder enquanto a classe oper\u00e1ria era presa, torturada e assassinada. No centro de exterm\u00ednio, a comida era suficiente apenas para que continu\u00e1ssemos vivos e a tortura prosseguisse\u201d. Pessoas de v\u00e1rios pa\u00edses tamb\u00e9m foram sequestradas e presas nesse centro. Cerca de 500 foram identificadas.<\/p>\n<p>O pr\u00e9dio do Clube Atl\u00e9tico foi demolido em 1988 para a constru\u00e7\u00e3o de um viaduto. Gra\u00e7as a interven\u00e7\u00e3o popular e ao trabalho de arque\u00f3logos, est\u00e3o sendo realizadas escava\u00e7\u00f5es no local e parte da hist\u00f3ria pode ser recuperada. Em 2022, a equipe de arque\u00f3logos localizou v\u00e1rios documentos e objetos durante as escava\u00e7\u00f5es. Uma meia vermelha e uma camiseta foram identificadas por S\u00edlvia Fontana, como pe\u00e7as de roupas que sua irm\u00e3 vestia quando foi sequestrada. Liliana n\u00e3o foi localizada at\u00e9 o momento, seu nome permanece na lista de pessoas desaparecidas. Hoje teria 69 anos.<\/p>\n<p>Liliana Fontana, a Lili, era militante sindical, estudante de cabeleireira e estava gr\u00e1vida de dois meses. Foi sequestrada da casa dos pais junto com o companheiro, Pedro Sandoval. Testemunhas disseram que os viram na pris\u00e3o do Clube Atl\u00e9tico. Seu filho, Alejandro Pedro Sandoval, \u00e9 o neto n\u00famero 84, resgatado pelas Av\u00f3s da Pra\u00e7a de Maio em 2006, ano em que recuperou sua identidade. Alejandro havia sido apropriado pelo policial V\u00edctor Enrique Rei, atualmente preso. O primeiro neto a ser identificado foi em 1978. At\u00e9 o momento, 140 recuperaram a identidade. Estima-se que 300 crian\u00e7as nasceram no c\u00e1rcere.<\/p>\n<p>Caminhos da Ditadura em Porto Alegre tamb\u00e9m conheceu a Universidade Popular de Las Madres, um projeto consolidado em abril de 2000. A universidade, que agora n\u00e3o recebe aux\u00edlio financeiro do governo Milei, fica ao lado da Casa das Madres, fundada por Hebe de Bonafini, j\u00e1 falecida, que teve dois dos seus tr\u00eas filhos sequestrados e desaparecidos. Com apoio de professores universit\u00e1rios e de intelectuais argentinos e estrangeiros, a universidade popular promove cursos de direitos humanos, festivais e cursos de profissionaliza\u00e7\u00e3o.<\/p>\n<p>O pessoal da universidade, a associa\u00e7\u00e3o das m\u00e3es e a das av\u00f3s, al\u00e9m de populares, participam \u00e0s quintas-feiras, sempre \u00e0s 15h30, da marcha da Pra\u00e7a de Maio, em que reivindicam o paradeiro das pessoas sequestradas e agregam demandas sociais \u00e0 agenda. O grupo de Porto Alegre se juntou \u00e0 marcha de n\u00ba 2.494, realizada dia 29 de janeiro.<\/p>\n<p>Para que o grupo do Caminhos pudesse ter encontros com ativistas de direitos humanos, Cec\u00edlia, organizadora do roteiro, fez contatos com v\u00e1rias organiza\u00e7\u00f5es utilizando os canais dos sites das entidades. \u201cNos contatos por e-mail eu escrevi sobre a hist\u00f3ria do Caminhos da Ditadura em Porto Alegre e solicitei agenda. As respostas foram muito positivas, as organiza\u00e7\u00f5es chamaram sobreviventes da ditadura e netos resgatados para conversar conosco, porque a inten\u00e7\u00e3o, al\u00e9m da visita, \u00e9 compor uma rede de ativistas, essa \u00e9 uma forma muito interessante de fazer capacita\u00e7\u00e3o e ampliar nossa consci\u00eancia pol\u00edtica\u201d, explica Cec\u00edlia.<\/p>\n<p class=\"intertit\">Mem\u00f3ria e testemunho<\/p>\n<p>O pr\u00e9dio de tr\u00eas andares onde funcionou o centro clandestino de deten\u00e7\u00e3o da rua Virrey Cevallos, 630, foi declarado de utilidade p\u00fablica em 2004. O local foi transformado em Centro de Mem\u00f3ria e Promo\u00e7\u00e3o dos Direitos Humanos e aberto para visita\u00e7\u00e3o em 2009. Neste centro, o grupo do Caminhos encontrou Daniel Santucho Navajas, 49 anos, conhecido como \u201cNeto 133\u201d. Daniel deu um testemunho potente sobre a recupera\u00e7\u00e3o de sua identidade, que aconteceu somente em 2023.<\/p>\n<figure id=\"attachment_100733\" aria-describedby=\"caption-attachment-100733\" style=\"width: 246px\" class=\"wp-caption alignleft\"><img decoding=\"async\" data-attachment-id=\"100733\" data-permalink=\"https:\/\/www.jornalja.com.br\/geral\/caminhos-da-ditadura-em-porto-alegre-cruza-a-fronteira-e-vai-a-argentina\/caminhos-da-ditadura3\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3.jpeg\" data-orig-size=\"807,1476\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Caminhos Da Ditadura3\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Daniel Santucho Navajas, \u00e9 o neto 133. Recuperou sua identidade em 2023.  Cr\u00e9dito: M\u00e1rcia Turcato&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3-492x900.jpeg\" class=\"size-medium wp-image-100733\" src=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3-246x450.jpeg\" alt=\"\" width=\"246\" height=\"450\" srcset=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3-246x450.jpeg 246w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3-492x900.jpeg 492w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3-768x1405.jpeg 768w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura3.jpeg 807w\" sizes=\"(max-width: 246px) 100vw, 246px\" \/><figcaption id=\"caption-attachment-100733\" class=\"wp-caption-text\">Daniel Santucho Navajas, \u00e9 o neto 133. Recuperou sua identidade em 2023. Cr\u00e9dito: M\u00e1rcia Turcato<\/figcaption><\/figure>\n<p>Ele nasceu na pris\u00e3o clandestina conhecida como Pozo de Banfield no dia 10 de janeiro de 1977, um setor do Ex\u00e9rcito argentino. Mais de 300 pessoas ficaram presas nesse local, incluindo quatro mulheres gr\u00e1vidas. Daniel \u00e9 filho de Cristina Navajas, professora, e J\u00falio Santucho, tamb\u00e9m professor e ex-seminarista. Quando foi sequestrado, o casal tinha tr\u00eas filhos e Cristina estava gr\u00e1vida de dois meses. Os pais de Daniel eram militantes do Partido Revolucion\u00e1rio dos Trabalhadores (PRT). Cristina permanece desaparecida. J\u00falio sobreviveu. Daniel Santucho Navajas \u00e9 ativista de direitos humanos e protagonista do document\u00e1rio Identidade Roubada, de 2024, e autor do livro Nieto 133- Mi Camino Hacia la Verdad, da editora Planeta.<\/p>\n<p>A suposta irm\u00e3 mais velha de Daniel foi quem o alertou de que n\u00e3o era filho biol\u00f3gico dos pais que acreditava ter, d\u00favidas que ele tinha desde os cinco anos de idade, sem nem saber explicar a raz\u00e3o. Em duas oportunidades, Daniel enfrentou o apropriador para saber a verdade, mas o homem, um ex-policial, sempre sustentou ser seu pai biol\u00f3gico. Ao procurar as Av\u00f3s da Pra\u00e7a de Maio, o neto n\u00ba 133 p\u00f4de fazer um exame de DNA que confirmou a sua verdadeira identidade.<\/p>\n<p class=\"intertit\"><b>O gene das av\u00f3s<\/b><\/p>\n<p>A av\u00f3 de Daniel, o neto n\u00ba 133, N\u00e9lida Navajas, morreu em 2012 sem o conhecer. N\u00e9lida \u00e9 uma das fundadoras das Av\u00f3s da Pra\u00e7a de Maio e contou com a ajuda do neto Miguel, irm\u00e3o mais velho de Daniel, para liderar as buscas que duraram 46 anos. Em 1983, N\u00e9lida e Estela Carlotto, agora com 95 anos, viajaram aos Estados Unidos para conhecer a geneticista Mary Claire King e pedir um novo tipo de exame de DNA, que permitisse a identifica\u00e7\u00e3o de uma pessoa n\u00e3o s\u00f3 pelos genes de m\u00e3e ou pai, mas tamb\u00e9m pelos genes das av\u00f3s.<\/p>\n<p>Em 1984, a premiada geneticista Mary-Claire embarcou para a Argentina com a quest\u00e3o resolvida. Ela conseguiu realizar o sequenciamento gen\u00e9tico mitocondrial das av\u00f3s para comparar com os genes de crian\u00e7as que haviam sido apropriadas e determinar a liga\u00e7\u00e3o biol\u00f3gica entre elas. O procedimento recebeu o nome de \u201c\u00edndice de abuelidad\u201d, o \u00edndice das av\u00f3s. \u00c9 importante destacar que em 1998, o ditador general Videla foi condenado, entre outros crimes graves, por ter colocado em pr\u00e1tica o Plano Sistem\u00e1tico de Apropria\u00e7\u00e3o de Beb\u00eas. As primeiras condena\u00e7\u00f5es de Videla ocorreram em 1985, apenas dois anos ap\u00f3s o fim da ditadura e a volta da democracia com Ra\u00fal Alfons\u00edn.<\/p>\n<p class=\"intertit\"><b>ESMA, uma escola de tortura<\/b><\/p>\n<p>O S\u00edtio de Mem\u00f3ria ESMA, inaugurado em 2015, foi declarado como Patrim\u00f4nio da Humanidade pela UNESCO &#8211; Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, Ci\u00eancia e Cultura &#8211; em 2023. No local funcionou um centro clandestino de deten\u00e7\u00e3o, tortura e exterm\u00ednio da Escola de Mec\u00e2nica da Armada (ESMA). No edif\u00edcio principal, que agora \u00e9 museu, existiu o Cassino dos Oficiais. O museu \u00e9 um dos 35 pr\u00e9dios erguidos em um terreno de 17 hectares onde h\u00e1 diversas institui\u00e7\u00f5es de mem\u00f3ria e verdade distribu\u00eddas em 17 ruas internas.<br \/>\nNesse local, o grupo de Porto Alegre foi recebido pelo mediador Guilhermo Amarilla Molfino, 48 anos. Ele \u00e9 filho de um casal sequestrado pela ditadura e nasceu na pris\u00e3o. Guilhermo recuperou sua identidade em 2009 e tem tr\u00eas irm\u00e3os.<\/p>\n<p>Cinco mil sequestrados passaram pela ESMA e a hist\u00f3ria cruel do centro de tortura e exterm\u00ednio pode ser contada gra\u00e7as ao testemunho de poucos sobreviventes e de pessoas como Andrea Fricmar. Quando tinha onze anos, Andrea viu pela janela uma pessoa encapuzada e algemada sendo levada pelo p\u00e1tio da ESMA, enquanto brincava com a filha de um comandante da escola militar. Outro testemunho importante \u00e9 o do gr\u00e1fico Victor Basterra, que foi for\u00e7ado a trabalhar como fot\u00f3grafo na ESMA e conseguiu esconder centenas de negativos de filmes que depois serviram de provas contra os torturadores. O mediador Guillermo explica que 85% dos presos tinham idade entre 16 e 35 anos. \u201cPessoas pobres e jovens eram presas pelo terrorismo de Estado, era um Estado de Terror\u201d, salienta. Gra\u00e7as aos testemunhos, sabe-se que nasceram 37 crian\u00e7as na ESMA, 14 delas recuperaram a identidade.<\/p>\n<p class=\"intertit\"><b>Casa da Identidade<\/b><\/p>\n<p>A Casa da Identidade \u00e9 um espa\u00e7o de mem\u00f3ria gerido pela Associa\u00e7\u00e3o das Av\u00f3s da Pra\u00e7a de Maio e fica no mesmo pr\u00e9dio da Mostra da Linha Fundadora das Madres da Pra\u00e7a de Maio, onde h\u00e1 uma exposi\u00e7\u00e3o permanente. A Casa da Identidade tem o prop\u00f3sito de dar visibilidade \u00e0 hist\u00f3ria de apropria\u00e7\u00e3o sistem\u00e1tica de crian\u00e7as e rec\u00e9m-nascidos durante a ditadura argentina. Na Casa s\u00e3o guardados arquivos documentais, fotogr\u00e1ficos e bibliogr\u00e1ficos da organiza\u00e7\u00e3o, e s\u00e3o realizadas atividades educativas e culturais.<\/p>\n<p>O grupo do Caminhos foi recebido por Juan Pablo Moyano, 51 anos. Ele foi sequestrado em 1978, aos 18 meses de idade, e entregue a uma mulher que j\u00e1 estava com uma menina apropriada. Sua av\u00f3 conseguiu localiz\u00e1-lo por meio de uma foto, tirada quando ele era beb\u00ea, que foi distribu\u00edda pela Justi\u00e7a por toda a Argentina, Juan Pablo j\u00e1 estava com sete anos, seus pais permanecem desaparecidos. \u201cAs m\u00e3es que perderam seus filhos se transformaram em av\u00f3s que procuram seus netos e netas e a luta prossegue\u201d. Havia um plano estrat\u00e9gico para o roubo e o com\u00e9rcio de beb\u00eas\u201d, diz Juan Pablo.<\/p>\n<p>Em 2012, militares foram condenados, entre eles o general Jorge Rafael Videla. Antes disso, por\u00e9m, deputados da extrema direita tentaram impedir a pris\u00e3o de subalternos criando a \u201clei da obedi\u00eancia devida e ponto final\u201d, que acabou revogada. A Lei 23.492 foi promulgada em 1986, durante a presid\u00eancia de Ra\u00fal Alfons\u00edn, estabelecendo a paralisa\u00e7\u00e3o dos processos judiciais contra os autores das deten\u00e7\u00f5es ilegais, torturas e assassinatos que ocorreram na ditadura militar.<\/p>\n<p>A lei, junto com a sua complementar, a de Obedi\u00eancia Devida, foi considerada nula pelo Congresso Nacional s\u00f3 em 2003, e finalmente declarada nula pela Corte Suprema de Justi\u00e7a, por ser inconstitucional, em 14 de Junho de 2005, possibilitando que fossem reabertos os casos relacionados aos crimes contra a humanidade.<\/p>\n<p>O primeiro dos casos, responsabilizando Miguel Etchecolatz, ex-vice-comandante da Pol\u00edcia Provincial de Buenos Aires, encerrou em setembro de 2006, estabelecendo jurisprud\u00eancia ao reconhecer que o terrorismo de Estado durante a ditadura foi uma forma de genoc\u00eddio.<\/p>\n<figure id=\"attachment_100734\" aria-describedby=\"caption-attachment-100734\" style=\"width: 450px\" class=\"wp-caption alignright\"><img decoding=\"async\" data-attachment-id=\"100734\" data-permalink=\"https:\/\/www.jornalja.com.br\/geral\/caminhos-da-ditadura-em-porto-alegre-cruza-a-fronteira-e-vai-a-argentina\/caminhos-da-ditadura2\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2.jpeg\" data-orig-size=\"1528,1159\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Caminhos Da Ditadura2\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Monitoras do Caminhos da Ditadura PoA. De saia, a criadora da a\u00e7\u00e3o,  Anita; de preto a direita, Cec\u00edlia,  respons\u00e1vel pelo roteiro. Foto no Parque da Mem\u00f3ria. Cr\u00e9dito: Caminhos da Ditadura PoA&lt;br \/&gt;\nEm Porto Alegre&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2-900x683.jpeg\" class=\"size-medium wp-image-100734\" src=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2-450x341.jpeg\" alt=\"\" width=\"450\" height=\"341\" srcset=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2-450x341.jpeg 450w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2-900x683.jpeg 900w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2-768x583.jpeg 768w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2-1200x910.jpeg 1200w, https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura2.jpeg 1528w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><figcaption id=\"caption-attachment-100734\" class=\"wp-caption-text\">Monitoras do Caminhos da Ditadura PoA. De saia, a criadora da a\u00e7\u00e3o, Anita; de preto a direita, Cec\u00edlia, respons\u00e1vel pelo roteiro. Foto no Parque da Mem\u00f3ria. Cr\u00e9dito: Caminhos da Ditadura PoA<br \/>Em Porto Alegre<\/figcaption><\/figure>\n<p>O roteiro do grupo de Porto Alegre encerrou com uma visita ao Parque de La Memoria, criado em 1998, na orla do rio da Prata. No local h\u00e1 longas paredes com os nomes das 30 mil pessoas desaparecidas na Argentina durante a ditadura, al\u00e9m de instala\u00e7\u00f5es que simbolizam os horrores que aconteceram no pa\u00eds.<\/p>\n<p>Ap\u00f3s a imers\u00e3o no contexto da ditadura na Argentina, a professora Anita revela que \u201c\u00e9 nossa inten\u00e7\u00e3o levar o Caminhos para outros estados do Brasil e outros pa\u00edses da Am\u00e9rica do Sul, expandir um pouco, porque vimos que as pessoas t\u00eam interesse em fazer uma viagem com esse foco. Muitas delas trabalham com este tema no Rio Grande do Sul, a maioria que fez a viagem para Buenos Aires \u00e9 da \u00e1rea da Hist\u00f3ria\u201d.<\/p>\n<p class=\"intertit\"><strong>Caminhos da mem\u00f3ria Em Porto Alegre<\/strong><\/p>\n<p>No mapa virtual do Caminhos da Ditadura em Porto Alegre constam os 39 locais de viola\u00e7\u00e3o dos direitos humanos identificados pela Comiss\u00e3o Nacional da Verdade em 2014 e v\u00e1rios locais de refer\u00eancia da milit\u00e2ncia pol\u00edtica e do movimento estudantil. Atualmente, s\u00e3o mais de 200 pontos mapeados.<\/p>\n<p>H\u00e1 ainda dois trajetos presenciais que percorrem refer\u00eancias hist\u00f3ricas, um no bairro Bom Fim e outro na Pra\u00e7a da Matriz, numa caminhada de aproximadamente duas horas, parando em diversos locais para ouvir as informa\u00e7\u00f5es das e dos mediadores e tamb\u00e9m conversar com os participantes, reunidos em grupos de 50 pessoas, no m\u00e1ximo.<\/p>\n<p>De acordo com Anita, que \u00e9 doutoranda da UFRGS em Ensino da Hist\u00f3ria, \u201cap\u00f3s essa imers\u00e3o nos locais de mem\u00f3ria na Argentina, percebemos que o Brasil tem movimentos muito importantes no caminho da preserva\u00e7\u00e3o dos lugares de mem\u00f3ria, mas s\u00e3o insuficientes. Ali\u00e1s, nunca ser\u00e1 suficiente o n\u00famero de memoriais e monumentos que vierem a ser erguidos. Mas avan\u00e7amos muito no processo da memorializa\u00e7\u00e3o, principalmente em rela\u00e7\u00e3o aos locais onde ocorreram viola\u00e7\u00f5es dos direitos humanos durante a ditadura no Brasil\u201d.<\/p>\n<p>A doutoranda est\u00e1 ciente que \u201cainda falta uma pol\u00edtica de mem\u00f3ria mais contundente, mais forte, pelo Estado, no Rio Grande do Sul e no Brasil, para que os espa\u00e7os de mem\u00f3ria se efetivem\u201d. Anita destaca tamb\u00e9m a exist\u00eancia de muitos monumentos em homenagem a ditadores e colaboradores do terrorismo de Estado no Brasil, inclusive um condom\u00ednio em Porto Alegre com o nome \u201831 de mar\u00e7o\u2019. \u00c9 importante realizar campanhas de conscientiza\u00e7\u00e3o sobre esses lugares. A sociedade civil, junto com o Estado, deve pensar em alternativas para esses espa\u00e7os. A ditadura \u00e9 um tema de disputa de mem\u00f3ria\u201d.<\/p>\n<p>O projeto\u00a0<strong>Caminhos da Ditadura<\/strong>\u00a0mant\u00e9m visitas programadas em trajetos de mem\u00f3ria que ocorrem nas regi\u00f5es centrais de Porto Alegre. Os passeios s\u00e3o abertos ao p\u00fablico e suas agendas e inscri\u00e7\u00f5es para participar s\u00e3o todas divulgadas na p\u00e1gina do Instagram\u00a0<a href=\"https:\/\/www.instagram.com\/caminhosdaditadura_poa\/\">@caminhosdaditadura_poa<\/a>\u00a0e adquiridos na p\u00e1gina do\u00a0<a href=\"https:\/\/www.sympla.com.br\/produtor\/caminhosdaditaduraemportoalegre\">Sympla<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1rcia Turcato A iniciativa Caminhos da Ditadura em Porto Alegre completa 10 anos. O projeto come\u00e7ou a ser constru\u00eddo em 2016 por estudantes do curso de Hist\u00f3ria da Universidade Federal do Rio Grande do Sul (UFRGS). Em janeiro de 2026, o Caminhos cruzou a fronteira e foi at\u00e9 Buenos Aires, capital da Argentina, dando mais [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":100732,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,12],"tags":[],"class_list":["post-100728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-manchete-do-site"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/02\/caminhos-da-ditadura1.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-qcE","jetpack-related-posts":[{"id":101058,"url":"https:\/\/www.jornalja.com.br\/geral\/jornalista-batista-filho-palestra-em-ato-pelos-62-anos-do-golpe-militar\/","url_meta":{"origin":100728,"position":0},"title":"Jornalista Batista Filho palestra em ato pelos 62 anos do Golpe Militar","author":"da Reda\u00e7\u00e3o","date":"8 de abril de 2026","format":false,"excerpt":"O jornalista Jo\u00e3o Batista Filho, de 86 anos, ser\u00e1 o palestrante do \u201cAto de Rep\u00fadio pelos 62 Anos da Ditadura Militar\u201d, que ocorre nesta quarta-feira (8), \u00e0s 19h, no Audit\u00f3rio Ana Terra da C\u00e2mara Municipal de Porto Alegre. A atividade \u00e9 promovida pela Associa\u00e7\u00e3o dos Ex-Presos e Perseguidos Pol\u00edticos do\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/sem-titulo-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/sem-titulo-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/sem-titulo-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/sem-titulo-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/sem-titulo-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":98074,"url":"https:\/\/www.jornalja.com.br\/geral\/projeto-mapeia-200-locais-que-marcam-os-caminhos-da-ditadura-em-porto-alege\/","url_meta":{"origin":100728,"position":1},"title":"Projeto mapeia 200 locais que marcam os &#8220;Caminhos da Ditadura&#8221; em Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"1 de novembro de 2024","format":false,"excerpt":"Eug\u00eanio Bortolon* No domingo, 10\/11, haver\u00e1 mais uma edi\u00e7\u00e3o do projeto\u00a0 \"Caminhos da Ditadura\" em Porto Alegre, que mapeia os locais que foram centros de repress\u00e3o pol\u00edtica ou de resist\u00eancia nos anos da ditadura militar (1964-1985). A ideia nasceu no curso de Hist\u00f3ria da Universidade Federal do Rio Grande do\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/10\/caminhos-da-ditadura.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/10\/caminhos-da-ditadura.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/10\/caminhos-da-ditadura.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":100091,"url":"https:\/\/www.jornalja.com.br\/geral\/a-atualidade-de-herzog-na-luta-pela-democracia-e-pelo-jornalismo\/","url_meta":{"origin":100728,"position":2},"title":"A atualidade de Herzog na luta pelo  jornalismo e a democracia","author":"da Reda\u00e7\u00e3o","date":"27 de outubro de 2025","format":false,"excerpt":"Foi impressionante. S\u00e1bado de sol, em plena de primavera, e l\u00e1 estavam aquelas pessoas, umas 60 ou pouco mais, confinadas no s\u00e9timo andar de um edif\u00edcio no centro de Porto Alegre para falar de um fato hediondo, ocorrido a meio s\u00e9culo. Foram trocar informa\u00e7\u00f5es e refletir sobre o assassinato de\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":98888,"url":"https:\/\/www.jornalja.com.br\/geral\/quando-a-noticia-pode-salvar-vidas-o-papel-do-jornalismo-no-combate-as-ditaduras\/","url_meta":{"origin":100728,"position":3},"title":"Quando a not\u00edcia pode salvar vidas: o papel do jornalismo no combate \u00e0s ditaduras","author":"da Reda\u00e7\u00e3o","date":"9 de maio de 2025","format":false,"excerpt":"M\u00e1rcia Turcato* O livro \"Quando a Not\u00edcia Pode Salvar Vidas \u2013 Quatro d\u00e9cadas do Pr\u00eamio de Direitos Humanos de Jornalismo\" \u00e9 um importante documento sobre a ditadura civil-militar e o avan\u00e7o civilizat\u00f3rio alcan\u00e7ado com a redemocratiza\u00e7\u00e3o do pa\u00eds. A publica\u00e7\u00e3o, de 206 p\u00e1ginas, coloca numa perspectiva hist\u00f3rica as reportagens laureadas\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/05\/livro-premio-mjdh.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":100981,"url":"https:\/\/www.jornalja.com.br\/geral\/carta-de-porto-alegre-propoe-frente-global-em-defesa-da-democracia\/","url_meta":{"origin":100728,"position":4},"title":"&#8220;Carta de Porto Alegre&#8221; prop\u00f5e frente global em defesa da democracia","author":"da Reda\u00e7\u00e3o","date":"31 de mar\u00e7o de 2026","format":false,"excerpt":"Na quinta-feira, Ol\u00edvio Dutra foi o primeiro a falar. Disse que a luta contra o fascismo \u00e9, essencialmente, uma luta contra governos que n\u00e3o colocam a vida humana como prioridade central das pol\u00edticas p\u00fablicas. \u201cA democracia deve ser social e participativa, e n\u00e3o um instrumento controlado por minorias ou pelo\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/systemuploadsnews36af8a82acdf9331cdd-700x460xfit-0aec1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/systemuploadsnews36af8a82acdf9331cdd-700x460xfit-0aec1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/systemuploadsnews36af8a82acdf9331cdd-700x460xfit-0aec1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/systemuploadsnews36af8a82acdf9331cdd-700x460xfit-0aec1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/100728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=100728"}],"version-history":[{"count":6,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/100728\/revisions"}],"predecessor-version":[{"id":100835,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/100728\/revisions\/100835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media\/100732"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=100728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=100728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=100728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}