{"id":101634,"date":"2026-07-14T22:07:39","date_gmt":"2026-07-15T01:07:39","guid":{"rendered":"https:\/\/www.jornalja.com.br\/geral\/?p=101634"},"modified":"2026-07-14T22:07:41","modified_gmt":"2026-07-15T01:07:41","slug":"mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/","title":{"rendered":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O prefeito de Porto Alegre, Sebasti\u00e3o Melo, <strong>sancionou o novo Plano Diretor<\/strong> em meio a uma <strong>disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF)<\/strong>  pede a suspens\u00e3o do que foi aprovado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o em primeira inst\u00e2ncia havia sido encerrada sob o argumento de que o conselho n\u00e3o tinha legitimidade e de que o Judici\u00e1rio n\u00e3o deveria interferir no Legislativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Tribunal Regional Federal da 4\u00aa Regi\u00e3o reverteu a decis\u00e3o por unanimidade, reconhecendo a legitimidade do CAU\/RS para contestar o plano, fazendo com que o processo voltasse a tramitar com for\u00e7a total na primeira inst\u00e2ncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O parecer assinado pelo procurador da Rep\u00fablica Enrico Rodrigues de Freitas refor\u00e7ou nesta ter\u00e7a-feira, 14\/07,  o pedido de liminar com urg\u00eancia. O documento apontou <strong>graves falhas jur\u00eddicas e t\u00e9cnicas<\/strong> na revis\u00e3o do plano:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9ficit de Participa\u00e7\u00e3o Popular<\/strong>: Falta de sistematiza\u00e7\u00e3o clara e justificativas sobre quais propostas enviadas pela popula\u00e7\u00e3o foram aceitas ou descartadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aus\u00eancia de Diretrizes Clim\u00e1ticas<\/strong>: Omiss\u00e3o de mapas de risco atualizados e falha em integrar as li\u00e7\u00f5es urban\u00edsticas decorrentes da enchente hist\u00f3rica que atingiu a capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Altera\u00e7\u00f5es Suspeitas nos Mapas<\/strong>: Den\u00fancias de vereadores de oposi\u00e7\u00e3o de que mapas das Zonas de Ordenamento Territorial (ZOTs) sofreram modifica\u00e7\u00f5es na reda\u00e7\u00e3o final sem terem sido deliberados em plen\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O prefeito optou por sancionar o projeto antes de uma decis\u00e3o liminar da Justi\u00e7a Federal, mas <strong>o processo n\u00e3o perde o objeto<\/strong>. A a\u00e7\u00e3o segue em andamento, mas o foco agora muda do impedimento da san\u00e7\u00e3o para o questionamento da validade jur\u00eddica e a poss\u00edvel <strong>anula\u00e7\u00e3o ou suspens\u00e3o dos efeitos da lei j\u00e1 sancionada<\/strong>. O novo regramento prev\u00ea um prazo de 180 dias de transi\u00e7\u00e3o para regulamenta\u00e7\u00e3o, per\u00edodo no qual novas decis\u00f5es judiciais podem travar as medidas de forma definitiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. \u00a0O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":100967,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-101634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Geral\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral\" \/>\n\t\t<meta property=\"og:description\" content=\"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2126\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T01:07:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T01:07:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#article\",\"name\":\"MP refor\\u00e7a pedido \\u00e0 Justi\\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral\",\"headline\":\"MP refor\\u00e7a pedido \\u00e0 Justi\\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/ede-8942.jpg\",\"width\":2126,\"height\":1417,\"caption\":\"Projeto que altera plano diretor prev\\u00ea pr\\u00e9dios mais altos. Foto: Brayan Martins\\\/PMPA.\"},\"datePublished\":\"2026-07-14T22:07:39-03:00\",\"dateModified\":\"2026-07-14T22:07:41-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#webpage\"},\"articleSection\":\"Geral-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/#listItem\",\"position\":2,\"name\":\"Geral-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#listItem\",\"name\":\"MP refor\\u00e7a pedido \\u00e0 Justi\\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#listItem\",\"position\":3,\"name\":\"MP refor\\u00e7a pedido \\u00e0 Justi\\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#organization\",\"name\":\"Geral\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/ja35.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/wp-content\\\/litespeed\\\/avatar\\\/4\\\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1783484837\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/\",\"name\":\"MP refor\\u00e7a pedido \\u00e0 Justi\\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral\",\"description\":\"O prefeito de Porto Alegre, Sebasti\\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\\u00eddica e uma nova manifesta\\u00e7\\u00e3o do Minist\\u00e9rio P\\u00fablico Federal (MPF) pede a suspens\\u00e3o do que foi aprovado. O processo tramita na Justi\\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\\u00e7\\u00e3o em primeira\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/ede-8942.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#mainImage\",\"width\":2126,\"height\":1417,\"caption\":\"Projeto que altera plano diretor prev\\u00ea pr\\u00e9dios mais altos. Foto: Brayan Martins\\\/PMPA.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\\\/#mainImage\"},\"datePublished\":\"2026-07-14T22:07:39-03:00\",\"dateModified\":\"2026-07-14T22:07:41-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/\",\"name\":\"Geral\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral","description":"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira","canonical_url":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#article","name":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral","headline":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre","author":{"@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/geral\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg","width":2126,"height":1417,"caption":"Projeto que altera plano diretor prev\u00ea pr\u00e9dios mais altos. Foto: Brayan Martins\/PMPA."},"datePublished":"2026-07-14T22:07:39-03:00","dateModified":"2026-07-14T22:07:41-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#webpage"},"articleSection":"Geral-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/geral","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/#listItem","name":"Geral-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/#listItem","position":2,"name":"Geral-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#listItem","name":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#listItem","position":3,"name":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/#listItem","name":"Geral-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/geral\/#organization","name":"Geral","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/geral\/","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#authorImage","url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/litespeed\/avatar\/4\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1783484837","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#webpage","url":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/","name":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral","description":"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/geral\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg","@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#mainImage","width":2126,"height":1417,"caption":"Projeto que altera plano diretor prev\u00ea pr\u00e9dios mais altos. Foto: Brayan Martins\/PMPA."},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/#mainImage"},"datePublished":"2026-07-14T22:07:39-03:00","dateModified":"2026-07-14T22:07:41-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/geral\/#website","url":"https:\/\/www.jornalja.com.br\/geral\/","name":"Geral","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/geral\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Geral","og:type":"article","og:title":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral","og:description":"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira","og:url":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/","og:image":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg","og:image:width":2126,"og:image:height":1417,"article:published_time":"2026-07-15T01:07:39+00:00","article:modified_time":"2026-07-15T01:07:41+00:00","twitter:card":"summary","twitter:title":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre | Geral","twitter:description":"O prefeito de Porto Alegre, Sebasti\u00e3o Melo, sancionou o novo Plano Diretor em meio a uma disputa jur\u00eddica e uma nova manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF) pede a suspens\u00e3o do que foi aprovado. O processo tramita na Justi\u00e7a Federal e foi originalmente movido pelo Conselho de Arquitetura e Urbanismo (CAU). A a\u00e7\u00e3o em primeira","twitter:image":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg"},"aioseo_meta_data":{"post_id":"101634","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 00:52:54","updated":"2026-07-15 01:07:59","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.jornalja.com.br\/geral\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/\" title=\"Geral-MAT\u00c9RIA\">Geral-MAT\u00c9RIA<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.jornalja.com.br\/geral"},{"label":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},{"label":"MP refor\u00e7a pedido \u00e0 Justi\u00e7a para que suspenda o Plano Diretor sancionado pelo prefeito de Porto Alegre","link":"https:\/\/www.jornalja.com.br\/geral\/mp-reforca-pedido-a-justica-para-que-suspenda-o-plano-diretor-sancionado-pelo-prefeito-de-porto-alegre\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/ede-8942.jpg","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-qrg","jetpack-related-posts":[{"id":101455,"url":"https:\/\/www.jornalja.com.br\/geral\/justica-reabilita-acao-que-pode-anular-plano-diretor-melo-tem-dez-dias-para-se-defender\/","url_meta":{"origin":101634,"position":0},"title":"Justi\u00e7a reabilita a\u00e7\u00e3o que pode anular Plano Diretor: Melo tem dez dias para se defender","author":"da Reda\u00e7\u00e3o","date":"1 de junho de 2026","format":false,"excerpt":"A ju\u00edza federal Clarides Rahmeier deu dez dias \u00e0 prefeitura de Porto Alegre para se manifestar na A\u00e7\u00e3o Civil P\u00fablica movida pelo Conselho de Arquitetura e Urbanismo e que aponta ilegalidades no projeto de revis\u00e3o do Plano Diretor, aprovado em abril. A decis\u00e3o, em grau de recurso, foi assinada na\u2026","rel":"","context":"Em &quot;MANCHETE do Site&quot;","block_context":{"text":"MANCHETE do Site","link":"https:\/\/www.jornalja.com.br\/geral\/category\/manchete-do-site\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/plano-diretor-melo-apresenta-a-camara.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/plano-diretor-melo-apresenta-a-camara.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/plano-diretor-melo-apresenta-a-camara.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":100403,"url":"https:\/\/www.jornalja.com.br\/geral\/plano-diretor-de-porto-alegre-mpc-pede-suspensao-do-projeto-em-votacao-na-camara\/","url_meta":{"origin":101634,"position":1},"title":"Plano Diretor de Porto Alegre: MPC pede suspens\u00e3o da vota\u00e7\u00e3o do projeto","author":"da Reda\u00e7\u00e3o","date":"17 de dezembro de 2025","format":false,"excerpt":"O Minist\u00e9rio P\u00fablico de Contas (MPC) pediu a suspens\u00e3o do projeto de lei que revisa o Plano Diretor de Porto Alegre, em tramita\u00e7\u00e3o na C\u00e2mara de Vereadores.. Ind\u00edcios de irregularidades na elei\u00e7\u00e3o do Conselho Municipal de Desenvolvimento Urbano e Ambiental (CMDUA) justificam o pedido. Na representa\u00e7\u00e3o, protocolada na sexta, 12\/12,\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/plano-diretor-forum.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/plano-diretor-forum.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/plano-diretor-forum.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":101113,"url":"https:\/\/www.jornalja.com.br\/geral\/chefe-do-mp-rs-plano-diretor-de-porto-alegre-e-mais-voltado-para-construcao-que-para-prevenir-enchentes\/","url_meta":{"origin":101634,"position":2},"title":"Chefe do MP-RS: \u201cPlano Diretor de Porto Alegre \u00e9 mais voltado para constru\u00e7\u00e3o que para prevenir enchentes&#8221;","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"O projeto do novo Plano Diretor de Porto Alegre, que tramita h\u00e1 mais de ano e est\u00e1 em fase final de vota\u00e7\u00e3o na C\u00e2mara Municipal, tem indicativos de aprova\u00e7\u00e3o, pela for\u00e7a da maioria que o prefeito Sebasti\u00e3o Melo tem no legislativo. J\u00e1, estudos do Minist\u00e9rio P\u00fablico apontam \"falhas jur\u00eddicas\" no\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/whatsapp-image-2026-04-01-at-164602-1536x1023-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/whatsapp-image-2026-04-01-at-164602-1536x1023-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/whatsapp-image-2026-04-01-at-164602-1536x1023-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/whatsapp-image-2026-04-01-at-164602-1536x1023-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/whatsapp-image-2026-04-01-at-164602-1536x1023-1.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/whatsapp-image-2026-04-01-at-164602-1536x1023-1.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":101014,"url":"https:\/\/www.jornalja.com.br\/geral\/porto-alegre-avanca-na-votacao-do-plano-diretor-sob-criticas-de-fatiamento-e-riscos-climaticos\/","url_meta":{"origin":101634,"position":3},"title":"Porto Alegre avan\u00e7a na vota\u00e7\u00e3o do Plano Diretor sob cr\u00edticas de \u201cfatiamento\u201d e riscos clim\u00e1ticos","author":"da Reda\u00e7\u00e3o","date":"5 de abril de 2026","format":false,"excerpt":"A C\u00e2mara Municipal de Porto Alegre entrou na fase final da revis\u00e3o do Plano Diretor. Ap\u00f3s meses de impasse, um acordo entre a base do prefeito Sebasti\u00e3o Melo (MDB) e a oposi\u00e7\u00e3o acelerou a vota\u00e7\u00e3o de mais de 200 emendas. A expectativa \u00e9 que o texto final seja apreciado ainda\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/ede-5907-foto-ederson-nunescmpa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/ede-5907-foto-ederson-nunescmpa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/ede-5907-foto-ederson-nunescmpa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/ede-5907-foto-ederson-nunescmpa.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/ede-5907-foto-ederson-nunescmpa.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/ede-5907-foto-ederson-nunescmpa.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":99615,"url":"https:\/\/www.jornalja.com.br\/geral\/entidades-pedem-que-camara-municipal-nao-aprecie-novo-plano-diretor\/","url_meta":{"origin":101634,"position":4},"title":"Entidades pedem que C\u00e2mara Municipal n\u00e3o aprecie novo Plano Diretor","author":"S\u00e9rgio Lagranha","date":"28 de agosto de 2025","format":false,"excerpt":"O Sindicato dos Engenheiros, a Associa\u00e7\u00e3o Ga\u00facha de Prote\u00e7\u00e3o ao Ambiente Natural e outras entidades da sociedade civil pediram que a C\u00e2mara Municipal n\u00e3o receba nem delibere sobre o novo Plano Diretor de Porto Alegre at\u00e9 que graves irregularidades na revis\u00e3o do documento urban\u00edstico sejam corrigidas. Com mais de 200\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/dsc-3076-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/dsc-3076-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/dsc-3076-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/dsc-3076-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/dsc-3076-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/dsc-3076-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":101624,"url":"https:\/\/www.jornalja.com.br\/geral\/melo-sanciona-plano-diretor-que-permite-predios-mais-altos-e-menos-espaco-entre-eles\/","url_meta":{"origin":101634,"position":5},"title":"Pr\u00e9dios mais altos, menos espa\u00e7os e recuos: essa \u00e9 a l\u00f3gica do Plano Diretor sancionado por Sebasti\u00e3o Melo","author":"da Reda\u00e7\u00e3o","date":"14 de julho de 2026","format":false,"excerpt":"O prefeito Sebasti\u00e3o Melo (MDB) sancionou, nesta ter\u00e7a-feira (14), as leis que instituem o novo Plano Diretor e a Lei de Uso e Ocupa\u00e7\u00e3o do Solo de Porto Alegre, concluindo o pol\u00eamico processo de revis\u00e3o do marco urban\u00edstico da Capital. Os textos foram publicados no Di\u00e1rio Oficial de Porto Alegre\u2026","rel":"","context":"Em &quot;MANCHETE do Site&quot;","block_context":{"text":"MANCHETE do Site","link":"https:\/\/www.jornalja.com.br\/geral\/category\/manchete-do-site\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/07\/plano-diretor-melo-sanciona.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/07\/plano-diretor-melo-sanciona.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/07\/plano-diretor-melo-sanciona.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/07\/plano-diretor-melo-sanciona.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/101634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=101634"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/101634\/revisions"}],"predecessor-version":[{"id":101636,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/101634\/revisions\/101636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media\/100967"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=101634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=101634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=101634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}