{"id":72012,"date":"2019-01-01T20:26:04","date_gmt":"2019-01-01T22:26:04","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=72012"},"modified":"2019-01-01T20:26:04","modified_gmt":"2019-01-01T22:26:04","slug":"festa-da-virada-levou-140-mil-a-orla-segundo-a-prefeitura","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/festa-da-virada-levou-140-mil-a-orla-segundo-a-prefeitura\/","title":{"rendered":"Festa da virada levou 140 mil \u00e0 orla, segundo a prefeitura"},"content":{"rendered":"<div class=\"m_-7556592864173112426gmail-texto_visualiza\">\u00a0A estimativa \u00e9 da EPTC.\u00a0 As atra\u00e7\u00f5es na Orla Moacir Scliar come\u00e7aram por volta das 20h, mas desde o fim da tarde as pessoas j\u00e1 chegavam com cadeiras, bebidas e comidas para ver o \u00faltimo p\u00f4r do sol de 2018 e garantir o lugar pr\u00f3ximo ao palco.<\/div>\n<div><\/div>\n<div class=\"m_-7556592864173112426gmail-texto_visualiza\">No entorno, muita gente aproveitando a estrutura montada na Usina do Gas\u00f4metro: food trucks, beer trucks e a tenda Recanto M\u00edstico tiveram uma grande procura do p\u00fablico.<\/p>\n<p dir=\"ltr\">A aposentada Ana Maria Ramos, 72 anos, veio para a Orla junto com parte da fam\u00edlia, que mora no bairro Tristeza para acompanhar a festa: \u201cChegamos aqui e vimos tudo organizado, limpinho e a atua\u00e7\u00e3o da Brigada Militar e da Guarda Municipal. Estamos felizes&#8221;, destaca.<\/p>\n<p dir=\"ltr\">O in\u00edcio do show ficou por conta da dupla sertaneja Marcelo e Vanutti. Na sequ\u00eancia, o grupo de pagode Kadinho e Banda subiu ao palco.<\/p>\n<p dir=\"ltr\">Minutos antes da meia-noite, a banda Papas da L\u00edngua come\u00e7ou sua apresenta\u00e7\u00e3o que fez uma parada para a contagem regressiva e a queima de fogos.<\/p>\n<p dir=\"ltr\"><b>Show pirot\u00e9cnico &#8211;\u00a0<\/b>Foram mais de 10 minutos de um show que coloriu o c\u00e9u da cidade. A novidade ficou por conta de fogos para o bem-estar de pessoas com hipersensibilidade ao som e dos animais.<\/p>\n<p dir=\"ltr\">Sob aplausos, os fogos cessaram e o show continuou com o Papas da L\u00edngua. Para encerrar a noite, a DJ Let\u00edcia Sartoretto seguiu animando a multid\u00e3o.<\/p>\n<p dir=\"ltr\">O prefeito Nelson Marchezan J\u00fanior, acompanhado do vice, Gustavo Paim, acompanhou de perto a retomada da celebra\u00e7\u00e3o em Porto Alegre.<\/p>\n<p dir=\"ltr\">H\u00e1 dois anos a cidade n\u00e3o tinha uma festa p\u00fablica no r\u00e9veillon.<\/p>\n<p dir=\"ltr\"><b>Investimento privado &#8211;\u00a0<\/b>Para o R\u00e9veillon de Porto Alegre &#8211; Pro Ano Nascer Feliz &#8211; foram investidos R$ 400 mil em recursos captados pela prefeitura junto \u00e0 iniciativa privada. Patrocinam o R\u00e9veillon de Porto Alegre a Casa Maria Bazar e Utilidades, Impacto Vento Norte e Marsala Alimentos. Tamb\u00e9m apoiam o evento: Simonei, do grupo Varieta, Federa\u00e7\u00e3o Afro Umbandista do Rio Grande do Sul, Sindilojas, Barco Porto Alegre 10, Barco Noiva do Ca\u00ed ll, Barco Cisne Branco, Sheik Burger e 360 POA Gastrobar.<\/p>\n<\/div>\n<div class=\"yj6qo ajU\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0A estimativa \u00e9 da EPTC.\u00a0 As atra\u00e7\u00f5es na Orla Moacir Scliar come\u00e7aram por volta das 20h, mas desde o fim da tarde as pessoas j\u00e1 chegavam com cadeiras, bebidas e comidas para ver o \u00faltimo p\u00f4r do sol de 2018 e garantir o lugar pr\u00f3ximo ao palco. No entorno, muita gente aproveitando a estrutura montada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72013,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-72012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-iJu","jetpack-related-posts":[{"id":73213,"url":"https:\/\/www.jornalja.com.br\/geral\/marca-das-gestoes-petistas-baile-da-cidade-volta-ao-parque-da-redencao\/","url_meta":{"origin":72012,"position":0},"title":"Marca das gest\u00f5es petistas, Baile da Cidade volta ao parque da Reden\u00e7\u00e3o","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2019","format":false,"excerpt":"Mais de 30 mil pessoas participaram do \u00faltimo dos bailes p\u00fablicos no Parque da Reden\u00e7\u00e3o em 2012, comemorando os 240 anos de Porto Alegre. A Banda Municipal interpretou m\u00fasicas que se tornaram hinos da cidade, na voz dos seguintes convidados: -Kleiton & Kledir, com \"Deu Pra Ti\", -Nei Lisboa (\"Berlim\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/03\/Baile-na-Reden%C3%A7%C3%A3o-Fortunati-com-S%C3%A9rgius-Gonzaga-450x334.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":88909,"url":"https:\/\/www.jornalja.com.br\/geral\/incluido-no-programa-orla-viaduto-otavio-rocha-tera-r-15-milhoes-para-revitalizacao\/","url_meta":{"origin":72012,"position":1},"title":"Inclu\u00eddo no Programa Orla, Viaduto Ot\u00e1vio Rocha ter\u00e1 R$ 15 milh\u00f5es para revitaliza\u00e7\u00e3o","author":"da Reda\u00e7\u00e3o","date":"23 de julho de 2021","format":false,"excerpt":"A prefeitura vai encaminhar nos pr\u00f3ximos dias as informa\u00e7\u00f5es finais para a inclus\u00e3o do Viaduto Ot\u00e1vio Rocha no \u201cPrograma Orla\u201d. O Programa Orla, financiado pelo Banco de Desenvolvimento da Am\u00e9rica Latina (CAF) come\u00e7ou com a urbaniza\u00e7\u00e3o dos trechos 2 e 3 da orla sul. Na atual administra\u00e7\u00e3o, o programa foi\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/07\/viaduto-da-borges-quando-ficou-pronto.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84462,"url":"https:\/\/www.jornalja.com.br\/geral\/com-recorde-em-ocupacoes-de-uti-por-covid-19-marchezan-fecha-orla-e-parques-em-porto-alegre\/","url_meta":{"origin":72012,"position":2},"title":"Com recorde em ocupa\u00e7\u00f5es de UTI por Covid-19, Marchezan fecha orla e parques em Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"3 de julho de 2020","format":false,"excerpt":"No final da tarde desta sexta-feira, 03\/07, o prefeito de Porto Alegre, Nelson Marchezan J\u00fanior, determinou novas medidas de restri\u00e7\u00e3o \u00e0 circula\u00e7\u00e3o de pessoas. A procupa\u00e7\u00e3o \u00e9 com o aumento na ocupa\u00e7\u00e3o de leitos hospitalares por pacientes de Covid-19. No in\u00edcio da noite, o n\u00famero de pacientes em leitos de\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/07\/040720-ac-smseg-8790.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/07\/040720-ac-smseg-8790.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/07\/040720-ac-smseg-8790.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/07\/040720-ac-smseg-8790.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":91235,"url":"https:\/\/www.jornalja.com.br\/geral\/dilma-posta-foto-pedalando-na-orla-para-desmentir-boatos-de-embolia-pulmonar\/","url_meta":{"origin":72012,"position":3},"title":"Dilma posta foto pedalando na orla para desmentir boatos de embolia pulmonar","author":"da Reda\u00e7\u00e3o","date":"5 de dezembro de 2021","format":false,"excerpt":"A ex-presidente Dilma \/Roussef\u00a0publicou uma foto na manh\u00e3 deste domingo (5) ironizando os boatos de que estaria\u00a0internada em um hospital de Porto Alegre com embolia pulmonar. \u201cEu e a minha embolia pulmonar agora pela manh\u00e3, em Porto Alegre\", escreveu Dilma em uma foto em que aparece andando de bicicleta na\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/dilma-na-orla.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/dilma-na-orla.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/dilma-na-orla.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":97184,"url":"https:\/\/www.jornalja.com.br\/geral\/estatua-do-ex-presidente-joao-goulart-na-orla-a-decisao-e-da-gam3\/","url_meta":{"origin":72012,"position":4},"title":"Est\u00e1tua do ex-presidente Jo\u00e3o Goulart na Orla: a decis\u00e3o ser\u00e1 da GAM3","author":"Elmar Bones","date":"17 de abril de 2024","format":false,"excerpt":"Depende da GAM3, a empresa concession\u00e1ria do trecho 1 da Orla, a localiza\u00e7\u00e3o de uma est\u00e1tua do ex-presidente Jo\u00e3o Goulart junto \u00e0 avenida que j\u00e1 leva seu nome, no centro hist\u00f3rico de Porto Alegre. O projeto \u00e9 da Funda\u00e7\u00e3o Caminhos da Soberania, que arrecadou fundos para bancar a obra do\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/04\/estatua-jango.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/04\/estatua-jango.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/04\/estatua-jango.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":76118,"url":"https:\/\/www.jornalja.com.br\/geral\/lerner-ve-a-orla-arquiteto-recebe-homenagem-e-visita-obra-que-projetou\/","url_meta":{"origin":72012,"position":5},"title":"Lerner v\u00ea a orla: arquiteto recebe homenagem  e visita obra que projetou","author":"da Reda\u00e7\u00e3o","date":"8 de agosto de 2019","format":false,"excerpt":"Um ano depois da inaugura\u00e7\u00e3o, Jaime Lerner, arquiteto e urbanista respons\u00e1vel pelo projeto vai conhecer ao vivo\u00a0 o trecho urbanizado da Orla Moacir Scliar. \u00c9 pouco mais de um quil\u00f4metro numa orla de mais de 70 quil\u00f4metros, mas mostrou-se suficiente para que o portoalegrense se reconciliasse com o Guaiba. Desde\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=72012"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=72012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=72012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=72012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}