{"id":72028,"date":"2019-01-02T02:06:18","date_gmt":"2019-01-02T04:06:18","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=72028"},"modified":"2019-01-02T02:06:18","modified_gmt":"2019-01-02T04:06:18","slug":"eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/","title":{"rendered":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot;"},"content":{"rendered":"<p>Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo.<br \/>\n&#8220;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas extras, enfim, todas as despesas que possam ser contingenciadas no custeio da m\u00e1quina p\u00fablica\u201d, disse em sua primeira entrevista depois de empossado..<br \/>\nOs decretos ser\u00e3o, segundo Leite, um &#8220;freio de arruma\u00e7\u00e3o&#8221; para organizar cada secretaria. \u201cVamos estabelecer um congelamento de gastos por pasta&#8221;<br \/>\nO novo governador ga\u00facho tem em perspectiva no seu primeiro ano um d\u00e9ficit estimado em R$ 4 bilh\u00f5es.<br \/>\nAl\u00e9m desse rombo, ele assume com duas folhas de sal\u00e1rios em atraso (dezembro e o d\u00e9cimo terceiro sal\u00e1rios) e d\u00edvidas com fornecedores e institui\u00e7\u00f5es (s\u00f3 aos hospitais filantr\u00f3picos, deve mais de R$ 500 milh\u00f5es).<\/p>\n<div class=\"article-paragraph\">\nPara o novo governador ga\u00facho, o caminho \u00e9 &#8220;romper com a ideologiza\u00e7\u00e3o das pautas e o &#8220;confronto in\u00fatil&#8221;, para concentrar no que \u00e9 essencial.<br \/>\n&#8220;O bom confronto \u00e9 o do bem comum contra os grupos de interesses&#8221;.\n<\/div>\n<div class=\"article-paragraph\">\nA frase foi entendida como um recado aos membros dos demais poderes que ficaram fora dos parcelamentos no governo Sartori e, no fim de 2018, ainda aprovaram aumentos de sal\u00e1rios.<br \/>\nSem\u00a0 fazer refer\u00eancia aos 36 meses de atrasos nos sal\u00e1rios impostos exclusivamente aos servidores do Executivo, o governador destacou que &#8220;todos devem participar dos esfor\u00e7os para alcan\u00e7ar o equil\u00edbrio fiscal&#8221;. &#8220;N\u00e3o \u00e9 justo que o esfor\u00e7o seja s\u00f3 de alguns quando todos compartilham do mesmo territ\u00f3rio e da mesma realidade&#8221;\n<\/div>\n<div class=\"article-paragraph\"><\/div>\n<div class=\"article-paragraph\"><\/div>\n<div class=\"article-paragraph\"><\/div>\n<div class=\"article-paragraph\"><\/div>\n<div class=\"article-paragraph\">\n&nbsp;\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. &#8220;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72042,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-72028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. &quot;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Geral\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot; | Geral\" \/>\n\t\t<meta property=\"og:description\" content=\"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. &quot;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-01-02T04:06:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-01-02T04:06:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot; | Geral\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. &quot;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#article\",\"name\":\"Eduardo Leite manda recado ao legislativo e judici\\u00e1rio: \\\"Sacrif\\u00edcio tem que ser de todos\\\" | Geral\",\"headline\":\"Eduardo Leite manda recado ao legislativo e judici\\u00e1rio: &quot;Sacrif\\u00edcio tem que ser de todos&quot;\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":72042},\"datePublished\":\"2019-01-02T02:06:18-02:00\",\"dateModified\":\"2019-01-02T02:06:18-02:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#webpage\"},\"articleSection\":\"Geral-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/#listItem\",\"position\":2,\"name\":\"Geral-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#listItem\",\"name\":\"Eduardo Leite manda recado ao legislativo e judici\\u00e1rio: &quot;Sacrif\\u00edcio tem que ser de todos&quot;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#listItem\",\"position\":3,\"name\":\"Eduardo Leite manda recado ao legislativo e judici\\u00e1rio: &quot;Sacrif\\u00edcio tem que ser de todos&quot;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#organization\",\"name\":\"Geral\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/ja35.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/wp-content\\\/litespeed\\\/avatar\\\/4\\\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1784089717\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/\",\"name\":\"Eduardo Leite manda recado ao legislativo e judici\\u00e1rio: \\\"Sacrif\\u00edcio tem que ser de todos\\\" | Geral\",\"description\":\"Na primeira reuni\\u00e3o com seus secret\\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. \\\"Vamos tratar das primeiras medidas, entre elas decretos com restri\\u00e7\\u00e3o de viagens, redu\\u00e7\\u00e3o em contratos, diminui\\u00e7\\u00e3o de horas\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":72042,\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\\\/#mainImage\"},\"datePublished\":\"2019-01-02T02:06:18-02:00\",\"dateModified\":\"2019-01-02T02:06:18-02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/\",\"name\":\"Geral\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/geral\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: \"Sacrif\u00edcio tem que ser de todos\" | Geral","description":"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. \"Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas","canonical_url":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#article","name":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: \"Sacrif\u00edcio tem que ser de todos\" | Geral","headline":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot;","author":{"@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/geral\/#organization"},"image":{"@type":"ImageObject","url":72042},"datePublished":"2019-01-02T02:06:18-02:00","dateModified":"2019-01-02T02:06:18-02:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#webpage"},"articleSection":"Geral-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/geral","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/#listItem","name":"Geral-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/#listItem","position":2,"name":"Geral-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#listItem","name":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#listItem","position":3,"name":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/#listItem","name":"Geral-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/geral\/#organization","name":"Geral","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/geral\/","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#authorImage","url":"https:\/\/www.jornalja.com.br\/geral\/wp-content\/litespeed\/avatar\/4\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1784089717","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#webpage","url":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/","name":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: \"Sacrif\u00edcio tem que ser de todos\" | Geral","description":"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. \"Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/geral\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/geral\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":72042,"@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/#mainImage"},"datePublished":"2019-01-02T02:06:18-02:00","dateModified":"2019-01-02T02:06:18-02:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/geral\/#website","url":"https:\/\/www.jornalja.com.br\/geral\/","name":"Geral","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/geral\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Geral","og:type":"article","og:title":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot; | Geral","og:description":"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. &quot;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas","og:url":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/","og:image":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg","article:published_time":"2019-01-02T04:06:18+00:00","article:modified_time":"2019-01-02T04:06:18+00:00","twitter:card":"summary","twitter:title":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot; | Geral","twitter:description":"Na primeira reuni\u00e3o com seus secret\u00e1rios, nesta quarta-feira, 2, o novo governador do Rio Grande do Sul, Eduardo Leite, vai tratar dos cortes que ser\u00e3o feitos em cada pasta para reduzir ainda mais as despesas do governo. &quot;Vamos tratar das primeiras medidas, entre elas decretos com restri\u00e7\u00e3o de viagens, redu\u00e7\u00e3o em contratos, diminui\u00e7\u00e3o de horas","twitter:image":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/ja35.jpg"},"aioseo_meta_data":{"post_id":"72028","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:02:40","updated":"2025-06-04 05:06:14","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.jornalja.com.br\/geral\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/\" title=\"Geral-MAT\u00c9RIA\">Geral-MAT\u00c9RIA<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEduardo Leite manda recado ao legislativo e judici\u00e1rio: \"Sacrif\u00edcio tem que ser de todos\"\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.jornalja.com.br\/geral"},{"label":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},{"label":"Eduardo Leite manda recado ao legislativo e judici\u00e1rio: &quot;Sacrif\u00edcio tem que ser de todos&quot;","link":"https:\/\/www.jornalja.com.br\/geral\/eduardo-leite-diz-que-sacrificio-tem-que-ser-de-todos\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-iJK","jetpack-related-posts":[{"id":100399,"url":"https:\/\/www.jornalja.com.br\/geral\/pt-e-pp-terao-maioria-na-cpi-dos-pedagios-leite-diz-que-governo-nao-se-acovardara\/","url_meta":{"origin":72028,"position":0},"title":"PT e PP ter\u00e3o maioria na CPI dos Ped\u00e1gios; Leite diz que governo &#8220;n\u00e3o se acovardar\u00e1&#8221;","author":"da Reda\u00e7\u00e3o","date":"15 de dezembro de 2025","format":false,"excerpt":"Ser\u00e1 instalada nesta ter\u00e7a-feira,\u00a0 CPI dos Ped\u00e1gios, para investigar os contratos de concess\u00e3o de rodovias pelo governo do Estado do Rio Grande do Sul. O in\u00edcio efetivo das atividades ser\u00e1 na sexta-feira (19), quando os titulares se re\u00fanem pela primeira vez para definir o relator, o vice-presidente e o plano\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/eduardo-leite-pedagios.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/eduardo-leite-pedagios.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/eduardo-leite-pedagios.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/eduardo-leite-pedagios.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101527,"url":"https:\/\/www.jornalja.com.br\/geral\/governo-leite-adia-por-um-mes-leilao-das-98-escolas-que-terao-gestao-privada\/","url_meta":{"origin":72028,"position":1},"title":"Governo Leite adia por um m\u00eas leil\u00e3o das 98 escolas que ter\u00e3o gest\u00e3o privada","author":"da Reda\u00e7\u00e3o","date":"26 de junho de 2026","format":false,"excerpt":"Tem nova data o leil\u00e3o de 98 escolas da rede p\u00fablica do Rio Grande do Sul que ser\u00e3o entregues \u00e0 gest\u00e3o de empresas privadas. Estava marcado para esta sexta-feira, 26\/06, foi adiado, segundo o governo a pedido de \u201cpotenciais participantes do certame\u201d. \u00c9 poss\u00edvel tamb\u00e9m que tenha influ\u00eddo no adiamento\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/privatizacao-de-escolas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/privatizacao-de-escolas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/privatizacao-de-escolas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/06\/privatizacao-de-escolas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":100908,"url":"https:\/\/www.jornalja.com.br\/geral\/com-pressao-de-cpi-e-auditoria-do-tce-governo-leite-adia-leilao-para-concessao-de-rodovias\/","url_meta":{"origin":72028,"position":2},"title":"Com press\u00e3o de CPI e auditoria do TCE, governo Leite adia leil\u00e3o para concess\u00e3o de rodovias","author":"da Reda\u00e7\u00e3o","date":"3 de mar\u00e7o de 2026","format":false,"excerpt":"O governador Eduardo Leite, em coletiva de imprensa realizada no Pal\u00e1cio Piratini nesta ter\u00e7a-feira (3\/3), prometeu uma redu\u00e7\u00e3o da tarifa e mudan\u00e7a na data do leil\u00e3o do Bloco 2 de rodovias no Estado. O bloco envolve estradas localizadas no Vale do Taquari e Norte do Rio Grande Sul. A tarifa\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/leite-faz-anuncio-no-palacio-piratini-sobre-bloco-2-de-rodovias-fev26.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/leite-faz-anuncio-no-palacio-piratini-sobre-bloco-2-de-rodovias-fev26.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/leite-faz-anuncio-no-palacio-piratini-sobre-bloco-2-de-rodovias-fev26.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/leite-faz-anuncio-no-palacio-piratini-sobre-bloco-2-de-rodovias-fev26.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/leite-faz-anuncio-no-palacio-piratini-sobre-bloco-2-de-rodovias-fev26.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/03\/leite-faz-anuncio-no-palacio-piratini-sobre-bloco-2-de-rodovias-fev26.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83129,"url":"https:\/\/www.jornalja.com.br\/geral\/leite-mantem-aulas-suspensas-e-divulga-novo-decreto-sobre-atividades-economicas-dia-30\/","url_meta":{"origin":72028,"position":3},"title":"Leite mant\u00e9m aulas suspensas e divulga novo decreto sobre atividades econ\u00f4micas dia 30","author":"da Reda\u00e7\u00e3o","date":"28 de abril de 2020","format":false,"excerpt":"As aulas em escolas da rede estadual, em universidades e em institui\u00e7\u00f5es de ensino p\u00fablicas e privadas n\u00e3o retornar\u00e3o na pr\u00f3xima segunda-feira (4\/5). \"Ainda estamos definindo se o retorno das aulas se dar\u00e1 ao longo do m\u00eas de maio ou a partir de junho. Estamos observando protocolos que dever\u00e3o ser\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/04\/20200410_141851-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/04\/20200410_141851-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/04\/20200410_141851-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/04\/20200410_141851-1-scaled.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":91469,"url":"https:\/\/www.jornalja.com.br\/geral\/como-serao-os-nove-anos-sob-o-regime-de-recuperacao-fiscal-no-rio-grande-do-sul\/","url_meta":{"origin":72028,"position":4},"title":"Como ser\u00e3o os nove anos sob o Regime de Recupera\u00e7\u00e3o Fiscal no Rio Grande do Sul","author":"da Reda\u00e7\u00e3o","date":"29 de dezembro de 2021","format":false,"excerpt":"O Rio Grande do Sul encaminhou ao Tesouro Nacional seu pedido de ades\u00e3o ao Regime de Recupera\u00e7\u00e3o Fiscal (RRF). Se o pedido for aceito, o \u00faltimo ano de Eduardo Leite e os dois governos seguintes estar\u00e3o\u00a0 \"engessados\" por regras r\u00edgidas de corte de gastos e controle estreito das contas estaduais\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/regme-de-recuperacao.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/regme-de-recuperacao.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/regme-de-recuperacao.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2021\/12\/regme-de-recuperacao.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":80556,"url":"https:\/\/www.jornalja.com.br\/geral\/leite-faz-primeiro-movimento-para-aprovar-o-pacote-em-convocacao-extraordinaria\/","url_meta":{"origin":72028,"position":5},"title":"Leite faz primeiro movimento para aprovar o pacote em convoca\u00e7\u00e3o extraordin\u00e1ria","author":"Elmar Bones","date":"15 de janeiro de 2020","format":false,"excerpt":"Um dia depois do recuo do sindicato dos professores, o governador Eduardo Leite apresentou sua nova proposta para a carreira do magist\u00e9rio, incorporando os 12,84% de reajuste do piso nacional. Na ter\u00e7a-feira \u00e0 tarde, em Assembleia Geral, os professores da rede estadual decidiram encerrar a greve que j\u00e1 durava 57\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/01\/Governador-apresenta-proposta-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/01\/Governador-apresenta-proposta-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/01\/Governador-apresenta-proposta-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/01\/Governador-apresenta-proposta-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=72028"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72028\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=72028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=72028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=72028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}