{"id":72189,"date":"2019-01-13T13:35:10","date_gmt":"2019-01-13T15:35:10","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=72189"},"modified":"2019-01-13T13:35:10","modified_gmt":"2019-01-13T15:35:10","slug":"celulose-suspende-producao-por-15-dias-para-manutencao-da-fabrica-em-guaiba","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/celulose-suspende-producao-por-15-dias-para-manutencao-da-fabrica-em-guaiba\/","title":{"rendered":"Celulose suspende produ\u00e7\u00e3o por 15 dias para manuten\u00e7\u00e3o da f\u00e1brica"},"content":{"rendered":"<p>A CMPC Celulose Riograndense anuncia a parada geral das opera\u00e7\u00f5es da Linha 2 de produ\u00e7\u00e3o da unidade de Gua\u00edba no per\u00edodo de 13 a 29 de janeiro.<br \/>\nManuten\u00e7\u00e3o preventiva e otimiza\u00e7\u00e3o em equipamentos, processos e instala\u00e7\u00f5es s\u00e3o os motivos da parada de 15 dias.<br \/>\n\u201cEsta ser\u00e1 a primeira parada depois de 12 meses que estamos operando em plena capacidade de produ\u00e7\u00e3o&#8221;.afirma Mauricio Harger, o novo diretor geral da CMPC Celulose Riograndense.<br \/>\nAs paradas agora v\u00e3o ocorrer a cada 15 meses e n\u00e3o a cada 12 meses como era antes, gra\u00e7as a melhorias t\u00e9cnicas na unidade de Gua\u00edba..<br \/>\n\u201cConquistamos mais tr\u00eas meses de opera\u00e7\u00e3o sem alterar nossos indicadores de produ\u00e7\u00e3o industrial e n\u00edveis de seguran\u00e7a\u201d, destaca Harger.<br \/>\nTrabalhar\u00e3o nos dias de parada geral cerca de 2 mil profissionais, entre colaboradores da pr\u00f3pria CMPC Celulose Riograndense e de aproximadamente 65 empresas prestadoras de servi\u00e7os.<br \/>\nA expectativa \u00e9 que a economia local de Gua\u00edba, em especial os servi\u00e7os de hotelaria, alimenta\u00e7\u00e3o e com\u00e9rcio, seja beneficiada com a presen\u00e7a de mais pessoas na cidade.<br \/>\nA companhia adotou todas as medidas necess\u00e1rias para reduzir ao m\u00e1ximo eventuais impactos para a comunidade nesse per\u00edodo.<br \/>\n(Com informa\u00e7\u00f5es da Assessoria de Imprensa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A CMPC Celulose Riograndense anuncia a parada geral das opera\u00e7\u00f5es da Linha 2 de produ\u00e7\u00e3o da unidade de Gua\u00edba no per\u00edodo de 13 a 29 de janeiro. Manuten\u00e7\u00e3o preventiva e otimiza\u00e7\u00e3o em equipamentos, processos e instala\u00e7\u00f5es s\u00e3o os motivos da parada de 15 dias. \u201cEsta ser\u00e1 a primeira parada depois de 12 meses que estamos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-72189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-iMl","jetpack-related-posts":[{"id":101060,"url":"https:\/\/www.jornalja.com.br\/geral\/ambientalistas-ampliam-debate-sobre-os-impactos-de-uma-nova-fabrica-de-celulose-as-margens-do-guaiba\/","url_meta":{"origin":72189,"position":0},"title":"Ambientalistas ampliam debate sobre os impactos de uma nova f\u00e1brica de celulose \u00e0s margens do Gua\u00edba","author":"da Reda\u00e7\u00e3o","date":"11 de abril de 2026","format":false,"excerpt":"Um comit\u00ea formado por bi\u00f3logos, engenheiros qu\u00edmicos, m\u00e9dicos, representantes dos povos ind\u00edgenas e quilombolas promoveu na ter\u00e7a-feira, 7 de abril, na C\u00e2mara Municipal de Porto Alegre, uma Audi\u00eancia P\u00fablica Popular para discutir os impactos da instala\u00e7\u00e3o de uma nova f\u00e1brica de celulose da CMPC, projetada para ser constru\u00edda no munic\u00edpio\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/20260407-0004-plenaria-cmpc-camara-poa-ramiro-sanchez-oaf1939.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/20260407-0004-plenaria-cmpc-camara-poa-ramiro-sanchez-oaf1939.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/20260407-0004-plenaria-cmpc-camara-poa-ramiro-sanchez-oaf1939.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/20260407-0004-plenaria-cmpc-camara-poa-ramiro-sanchez-oaf1939.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/20260407-0004-plenaria-cmpc-camara-poa-ramiro-sanchez-oaf1939.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":100660,"url":"https:\/\/www.jornalja.com.br\/geral\/audiencia-publica-sobre-maior-projeto-agro-industrial-do-rs-nao-e-noticia\/","url_meta":{"origin":72189,"position":1},"title":"Audi\u00eancia p\u00fablica sobre maior projeto agro-industrial do RS n\u00e3o \u00e9 not\u00edcia?","author":"Elmar Bones","date":"29 de janeiro de 2026","format":false,"excerpt":"N\u00e3o mereceu manchete nos jornais tradicionais de Porto Alegre a audi\u00eancia p\u00fablica sobre a nova f\u00e1brica de celulose da CMPC em Barra do Ribeiro, que ocorre neste 29 de janeiro de 2026, \u00e0s 16h, no Parque Municipal Nen\u00ea Naibert. A reuni\u00e3o aborda o Projeto Natureza, com investimentos de R$ 24\u2026","rel":"","context":"Em &quot;MANCHETE do Site&quot;","block_context":{"text":"MANCHETE do Site","link":"https:\/\/www.jornalja.com.br\/geral\/category\/manchete-do-site\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/cmpc-protesto-pede-mais-audiencias.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/cmpc-protesto-pede-mais-audiencias.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/cmpc-protesto-pede-mais-audiencias.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/cmpc-protesto-pede-mais-audiencias.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72187,"url":"https:\/\/www.jornalja.com.br\/geral\/venda-da-fibria-marca-saida-do-grupo-votorantim-do-setor-de-celulose-papel\/","url_meta":{"origin":72189,"position":2},"title":"Venda da Fibria marca sa\u00edda do grupo Votorantim do setor de celulose\/papel","author":"da Reda\u00e7\u00e3o","date":"11 de janeiro de 2019","format":false,"excerpt":"O grande fato do mercado internacional da celulose e papel acontece no Brasil. \u00c9 a fus\u00e3o da Suzano com a Fibria, a ser\u00a0concretizada na segunda-feira, dia 14. No jarg\u00e3o tecnocrata \u00e9 um \"processo de combina\u00e7\u00e3o de opera\u00e7\u00f5es e bases acion\u00e1rias com a Fibria\".. Na verdade \u00e9\u00a0 uma incorpora\u00e7\u00e3o da Fibria,\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":101043,"url":"https:\/\/www.jornalja.com.br\/geral\/audiencia-publica-em-porto-alegre-discute-ampliacao-da-cmpc\/","url_meta":{"origin":72189,"position":3},"title":"Audi\u00eancia p\u00fablica em Porto Alegre discute amplia\u00e7\u00e3o da CMPC","author":"da Reda\u00e7\u00e3o","date":"7 de abril de 2026","format":false,"excerpt":"Uma audi\u00eancia p\u00fablica, nesta ter\u00e7a-feira, 07 de abril, a partir das 18h, na C\u00e2mara de Vereadores de Porto Alegre, debate o projeto de expans\u00e3o da multinacional CMPC, que planeja instalar em Barra do Ribeiro o que pode ser a maior ind\u00fastria de celulose da Am\u00e9rica Latina, com investimento de R$\u2026","rel":"","context":"Em &quot;Geral-NOTAS&quot;","block_context":{"text":"Geral-NOTAS","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral-notas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/oi-e1775590247597.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/oi-e1775590247597.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/04\/oi-e1775590247597.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":100627,"url":"https:\/\/www.jornalja.com.br\/geral\/fiergs-preve-expansao-do-pib-e-do-emprego-com-acordo-mercosul-uniao-europeia\/","url_meta":{"origin":72189,"position":4},"title":"Fiergs prev\u00ea expans\u00e3o do PIB e do emprego com acordo Mercosul-Uni\u00e3o Europeia","author":"da Reda\u00e7\u00e3o","date":"19 de janeiro de 2026","format":false,"excerpt":"Presidente Claudio Bier aposta no aumento no fluxo de com\u00e9rcio entre as duas regi\u00f5es; entidade estima alta de 4,6% do PIB ga\u00facho em 15 anos e gera\u00e7\u00e3o de 31 mil empregos. O acordo entre Mercosul e Uni\u00e3o Europeia, assinado neste s\u00e1bado (17), no Paraguai, \u00e9 \"um avan\u00e7o importante\", segundo a\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/fiergs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/fiergs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/fiergs.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/fiergs.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72670,"url":"https:\/\/www.jornalja.com.br\/geral\/cooperativa-dos-apicultores-elege-presidente-por-unanimidade\/","url_meta":{"origin":72189,"position":5},"title":"Cooperativa dos Apicultores elege presidente por unanimidade","author":"Geraldo Hasse","date":"9 de fevereiro de 2019","format":false,"excerpt":"O apicultor Jos\u00e9 Adair de Souza, que trabalha na esta\u00e7\u00e3o experimental da UFRGS em Eldorado do Sul, \u00e9 o novo presidente da Cooperativa dos Apicultores do Sul (Coapisul) para o bi\u00eanio 2019\/2020. Bra\u00e7o direito do professor Aroni Sattler, diretor do Departamento de Apicultura da Faculdade de Agronomia de Porto Alegre,\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/02\/Apicultor-feliz-351x450.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=72189"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=72189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=72189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=72189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}