{"id":72990,"date":"2019-02-24T15:49:06","date_gmt":"2019-02-24T18:49:06","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=72990"},"modified":"2019-02-24T15:49:06","modified_gmt":"2019-02-24T18:49:06","slug":"carta-ao-exercito-qual-o-sentido-de-uma-guerra-contra-a-venezuela","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/carta-ao-exercito-qual-o-sentido-de-uma-guerra-contra-a-venezuela\/","title":{"rendered":"Carta ao Ex\u00e9rcito: qual o sentido de uma guerra contra a Venezuela?"},"content":{"rendered":"<p style=\"font-weight: 400\"><strong>\u00a0Divis\u00e3o de Rela\u00e7\u00f5es P\u00fablicas do Ex\u00e9rcito Brasileiro \u2013 CCOMSEx (<a href=\"mailto:faleconosco@ccomsex.eb.mil.br\">faleconosco@ccomsex.eb.mil.br<\/a>),<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Prezados Senhores Militares,<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><strong>Vejo com muita tristeza e apreens\u00e3o as not\u00edcias de uma poss\u00edvel declara\u00e7\u00e3o de guerra dos EUA contra a Venezuela, com especula\u00e7\u00f5es de poss\u00edvel colabora\u00e7\u00e3o, e at\u00e9 participa\u00e7\u00e3o, das For\u00e7as Armadas Brasileiras.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Tristeza, porque ser\u00e1 quebrado nosso elogioso recorde humanit\u00e1rio de 150 anos sem guerras. Esse \u00e9 o verdadeiro feito da nossa P\u00e1tria, de nossas For\u00e7as Armadas.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Tristeza, tamb\u00e9m, porque a Venezuela nunca nos fez mal, ao contr\u00e1rio, tem colaborado com o Brasil e, acredito, o Brasil com ela.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Apreens\u00e3o porque \u00e9 um privil\u00e9gio ter a maior reserva de petr\u00f3leo nas nossas fronteiras; ter, o Brasil, uma empresa estatal com a capacidade de explora\u00e7\u00e3o e refino como a Petrobras, ao lado dessa reserva, \u00e9 uma vantagem incomensur\u00e1vel. N\u00e3o h\u00e1 interesse algum, por parte do Brasil, em quebrar, com o vizinho pa\u00eds irm\u00e3o, esse la\u00e7o de amizade, e essa teia de oportunidades rec\u00edprocas.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Apreens\u00e3o, tamb\u00e9m, porque o Brasil e seu povo vivem grandes dificuldades internas e seria um grande malef\u00edcio agregar mais um.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>A Venezuela tem, sim, seus problemas, como muitos pa\u00edses do mundo e como n\u00f3s temos, em maiores ou menores propor\u00e7\u00f5es. Cada um deve resolver os seus problemas e, para tanto, a pr\u00f3pria ONU estabelece cl\u00e1usula de n\u00e3o interfer\u00eancia rec\u00edproca.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Governos com suas voca\u00e7\u00f5es doutrin\u00e1rias e modelos de gest\u00e3o passam c\u00e9leres e s\u00e3o substitu\u00eddos por outros, muitas vezes, bastante diferenciados. Mas, a agress\u00e3o b\u00e9lica recebida por um pa\u00eds pelo seu vizinho, principalmente numa situa\u00e7\u00e3o cr\u00edtica, deixa cicatrizes profundas e d\u00e9cadas podem n\u00e3o ser suficientes para estancar a sangria. Ademais, a hist\u00f3ria nunca inocenta agressores.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>A natureza pac\u00edfica do nosso povo, com certeza, n\u00e3o aprovaria uma interfer\u00eancia do Brasil em assuntos internos de outros pa\u00edses, principalmente se for, apenas, para atender a exig\u00eancias de outro pa\u00eds que sempre fez, da guerra, um\u00a0instrumento de Estado para resolver os problemas do mundo, e sem conseguir resolv\u00ea-los, na maioria dos casos.<\/strong><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Finalmente, a morte de jovens brasileiros numa guerra sem prop\u00f3sito como essa, afetaria profundamente a estrutura ps\u00edquica das nossas fam\u00edlias.<\/strong><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Contamos com um gesto verdadeiramente soberano das nossas For\u00e7as Armadas.<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><strong>C\u00e9sar Cantu<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>21.02.19<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Divis\u00e3o de Rela\u00e7\u00f5es P\u00fablicas do Ex\u00e9rcito Brasileiro \u2013 CCOMSEx (faleconosco@ccomsex.eb.mil.br), \u00a0 Prezados Senhores Militares, \u00a0Vejo com muita tristeza e apreens\u00e3o as not\u00edcias de uma poss\u00edvel declara\u00e7\u00e3o de guerra dos EUA contra a Venezuela, com especula\u00e7\u00f5es de poss\u00edvel colabora\u00e7\u00e3o, e at\u00e9 participa\u00e7\u00e3o, das For\u00e7as Armadas Brasileiras. Tristeza, porque ser\u00e1 quebrado nosso elogioso recorde humanit\u00e1rio de 150 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-72990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-iZg","jetpack-related-posts":[{"id":100467,"url":"https:\/\/www.jornalja.com.br\/geral\/estados-unidos-sequestram-nicolas-maduro-em-desafio-explicito-a-china-comissao-chinesa-estava-na-venezuela\/","url_meta":{"origin":72990,"position":0},"title":"Estados Unidos sequestram Nicolas Maduro em desafio expl\u00edcito \u00e0 China; comiss\u00e3o chinesa estava na Venezuela","author":"da Reda\u00e7\u00e3o","date":"3 de janeiro de 2026","format":false,"excerpt":"O ataque dos Estados Unidos \u00e0 Venezuela com\u00a0 o sequestro do presidente Nicolas Mauro e sua esposa na madrugada desta s\u00e1bado (3), ocorreu poucas horas depois de uma reuni\u00e3o do presidente venezuelano com representantes oficiais do governo chin\u00eas, em Caracas. A China tem sido um parceiro importante do governo Maduro,\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":100500,"url":"https:\/\/www.jornalja.com.br\/geral\/lider-chines-condena-atos-unilaterais-que-solapam-a-ordem-mundial-sem-citar-estados-unidos-ou-trump\/","url_meta":{"origin":72990,"position":1},"title":"L\u00edder chin\u00eas condena &#8220;atos unilaterais&#8221; sem citar Estados Unidos ou Trump","author":"da Reda\u00e7\u00e3o","date":"5 de janeiro de 2026","format":false,"excerpt":"Vinte quatro horas depois do ataque em que o presidente Nicolas Maduro e sua mulher Cilia Flores foram sequestrados por for\u00e7as militares dos Estados Unidos, n\u00e3o h\u00e1 um desfecho previs\u00edvel para a crise internacional desencadeada pela invas\u00e3o da Venezuela, no s\u00e1bado, 3. Donald Trump, o presidente americano, que comemorou nas\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-venezuela-xi-jinping.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-venezuela-xi-jinping.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-venezuela-xi-jinping.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":100476,"url":"https:\/\/www.jornalja.com.br\/geral\/china-e-russia-foram-avisadas-antes-do-ataque-a-venezuela-ha-um-acordo-com-trump-para-uma-nova-divisao-mundial\/","url_meta":{"origin":72990,"position":2},"title":"China e R\u00fassia foram avisadas antes do ataque \u00e0 Venezuela? H\u00e1 um acordo com Trump para uma nova divis\u00e3o mundial?","author":"da Reda\u00e7\u00e3o","date":"3 de janeiro de 2026","format":false,"excerpt":"S\u00e3o muitas as perguntas sem resposta neste s\u00e1bado em que o mundo acompanha, estarrecido, o ataque dos Estados Unidos \u00e0 Venezuela e o sequestro do presidente Nicolas Maduro e sua esposa, Cilia Flores. A principal e a mais inquietante das perguntas \u00e9 esta: esse movimento de Trump na Venezuela faz\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela-esta-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela-esta-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela-esta-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2026\/01\/ataque-a-venezuela-esta-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":99560,"url":"https:\/\/www.jornalja.com.br\/geral\/legalidade-o-dia-em-que-o-rio-grande-resistiu\/","url_meta":{"origin":72990,"position":3},"title":"Legalidade: O dia em que o Rio Grande resistiu","author":"S\u00e9rgio Lagranha","date":"25 de agosto de 2025","format":false,"excerpt":"S\u00e9rgio Lagranha* M\u00eas do cachorro louco, das bruxas. M\u00eas em que bombas at\u00f4micas foram lan\u00e7adas sobre Hiroshima e Nagazaki, em 1945. M\u00eas em que o presidente Get\u00falio Vargas se suicidou com um tiro no peito, em 1954. Aquele agosto de 1961\u00a0 come\u00e7ou fazendo jus \u00e0 fama. J\u00e1 no dia 5,\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/legalidade5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/legalidade5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/legalidade5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/08\/legalidade5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":78257,"url":"https:\/\/www.jornalja.com.br\/geral\/78257-2\/","url_meta":{"origin":72990,"position":4},"title":"Transporte clandestino de petr\u00f3leo pode estar na origem da mancha de \u00f3leo","author":"da Reda\u00e7\u00e3o","date":"13 de outubro de 2019","format":false,"excerpt":"Navios que circulam clandestinamente pelo Atlantico para\u00a0 burlar o embargo comercial imposto pelos Estados Unidos \u00e0 Venezuela. Um deles teria descartado a mercadoria para n\u00e3o ser flagrado. Esta \u00e9 a nova hip\u00f3tese para as causas do vazamento de \u00f3leo cr\u00fa que atinge a costa de 12 Estados brasileiros. As manchas\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":94917,"url":"https:\/\/www.jornalja.com.br\/geral\/lula-quer-forcas-armadas-e-policia-federal-para-proteger-a-amazonia-e-as-fronteiras\/","url_meta":{"origin":72990,"position":5},"title":"Lula quer For\u00e7as Armadas e Pol\u00edcia Federal para proteger a Amaz\u00f4nia e as fronteiras","author":"da Reda\u00e7\u00e3o","date":"19 de janeiro de 2023","format":false,"excerpt":"\u201cN\u00e3o queremos transformar a Amaz\u00f4nia num santu\u00e1rio\u201d, afirmou Lula ao anunciar que pretende reunir-se com os presidentes dos pa\u00edses pelos quais a Amaz\u00f4nia se estende \u2013 Col\u00f4mbia, Peru, Equador, Venezuela, Bol\u00edvia e Guiana Francesa - para discutir uma pol\u00edtica continental e \u201cpra saber se esse famoso cr\u00e9dito de carbono existe\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2023\/01\/lula-a-natuza-18-1-23-reproducao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2023\/01\/lula-a-natuza-18-1-23-reproducao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2023\/01\/lula-a-natuza-18-1-23-reproducao.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=72990"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/72990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=72990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=72990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=72990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}