{"id":73031,"date":"2019-02-25T14:55:41","date_gmt":"2019-02-25T17:55:41","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=73031"},"modified":"2019-02-25T14:55:41","modified_gmt":"2019-02-25T17:55:41","slug":"apiterapia-a-picada-de-abelha-que-faz-bem-a-saude","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/apiterapia-a-picada-de-abelha-que-faz-bem-a-saude\/","title":{"rendered":"Apiterapia: a picada de abelha que faz bem \u00e0 sa\u00fade"},"content":{"rendered":"<p><em>Reconhecida pelo Minist\u00e9rio da Sa\u00fade como Terapia Integrativa em 2018, t\u00e9cnica existe h\u00e1 mais de 100 anos e usa produtos das abelhas, sendo o principal deles o veneno<\/em><br \/>\n<em>\u00a0<\/em>Picada de abelha pode fazer bem. \u00c9 o que garantem especialistas que utilizam a apiterapia, um tipo de terapia natural que usa como base do tratamento as toxinas liberadas na picada de abelha e tem subst\u00e2ncias analg\u00e9sicas e anti-inflamat\u00f3rias.<br \/>\nA t\u00e9cnica existe h\u00e1 mais de 100 anos, mas s\u00f3 agora foi reconhecida como tratamento pelo Sistema \u00danico de Sa\u00fade (SUS). Com isso, a apiterapia passa a integrar as 19 terapias alternativas adotadas pelo Minist\u00e9rio da Sa\u00fade.<br \/>\nDo total, 19 datam de 2006 e, dez, de 2018.\u00a0Vale lembrar que o Minist\u00e9rio da Sa\u00fade aponta evid\u00eancias cient\u00edficas que t\u00eam mostrado os benef\u00edcios do tratamento integrado entre medicina convencional e pr\u00e1ticas integrativas e complementares.<br \/>\nEntre os principais benef\u00edcios desta terapia, o baixo custo, assertividade e\u00a0\u00a0resultado, al\u00e9m do equil\u00edbrio ecol\u00f3gico e respeito \u00e0 natureza.<br \/>\nDe acordo com\u00a0Lilian Rosana dos Santos Moraes, coordenadora do curso de Terapias Integrativas da Unicesumar, dentro dos tratamentos desta t\u00e9cnica \u00e9 verificado o fortalecimento e equil\u00edbrio do sistema imunol\u00f3gico.<br \/>\n\u201cA apiterapia tem como objetivo estimular o organismo a produzir subst\u00e2ncias de defesa para fortalecer o sistema Imunol\u00f3gico, orientando-o a superar suas pr\u00f3prias barreiras de defesa, por meio de uma estimula\u00e7\u00e3o apropriada\u201d.<br \/>\nEmbora muitos ainda desconhe\u00e7am a terapia das abelhas, a tend\u00eancia \u00e9 que a procura aumente, especialmente no tratamento de dores cr\u00f4nicas e inflama\u00e7\u00f5es.<br \/>\nVale lembrar que a apiterapia pretende proporcionar ao m\u00e9dico e ao apiterapeuta um n\u00famero maior de ferramentas, que venham a completar e ampliar o programa terap\u00eautico do paciente. \u201cA base do trabalho da apiterapia vale-se de v\u00e1rios produtos das abelhas, sendo o principal deles o veneno\u201d, afirma a professora.<br \/>\nMas como o veneno pode ser ben\u00e9fico? Basta saber que um dos componentes do veneno, a Melitina, \u00e9 200 vezes superior ao mais potente corticoide sint\u00e9tico, e a Apamina inibe a destrui\u00e7\u00e3o da Mielina, respons\u00e1vel pelas rela\u00e7\u00f5es entre as c\u00e9lulas nervosas.<br \/>\nE segundo a coordenadora, o maior poder de \\piterapia reside na mistura de v\u00e1rios produtos e na explora\u00e7\u00e3o sin\u00e9rgica entre eles.<br \/>\nA terapia utiliza produtos naturais, uma forma de Medicina Verde das mais antigas na hist\u00f3ria da humanidade. \u201cPara se ter uma ideia, \u00e9 mais antiga que qualquer medicamento industrial. Como um medicamento verde, a apiterapia harmoniza a pessoa em primeiro plano, e ent\u00e3o, a enfermidade\u201d, completa Lilian Moraes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reconhecida pelo Minist\u00e9rio da Sa\u00fade como Terapia Integrativa em 2018, t\u00e9cnica existe h\u00e1 mais de 100 anos e usa produtos das abelhas, sendo o principal deles o veneno \u00a0Picada de abelha pode fazer bem. \u00c9 o que garantem especialistas que utilizam a apiterapia, um tipo de terapia natural que usa como base do tratamento as [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73032,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-73031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-iZV","jetpack-related-posts":[{"id":92970,"url":"https:\/\/www.jornalja.com.br\/geral\/chapeco-sera-capital-brasileira-do-mel-neste-fim-de-semana\/","url_meta":{"origin":73031,"position":0},"title":"Chapec\u00f3 ser\u00e1 capital brasileira do mel neste fim de semana","author":"Elmar Bones","date":"30 de junho de 2022","format":false,"excerpt":"Os tr\u00eas estados do sul respondem por cerca de 40% da produ\u00e7\u00e3o de mel do Brasil. A regi\u00e3o tem 66.554 apicultores e meliponicultores, sendo 12.491 no Paran\u00e1, 16.838 em SC e 37.225 no Rio Grande do Sul. Parte representativa desse universo estar\u00e1 em Chapec\u00f3, nesta semana, para participar dos principais\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2022\/06\/abelhas-colmeia-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2022\/06\/abelhas-colmeia-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2022\/06\/abelhas-colmeia-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2022\/06\/abelhas-colmeia-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2022\/06\/abelhas-colmeia-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2022\/06\/abelhas-colmeia-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":78191,"url":"https:\/\/www.jornalja.com.br\/geral\/abelhas-sem-ferrao-em-exposicao-no-5o-festimel\/","url_meta":{"origin":73031,"position":1},"title":"Abelhas sem ferr\u00e3o em exposi\u00e7\u00e3o no 5\u00ba Festimel","author":"da Reda\u00e7\u00e3o","date":"9 de outubro de 2019","format":false,"excerpt":"Uma oportunidade de conhecer os insetos que formam uma das sociedades mais organizadas e que produz um dos alimentos mais nutritivos e saud\u00e1veis. Assim \u00e9 a exposi\u00e7\u00e3o de Meliponicultura- as abelhas sem ferr\u00e3o, que podem ser vistas nos pavilh\u00f5es do 5\u00ba Festimel, a Feira do Mel e do Doce que\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":79919,"url":"https:\/\/www.jornalja.com.br\/geral\/ha-uma-rede-de-pesquisadores-de-plantas-medicinais-no-servico-publico-de-saude\/","url_meta":{"origin":73031,"position":2},"title":"H\u00e1 uma rede de pesquisadores de plantas medicinais no servi\u00e7o p\u00fablico de sa\u00fade","author":"Geraldo Hasse","date":"11 de dezembro de 2019","format":false,"excerpt":"Em vias de aposentar-se na Secretaria da Sa\u00fade do Estado do Rio Grande do Sul, onde trabalha h\u00e1 39 anos, a farmac\u00eautica Silvia Ciemainski decidiu manter-se trabalhando em sua especialidade -- o uso de plantas medicinais na sa\u00fade p\u00fablica --, mesmo sabendo que a escassez de recursos or\u00e7ament\u00e1rios criou uma\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":96879,"url":"https:\/\/www.jornalja.com.br\/geral\/apicultores-assumem-centro-para-pesquisar-viroses-que-dizimam-abelhas\/","url_meta":{"origin":73031,"position":3},"title":"Apicultores assumem centro para pesquisar viroses que dizimam abelhas","author":"Geraldo Hasse","date":"8 de janeiro de 2024","format":false,"excerpt":"Seis anos depois da extin\u00e7\u00e3o da Fepagro pelo governador Ivo Sartori, a Federa\u00e7\u00e3o Ap\u00edcola do RS assumiu a gest\u00e3o do hist\u00f3rico Centro de Pesquisas de Taquari, que est\u00e1 em ru\u00ednas e ser\u00e1 recuperado para pesquisas gen\u00e9ticas, forma\u00e7\u00e3o, treinamento e reciclagem de produtores de mel. Estima-se que ser\u00e3o necess\u00e1rios seis meses\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/01\/mel-materia-ipagro.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/01\/mel-materia-ipagro.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/01\/mel-materia-ipagro.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/01\/mel-materia-ipagro.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/01\/mel-materia-ipagro.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2024\/01\/mel-materia-ipagro.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":74659,"url":"https:\/\/www.jornalja.com.br\/geral\/mercado-do-mel-em-crise-enquanto-abelhas-morrem-envenenadas\/","url_meta":{"origin":73031,"position":4},"title":"Mercado do mel em crise enquanto abelhas morrem envenenadas","author":"Geraldo Hasse","date":"29 de maio de 2019","format":false,"excerpt":"Refletindo a crise do mercado do mel, reduziu-se a menos da metade o p\u00fablico que costuma comparecer aos concorridos semin\u00e1rios t\u00e9cnicos promovidos pelo Departamento de Apicultura da UFRGS. No s\u00e1bado passado, dia 25, a foto sob a figueira do campus rural em Eldorado do Sul registrou um dos menores quoruns\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":100343,"url":"https:\/\/www.jornalja.com.br\/geral\/estudo-aponta-perdas-de-r-38-bilhoes-por-ano-com-efeitos-colaterais-das-bets\/","url_meta":{"origin":73031,"position":5},"title":"Estudo aponta perdas de R$ 38 bilh\u00f5es por ano com efeitos colaterais das bets","author":"da Reda\u00e7\u00e3o","date":"2 de dezembro de 2025","format":false,"excerpt":"Jogos de azar e apostas\u00a0online, popularizadas pelas chamadas\u00a0bets, provocam perdas econ\u00f4micas e sociais ao pa\u00eds estimadas em R$ 38,8 bilh\u00f5es anualmente. Esse valor \u00e9 o somat\u00f3rio de danos \u00e0 sociedade, como suic\u00eddios, desemprego, gastos com sa\u00fade e afastamento do trabalho. O c\u00e1lculo \u00e9 do estudo in\u00e9dito\u00a0A sa\u00fade dos brasileiros em\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/bets-efeitos-colaterais.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/bets-efeitos-colaterais.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2025\/12\/bets-efeitos-colaterais.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/73031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=73031"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/73031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=73031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=73031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=73031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}