{"id":73248,"date":"2019-03-11T15:57:46","date_gmt":"2019-03-11T18:57:46","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=73248"},"modified":"2019-03-11T15:57:46","modified_gmt":"2019-03-11T18:57:46","slug":"fantasia-inspirada-em-flavio-bolsonaro-vence-concurso-no-rio","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/fantasia-inspirada-em-flavio-bolsonaro-vence-concurso-no-rio\/","title":{"rendered":"Fantasia inspirada nos dep\u00f3sitos de Queiroz vence concurso no Rio"},"content":{"rendered":"<p>A fantasia do caixa eletr\u00f4nico e 48 envelopes para dep\u00f3sito foi a mais votada pelos leitores e ganhou o tradicional Concurso de Fantasia Serpentina de Ouro, do jornal o Globo, no Rio. GLOBO.<br \/>\nA inspira\u00e7\u00e3o da fantasia s\u00e3o as &#8220;movimenta\u00e7\u00f5es financeiras at\u00edpicas&#8221; de Fabr\u00edcio Queiroz, ex-assessor do senador Fl\u00e1vio Bolsonaro (PSL-RJ).<br \/>\nA ideia foi do professor Faber Paganoto, a partir de um meme no Twitter que dizia: &#8221; somos todos dep\u00f3sitos do Bolsonaro&#8221;.<\/p>\n<div class=\"article__newsletter\"><label class=\"article__newsletter-email-label\" for=\"article__newsletter-email\">\u00a0<span style=\"font-weight: 300\">Faber vestiu-se de caixa eletr\u00f4nico, juntou mais 48 amigos, que se vestiram de envelopes para dep\u00f3sito de R$ 2 mil, para simular os 48 dep\u00f3sitos de Queiroz descobertos na conta do filho do presidente..\u00a0<\/span><\/label><\/div>\n<p>\u2014 A escala da fantasia deu uma dimens\u00e3o maior do problema. Acho que por isso a fantasia fez tanto sucesso \u2014 conta o professor.<br \/>\nPara o concurso, foram selecionadas dez fantasias entre as inscritas no Instagram e\u00a0 as selecionadas nas ruas pela equipe de rep\u00f3rteres que fez a cobertura do carnaval de rua no Rio. A vota\u00e7\u00e3o foi feita pelos leitores no site do\u00a0 jornal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fantasia do caixa eletr\u00f4nico e 48 envelopes para dep\u00f3sito foi a mais votada pelos leitores e ganhou o tradicional Concurso de Fantasia Serpentina de Ouro, do jornal o Globo, no Rio. GLOBO. A inspira\u00e7\u00e3o da fantasia s\u00e3o as &#8220;movimenta\u00e7\u00f5es financeiras at\u00edpicas&#8221; de Fabr\u00edcio Queiroz, ex-assessor do senador Fl\u00e1vio Bolsonaro (PSL-RJ). A ideia foi do [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73249,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-73248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-j3q","jetpack-related-posts":[{"id":72316,"url":"https:\/\/www.jornalja.com.br\/geral\/o-caso-queiroz-e-os-negocios-imobiliarios-de-flavio-bolsonaro\/","url_meta":{"origin":73248,"position":0},"title":"O &quot;caso Queiroz&quot; e os neg\u00f3cios imobili\u00e1rios de Fl\u00e1vio Bolsonaro","author":"da Reda\u00e7\u00e3o","date":"21 de janeiro de 2019","format":false,"excerpt":"O deputado e agora senador eleito Fl\u00e1vio Bolsonaro escolheu a Record e a Rede TV para dar suas explica\u00e7\u00f5es sobre as \"movimenta\u00e7\u00f5es at\u00edpicas\" em sua conta banc\u00e1ria, reveladas pelo Jornal Nacional, da Globo. As duas entrevistas, que Fl\u00e1vio Bolsonaro deu na noite de domingo,\u00a0 ainda estavam nas manchetes \u00e0s seis\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":75405,"url":"https:\/\/www.jornalja.com.br\/geral\/caso-queiroz-toffoli-manda-suspender-investigacoes-que-envolvem-flavio-bolsonaro\/","url_meta":{"origin":73248,"position":1},"title":"Toffoli manda suspender investiga\u00e7\u00f5es que envolvem Fl\u00e1vio Bolsonaro","author":"da Reda\u00e7\u00e3o","date":"16 de julho de 2019","format":false,"excerpt":"O ministro Dias Toffoli, presidente do STF, suspendeu, todas as investiga\u00e7\u00f5es que envolvam o senador Fl\u00e1vio Bolsonaro, com base em dados sigilosos do Conselho de Controle de Atividades Financeiras (Coaf) e da Receita Federal. Respons\u00e1vel pelo plant\u00e3o no recesso do Judici\u00e1rio, Toffoli assinou a decis\u00e3o na segunda-feira (15), mas s\u00f3\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":76876,"url":"https:\/\/www.jornalja.com.br\/geral\/revista-descobre-o-paradeiro-de-queiroz-o-ex-assessor-de-flavio-bolsonaro\/","url_meta":{"origin":73248,"position":2},"title":"Revista descobre o paradeiro de Queiroz, o ex-assessor de Fl\u00e1vio Bolsonaro","author":"da Reda\u00e7\u00e3o","date":"30 de agosto de 2019","format":false,"excerpt":"Por volta das 17h50 do \u00faltimo dia 26, o desaparecido mais famoso do Brasil passou, sem chamar aten\u00e7\u00e3o de ningu\u00e9m, pela porta e se encaminhou para a recep\u00e7\u00e3o do Centro de Oncologia e Hematologia do Hospital Albert Einstein, em S\u00e3o Paulo. Ali s\u00e3o oferecidos consultas e servi\u00e7os como quimioterapia e\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":81407,"url":"https:\/\/www.jornalja.com.br\/geral\/carnaval-bancos-so-abrem-na-quarta-a-partir-do-meio-dia\/","url_meta":{"origin":73248,"position":3},"title":"Carnaval: bancos s\u00f3 abrem na quarta a partir do meio dia","author":"da Reda\u00e7\u00e3o","date":"23 de fevereiro de 2020","format":false,"excerpt":"Os bancos v\u00e3o ficar fechados na segunda (24) e ter\u00e7a (25) de carnaval. Na Quarta-feira de Cinzas, o atendimento ser\u00e1 feito a partir do meio-dia nas ag\u00eancias que normalmente fecham \u00e0s 16 horas e um pouco mais cedo naquelas que fecham antes das 15h. Com isso, neste feriado, quem precisar\u2026","rel":"","context":"Em &quot;Geral-NOTAS&quot;","block_context":{"text":"Geral-NOTAS","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral-notas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":78722,"url":"https:\/\/www.jornalja.com.br\/geral\/bolsonaro-diz-que-nao-vai-ter-jeitinho-na-hora-de-renovar-a-concessao-da-globo\/","url_meta":{"origin":73248,"position":4},"title":"Bolsonaro diz que &quot;n\u00e3o vai ter jeitinho&quot; na hora de renovar a concess\u00e3o da Globo","author":"da Reda\u00e7\u00e3o","date":"30 de outubro de 2019","format":false,"excerpt":"Mais um vazamento de processo que corre em segredo de Justi\u00e7a sacode a Rep\u00fablica. Desta vez s\u00e3o os registros da portaria do condom\u00ednio onde mora o ex- policial Ronnie Lessa , vazados para o Jornal Nacional desta ter\u00e7a-feira. Ronnie Lessa, sargento aponsentado da PM, \u00e9 um dos suspeitos de matar\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84104,"url":"https:\/\/www.jornalja.com.br\/geral\/queiroz-mandou-recado-aos-bolsonaro-todos-vao-dancar\/","url_meta":{"origin":73248,"position":5},"title":"Queiroz mandou recado aos Bolsonaro: &#8220;Todos v\u00e3o dan\u00e7ar&#8221;","author":"da Reda\u00e7\u00e3o","date":"18 de junho de 2020","format":false,"excerpt":"A pris\u00e3o de Fabr\u00edcio Queiroz na primeira hora desta quinta-feira\u00a0 \u00e9 o mais duro golpe na fam\u00edlia Bolsonaro e atinge tamb\u00e9m o presidente. Amigo da fam\u00edlia h\u00e1 mais de 30 anos e ex-assessor de Fl\u00e1vio Bolsonaro, Queiroz era o articulador do esquema de \"rachadinha\" no gabinete de Fl\u00e1vio durante o\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/06\/Queroz-dan%C3%A7a-nohosptal-video-gravado-por-uma-filha..jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/06\/Queroz-dan%C3%A7a-nohosptal-video-gravado-por-uma-filha..jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/06\/Queroz-dan%C3%A7a-nohosptal-video-gravado-por-uma-filha..jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/geral\/wp-content\/uploads\/sites\/4\/2020\/06\/Queroz-dan%C3%A7a-nohosptal-video-gravado-por-uma-filha..jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/73248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=73248"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/73248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=73248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=73248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=73248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}