{"id":73315,"date":"2019-03-15T00:26:02","date_gmt":"2019-03-15T03:26:02","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=73315"},"modified":"2019-03-15T00:26:02","modified_gmt":"2019-03-15T03:26:02","slug":"o-grito-ecoa-nas-ruas-quem-mandou-matar-marielle","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/geral\/o-grito-ecoa-nas-ruas-quem-mandou-matar-marielle\/","title":{"rendered":"O grito ecoa nas ruas: &quot;Quem mandou matar Marielle?&quot;"},"content":{"rendered":"<p>A avenida Borges de Medeiros, no centro hist\u00f3rico de Porto Alegre, tornou-se rua Marielle Franco no anoitecer desta quinta-feira, 14 de mar\u00e7o.<br \/>\nAs palavras de ordem ecoaram pelos arcos do viaduto: &#8220;Quem mandou matar Marielle?&#8221;.<br \/>\nNo ato que marcou um ano do assassinato da vereadora carioca Marielle Franco e do motorista Anderson Gomes,\u00a0 milhares de militantes de\u00a0 todas as idades e tend\u00eancias diversas juntaram-se cidad\u00e3os sem bandeiras partid\u00e1rias. N\u00e3o foram ouvidas buzinas em protesto ao interrompimento do tr\u00e2nsito, e uma viatura da pol\u00edcia militar seguiu o cortejo em sil\u00eancio.<br \/>\nA imagem do rosto de Marielle passou pela avenida como um estandarte.<br \/>\nManifesta\u00e7\u00f5es exigindo esclarecimentos e justi\u00e7a ocorreram em todo o pa\u00eds e em diversas cidades do mundo.<br \/>\n&#8220;Os que mataram\u00a0n\u00e3o imaginavam que as sementes de Marielle ocupariam as ruas quantas vezes fossem necess\u00e1rias at\u00e9 conseguirmos justi\u00e7a\u201d, discursou em Porto Alegre a deputada federal Fernanda Melchionna, do Psol, mesmo partido de Marielle.<\/p>\n<div class=\"\">\n<div id=\"content\">\n<div id=\"content-core\">\nAtos e eventos clamando pela vida, pela democracia e pela justi\u00e7a, se alastraram por v\u00e1rias cidades do Brasil e do mundo.\u00a0Os eventos acontecem n\u00e3o apenas na data do crime, mas se estendem at\u00e9 a semana que vem, em v\u00e1rias cidades do planeta.<br \/>\n<a class=\"external-link\" title=\"\" href=\"http:\/\/midianinja.org\/news\/agenda-de-atos-pelo-brasil-e-mundo-por-marielle-e-anderson\/\" target=\"_self\" rel=\"noopener noreferrer\">Confira agenda de atos por Marielle no Brasil e no mundo<\/a>.<br \/>\n<figure id=\"attachment_73319\" aria-describedby=\"caption-attachment-73319\" style=\"width: 271px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\" wp-image-73319\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/03\/Pra\u00e7a-Lu\u00eds-de-Cam\u00f5es-em-Lisboa-um-ano-morte-Mariellle.jpg\" alt=\"\" width=\"271\" height=\"206\" \/><figcaption id=\"caption-attachment-73319\" class=\"wp-caption-text\">Pra\u00e7a Lu\u00eds de Cam\u00f5es, em Lisboa<\/figcaption><\/figure><br \/>\nEm cidades como Lisboa, Buenos Aires, Berlim, Amsterd\u00e3, Genebra, Bolonha, Madri, Melbourne, Londres, Nova York, Boston, Los Angeles, Montreal, Ottawa e Montevid\u00e9u houve manifesta\u00e7\u00f5es com o mesmo mote: &#8220;Quem mandou matar Marielle?&#8221;\n<\/div>\n<\/div>\n<\/div>\n<div id=\"viewlet-below-content\">\n<div class=\"\">\n<div id=\"content\">\n<div id=\"content-core\">\n<div>\nO ex-candidato \u00e0 presid\u00eancia da Rep\u00fablica pelo Psol, Guilherme Boulos, tamb\u00e9m lembrou que o assassinato da vereadora completou um ano sem que se soubesse quem foram os mandantes do crime. &#8220;H\u00e1 poucos dias identificaram\u00a0<a class=\"internal-link\" title=\"\" href=\"http:\/\/www.redebrasilatual.com.br\/cidadania\/2019\/03\/policia-do-rio-prende-dois-suspeitos-do-assassinato-de-marielle-franco\" target=\"_self\" rel=\"noopener noreferrer\">os suspeitos do assassinato<\/a>. Mas n\u00e3o basta saber quem apertou o gatilho. \u00c9 preciso saber quem mandou matar Marielle&#8221; registrou. &#8220;\u00c9 isso que este ato aqui em S\u00e3o Paulo e manifesta\u00e7\u00f5es em todo o Brasil est\u00e3o querendo saber.&#8221; Porque\u00a0<span style=\"font-weight: 300\">&#8220;a\u00a0morte de Marielle foi um crime pol\u00edtico&#8221;.\u00a0<\/span>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"viewlet-below-content\">\n<div class=\"\">\n<div id=\"content\">\n<div id=\"content-core\">\nO padre J\u00falio Lancelotti, da Pastoral do Povo de Rua, saudou a \u201ccoragem dos que enfrentam os poderosos e nunca ficam do lado dos que pisam nos pobres\u201d.\u00a0O religioso clamou para que a popula\u00e7\u00e3o defenda os oprimidos, como fazia a vereadora. \u201cDefendam aqueles que s\u00e3o exterminados pelo preconceito e pela viol\u00eancia. Marielle est\u00e1 viva, Anderson (<em>o motorista da vereadora, tamb\u00e9m morto em 14 de mar\u00e7o de 2018<\/em>) est\u00e1 vivo, junto com todos os que lutam.\u201d\n<\/div>\n<div id=\"viewlet-below-content-body\">\n<div class=\"documentActions\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A avenida Borges de Medeiros, no centro hist\u00f3rico de Porto Alegre, tornou-se rua Marielle Franco no anoitecer desta quinta-feira, 14 de mar\u00e7o. As palavras de ordem ecoaram pelos arcos do viaduto: &#8220;Quem mandou matar Marielle?&#8221;. No ato que marcou um ano do assassinato da vereadora carioca Marielle Franco e do motorista Anderson Gomes,\u00a0 milhares de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73316,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-73315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pbKhrD-j4v","jetpack-related-posts":[{"id":83802,"url":"https:\/\/www.jornalja.com.br\/geral\/caso-marielle-investigacoes-continuam-com-a-policia-do-rio\/","url_meta":{"origin":73315,"position":0},"title":"Caso Marielle: investiga\u00e7\u00f5es continuam com a pol\u00edcia do Rio","author":"da Reda\u00e7\u00e3o","date":"28 de maio de 2020","format":false,"excerpt":"O Superior Tribunal de Justi\u00e7a rejeitou o pedido de federaliza\u00e7\u00e3o das investiga\u00e7\u00f5es sobre o assassinato da vereadora Marielle Franco e do motorista Anderson Gomes. O crime ocorreu em 14 de mar\u00e7o de 2018, no centro do Rio de Janeiro. A decis\u00e3o, por unanimidade, foi tomada nesta quarta-feira, 27. O pedido\u2026","rel":"","context":"Em &quot;Geral-NOTAS&quot;","block_context":{"text":"Geral-NOTAS","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral-notas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":75879,"url":"https:\/\/www.jornalja.com.br\/geral\/policia-nao-consegue-desbloquear-celulares-dos-suspeitos-da-matar-marielle\/","url_meta":{"origin":73315,"position":1},"title":"Pol\u00edcia n\u00e3o consegue desbloquear celulares dos suspeitos da matar Marielle","author":"da Reda\u00e7\u00e3o","date":"2 de agosto de 2019","format":false,"excerpt":"A Justi\u00e7a autorizou uma per\u00edcia particular nos cinco celulares apreendidos com Ronnie Lessa e \u00c9lcio Queiroz presos em mar\u00e7o, apontados como autores dos assassinatos da vereadora carioca Marielle Franco e do motorista dela, Anderson Gomes. Os telefones foram remetidos \u00e0 Cellebrite, empresa de S\u00e3o Paulo. A pol\u00edcia n\u00e3o conseguiu desbloquear\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":73360,"url":"https:\/\/www.jornalja.com.br\/geral\/marielle-traz-uma-novidade-muito-grande-no-que-ela-encarna-diz-sociologo\/","url_meta":{"origin":73315,"position":2},"title":"Marielle traz uma novidade muito grande, diz soci\u00f3logo","author":"da Reda\u00e7\u00e3o","date":"17 de mar\u00e7o de 2019","format":false,"excerpt":"Entrevista a Eduardo Maretti, da RBA Para Laymert Garcia dos Santos, a morte de Marielle provocou um despertar, revelado pela grande repercuss\u00e3o no 14 de mar\u00e7o: \"as pessoas come\u00e7aram a se tocar de que n\u00e3o podiam mais tolerar o intoler\u00e1vel\" A enorme propaga\u00e7\u00e3o de manifesta\u00e7\u00f5es e atos pol\u00edticos no Brasil\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":73336,"url":"https:\/\/www.jornalja.com.br\/geral\/marielle-franco-se-tornou-um-grito-de-guerra-num-brasil-polarizado\/","url_meta":{"origin":73315,"position":3},"title":"&quot;Marielle Franco se tornou um grito de guerra num Brasil polarizado&quot;","author":"da Reda\u00e7\u00e3o","date":"17 de mar\u00e7o de 2019","format":false,"excerpt":"Reportagem do The New York Times sobre as manifesta\u00e7\u00f5es do 14 de mar\u00e7o. \u00a0A quest\u00e3o paira sobre a cidade: \u201cQuem matou Marielle Franco?\u201d \u00c9 criada em grafite em praticamente todos os bairros, estampada em camisetas e escrita em faixas exibidas desafiadoramente em manifesta\u00e7\u00f5es de massa. Esta semana, poucos dias antes\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":72409,"url":"https:\/\/www.jornalja.com.br\/geral\/secretaria-que-estava-no-carro-com-marielle-levou-familia-para-o-exterior\/","url_meta":{"origin":73315,"position":4},"title":"Secret\u00e1ria que estava no carro com Marielle levou familia para o exterior","author":"da Reda\u00e7\u00e3o","date":"25 de janeiro de 2019","format":false,"excerpt":"Fernanda Chaves, a secret\u00e1ria que estava no ve\u00edculo em que Marielle Franco e Anderson Gomes foram assassinados, em mar\u00e7o do ano passado, falou \u00e0 TVT. Ela critica a falta de respostas em rela\u00e7\u00e3o ao crime. Fernanda, que atuou na CPI das Mil\u00edcias, criticou a postura da fam\u00edlia Bolsonaro (PSL), que\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":89005,"url":"https:\/\/www.jornalja.com.br\/geral\/chefe-de-milicia-suspeito-na-morte-de-marielle-franco-foi-preso-na-paraiba\/","url_meta":{"origin":73315,"position":5},"title":"Chefe de mil\u00edcia suspeito na morte de Marielle Franco foi preso na Para\u00edba","author":"da Reda\u00e7\u00e3o","date":"28 de julho de 2021","format":false,"excerpt":"A pol\u00edcia da Para\u00edba prendeu nesta quarta-feira (28), um homem suspeito de envolvimento na morte da vereadora Marielle Franco e do motorista Anderson Gomes. Almir Rog\u00e9rio Gomes da Silva seria integrante de uma mil\u00edcia do Rio de Janeiro, que participou do crime. Segundo a pol\u00edcia paraibana, o grupo foi citado\u2026","rel":"","context":"Em &quot;Geral-MAT\u00c9RIA&quot;","block_context":{"text":"Geral-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/geral\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/73315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/comments?post=73315"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/posts\/73315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/media?parent=73315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/categories?post=73315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/geral\/wp-json\/wp\/v2\/tags?post=73315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}